{"id":31314,"date":"2017-01-10T00:00:00","date_gmt":"2017-01-10T04:00:00","guid":{"rendered":"http:\/\/192.81.217.108\/interamerica\/2017\/01\/ninos-refugiados-sirios-entibian-un-helado-refugio-en-el-oriente-medio\/"},"modified":"2017-12-06T14:15:08","modified_gmt":"2017-12-06T18:15:08","slug":"ninos-refugiados-sirios-entibian-un-helado-refugio-en-el-oriente-medio","status":"publish","type":"post","link":"https:\/\/interamerica.org\/es\/2017\/01\/ninos-refugiados-sirios-entibian-un-helado-refugio-en-el-oriente-medio\/","title":{"rendered":"Ni\u00f1os refugiados sirios entibian un helado refugio en el Oriente Medio"},"content":{"rendered":"<div class=\"article__meta\">\n<div id=\"attachment_25639\" style=\"width: 682px\" class=\"wp-caption aligncenter\"><a href=\"\/interamerica\/wp-content\/uploads\/2017\/06\/csm_syria_26194645d2.jpeg\" rel=\"fancybox\" title=\"Ni\u00f1os refugiados sirios entibian un helado refugio en el Oriente Medio\"><img fetchpriority=\"high\" decoding=\"async\" aria-describedby=\"caption-attachment-25639\" class=\"size-full wp-image-25639\" src=\"\/interamerica\/wp-content\/uploads\/2017\/06\/csm_syria_26194645d2.jpeg\" alt=\"\" width=\"672\" height=\"378\" \/><\/a><p id=\"caption-attachment-25639\" class=\"wp-caption-text\">Imagen provista por: Chanmin Chung, Uni\u00f3n de Oriente Medio y Norte de \u00c1frica]<\/p><\/div>\n<p><span class=\"pub_date font--secondary--s gray can-be--white\">Jan 09, 2017<\/span> <span class=\"divider\">|<\/span> <span class=\"pub_region font--secondary--s gray can-be--white\">Beirut, Lebanon<\/span> <span class=\"divider\">|<\/span> <span class=\"byline font--secondary--s gray can-be--white\">Chanmin Chung, coordinador de comunicaci\u00f3n de la Uni\u00f3n de Oriente Medio y Norte de \u00c1frica <\/span><\/p>\n<\/div>\n<div class=\"article__meta\">Veintisiete estudiantes refugiados sirios, del Centro Adventista de Aprendizaje (ALC por sus siglas en ingl\u00e9s), en Beirut, L\u00edbano, se api\u00f1aron a bordo de un peque\u00f1o autob\u00fas arrendado, para iniciar el viaje de una hora y media hasta el norte de L\u00edbano, a fin de distribuir bolsas de ropa y algunos alimentos donados.<\/div>\n<div class=\"article__meta\">\n<p>Este proyecto anual comenz\u00f3 simplemente como una asignaci\u00f3n dada a este Centro Adventista de Aprendizaje para expresar gratitud por las donaciones y apoyo que recibe de todo el mundo. Por ejemplo, a los ni\u00f1os refugiados de ALC se les dieron abrigos de invierno y botas para la lluvia.<\/p>\n<p>Cada Navidad, el centro le entrega a cada jovencito una caja de zapatos llena de cosas \u00fatiles. Esta Navidad, los estudiantes recibieron el desaf\u00edo de pensar en un proyecto que pudiera beneficiar a alguien m\u00e1s.<\/p>\n<p>\u201cCada uno de nuestros estudiantes tiene su propia historia de p\u00e9rdidas y traumas; pero, a pesar de su pasado, ellos han podido extender su mano hacia los dem\u00e1s y ser tambi\u00e9n una bendici\u00f3n para otros\u201d, dijo Alexis Hurd-Shires, director del Centro Adventista de Aprendizaje.<\/p>\n<p>El director Hurd-Shires dijo que aun cuando muchos de estos ni\u00f1os proceden de hogares que carecen de puertas, ventanas y paredes apropiadas y en los que sus padres no tienen trabajo; y de familias que no saben c\u00f3mo van a pagar la renta o c\u00f3mo proveer de alimento a la familia, de todas maneras, cumplieron con gran diligencia su tarea.<\/p>\n<p>Solicitando donaciones a sus amigos y vecinos, y aun tomando de las donaciones personales que recibieron, los estudiantes reunieron bolsa por bolsa de ropa y zapatos. Como resultado, juntaron m\u00e1s de 30 grandes bolsas negras para basura, llenas de tales art\u00edculos.<\/p>\n<p>Este gesto de sacrificio personal de parte de los ni\u00f1os refugiados toc\u00f3 el coraz\u00f3n de los dirigentes de la iglesia.<\/p>\n<p>\u201cMe conmueve a veces el hecho de que en muchas ocasiones damos aquello que tenemos sin sacrificarnos de ninguna manera, pero que otros comparten aun de aquello que necesitan, a costa de un gran sacrificio\u201d, se\u00f1al\u00f3 Rick McEdward, presidente de la Uni\u00f3n del Oriente Medio y Norte de \u00c1frica.<\/p>\n<p>La historia de este acto realizado por los ni\u00f1os refugiados lo llev\u00f3 a seguir reflexionando sobre el asunto: \u201c\u00bfSer\u00e1 que los pobres est\u00e1n menos apegados a las cosas materiales, de manera que est\u00e1n dispuestos a compartir con los dem\u00e1s aun a pesar de su pobreza?\u201d, dijo el presidente McEdward.<\/p>\n<p>Tan pronto como el veh\u00edculo se detuvo en el lodoso sitio, el autob\u00fas se vio rodeado por los ocupantes de las esparcidas tiendas de campa\u00f1a de la UNICEF.<\/p>\n<p>Cuando se bajaron del autob\u00fas los estudiantes refugiados, los cuales llegaron vistiendo chaquetas abrigadas, botas para la lluvia y tibias gorras que les cubr\u00edan los o\u00eddos, se asombraron de ver muchas escenas inusuales, tales como las de ni\u00f1os caminando sin zapatos y personas refugiadas lavando ropa afuera, en ese clima helado.<\/p>\n<p>Los maestros se impresionaron de igual manera.<\/p>\n<p>\u201cMe tom\u00f3 completamente de sorpresa cuando una gota de agua helada cay\u00f3 sobre mi cuello y dos m\u00e1s mojaron mi cabello\u201d, dijo Giedre Asmar, maestro de cuarto grado del Centro Adventista de Aprendizaje. \u201cCuando manifest\u00e9 mi sorpresa al ver el techo roto de la carpa, por causa del peso del agua de lluvia, los refugiados me dijeron que sus condiciones de vida son solamente tolerables, hasta que empieza a nevar\u201d.<br \/>\nDespu\u00e9s de su visita, comenz\u00f3 la temporada de nieve en el norte de L\u00edbano.<\/p>\n<p>Los ni\u00f1os refugiados de Siria, que llegaron del Centro Adventista de Aprendizaje, se turnaron para cargar las bolsas de ropa y alimentos a cada tienda de campa\u00f1a y luego se esparcieron para pasar alg\u00fan tiempo con los refugiados.<\/p>\n<p>Esto les proporcion\u00f3 la oportunidad de observar las condiciones de vida reinantes.<\/p>\n<p>\u201cNo tienen agua corriente, no alfombra en el piso, y no tienen escuela\u201d, dijo Mohammad, un refugiado sirio de 10 a\u00f1os de edad que estudia en el Centro Adventista de Aprendizaje.<\/p>\n<p>Algunos de los estudiantes jugaron un juego de f\u00fatbol bajo los olivos, con los ni\u00f1os que viven en estas tiendas de campa\u00f1a, los cuales no hab\u00edan visto un bal\u00f3n en mucho tiempo; mientras que otros caminaron en torno a las tiendas hablando con la gente que vive en ellas.<\/p>\n<p>Detr\u00e1s de una tienda de campa\u00f1a, un grupo de estudiantes encontraron a una joven adolescente que estaba tratando de encender un peque\u00f1o fuego a fin de calentar un poco de agua para lavar ropa. R\u00e1pidamente se esparcieron para ayudarla a encontrar m\u00e1s le\u00f1a y manejar entonces el fuego debajo de la olla de metal.<\/p>\n<p>Despu\u00e9s de la visita, los visitantes y los refugiados del lugar se reunieron en el lodoso campo para decirse adi\u00f3s.<\/p>\n<p>\u201cCuando est\u00e1bamos por partir, una anciana me dijo al o\u00eddo que, por unas cuantas horas, la hicimos olvidar sus circunstancias y el lugar donde se encontraban\u201d, dijo el director Hurd-Shires.<\/p>\n<\/div>\n<p>Traducci\u00f3n por Gloria A. Castrej\u00f3n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Veintisiete estudiantes refugiados sirios, del Centro Adventista de Aprendizaje (ALC por sus siglas en ingl\u00e9s), en Beirut, L\u00edbano, se api\u00f1aron a bordo de un peque\u00f1o autob\u00fas arrendado, para iniciar el viaje de una hora y media hasta el norte de L\u00edbano, a fin de distribuir bolsas de ropa y algunos alimentos donados. Este proyecto anual comenz\u00f3 simplemente como una asignaci\u00f3n dada a este Centro Adventista de Aprendizaje para expresar gratitud por las donaciones y apoyo que recibe de todo el mundo. Por ejemplo, a los ni\u00f1os refugiados de ALC se les dieron abrigos de invierno y botas para la lluvia.<\/p>\n","protected":false},"author":1,"featured_media":29132,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[14,15],"tags":[],"class_list":["post-31314","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-de-la-iglesia-mundial","category-rss-espanol"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ni\u00f1os refugiados sirios entibian un helado refugio en el Oriente Medio - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/interamerica.org\/es\/2017\/01\/ninos-refugiados-sirios-entibian-un-helado-refugio-en-el-oriente-medio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ni\u00f1os refugiados sirios entibian un helado refugio en el Oriente Medio - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana\" \/>\n<meta property=\"og:description\" content=\"Veintisiete estudiantes refugiados sirios, del Centro Adventista de Aprendizaje (ALC por sus siglas en ingl\u00e9s), en Beirut, L\u00edbano, se api\u00f1aron a bordo de un peque\u00f1o autob\u00fas arrendado, para iniciar el viaje de una hora y media hasta el norte de L\u00edbano, a fin de distribuir bolsas de ropa y algunos alimentos donados. Este proyecto anual comenz\u00f3 simplemente como una asignaci\u00f3n dada a este Centro Adventista de Aprendizaje para expresar gratitud por las donaciones y apoyo que recibe de todo el mundo. Por ejemplo, a los ni\u00f1os refugiados de ALC se les dieron abrigos de invierno y botas para la lluvia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/interamerica.org\/es\/2017\/01\/ninos-refugiados-sirios-entibian-un-helado-refugio-en-el-oriente-medio\/\" \/>\n<meta property=\"og:site_name\" content=\"Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana\" \/>\n<meta property=\"article:published_time\" content=\"2017-01-10T04:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-12-06T18:15:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/interamerica.org\/wp-content\/uploads\/2017\/06\/csm_syria_26194645d2.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"672\" \/>\n\t<meta property=\"og:image:height\" content=\"378\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lorenzo Verduzco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lorenzo Verduzco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2017\\\/01\\\/ninos-refugiados-sirios-entibian-un-helado-refugio-en-el-oriente-medio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2017\\\/01\\\/ninos-refugiados-sirios-entibian-un-helado-refugio-en-el-oriente-medio\\\/\"},\"author\":{\"name\":\"Lorenzo Verduzco\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#\\\/schema\\\/person\\\/68ede8bdc292885bb76c1e3810e73c39\"},\"headline\":\"Ni\u00f1os refugiados sirios entibian un helado refugio en el Oriente Medio\",\"datePublished\":\"2017-01-10T04:00:00+00:00\",\"dateModified\":\"2017-12-06T18:15:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2017\\\/01\\\/ninos-refugiados-sirios-entibian-un-helado-refugio-en-el-oriente-medio\\\/\"},\"wordCount\":916,\"image\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2017\\\/01\\\/ninos-refugiados-sirios-entibian-un-helado-refugio-en-el-oriente-medio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/csm_syria_26194645d2.jpeg\",\"articleSection\":[\"Desde la iglesia mundial\",\"RSS Espa\u00f1ol\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2017\\\/01\\\/ninos-refugiados-sirios-entibian-un-helado-refugio-en-el-oriente-medio\\\/\",\"url\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2017\\\/01\\\/ninos-refugiados-sirios-entibian-un-helado-refugio-en-el-oriente-medio\\\/\",\"name\":\"Ni\u00f1os refugiados sirios entibian un helado refugio en el Oriente Medio - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2017\\\/01\\\/ninos-refugiados-sirios-entibian-un-helado-refugio-en-el-oriente-medio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2017\\\/01\\\/ninos-refugiados-sirios-entibian-un-helado-refugio-en-el-oriente-medio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/csm_syria_26194645d2.jpeg\",\"datePublished\":\"2017-01-10T04:00:00+00:00\",\"dateModified\":\"2017-12-06T18:15:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#\\\/schema\\\/person\\\/68ede8bdc292885bb76c1e3810e73c39\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2017\\\/01\\\/ninos-refugiados-sirios-entibian-un-helado-refugio-en-el-oriente-medio\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/interamerica.org\\\/es\\\/2017\\\/01\\\/ninos-refugiados-sirios-entibian-un-helado-refugio-en-el-oriente-medio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2017\\\/01\\\/ninos-refugiados-sirios-entibian-un-helado-refugio-en-el-oriente-medio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/csm_syria_26194645d2.jpeg\",\"contentUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/csm_syria_26194645d2.jpeg\",\"width\":672,\"height\":378},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2017\\\/01\\\/ninos-refugiados-sirios-entibian-un-helado-refugio-en-el-oriente-medio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/interamerica.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ni\u00f1os refugiados sirios entibian un helado refugio en el Oriente Medio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/interamerica.org\\\/es\\\/\",\"name\":\"Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/interamerica.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#\\\/schema\\\/person\\\/68ede8bdc292885bb76c1e3810e73c39\",\"name\":\"Lorenzo Verduzco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g\",\"caption\":\"Lorenzo Verduzco\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ni\u00f1os refugiados sirios entibian un helado refugio en el Oriente Medio - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/interamerica.org\/es\/2017\/01\/ninos-refugiados-sirios-entibian-un-helado-refugio-en-el-oriente-medio\/","og_locale":"es_ES","og_type":"article","og_title":"Ni\u00f1os refugiados sirios entibian un helado refugio en el Oriente Medio - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","og_description":"Veintisiete estudiantes refugiados sirios, del Centro Adventista de Aprendizaje (ALC por sus siglas en ingl\u00e9s), en Beirut, L\u00edbano, se api\u00f1aron a bordo de un peque\u00f1o autob\u00fas arrendado, para iniciar el viaje de una hora y media hasta el norte de L\u00edbano, a fin de distribuir bolsas de ropa y algunos alimentos donados. Este proyecto anual comenz\u00f3 simplemente como una asignaci\u00f3n dada a este Centro Adventista de Aprendizaje para expresar gratitud por las donaciones y apoyo que recibe de todo el mundo. Por ejemplo, a los ni\u00f1os refugiados de ALC se les dieron abrigos de invierno y botas para la lluvia.","og_url":"https:\/\/interamerica.org\/es\/2017\/01\/ninos-refugiados-sirios-entibian-un-helado-refugio-en-el-oriente-medio\/","og_site_name":"Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","article_published_time":"2017-01-10T04:00:00+00:00","article_modified_time":"2017-12-06T18:15:08+00:00","og_image":[{"width":672,"height":378,"url":"https:\/\/interamerica.org\/wp-content\/uploads\/2017\/06\/csm_syria_26194645d2.jpeg","type":"image\/jpeg"}],"author":"Lorenzo Verduzco","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Lorenzo Verduzco","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/interamerica.org\/es\/2017\/01\/ninos-refugiados-sirios-entibian-un-helado-refugio-en-el-oriente-medio\/#article","isPartOf":{"@id":"https:\/\/interamerica.org\/es\/2017\/01\/ninos-refugiados-sirios-entibian-un-helado-refugio-en-el-oriente-medio\/"},"author":{"name":"Lorenzo Verduzco","@id":"https:\/\/interamerica.org\/es\/#\/schema\/person\/68ede8bdc292885bb76c1e3810e73c39"},"headline":"Ni\u00f1os refugiados sirios entibian un helado refugio en el Oriente Medio","datePublished":"2017-01-10T04:00:00+00:00","dateModified":"2017-12-06T18:15:08+00:00","mainEntityOfPage":{"@id":"https:\/\/interamerica.org\/es\/2017\/01\/ninos-refugiados-sirios-entibian-un-helado-refugio-en-el-oriente-medio\/"},"wordCount":916,"image":{"@id":"https:\/\/interamerica.org\/es\/2017\/01\/ninos-refugiados-sirios-entibian-un-helado-refugio-en-el-oriente-medio\/#primaryimage"},"thumbnailUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2017\/06\/csm_syria_26194645d2.jpeg","articleSection":["Desde la iglesia mundial","RSS Espa\u00f1ol"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/interamerica.org\/es\/2017\/01\/ninos-refugiados-sirios-entibian-un-helado-refugio-en-el-oriente-medio\/","url":"https:\/\/interamerica.org\/es\/2017\/01\/ninos-refugiados-sirios-entibian-un-helado-refugio-en-el-oriente-medio\/","name":"Ni\u00f1os refugiados sirios entibian un helado refugio en el Oriente Medio - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","isPartOf":{"@id":"https:\/\/interamerica.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/interamerica.org\/es\/2017\/01\/ninos-refugiados-sirios-entibian-un-helado-refugio-en-el-oriente-medio\/#primaryimage"},"image":{"@id":"https:\/\/interamerica.org\/es\/2017\/01\/ninos-refugiados-sirios-entibian-un-helado-refugio-en-el-oriente-medio\/#primaryimage"},"thumbnailUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2017\/06\/csm_syria_26194645d2.jpeg","datePublished":"2017-01-10T04:00:00+00:00","dateModified":"2017-12-06T18:15:08+00:00","author":{"@id":"https:\/\/interamerica.org\/es\/#\/schema\/person\/68ede8bdc292885bb76c1e3810e73c39"},"breadcrumb":{"@id":"https:\/\/interamerica.org\/es\/2017\/01\/ninos-refugiados-sirios-entibian-un-helado-refugio-en-el-oriente-medio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/interamerica.org\/es\/2017\/01\/ninos-refugiados-sirios-entibian-un-helado-refugio-en-el-oriente-medio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/interamerica.org\/es\/2017\/01\/ninos-refugiados-sirios-entibian-un-helado-refugio-en-el-oriente-medio\/#primaryimage","url":"https:\/\/interamerica.org\/wp-content\/uploads\/2017\/06\/csm_syria_26194645d2.jpeg","contentUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2017\/06\/csm_syria_26194645d2.jpeg","width":672,"height":378},{"@type":"BreadcrumbList","@id":"https:\/\/interamerica.org\/es\/2017\/01\/ninos-refugiados-sirios-entibian-un-helado-refugio-en-el-oriente-medio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/interamerica.org\/es\/"},{"@type":"ListItem","position":2,"name":"Ni\u00f1os refugiados sirios entibian un helado refugio en el Oriente Medio"}]},{"@type":"WebSite","@id":"https:\/\/interamerica.org\/es\/#website","url":"https:\/\/interamerica.org\/es\/","name":"Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/interamerica.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/interamerica.org\/es\/#\/schema\/person\/68ede8bdc292885bb76c1e3810e73c39","name":"Lorenzo Verduzco","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g","caption":"Lorenzo Verduzco"}}]}},"_links":{"self":[{"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/posts\/31314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/comments?post=31314"}],"version-history":[{"count":0,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/posts\/31314\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/media\/29132"}],"wp:attachment":[{"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/media?parent=31314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/categories?post=31314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/tags?post=31314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}