{"id":38415,"date":"2018-01-29T00:00:00","date_gmt":"2018-01-29T04:00:00","guid":{"rendered":"http:\/\/192.81.217.108\/2018\/01\/dominica-pasa-de-la-asistencia-a-la-reconstruccion-gracias-al-apoyo-internacional\/"},"modified":"2018-02-20T14:46:06","modified_gmt":"2018-02-20T18:46:06","slug":"dominica-pasa-de-la-asistencia-a-la-reconstruccion-gracias-al-apoyo-internacional","status":"publish","type":"post","link":"https:\/\/interamerica.org\/es\/2018\/01\/dominica-pasa-de-la-asistencia-a-la-reconstruccion-gracias-al-apoyo-internacional\/","title":{"rendered":"Dominica pasa de la asistencia a la reconstrucci\u00f3n gracias al apoyo internacional"},"content":{"rendered":"<div id=\"attachment_33112\" style=\"width: 786px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/01\/dominica-goes-from-relief-to-rebuild-thanks-to-international-support.jpg\" rel=\"fancybox\" title=\"Dominica pasa de la asistencia a la reconstrucci\u00f3n gracias al apoyo internacional\"><img fetchpriority=\"high\" decoding=\"async\" aria-describedby=\"caption-attachment-33112\" class=\" wp-image-33112\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/01\/dominica-goes-from-relief-to-rebuild-thanks-to-international-support.jpg\" alt=\"\" width=\"776\" height=\"388\" \/><\/a><p id=\"caption-attachment-33112\" class=\"wp-caption-text\"><br \/>Un par de miembros de iglesia de la Asociaci\u00f3n Noreste de Nueva York, Estados Unidos, colaboraron con los esfuerzos de reconstrucci\u00f3n en Dominica este mes. Grupos de diversas regions eclesi\u00e1sticas est\u00e1n colaborando con los esfuerzos de reconstrucci\u00f3n en la isla. Imagen de David Lopez, Maranatha Volunteers International<\/p><\/div>\n<p>27 de junio de 2018 | <span class=\"byline-news\"><em>Adventist Review<\/em><\/span><\/p>\n<div id=\"attachment_33115\" style=\"width: 465px\" class=\"wp-caption alignright\"><a href=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/01\/dominica-mvi.jpg\" rel=\"fancybox\" title=\"Dominica pasa de la asistencia a la reconstrucci\u00f3n gracias al apoyo internacional\"><img decoding=\"async\" aria-describedby=\"caption-attachment-33115\" class=\" wp-image-33115\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/01\/dominica-mvi.jpg\" alt=\"\" width=\"455\" height=\"341\" \/><\/a><p id=\"caption-attachment-33115\" class=\"wp-caption-text\">Grupos de voluntarios de diversas regiones eclesi\u00e1sticas est\u00e1n viajando a Dominica para ayudar a reconstruir iglesias y hogares afectados por el hurac\u00e1n Mar\u00eda, y construir nuevos. Imagen de David Lopez, Maranatha Volunteers International<\/p><\/div>\n<p><span class=\"cap\">La Agencia Adventista de Desarrollo y Recursos Asistenciales (ADRA) Dominica est\u00e1 pasando actualmente de la asistencia a la reconstrucci\u00f3n, dijeron los l\u00edderes de la organizaci\u00f3n en esa naci\u00f3n del Caribe, despu\u00e9s de que el hurac\u00e1n Mar\u00eda da\u00f1\u00f3 casas, iglesias y escuelas en la isla el a\u00f1o pasado. ADRA, el brazo humanitario de la Iglesia Adventista del S\u00e9ptimo D\u00eda, <a href=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/es\/2015\/08\/en-la-region-venezolana-oriental-los-adventistas-participan-en-historico-impacto-en-multiples-ciudades\/\">recibi\u00f3 hace poco un contenedor de seis metros de la sede de la Divisi\u00f3n Interamericana en Miami, Florida<\/a>, Estados Unidos, con cubos llenos de art\u00edculos de limpieza, que ahora est\u00e1n siendo distribuidos en las comunidades afectadas.<\/span><\/p>\n<p>Otro contenedor de doce metros proveniente del Colegio Adventista Crawford en Toronto, Canad\u00e1, con art\u00edculos del hogar y alimentos, fue liberado de la Aduana el 22 de enero.<\/p>\n<p>Mientras tanto, un equipo de 16 voluntarios bajo la coordinaci\u00f3n de Fitzgerald Kerr, pastor en la Asociaci\u00f3n Noreste de Nueva York, Estados Unidos, dej\u00f3 Dominica el 19 de enero despu\u00e9s de diez d\u00edas de duro trabajo en el nuevo templo de Pointe Michel. La Antigua iglesia es una de las que fue totalmente destruida por el hurac\u00e1n Mar\u00eda.<\/p>\n<p>Los voluntarios estuvieron acompa\u00f1ados por miembros de la iglesia local y la pastora Sherry Augustus y un equipo de cuatro personas desde Canad\u00e1. Mientras estaban all\u00ed, tambi\u00e9n ayudaron a que dos familias de Egleston repararan el techo de sus casas, que fue volado por la tormenta.<\/p>\n<p>El 7 de febrero, se espera que llegue el grupo Ambassadors de Trinidad para seguir apoyando los esfuerzos de reconstrucci\u00f3n, dijo Priscilla Prevost coordinadora asociada de ADRA Dominica, quien est\u00e1 a cargo de coordinar los equipos de voluntarios que llegan a la isla. Dijo que est\u00e1n esperando otro equipo de la Asociaci\u00f3n del Noreste el 24 de febrero.<\/p>\n<div id=\"attachment_33118\" style=\"width: 465px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/01\/dominica-buckets.jpg\" rel=\"fancybox\" title=\"Dominica pasa de la asistencia a la reconstrucci\u00f3n gracias al apoyo internacional\"><img decoding=\"async\" aria-describedby=\"caption-attachment-33118\" class=\" wp-image-33118\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/01\/dominica-buckets.jpg\" alt=\"\" width=\"455\" height=\"303\" \/><\/a><p id=\"caption-attachment-33118\" class=\"wp-caption-text\">Cubos donados por Servicios Comunitarios de la Asociaci\u00f3n de Allegheny Oriental en Pennsylvania y la Uni\u00f3n de Columbia en Maryland llegaron a Dominica en un env\u00edo de la Divisi\u00f3n Interamericana el mes pasado, Imagen de Maranatha Volunteers International<\/p><\/div>\n<p>Por otro lado, Maranatha Volunteers International (MVI), un ministerio de apoyo de la Iglesia Adventista del S\u00e9ptimo D\u00eda, llev\u00f3 a cabo hace poco una visita de exploraci\u00f3n para trabajar en la log\u00edstica, antes de que un grupo de voluntarios lleve a cabo un proyecto en la isla dentro de unos meses, seg\u00fan David Lopez, director de Proyectos Voluntarios de MVI.<\/p>\n<p>\u201cVoluntarios de Maranatha [\u2026] llegar\u00e1n pronto para ayudar a reconstruir iglesias y construir nuevas iglesias en Dominica\u201d, dijo Lopez.<\/p>\n<p>Prevost, que ayud\u00f3 a Lopez en la planificaci\u00f3n del alojamiento y la log\u00edstica de los pr\u00f3ximos proyectos en la isla, dijo que ADRA est\u00e1 agradecida de recibir todo el apoyo de la iglesia que sea posible.<\/p>\n<p>\u201cEstamos agradecidos por la contribuci\u00f3n de nuestros hermanos\u201d, expres\u00f3.<\/p>\n<p><em>ADRA Dominica colabor\u00f3 con este informe.<\/em><\/p>\n<p>Traducci\u00f3n de Marcos Paseggi<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Agencia Adventista de Desarrollo y Recursos Asistenciales (ADRA) Dominica est\u00e1 pasando actualmente de la asistencia a la reconstrucci\u00f3n, dijeron los l\u00edderes de la organizaci\u00f3n en esa naci\u00f3n del Caribe, despu\u00e9s de que el hurac\u00e1n Mar\u00eda da\u00f1\u00f3 casas, iglesias y escuelas en la isla el a\u00f1o pasado. ADRA, el brazo humanitario de la Iglesia Adventista del S\u00e9ptimo D\u00eda, recibi\u00f3 hace poco un contenedor de seis metros de la sede de la Divisi\u00f3n Interamericana en Miami, Florida<\/a>, Estados Unidos, con cubos llenos de art\u00edculos de limpieza, que ahora est\u00e1n siendo distribuidos en las comunidades afectadas.<\/p>\n","protected":false},"author":1,"featured_media":38348,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17,15],"tags":[],"class_list":["post-38415","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-desde-el-campo","category-rss-espanol"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dominica pasa de la asistencia a la reconstrucci\u00f3n gracias al apoyo internacional - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/interamerica.org\/es\/2018\/01\/dominica-pasa-de-la-asistencia-a-la-reconstruccion-gracias-al-apoyo-internacional\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dominica pasa de la asistencia a la reconstrucci\u00f3n gracias al apoyo internacional - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana\" \/>\n<meta property=\"og:description\" content=\"La Agencia Adventista de Desarrollo y Recursos Asistenciales (ADRA) Dominica est\u00e1 pasando actualmente de la asistencia a la reconstrucci\u00f3n, dijeron los l\u00edderes de la organizaci\u00f3n en esa naci\u00f3n del Caribe, despu\u00e9s de que el hurac\u00e1n Mar\u00eda da\u00f1\u00f3 casas, iglesias y escuelas en la isla el a\u00f1o pasado. ADRA, el brazo humanitario de la Iglesia Adventista del S\u00e9ptimo D\u00eda, recibi\u00f3 hace poco un contenedor de seis metros de la sede de la Divisi\u00f3n Interamericana en Miami, Florida, Estados Unidos, con cubos llenos de art\u00edculos de limpieza, que ahora est\u00e1n siendo distribuidos en las comunidades afectadas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/interamerica.org\/es\/2018\/01\/dominica-pasa-de-la-asistencia-a-la-reconstruccion-gracias-al-apoyo-internacional\/\" \/>\n<meta property=\"og:site_name\" content=\"Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-29T04:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-02-20T18:46:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/02\/dominica-goes-from-relief-to-rebuild-thanks-to-international-support.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lorenzo Verduzco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lorenzo Verduzco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/01\\\/dominica-pasa-de-la-asistencia-a-la-reconstruccion-gracias-al-apoyo-internacional\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/01\\\/dominica-pasa-de-la-asistencia-a-la-reconstruccion-gracias-al-apoyo-internacional\\\/\"},\"author\":{\"name\":\"Lorenzo Verduzco\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#\\\/schema\\\/person\\\/68ede8bdc292885bb76c1e3810e73c39\"},\"headline\":\"Dominica pasa de la asistencia a la reconstrucci\u00f3n gracias al apoyo internacional\",\"datePublished\":\"2018-01-29T04:00:00+00:00\",\"dateModified\":\"2018-02-20T18:46:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/01\\\/dominica-pasa-de-la-asistencia-a-la-reconstruccion-gracias-al-apoyo-internacional\\\/\"},\"wordCount\":618,\"image\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/01\\\/dominica-pasa-de-la-asistencia-a-la-reconstruccion-gracias-al-apoyo-internacional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/dominica-goes-from-relief-to-rebuild-thanks-to-international-support.jpg\",\"articleSection\":[\"Desde el campo\",\"RSS Espa\u00f1ol\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/01\\\/dominica-pasa-de-la-asistencia-a-la-reconstruccion-gracias-al-apoyo-internacional\\\/\",\"url\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/01\\\/dominica-pasa-de-la-asistencia-a-la-reconstruccion-gracias-al-apoyo-internacional\\\/\",\"name\":\"Dominica pasa de la asistencia a la reconstrucci\u00f3n gracias al apoyo internacional - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/01\\\/dominica-pasa-de-la-asistencia-a-la-reconstruccion-gracias-al-apoyo-internacional\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/01\\\/dominica-pasa-de-la-asistencia-a-la-reconstruccion-gracias-al-apoyo-internacional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/dominica-goes-from-relief-to-rebuild-thanks-to-international-support.jpg\",\"datePublished\":\"2018-01-29T04:00:00+00:00\",\"dateModified\":\"2018-02-20T18:46:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#\\\/schema\\\/person\\\/68ede8bdc292885bb76c1e3810e73c39\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/01\\\/dominica-pasa-de-la-asistencia-a-la-reconstruccion-gracias-al-apoyo-internacional\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/01\\\/dominica-pasa-de-la-asistencia-a-la-reconstruccion-gracias-al-apoyo-internacional\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/01\\\/dominica-pasa-de-la-asistencia-a-la-reconstruccion-gracias-al-apoyo-internacional\\\/#primaryimage\",\"url\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/dominica-goes-from-relief-to-rebuild-thanks-to-international-support.jpg\",\"contentUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/dominica-goes-from-relief-to-rebuild-thanks-to-international-support.jpg\",\"width\":1000,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/01\\\/dominica-pasa-de-la-asistencia-a-la-reconstruccion-gracias-al-apoyo-internacional\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/interamerica.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dominica pasa de la asistencia a la reconstrucci\u00f3n gracias al apoyo internacional\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/interamerica.org\\\/es\\\/\",\"name\":\"Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/interamerica.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#\\\/schema\\\/person\\\/68ede8bdc292885bb76c1e3810e73c39\",\"name\":\"Lorenzo Verduzco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g\",\"caption\":\"Lorenzo Verduzco\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dominica pasa de la asistencia a la reconstrucci\u00f3n gracias al apoyo internacional - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/interamerica.org\/es\/2018\/01\/dominica-pasa-de-la-asistencia-a-la-reconstruccion-gracias-al-apoyo-internacional\/","og_locale":"es_ES","og_type":"article","og_title":"Dominica pasa de la asistencia a la reconstrucci\u00f3n gracias al apoyo internacional - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","og_description":"La Agencia Adventista de Desarrollo y Recursos Asistenciales (ADRA) Dominica est\u00e1 pasando actualmente de la asistencia a la reconstrucci\u00f3n, dijeron los l\u00edderes de la organizaci\u00f3n en esa naci\u00f3n del Caribe, despu\u00e9s de que el hurac\u00e1n Mar\u00eda da\u00f1\u00f3 casas, iglesias y escuelas en la isla el a\u00f1o pasado. ADRA, el brazo humanitario de la Iglesia Adventista del S\u00e9ptimo D\u00eda, recibi\u00f3 hace poco un contenedor de seis metros de la sede de la Divisi\u00f3n Interamericana en Miami, Florida, Estados Unidos, con cubos llenos de art\u00edculos de limpieza, que ahora est\u00e1n siendo distribuidos en las comunidades afectadas.","og_url":"https:\/\/interamerica.org\/es\/2018\/01\/dominica-pasa-de-la-asistencia-a-la-reconstruccion-gracias-al-apoyo-internacional\/","og_site_name":"Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","article_published_time":"2018-01-29T04:00:00+00:00","article_modified_time":"2018-02-20T18:46:06+00:00","og_image":[{"width":1000,"height":500,"url":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/02\/dominica-goes-from-relief-to-rebuild-thanks-to-international-support.jpg","type":"image\/jpeg"}],"author":"Lorenzo Verduzco","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Lorenzo Verduzco","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/interamerica.org\/es\/2018\/01\/dominica-pasa-de-la-asistencia-a-la-reconstruccion-gracias-al-apoyo-internacional\/#article","isPartOf":{"@id":"https:\/\/interamerica.org\/es\/2018\/01\/dominica-pasa-de-la-asistencia-a-la-reconstruccion-gracias-al-apoyo-internacional\/"},"author":{"name":"Lorenzo Verduzco","@id":"https:\/\/interamerica.org\/es\/#\/schema\/person\/68ede8bdc292885bb76c1e3810e73c39"},"headline":"Dominica pasa de la asistencia a la reconstrucci\u00f3n gracias al apoyo internacional","datePublished":"2018-01-29T04:00:00+00:00","dateModified":"2018-02-20T18:46:06+00:00","mainEntityOfPage":{"@id":"https:\/\/interamerica.org\/es\/2018\/01\/dominica-pasa-de-la-asistencia-a-la-reconstruccion-gracias-al-apoyo-internacional\/"},"wordCount":618,"image":{"@id":"https:\/\/interamerica.org\/es\/2018\/01\/dominica-pasa-de-la-asistencia-a-la-reconstruccion-gracias-al-apoyo-internacional\/#primaryimage"},"thumbnailUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/02\/dominica-goes-from-relief-to-rebuild-thanks-to-international-support.jpg","articleSection":["Desde el campo","RSS Espa\u00f1ol"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/interamerica.org\/es\/2018\/01\/dominica-pasa-de-la-asistencia-a-la-reconstruccion-gracias-al-apoyo-internacional\/","url":"https:\/\/interamerica.org\/es\/2018\/01\/dominica-pasa-de-la-asistencia-a-la-reconstruccion-gracias-al-apoyo-internacional\/","name":"Dominica pasa de la asistencia a la reconstrucci\u00f3n gracias al apoyo internacional - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","isPartOf":{"@id":"https:\/\/interamerica.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/interamerica.org\/es\/2018\/01\/dominica-pasa-de-la-asistencia-a-la-reconstruccion-gracias-al-apoyo-internacional\/#primaryimage"},"image":{"@id":"https:\/\/interamerica.org\/es\/2018\/01\/dominica-pasa-de-la-asistencia-a-la-reconstruccion-gracias-al-apoyo-internacional\/#primaryimage"},"thumbnailUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/02\/dominica-goes-from-relief-to-rebuild-thanks-to-international-support.jpg","datePublished":"2018-01-29T04:00:00+00:00","dateModified":"2018-02-20T18:46:06+00:00","author":{"@id":"https:\/\/interamerica.org\/es\/#\/schema\/person\/68ede8bdc292885bb76c1e3810e73c39"},"breadcrumb":{"@id":"https:\/\/interamerica.org\/es\/2018\/01\/dominica-pasa-de-la-asistencia-a-la-reconstruccion-gracias-al-apoyo-internacional\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/interamerica.org\/es\/2018\/01\/dominica-pasa-de-la-asistencia-a-la-reconstruccion-gracias-al-apoyo-internacional\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/interamerica.org\/es\/2018\/01\/dominica-pasa-de-la-asistencia-a-la-reconstruccion-gracias-al-apoyo-internacional\/#primaryimage","url":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/02\/dominica-goes-from-relief-to-rebuild-thanks-to-international-support.jpg","contentUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/02\/dominica-goes-from-relief-to-rebuild-thanks-to-international-support.jpg","width":1000,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/interamerica.org\/es\/2018\/01\/dominica-pasa-de-la-asistencia-a-la-reconstruccion-gracias-al-apoyo-internacional\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/interamerica.org\/es\/"},{"@type":"ListItem","position":2,"name":"Dominica pasa de la asistencia a la reconstrucci\u00f3n gracias al apoyo internacional"}]},{"@type":"WebSite","@id":"https:\/\/interamerica.org\/es\/#website","url":"https:\/\/interamerica.org\/es\/","name":"Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/interamerica.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/interamerica.org\/es\/#\/schema\/person\/68ede8bdc292885bb76c1e3810e73c39","name":"Lorenzo Verduzco","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g","caption":"Lorenzo Verduzco"}}]}},"_links":{"self":[{"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/posts\/38415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/comments?post=38415"}],"version-history":[{"count":0,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/posts\/38415\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/media\/38348"}],"wp:attachment":[{"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/media?parent=38415"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/categories?post=38415"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/tags?post=38415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}