{"id":38420,"date":"2018-01-28T00:00:00","date_gmt":"2018-01-28T04:00:00","guid":{"rendered":"http:\/\/192.81.217.108\/2018\/01\/en-las-naciones-unidas-los-adventistas-enfatizan-la-compasion-por-los-refugiados\/"},"modified":"2018-12-03T22:03:35","modified_gmt":"2018-12-04T02:03:35","slug":"en-las-naciones-unidas-los-adventistas-enfatizan-la-compasion-por-los-refugiados","status":"publish","type":"post","link":"https:\/\/interamerica.org\/es\/2018\/01\/en-las-naciones-unidas-los-adventistas-enfatizan-la-compasion-por-los-refugiados\/","title":{"rendered":"En las Naciones Unidas, los adventistas enfatizan la compasi\u00f3n por los refugiados"},"content":{"rendered":"<div id=\"attachment_33091\" style=\"width: 802px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/01\/United-Nations.jpg\" rel=\"fancybox\" title=\"En las Naciones Unidas, los adventistas enfatizan la compasi\u00f3n por los refugiados\"><img fetchpriority=\"high\" decoding=\"async\" aria-describedby=\"caption-attachment-33091\" class=\"wp-image-33091 \" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/01\/United-Nations.jpg\" alt=\"\" width=\"792\" height=\"396\" \/><\/a><p id=\"caption-attachment-33091\" class=\"wp-caption-text\">El auditorio en le Secretar\u00eda de las Naciones Unidas, en Nueva York, en donde se llev\u00f3 a cabo el Cuarto Simposio Anual sobre el Papel de la Religi\u00f3n y de las Organizaciones de Base Religiosa en los Asuntos Internacionales, el 22 de enero. La Iglesia Adventista del S\u00e9ptimo D\u00eda copatrocin\u00f3 el evento. Imagen cortes\u00eda de la Asociaci\u00f3n Internacional de Libertad Religiosa<\/p><\/div>\n<p>26 de enero de 2018 | Nueva York, Estados Unidos | <span class=\"byline-news\">Bettina Krause, Asociaci\u00f3n Internacional de Libertad Religiosa<\/span><\/p>\n<p><span class=\"cap\">I<\/span>nmigrantes y refugiados no son \u201cproblemas para ser resueltos\u201d, sino personas vulnerables que deben ser tratadas con respeto y compasi\u00f3n, dijeron los participantes esta semana en un simposio en las Naciones Unidas, copatrocinado por la Iglesia Adventista del S\u00e9ptimo D\u00eda. Este evento, celebrado el 22 de enero del presente en la Secretar\u00eda de las Naciones Unidas, en Nueva York, Estados Unidos, fue el Cuarto Simposio Anual sobre el Papel de la Religi\u00f3n y de las Organizaciones de Base Religiosa en los Asuntos Internacionales, el cual reuni\u00f3 a aproximadamente 250 representantes de la comunidad de las Naciones Unidas, grupos religiosos y organizaciones no gubernamentales.<\/p>\n<p>\u201cLos refugiados e inmigrantes no son los \u2018otros\u2019, ellos son \u2018nosotros\u2019\u201d, dijo la subsecretaria general de la ONU, Sra. Amina J. Mohammed, en su discurso de apertura ante el grupo de asistentes. \u201cEllos son parte del pasado y presente de la historia de la familia global\u201d. Inst\u00f3 a los dirigentes religiosos y a las organizaciones de base religiosa a aportar a trav\u00e9s de su voz moral y experiencia en favor de atenci\u00f3n y cuidados hacia estas personas vulnerables, y a\u00f1adi\u00f3 que los grupos religiosos est\u00e1n en la muy \u00fanica posici\u00f3n de enfocar su atenci\u00f3n en la gente, en vez de en la pol\u00edtica. \u201cUstedes reafirman incansablemente los derechos humanos y dignidad de los inmigrantes y refugiados, independientemente de los intereses y agendas nacionales\u201d, dijo la subsecretaria Mohammed.<\/p>\n<p>Las estad\u00edsticas sobre inmigrantes y refugiados son realmente impactantes. De acuerdo con la ONU, el mundo est\u00e1 actualmente experimentando una gran movilidad sin precedente en la historia de la humanidad, de personas que abandonan sus pa\u00edses por razones de conflicto, pobreza y muchos otros desaf\u00edos. Se estima que el a\u00f1o pasado, 65.6 millones de personas fueron desplazadas de sus hogares. De entre ellas, una vasta cantidad \u2014casi un 50 por ciento de las mismas\u2014 eran ni\u00f1os y personas j\u00f3venes.<\/p>\n<p>El director de Asuntos P\u00fablicos y Libertad Religiosa de la Iglesia Adventista, Ganoune Diop, fue uno de los principales organizadores del simposio, el cual les dijo a los presentes que la intenci\u00f3n de este evento era ir un tanto m\u00e1s all\u00e1 de \u201csimplemente palabras\u201d.<\/p>\n<p>\u201cNo solamente deseamos hacer una diferencia en la base misma, en el nivel local, sino que deseamos ayudar a cambiar la narrativa acerca de inmigrantes y refugiados\u201d, dijo el director Diop.<\/p>\n<p>Dijo que la Iglesia Adventista contin\u00faa dedicada a ayudar a aliviar el sufrimiento de las personas desplazadas y habl\u00f3 tambi\u00e9n acerca del \u201cportafolio de servicio\u201d de la Iglesia Adventista, incluyendo su enfoque en los cuidados de salud, su red mundial educativa y la obra global humanitaria desempe\u00f1ada por la Agencia de Desarrollo y Recursos Asistenciales (ADRA) de esta iglesia.<\/p>\n<p>La refugiada Sana Mustafa ofreci\u00f3 una apasionada presentaci\u00f3n, acerca de un tema cuyos ecos resonaron en otras presentaciones de oradores durante el d\u00eda: el peligro de \u201cdeshumanizar\u201d a los refugiados e inmigrantes. Sana Mustafa fue separada de su familia, quien huy\u00f3 de la guerra en Siria y descubri\u00f3 por experiencia personal cu\u00e1n desorientadora e impersonal puede ser la experiencia de un refugiado.<\/p>\n<p>\u201cPor favor, traten a los refugiados como individuos, no como \u2018complicaciones\u2019 o \u2018asuntos sociales\u2019, dijo. Hizo notar tambi\u00e9n que las noticias e informes en el mundo occidental raramente cuentan las historias desde el punto de vista individual de los inmigrantes y refugiados, sino m\u00e1s bien, tienden a enfocar su atenci\u00f3n en los desaf\u00edos sociales que los reci\u00e9n llegados posan para una determinada comunidad.<\/p>\n<p>Dijo que los grupos de base religiosa pueden jugar un papel clave en cuanto a combatir el prejuicio y la discriminaci\u00f3n, educando a los ciudadanos de los pa\u00edses anfitriones acerca del trauma soportado por las personas desplazadas y ayudando a la gente a abrir su coraz\u00f3n para dar la bienvenida a tales inmigrantes y refugiados.<\/p>\n<p>La Agencia Internacional de Desarrollo y Recursos Asistenciales copatrocin\u00f3 tambi\u00e9n el simposio de este a\u00f1o. El presidente de ADRA, Jonathan Duffy, les dijo a los asistentes que los grupos de base religiosa eran muy frecuentemente, valiosos socios locales de las organizaciones que trabajan en favor de inmigrantes y refugiados.<\/p>\n<p>\u201cLa fe juega un papel muy importante en la vida de muchas personas; por lo tanto, en tiempos de aflicci\u00f3n y problemas, las personas son atra\u00eddas hacia ella\u201d, dijo el presidente Duffy. Cit\u00f3 entonces el caso ocurrido a mediados del 2016, cuando hasta un total de 5,000 personas se refugiaron a la vez en unas instalaciones adventistas en Sud\u00e1n del Sur, mientras la violencia civil reinaba en la regi\u00f3n. ADRA se esforz\u00f3 por proveer alimentos, agua pura y cuidados de emergencia m\u00e9dica a los hombres, mujeres y ni\u00f1os que se amontonaron en tales instalaciones.<\/p>\n<p>El simposio de esta semana se llev\u00f3 a cabo ante el trasfondo de las continuas deliberaciones en la ONU acerca de la dif\u00edcil situaci\u00f3n de los inmigrantes y refugiados. Marca la cuarta ocasi\u00f3n en que la Iglesia Adventista ha ayudado a reunir a los grupos de base religiosa con representantes de la comunidad internacional en la ONU, para discutir asuntos globales significativos. Los simposios previos han enfocado su atenci\u00f3n en t\u00f3picos tales como b\u00fasqueda del mantenimiento de la paz y el extremismo religioso.<\/p>\n<p>Azza Karam, consejera s\u00e9nior de Cultura y Desarrollo Social del Fondo de Poblaci\u00f3n de las Naciones Unidas y socia clave en la organizaci\u00f3n del simposio, tuvo a su cargo el \u00faltimo de los discursos. Azza Karam subray\u00f3 algunos de los temas que hab\u00edan surgido durante el d\u00eda y dijo que hab\u00eda quedado muy claro que las organizaciones de base religiosa tienen diversos y esenciales papeles a desempe\u00f1ar al tratar con inmigrantes y refugiados. A\u00f1adi\u00f3 que la serie de simposios presentados durante los pasados cuatro a\u00f1os, hab\u00edan provocado una \u201cjornada de comunicaci\u00f3n y colaboraci\u00f3n\u201d muy \u00fanica entre grupos religiosos, organizaciones no gubernamentales y la comunidad internacional.<\/p>\n<p>Al hablar despu\u00e9s del evento, el director Diop dijo que la serie de simposios en la ONU ha provisto una oportunidad sin precedentes para que los adventistas contribuyan dentro del discurso p\u00fablico en una forma significativa y a\u00f1adi\u00f3 que ya han comenzado los planes para el quinto evento que habr\u00e1 de celebrarse en el mes de enero del a\u00f1o pr\u00f3ximo.<\/p>\n<p>\u201cComo adventistas, ofrecemos perspectivas fundadas sobre valores b\u00edblicos y moldeadas por nuestra convicci\u00f3n de que cada ser humano ha sido dotado por el Creador, de valor y dignidad infinitos\u201d, dijo el director Diop.<\/p>\n<p>Entre los muchos presentadores de alto nivel en el simposio de esta semana, figuraron Adama Dieng, el consejero especial del Secretario General de la ONU para la Prevenci\u00f3n del Genocidio; el Profesor Afe Adogame, de Maxwell M. Upson profesor de Cristianismo y Estudios Religiosos de la Escuela de Divinidades Princeton; el Rev. Dr. Liberato C. Bautista, secretario general asistente para naciones Unidas y Asuntos Internacionales de la Iglesia Metodista Unida; Rudelmar Bueno de Faria, secretario general de la coalici\u00f3n religiosa humanitaria ACT Alliance; Jason Cone, director ejecutivo de M\u00e9dicos sin Fronteras en los Estados Unidos; Dr. Elizabeta Kitanovic, secretaria ejecutiva de Derechos Humanos de la Conferencia de Iglesias Europeas en Bruselas; y Martin Mauthe-Kater, consejero para asuntos de Migraci\u00f3n y Desarrollo Sustentable en la Delegaci\u00f3n de la Uni\u00f3n Europea ante las Naciones Unidas.<\/p>\n<p>Entre los otros copatrocinadores del simposio, se encuentran la Alianza ACT, el Fondo de las Naciones Unidas para la Infancia (UNICEF), la Oficina de Prevenci\u00f3n de Genocidio y Responsabilidad de Proteger, de las Naciones Unidas, y el Cuerpo Especial de la Inter Agencia para la Colaboraci\u00f3n con Organizaciones de Base Religiosa, de las Naciones Unidas.<\/p>\n<p>Traducci\u00f3n \u2013 Gloria A Castrej\u00f3n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I<\/span>nmigrantes y refugiados no son \u201cproblemas para ser resueltos\u201d, sino personas vulnerables que deben ser tratadas con respeto y compasi\u00f3n, dijeron los participantes esta semana en un simposio en las Naciones Unidas, copatrocinado por la Iglesia Adventista del S\u00e9ptimo D\u00eda. Este evento, celebrado el 22 de enero del presente en la Secretar\u00eda de las Naciones Unidas, en Nueva York, Estados Unidos, fue el Cuarto Simposio Anual  sobre el Papel de la Religi\u00f3n y de las Organizaciones de Base Religiosa en los Asuntos Internacionales, el cual reuni\u00f3 a aproximadamente 250 representantes de la comunidad de las Naciones Unidas, grupos religiosos y organizaciones no gubernamentales<\/p>\n","protected":false},"author":1,"featured_media":38340,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[14,15],"tags":[],"class_list":["post-38420","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-de-la-iglesia-mundial","category-rss-espanol"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>En las Naciones Unidas, los adventistas enfatizan la compasi\u00f3n por los refugiados - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/interamerica.org\/es\/2018\/01\/en-las-naciones-unidas-los-adventistas-enfatizan-la-compasion-por-los-refugiados\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En las Naciones Unidas, los adventistas enfatizan la compasi\u00f3n por los refugiados - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana\" \/>\n<meta property=\"og:description\" content=\"Inmigrantes y refugiados no son \u201cproblemas para ser resueltos\u201d, sino personas vulnerables que deben ser tratadas con respeto y compasi\u00f3n, dijeron los participantes esta semana en un simposio en las Naciones Unidas, copatrocinado por la Iglesia Adventista del S\u00e9ptimo D\u00eda. Este evento, celebrado el 22 de enero del presente en la Secretar\u00eda de las Naciones Unidas, en Nueva York, Estados Unidos, fue el Cuarto Simposio Anual sobre el Papel de la Religi\u00f3n y de las Organizaciones de Base Religiosa en los Asuntos Internacionales, el cual reuni\u00f3 a aproximadamente 250 representantes de la comunidad de las Naciones Unidas, grupos religiosos y organizaciones no gubernamentales\" \/>\n<meta property=\"og:url\" content=\"https:\/\/interamerica.org\/es\/2018\/01\/en-las-naciones-unidas-los-adventistas-enfatizan-la-compasion-por-los-refugiados\/\" \/>\n<meta property=\"og:site_name\" content=\"Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-28T04:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-04T02:03:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/02\/girl-1816168-1280.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"851\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lorenzo Verduzco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lorenzo Verduzco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/01\\\/en-las-naciones-unidas-los-adventistas-enfatizan-la-compasion-por-los-refugiados\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/01\\\/en-las-naciones-unidas-los-adventistas-enfatizan-la-compasion-por-los-refugiados\\\/\"},\"author\":{\"name\":\"Lorenzo Verduzco\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#\\\/schema\\\/person\\\/68ede8bdc292885bb76c1e3810e73c39\"},\"headline\":\"En las Naciones Unidas, los adventistas enfatizan la compasi\u00f3n por los refugiados\",\"datePublished\":\"2018-01-28T04:00:00+00:00\",\"dateModified\":\"2018-12-04T02:03:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/01\\\/en-las-naciones-unidas-los-adventistas-enfatizan-la-compasion-por-los-refugiados\\\/\"},\"wordCount\":1412,\"image\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/01\\\/en-las-naciones-unidas-los-adventistas-enfatizan-la-compasion-por-los-refugiados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/girl-1816168-1280.jpg\",\"articleSection\":[\"Desde la iglesia mundial\",\"RSS Espa\u00f1ol\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/01\\\/en-las-naciones-unidas-los-adventistas-enfatizan-la-compasion-por-los-refugiados\\\/\",\"url\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/01\\\/en-las-naciones-unidas-los-adventistas-enfatizan-la-compasion-por-los-refugiados\\\/\",\"name\":\"En las Naciones Unidas, los adventistas enfatizan la compasi\u00f3n por los refugiados - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/01\\\/en-las-naciones-unidas-los-adventistas-enfatizan-la-compasion-por-los-refugiados\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/01\\\/en-las-naciones-unidas-los-adventistas-enfatizan-la-compasion-por-los-refugiados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/girl-1816168-1280.jpg\",\"datePublished\":\"2018-01-28T04:00:00+00:00\",\"dateModified\":\"2018-12-04T02:03:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#\\\/schema\\\/person\\\/68ede8bdc292885bb76c1e3810e73c39\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/01\\\/en-las-naciones-unidas-los-adventistas-enfatizan-la-compasion-por-los-refugiados\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/01\\\/en-las-naciones-unidas-los-adventistas-enfatizan-la-compasion-por-los-refugiados\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/01\\\/en-las-naciones-unidas-los-adventistas-enfatizan-la-compasion-por-los-refugiados\\\/#primaryimage\",\"url\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/girl-1816168-1280.jpg\",\"contentUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/girl-1816168-1280.jpg\",\"width\":1280,\"height\":851},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/01\\\/en-las-naciones-unidas-los-adventistas-enfatizan-la-compasion-por-los-refugiados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/interamerica.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En las Naciones Unidas, los adventistas enfatizan la compasi\u00f3n por los refugiados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/interamerica.org\\\/es\\\/\",\"name\":\"Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/interamerica.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#\\\/schema\\\/person\\\/68ede8bdc292885bb76c1e3810e73c39\",\"name\":\"Lorenzo Verduzco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g\",\"caption\":\"Lorenzo Verduzco\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En las Naciones Unidas, los adventistas enfatizan la compasi\u00f3n por los refugiados - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/interamerica.org\/es\/2018\/01\/en-las-naciones-unidas-los-adventistas-enfatizan-la-compasion-por-los-refugiados\/","og_locale":"es_ES","og_type":"article","og_title":"En las Naciones Unidas, los adventistas enfatizan la compasi\u00f3n por los refugiados - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","og_description":"Inmigrantes y refugiados no son \u201cproblemas para ser resueltos\u201d, sino personas vulnerables que deben ser tratadas con respeto y compasi\u00f3n, dijeron los participantes esta semana en un simposio en las Naciones Unidas, copatrocinado por la Iglesia Adventista del S\u00e9ptimo D\u00eda. Este evento, celebrado el 22 de enero del presente en la Secretar\u00eda de las Naciones Unidas, en Nueva York, Estados Unidos, fue el Cuarto Simposio Anual sobre el Papel de la Religi\u00f3n y de las Organizaciones de Base Religiosa en los Asuntos Internacionales, el cual reuni\u00f3 a aproximadamente 250 representantes de la comunidad de las Naciones Unidas, grupos religiosos y organizaciones no gubernamentales","og_url":"https:\/\/interamerica.org\/es\/2018\/01\/en-las-naciones-unidas-los-adventistas-enfatizan-la-compasion-por-los-refugiados\/","og_site_name":"Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","article_published_time":"2018-01-28T04:00:00+00:00","article_modified_time":"2018-12-04T02:03:35+00:00","og_image":[{"width":1280,"height":851,"url":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/02\/girl-1816168-1280.jpg","type":"image\/jpeg"}],"author":"Lorenzo Verduzco","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Lorenzo Verduzco","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/interamerica.org\/es\/2018\/01\/en-las-naciones-unidas-los-adventistas-enfatizan-la-compasion-por-los-refugiados\/#article","isPartOf":{"@id":"https:\/\/interamerica.org\/es\/2018\/01\/en-las-naciones-unidas-los-adventistas-enfatizan-la-compasion-por-los-refugiados\/"},"author":{"name":"Lorenzo Verduzco","@id":"https:\/\/interamerica.org\/es\/#\/schema\/person\/68ede8bdc292885bb76c1e3810e73c39"},"headline":"En las Naciones Unidas, los adventistas enfatizan la compasi\u00f3n por los refugiados","datePublished":"2018-01-28T04:00:00+00:00","dateModified":"2018-12-04T02:03:35+00:00","mainEntityOfPage":{"@id":"https:\/\/interamerica.org\/es\/2018\/01\/en-las-naciones-unidas-los-adventistas-enfatizan-la-compasion-por-los-refugiados\/"},"wordCount":1412,"image":{"@id":"https:\/\/interamerica.org\/es\/2018\/01\/en-las-naciones-unidas-los-adventistas-enfatizan-la-compasion-por-los-refugiados\/#primaryimage"},"thumbnailUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/02\/girl-1816168-1280.jpg","articleSection":["Desde la iglesia mundial","RSS Espa\u00f1ol"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/interamerica.org\/es\/2018\/01\/en-las-naciones-unidas-los-adventistas-enfatizan-la-compasion-por-los-refugiados\/","url":"https:\/\/interamerica.org\/es\/2018\/01\/en-las-naciones-unidas-los-adventistas-enfatizan-la-compasion-por-los-refugiados\/","name":"En las Naciones Unidas, los adventistas enfatizan la compasi\u00f3n por los refugiados - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","isPartOf":{"@id":"https:\/\/interamerica.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/interamerica.org\/es\/2018\/01\/en-las-naciones-unidas-los-adventistas-enfatizan-la-compasion-por-los-refugiados\/#primaryimage"},"image":{"@id":"https:\/\/interamerica.org\/es\/2018\/01\/en-las-naciones-unidas-los-adventistas-enfatizan-la-compasion-por-los-refugiados\/#primaryimage"},"thumbnailUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/02\/girl-1816168-1280.jpg","datePublished":"2018-01-28T04:00:00+00:00","dateModified":"2018-12-04T02:03:35+00:00","author":{"@id":"https:\/\/interamerica.org\/es\/#\/schema\/person\/68ede8bdc292885bb76c1e3810e73c39"},"breadcrumb":{"@id":"https:\/\/interamerica.org\/es\/2018\/01\/en-las-naciones-unidas-los-adventistas-enfatizan-la-compasion-por-los-refugiados\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/interamerica.org\/es\/2018\/01\/en-las-naciones-unidas-los-adventistas-enfatizan-la-compasion-por-los-refugiados\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/interamerica.org\/es\/2018\/01\/en-las-naciones-unidas-los-adventistas-enfatizan-la-compasion-por-los-refugiados\/#primaryimage","url":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/02\/girl-1816168-1280.jpg","contentUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/02\/girl-1816168-1280.jpg","width":1280,"height":851},{"@type":"BreadcrumbList","@id":"https:\/\/interamerica.org\/es\/2018\/01\/en-las-naciones-unidas-los-adventistas-enfatizan-la-compasion-por-los-refugiados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/interamerica.org\/es\/"},{"@type":"ListItem","position":2,"name":"En las Naciones Unidas, los adventistas enfatizan la compasi\u00f3n por los refugiados"}]},{"@type":"WebSite","@id":"https:\/\/interamerica.org\/es\/#website","url":"https:\/\/interamerica.org\/es\/","name":"Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/interamerica.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/interamerica.org\/es\/#\/schema\/person\/68ede8bdc292885bb76c1e3810e73c39","name":"Lorenzo Verduzco","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g","caption":"Lorenzo Verduzco"}}]}},"_links":{"self":[{"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/posts\/38420","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/comments?post=38420"}],"version-history":[{"count":0,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/posts\/38420\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/media\/38340"}],"wp:attachment":[{"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/media?parent=38420"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/categories?post=38420"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/tags?post=38420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}