{"id":38423,"date":"2018-02-05T00:00:00","date_gmt":"2018-02-05T04:00:00","guid":{"rendered":"http:\/\/192.81.217.108\/2018\/02\/interamerica-lanza-nuevo-programa-de-vbs-para-alcanzar-mejor-a-la-comunidad\/"},"modified":"2018-04-02T23:15:26","modified_gmt":"2018-04-03T03:15:26","slug":"interamerica-lanza-nuevo-programa-de-vbs-para-alcanzar-mejor-a-la-comunidad","status":"publish","type":"post","link":"https:\/\/interamerica.org\/es\/2018\/02\/interamerica-lanza-nuevo-programa-de-vbs-para-alcanzar-mejor-a-la-comunidad\/","title":{"rendered":"Interam\u00e9rica lanza nuevo programa de VBS para alcanzar mejor a la comunidad"},"content":{"rendered":"<div id=\"attachment_33261\" style=\"width: 759px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/02\/VBS-stage-flags.jpg\" rel=\"fancybox\" title=\"Interam\u00e9rica lanza nuevo programa de VBS para alcanzar mejor a la comunidad\"><img fetchpriority=\"high\" decoding=\"async\" aria-describedby=\"caption-attachment-33261\" class=\" wp-image-33261\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/02\/VBS-stage-flags.jpg\" alt=\"\" width=\"749\" height=\"499\" \/><\/a><p id=\"caption-attachment-33261\" class=\"wp-caption-text\">L\u00edderes del Ministerio del Ni\u00f1o y del Adolescente de Interam\u00e9rica posan en el escenario durante la apertura del taller de dos d\u00edas sobre el programa de la Escuela B\u00edblica de Vacaciones, que comenz\u00f3 el 31 de enero de 2018 en Miami, Florida, Estados Unidos. Imagen de Libna Stevens\/DIA<\/p><\/div>\n<p>5 de febrero de 2018 | Miami, Florida, Estados Unidos | Libna Stevens\/DIA<\/p>\n<p>La Iglesia Adventista del S\u00e9ptimo D\u00eda en Interam\u00e9rica continu\u00f3 tras los pasos del reci\u00e9n lanzado <a href=\"mailto:https:\/\/recursing-golick.147-182-135-0.plesk.page\/2017\/12\/13\/inter-america-launches-year-child-adolescent-online-program\/\"> A\u00f1o del Ni\u00f1o y el Adolescente<\/a> con la presentaci\u00f3n de su nuevo programa de la Escuela B\u00edblica de Vacaciones la semana pasada.<\/p>\n<p>M\u00e1s de 160 directores de ministerios del ni\u00f1o y adolescente de todo el territorio de la Divisi\u00f3n Interamericana (DIA) se reunieron para un taller de dos d\u00edas en Miami, Florida, Estados Unidos, del 31 de enero al 1 de febrero, para reafirmar su compromiso con uno de sus m\u00e1s s\u00f3lidos programas del a\u00f1o para los miembros y la comunidad.<\/p>\n<div id=\"attachment_33249\" style=\"width: 424px\" class=\"wp-caption alignright\"><a href=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/02\/DinorahRivera-VBS-program.jpg\" rel=\"fancybox\" title=\"Interam\u00e9rica lanza nuevo programa de VBS para alcanzar mejor a la comunidad\"><img decoding=\"async\" aria-describedby=\"caption-attachment-33249\" class=\" wp-image-33249\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/02\/DinorahRivera-VBS-program.jpg\" alt=\"\" width=\"414\" height=\"276\" \/><\/a><p id=\"caption-attachment-33249\" class=\"wp-caption-text\">Dinorah Rivera, directora de Ministerios del Ni\u00f1o y el Adolescente de la Divisi\u00f3n Interamericana. Imagen de Libna Stevens\/IAD<\/p><\/div>\n<p>\u201cEstamos aqu\u00ed para redoblar nuestros esfuerzos y llevar a los ni\u00f1os a los pies de Jes\u00fas\u201d, dijo Dinorah Rivera, directora de Ministerios del Ni\u00f1o y el Adolescente de la Iglesia Adventista en Interam\u00e9rica y principal organizadora del evento. \u201cLa pasi\u00f3n que sienten por este ministerio requiere de humildad y entrega, para que Dios pueda usarlos para tocar la vida de los m\u00e1s grandes recursos que tenemos en nuestras iglesias y comunidades\u201d.<\/p>\n<p>Esa pasi\u00f3n tendr\u00e1 que traducirse en esfuerzos que los l\u00edderes transmitir\u00e1n a los m\u00e1s de 300 mil ni\u00f1os y adolescentes que participar\u00e1n de las Escuelas B\u00edblicas de Vacaciones de este a\u00f1o en miles de iglesias locales y grupos peque\u00f1os a lo largo y a lo ancho de Interam\u00e9rica.<\/p>\n<p>\u201cQueremos encender una vez este ministerio de la Escuela B\u00edblica de Vacaciones por medio de este taller de capacitaci\u00f3n, porque queremos que los l\u00edderes de nuestra uni\u00f3n y campo local capten la importancia de este concepto de VBS y lo transmitan a los incontables hombres y mujeres que cada verano colaboran como voluntarios en nuestras iglesias\u201d, explic\u00f3 Rivera. La interacci\u00f3n entre l\u00edderes de diferentes territorios regionales tambi\u00e9n es una parte importante del encuentro, a\u00f1adi\u00f3.<\/p>\n<p>El taller se enfoc\u00f3 en garantizar una mayor inclusi\u00f3n en las iglesias, al atender tambi\u00e9n a los ni\u00f1os con necesidades especiales, incluir soluciones pr\u00e1cticas de seguridad infantil, y hacer que los ni\u00f1os efect\u00faen la transici\u00f3n a la vida de la iglesia despu\u00e9s de VBS.<\/p>\n<div id=\"attachment_33252\" style=\"width: 425px\" class=\"wp-caption alignright\"><a href=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/02\/VBS-delegates.jpg\" rel=\"fancybox\" title=\"Interam\u00e9rica lanza nuevo programa de VBS para alcanzar mejor a la comunidad\"><img decoding=\"async\" aria-describedby=\"caption-attachment-33252\" class=\" wp-image-33252\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/02\/VBS-delegates.jpg\" alt=\"\" width=\"415\" height=\"241\" \/><\/a><p id=\"caption-attachment-33252\" class=\"wp-caption-text\">M\u00e1s de 160 delegados asistieron a un taller de dos d\u00edas en la sede de la Divisi\u00f3n Interamericana en Miami, Florida, Estados Unidos. Imagen de Libna Stevens\/DIA<\/p><\/div>\n<p>Los delegados rotaron a trav\u00e9s de las diferentes estaciones que tendr\u00e1n que incluir cada d\u00eda en el programa de VBS en sus iglesias para incluir valores que edifican el car\u00e1cter, c\u00f3mo conservar los recursos naturales y el medio ambiente, actividades y manualidades pr\u00e1cticas, actividades para jugar en equipos al aire libre, h\u00e1bitos saludables de comida, y la toma de fotograf\u00edas y videos, entre otros.<\/p>\n<p>\u201cCada decoraci\u00f3n que usamos para destacar el tema de este a\u00f1o fue hecha con art\u00edculos reciclados y materiales que pueden ser obtenidos f\u00e1cilmente, y que resultan sumamente asequibles en el territorio local\u201d, explic\u00f3 Rivera, que cre\u00f3 el programa de VBS.<\/p>\n<p>El programa, que estar\u00e1 disponible en ingl\u00e9s, espa\u00f1ol y franc\u00e9s, tambi\u00e9n incluye c\u00e1nticos lema y m\u00fasica para cada d\u00eda de la semana.<\/p>\n<p>Gabriela Barrutia, l\u00edder de ministerios del ni\u00f1o y el adolescente de la Asociaci\u00f3n de Baja California en la regi\u00f3n Mexicana del Norte, dijo que participar del taller ayudar\u00e1 a inspirar y motivar a 420 docentes que participar\u00e1n del taller de VBS y Escuela Sab\u00e1tica el mes pr\u00f3ximo, en preparaci\u00f3n para el programa para los ni\u00f1os en sus iglesias.<\/p>\n<p>\u201cEstoy entusiasmada de transmitir el lema que ense\u00f1aremos a los ni\u00f1os, de que la Biblia es una aventura que nos lleva a aprender de qu\u00e9 manera Dios nos ama aun a pesar de nuestras diferencias\u201d, dijo Barrutia. Barrutia dijo que 129 de esas congregaciones adventistas de la asociaci\u00f3n podr\u00e1n recibir a m\u00e1s de tres mil ni\u00f1os este verano. \u201cAlgunas iglesias pueden tener veinte ni\u00f1os en el programa de VBS, otras m\u00e1s de cien, y as\u00ed sucesivamente, de manera que conectarse, escuchar y amar a los ni\u00f1os es una delicia tan grande y una responsabilidad importante que tenemos\u201d, a\u00f1adi\u00f3.<\/p>\n<div id=\"attachment_33255\" style=\"width: 425px\" class=\"wp-caption alignright\"><a href=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/02\/VBS-games-Gabriela-Barrutia.jpg\" rel=\"fancybox\" title=\"Interam\u00e9rica lanza nuevo programa de VBS para alcanzar mejor a la comunidad\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-33255\" class=\" wp-image-33255\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/02\/VBS-games-Gabriela-Barrutia.jpg\" alt=\"\" width=\"415\" height=\"250\" \/><\/a><p id=\"caption-attachment-33255\" class=\"wp-caption-text\">Grabiela Barrutia, de Baja California, en la regi\u00f3n Mexicana del Norte (derecha), muestra el \u201cdinero\u201d que gan\u00f3 con su colega despu\u00e9s de jugar en la estaci\u00f3n de deporte del programa de VBS. Imagen de Libna Stevens\/DIA<\/p><\/div>\n<p>Barrutia es uno de las quince delegadas de la Uni\u00f3n Mexicana del Norte, la delegaci\u00f3n m\u00e1s grande en el programa de VBS este a\u00f1o, y uno de los programas m\u00e1s s\u00f3lidos en la Divisi\u00f3n Interamericana, dijo Rivera.<\/p>\n<p>Norma Villegas, directora del ministerio del ni\u00f1o y el adolescente en la regi\u00f3n Mexicana del Norte, inform\u00f3 que el programa de VBS del a\u00f1o pasado alcanz\u00f3 a 45 mil ni\u00f1os y adolescentes no adventistas. El a\u00f1o anterior alcanz\u00f3 a 37 mil ni\u00f1os, y este verano est\u00e1n esperando a m\u00e1s de 70 mil.<\/p>\n<p>\u201cSabemos por experiencia que estos ni\u00f1os quieren quedarse, y nuestro deber va m\u00e1s all\u00e1 del programa de VBS\u201d, dijo Villegas. Es otra fase del programa para retener a los ni\u00f1os, continuar con la conexi\u00f3n con ellos con m\u00e1s actividades y ense\u00f1anzas, para que efect\u00faen la transici\u00f3n a la vida de la iglesia en la Escuela Sab\u00e1tica, el Club de Aventureros y as\u00ed sucesivamente, explic\u00f3 Villegas.<\/p>\n<p>Villegas estuvo al frente del equipo de directores de las uniones que presentaron en el programa del Club de Amistad de Interam\u00e9rica, un club que invita a los ni\u00f1os para que participen en actividades semanales de aprendizaje despu\u00e9s de completar el programa de VBS.<\/p>\n<p>El programa tem\u00e1tico de ocho semanas que se presentar\u00e1 en el Club de la Amistad se enfocar\u00e1 en el valor especial que Dios coloca en cada ni\u00f1o, como as\u00ed tambi\u00e9n en ocho personas hist\u00f3ricas que han marcado un impacto significativo en el mundo, dijo Rivera, que supervisa los programas anuales para los ni\u00f1os y adolescentes. Una vez que el club complete su programa, continuar\u00e1n programas de estudios b\u00edblicos adicionales en la Escuela Sab\u00e1tica de cada s\u00e1bado, a\u00f1adi\u00f3 Rivera.<\/p>\n<p>Para Debra Henry, directora del ministerio del ni\u00f1o y adolescente de la iglesia en la Uni\u00f3n del Caribe, participar del evento signific\u00f3 estar un paso m\u00e1s cerca de motivar a las iglesias locales en decenas de islas de la regi\u00f3n del Caribe Ingl\u00e9s. Ella trajo consigo a ocho de sus l\u00edderes de misi\u00f3n o asociaci\u00f3n al taller, para que pudieran ver, sentir y sentirse inspirados de manera de motivar a los l\u00edderes de la iglesia local para que organicen un programa de VBS este verano.<\/p>\n<div id=\"attachment_33246\" style=\"width: 421px\" class=\"wp-caption alignright\"><a href=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/02\/DebraHenry-tourgroup.jpg\" rel=\"fancybox\" title=\"Interam\u00e9rica lanza nuevo programa de VBS para alcanzar mejor a la comunidad\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-33246\" class=\" wp-image-33246\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/02\/DebraHenry-tourgroup.jpg\" alt=\"\" width=\"411\" height=\"260\" \/><\/a><p id=\"caption-attachment-33246\" class=\"wp-caption-text\">Debra Henry, de la Uni\u00f3n del Caribe, sostiene el cartel de su grupo, mientras pasa de una estaci\u00f3n a otra. Imagen de Libna Stevens\/DIA<\/p><\/div>\n<p>En el pasado, muchas iglesias tomaban los programas de VBS que encontraban en l\u00ednea y los usaban para el verano, dijo Henry.<\/p>\n<p>\u201cEn algunas de nuestras islas ha habido una disminuci\u00f3n de nuestros programas de VBS\u201d, a\u00f1adi\u00f3. \u201cEn un caso, una isla que tiene 32 iglesias llev\u00f3 a cabo s<br \/>\none case, one island that has 32 churches held only five VBS programs last year. This cannot be,\u201d said Henry. She has been working for the past two years to change that and said now is a great opportunity to reemphasize the importance of this evangelism tool to reach out into the community.<\/p>\n<p>\u201cNuestro grupo lo ha visto y ha sentido, y estamos comprometidos para garantizar que las iglesias locales de la regi\u00f3n del Caribe lleven a cabo un programa de VBS\u201d, dijo Henry. \u201cNuestro objetivo es que cada iglesia llegue a la comunidad con ese programa, buscando a los que tienen necesidades especiales y prepar\u00e1ndolo para aprender m\u00e1s de la Biblia y del amor de Jes\u00fas\u201d.<\/p>\n<p>Ese es el objetivo \u00faltimo: atraer a los ni\u00f1os y adolescentes a Jes\u00fas y ense\u00f1arles a compartirlo dondequiera vayan, dijo Rivera.<\/p>\n<p>Para saber m\u00e1s del A\u00f1o del Ni\u00f1o y el Adolescente en Interam\u00e9rica, e informaci\u00f3n sobre el programa de VBS de este a\u00f1o, visite la P\u00e1gina de Facebook <a href=\"mailto:https:\/\/www.facebook.com\/ChildrenandWomensMinistries\/\">AQU\u00cd<\/a>.<\/p>\n<p>Vea una galer\u00eda de fotograf\u00edas del evento <a href=\"mailto:https:\/\/www.flickr.com\/photos\/interamerica\/albums\/72157691322135931\">AQU\u00cd<\/a><\/p>\n<div id=\"attachment_33258\" style=\"width: 773px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/02\/VBS-group.jpg\" rel=\"fancybox\" title=\"Interam\u00e9rica lanza nuevo programa de VBS para alcanzar mejor a la comunidad\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-33258\" class=\" wp-image-33258\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/02\/VBS-group.jpg\" alt=\"\" width=\"763\" height=\"336\" \/><\/a><p id=\"caption-attachment-33258\" class=\"wp-caption-text\">Imagen de Abel M\u00e1rquez\/DIA<\/p><\/div>\n<p>Traducci\u00f3n de Marcos Paseggi<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Iglesia Adventista del S\u00e9ptimo D\u00eda en Interam\u00e9rica continu\u00f3 tras los pasos del reci\u00e9n lanzado A\u00f1o del Ni\u00f1o y el Adolescente con la presentaci\u00f3n de su nuevo programa de la Escuela B\u00edblica de Vacaciones la semana pasada.<\/p>\n<p>M\u00e1s de 160 directores de ministerios del ni\u00f1o y adolescente de todo el territorio de la Divisi\u00f3n Interamericana (DIA) se reunieron para un taller de dos d\u00edas en Miami, Florida, Estados Unidos, del 31 de enero al 1 de febrero, para reafirmar su compromiso con uno de sus m\u00e1s s\u00f3lidos programas del a\u00f1o para los miembros y la comunidad.<\/p>\n","protected":false},"author":1,"featured_media":38366,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16,15],"tags":[],"class_list":["post-38423","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-desde-la-sede","category-rss-espanol"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Interam\u00e9rica lanza nuevo programa de VBS para alcanzar mejor a la comunidad - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/interamerica.org\/es\/2018\/02\/interamerica-lanza-nuevo-programa-de-vbs-para-alcanzar-mejor-a-la-comunidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Interam\u00e9rica lanza nuevo programa de VBS para alcanzar mejor a la comunidad - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana\" \/>\n<meta property=\"og:description\" content=\"La Iglesia Adventista del S\u00e9ptimo D\u00eda en Interam\u00e9rica continu\u00f3 tras los pasos del reci\u00e9n lanzado A\u00f1o del Ni\u00f1o y el Adolescente con la presentaci\u00f3n de su nuevo programa de la Escuela B\u00edblica de Vacaciones la semana pasada.  M\u00e1s de 160 directores de ministerios del ni\u00f1o y adolescente de todo el territorio de la Divisi\u00f3n Interamericana (DIA) se reunieron para un taller de dos d\u00edas en Miami, Florida, Estados Unidos, del 31 de enero al 1 de febrero, para reafirmar su compromiso con uno de sus m\u00e1s s\u00f3lidos programas del a\u00f1o para los miembros y la comunidad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/interamerica.org\/es\/2018\/02\/interamerica-lanza-nuevo-programa-de-vbs-para-alcanzar-mejor-a-la-comunidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-05T04:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-04-03T03:15:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/02\/vbs-games-gabriela-barrutia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"386\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lorenzo Verduzco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lorenzo Verduzco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/02\\\/interamerica-lanza-nuevo-programa-de-vbs-para-alcanzar-mejor-a-la-comunidad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/02\\\/interamerica-lanza-nuevo-programa-de-vbs-para-alcanzar-mejor-a-la-comunidad\\\/\"},\"author\":{\"name\":\"Lorenzo Verduzco\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#\\\/schema\\\/person\\\/68ede8bdc292885bb76c1e3810e73c39\"},\"headline\":\"Interam\u00e9rica lanza nuevo programa de VBS para alcanzar mejor a la comunidad\",\"datePublished\":\"2018-02-05T04:00:00+00:00\",\"dateModified\":\"2018-04-03T03:15:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/02\\\/interamerica-lanza-nuevo-programa-de-vbs-para-alcanzar-mejor-a-la-comunidad\\\/\"},\"wordCount\":1585,\"image\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/02\\\/interamerica-lanza-nuevo-programa-de-vbs-para-alcanzar-mejor-a-la-comunidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/vbs-games-gabriela-barrutia.jpg\",\"articleSection\":[\"Desde la sede\",\"RSS Espa\u00f1ol\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/02\\\/interamerica-lanza-nuevo-programa-de-vbs-para-alcanzar-mejor-a-la-comunidad\\\/\",\"url\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/02\\\/interamerica-lanza-nuevo-programa-de-vbs-para-alcanzar-mejor-a-la-comunidad\\\/\",\"name\":\"Interam\u00e9rica lanza nuevo programa de VBS para alcanzar mejor a la comunidad - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/02\\\/interamerica-lanza-nuevo-programa-de-vbs-para-alcanzar-mejor-a-la-comunidad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/02\\\/interamerica-lanza-nuevo-programa-de-vbs-para-alcanzar-mejor-a-la-comunidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/vbs-games-gabriela-barrutia.jpg\",\"datePublished\":\"2018-02-05T04:00:00+00:00\",\"dateModified\":\"2018-04-03T03:15:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#\\\/schema\\\/person\\\/68ede8bdc292885bb76c1e3810e73c39\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/02\\\/interamerica-lanza-nuevo-programa-de-vbs-para-alcanzar-mejor-a-la-comunidad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/02\\\/interamerica-lanza-nuevo-programa-de-vbs-para-alcanzar-mejor-a-la-comunidad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/02\\\/interamerica-lanza-nuevo-programa-de-vbs-para-alcanzar-mejor-a-la-comunidad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/vbs-games-gabriela-barrutia.jpg\",\"contentUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/vbs-games-gabriela-barrutia.jpg\",\"width\":640,\"height\":386},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/02\\\/interamerica-lanza-nuevo-programa-de-vbs-para-alcanzar-mejor-a-la-comunidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/interamerica.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Interam\u00e9rica lanza nuevo programa de VBS para alcanzar mejor a la comunidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/interamerica.org\\\/es\\\/\",\"name\":\"Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/interamerica.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#\\\/schema\\\/person\\\/68ede8bdc292885bb76c1e3810e73c39\",\"name\":\"Lorenzo Verduzco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g\",\"caption\":\"Lorenzo Verduzco\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Interam\u00e9rica lanza nuevo programa de VBS para alcanzar mejor a la comunidad - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/interamerica.org\/es\/2018\/02\/interamerica-lanza-nuevo-programa-de-vbs-para-alcanzar-mejor-a-la-comunidad\/","og_locale":"es_ES","og_type":"article","og_title":"Interam\u00e9rica lanza nuevo programa de VBS para alcanzar mejor a la comunidad - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","og_description":"La Iglesia Adventista del S\u00e9ptimo D\u00eda en Interam\u00e9rica continu\u00f3 tras los pasos del reci\u00e9n lanzado A\u00f1o del Ni\u00f1o y el Adolescente con la presentaci\u00f3n de su nuevo programa de la Escuela B\u00edblica de Vacaciones la semana pasada.  M\u00e1s de 160 directores de ministerios del ni\u00f1o y adolescente de todo el territorio de la Divisi\u00f3n Interamericana (DIA) se reunieron para un taller de dos d\u00edas en Miami, Florida, Estados Unidos, del 31 de enero al 1 de febrero, para reafirmar su compromiso con uno de sus m\u00e1s s\u00f3lidos programas del a\u00f1o para los miembros y la comunidad.","og_url":"https:\/\/interamerica.org\/es\/2018\/02\/interamerica-lanza-nuevo-programa-de-vbs-para-alcanzar-mejor-a-la-comunidad\/","og_site_name":"Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","article_published_time":"2018-02-05T04:00:00+00:00","article_modified_time":"2018-04-03T03:15:26+00:00","og_image":[{"width":640,"height":386,"url":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/02\/vbs-games-gabriela-barrutia.jpg","type":"image\/jpeg"}],"author":"Lorenzo Verduzco","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Lorenzo Verduzco","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/interamerica.org\/es\/2018\/02\/interamerica-lanza-nuevo-programa-de-vbs-para-alcanzar-mejor-a-la-comunidad\/#article","isPartOf":{"@id":"https:\/\/interamerica.org\/es\/2018\/02\/interamerica-lanza-nuevo-programa-de-vbs-para-alcanzar-mejor-a-la-comunidad\/"},"author":{"name":"Lorenzo Verduzco","@id":"https:\/\/interamerica.org\/es\/#\/schema\/person\/68ede8bdc292885bb76c1e3810e73c39"},"headline":"Interam\u00e9rica lanza nuevo programa de VBS para alcanzar mejor a la comunidad","datePublished":"2018-02-05T04:00:00+00:00","dateModified":"2018-04-03T03:15:26+00:00","mainEntityOfPage":{"@id":"https:\/\/interamerica.org\/es\/2018\/02\/interamerica-lanza-nuevo-programa-de-vbs-para-alcanzar-mejor-a-la-comunidad\/"},"wordCount":1585,"image":{"@id":"https:\/\/interamerica.org\/es\/2018\/02\/interamerica-lanza-nuevo-programa-de-vbs-para-alcanzar-mejor-a-la-comunidad\/#primaryimage"},"thumbnailUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/02\/vbs-games-gabriela-barrutia.jpg","articleSection":["Desde la sede","RSS Espa\u00f1ol"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/interamerica.org\/es\/2018\/02\/interamerica-lanza-nuevo-programa-de-vbs-para-alcanzar-mejor-a-la-comunidad\/","url":"https:\/\/interamerica.org\/es\/2018\/02\/interamerica-lanza-nuevo-programa-de-vbs-para-alcanzar-mejor-a-la-comunidad\/","name":"Interam\u00e9rica lanza nuevo programa de VBS para alcanzar mejor a la comunidad - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","isPartOf":{"@id":"https:\/\/interamerica.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/interamerica.org\/es\/2018\/02\/interamerica-lanza-nuevo-programa-de-vbs-para-alcanzar-mejor-a-la-comunidad\/#primaryimage"},"image":{"@id":"https:\/\/interamerica.org\/es\/2018\/02\/interamerica-lanza-nuevo-programa-de-vbs-para-alcanzar-mejor-a-la-comunidad\/#primaryimage"},"thumbnailUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/02\/vbs-games-gabriela-barrutia.jpg","datePublished":"2018-02-05T04:00:00+00:00","dateModified":"2018-04-03T03:15:26+00:00","author":{"@id":"https:\/\/interamerica.org\/es\/#\/schema\/person\/68ede8bdc292885bb76c1e3810e73c39"},"breadcrumb":{"@id":"https:\/\/interamerica.org\/es\/2018\/02\/interamerica-lanza-nuevo-programa-de-vbs-para-alcanzar-mejor-a-la-comunidad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/interamerica.org\/es\/2018\/02\/interamerica-lanza-nuevo-programa-de-vbs-para-alcanzar-mejor-a-la-comunidad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/interamerica.org\/es\/2018\/02\/interamerica-lanza-nuevo-programa-de-vbs-para-alcanzar-mejor-a-la-comunidad\/#primaryimage","url":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/02\/vbs-games-gabriela-barrutia.jpg","contentUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/02\/vbs-games-gabriela-barrutia.jpg","width":640,"height":386},{"@type":"BreadcrumbList","@id":"https:\/\/interamerica.org\/es\/2018\/02\/interamerica-lanza-nuevo-programa-de-vbs-para-alcanzar-mejor-a-la-comunidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/interamerica.org\/es\/"},{"@type":"ListItem","position":2,"name":"Interam\u00e9rica lanza nuevo programa de VBS para alcanzar mejor a la comunidad"}]},{"@type":"WebSite","@id":"https:\/\/interamerica.org\/es\/#website","url":"https:\/\/interamerica.org\/es\/","name":"Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/interamerica.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/interamerica.org\/es\/#\/schema\/person\/68ede8bdc292885bb76c1e3810e73c39","name":"Lorenzo Verduzco","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g","caption":"Lorenzo Verduzco"}}]}},"_links":{"self":[{"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/posts\/38423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/comments?post=38423"}],"version-history":[{"count":0,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/posts\/38423\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/media\/38366"}],"wp:attachment":[{"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/media?parent=38423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/categories?post=38423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/tags?post=38423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}