{"id":38512,"date":"2018-02-08T14:04:34","date_gmt":"2018-02-08T18:04:34","guid":{"rendered":"http:\/\/192.81.217.108\/?p=38512"},"modified":"2018-02-20T14:05:32","modified_gmt":"2018-02-20T18:05:32","slug":"iglesia-adventista-celebra-cien-anos-de-crecimiento-en-la-republica-dominicana","status":"publish","type":"post","link":"https:\/\/interamerica.org\/es\/2018\/02\/iglesia-adventista-celebra-cien-anos-de-crecimiento-en-la-republica-dominicana\/","title":{"rendered":"Iglesia Adventista celebra cien a\u00f1os de crecimiento en la Rep\u00fablica Dominicana"},"content":{"rendered":"<div class=\"at-above-post addthis_tool\" data-url=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/es\/2018\/02\/08\/iglesia-adventista-celebra-cien-anos-de-crecimiento-en-la-republica-dominicana\/\"><\/div>\n<div id=\"attachment_33300\" class=\"wp-caption aligncenter\">\n<div id=\"attachment_33300\" style=\"width: 778px\" class=\"wp-caption aligncenter\"><a title=\"Iglesia Adventista celebra cien a\u00f1os de crecimiento en la Rep\u00fablica Dominicana\" href=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/02\/DOMU-MellaChurch.gif\" rel=\"fancybox\" title=\"Iglesia Adventista celebra cien a\u00f1os de crecimiento en la Rep\u00fablica Dominicana\" rel=\"fancybox\"><img fetchpriority=\"high\" decoding=\"async\" aria-describedby=\"caption-attachment-33300\" class=\"wp-image-33300\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/02\/DOMU-MellaChurch.gif\" alt=\"\" width=\"768\" height=\"480\" \/><\/a><p id=\"caption-attachment-33300\" class=\"wp-caption-text\">El pastor Juan Prestol, tesorero de la Iglesia Adventista mundial (al centro), junto al pastor Cesario Acevedo, presidente de la Uni\u00f3n Dominicana (izquierda), y Mose Javier (derecha), terminan de cortar la cinta de la recientemente renovada iglesia adventista Mella en Santo Domingo, Rep\u00fablica Dominicana, el 2 de diciembre de 2018. Imagen por cortes\u00eda de la Uni\u00f3n Dominicana\/DIA<\/p><\/div>\n<\/div>\n<p>8 de febrero de 2018 | Santo Domingo, Rep\u00fablica Dominicana [Libna Stevens\/DIA]<\/p>\n<p>Los adventistas del s\u00e9ptimo d\u00eda en la Rep\u00fablica Dominicana celebraron hace poco el cent\u00e9simo aniversario de la iglesia. Los l\u00edderes y miembros de la iglesia celebraron el crecimiento exponencial desde que comenz\u00f3 el mensaje adventista en la isla.<\/p>\n<p>\u201cHoy es un d\u00eda memorable para la Iglesia Adventista del S\u00e9ptimo D\u00eda aqu\u00ed, al ver de qu\u00e9 manera la llama de nuestro mensaje se ha expandido durante estos cien a\u00f1os en el pa\u00eds\u201d, dijo el pastor Cesario Acevedo, presidente de la Iglesia Adventista en la Rep\u00fablica Dominicana, en su visita a la iglesia adventista Mella en Santo Domingo en diciembre pasado.<\/p>\n<div id=\"attachment_33310\" class=\"wp-caption alignright\">\n<div id=\"attachment_33310\" style=\"width: 411px\" class=\"wp-caption alignright\"><a title=\"Iglesia Adventista celebra cien a\u00f1os de crecimiento en la Rep\u00fablica Dominicana\" href=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/02\/Mella-Adventist-Church-Outside.gif\" rel=\"fancybox\" title=\"Iglesia Adventista celebra cien a\u00f1os de crecimiento en la Rep\u00fablica Dominicana\" rel=\"fancybox\"><img decoding=\"async\" aria-describedby=\"caption-attachment-33310\" class=\"wp-image-33310\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/02\/Mella-Adventist-Church-Outside.gif\" alt=\"\" width=\"401\" height=\"251\" \/><\/a><p id=\"caption-attachment-33310\" class=\"wp-caption-text\">La iglesia adventista Mella en Santo Domingo fue construida originalmente en 1917, y ha pasado por varias remodelaciones durante los \u00faltimos cien a\u00f1os. Imagen por cortes\u00eda de la Uni\u00f3n Dominicana\/DIA<\/p><\/div>\n<\/div>\n<p>El pastor Acevedo, junto con el pastor Juan Prestol, tesorero de la Iglesia Adventista mundial y oriundo de la Rep\u00fablica Dominicana, cortaron las cintas de la reci\u00e9n remodelada iglesia adventista Mella, que fue construida en 1917 y fue la primera iglesia adventista en la isla.<\/p>\n<p>\u201cNuestra fe en la bienaventurada esperanza del pronto regreso del Se\u00f1or es la llama que deber\u00eda sostenernos para el cumplimiento de la misi\u00f3n de evangelizaci\u00f3n\u201d, dijo el pastor Prestol. \u201cHoy m\u00e1s que nunca, deber\u00edamos dar ese mensaje\u2026 un mensaje que sigue siendo el mismo: Cristo viene pronto\u201d.<\/p>\n<p>Los l\u00edderes de la iglesia tambi\u00e9n inauguraron una nueva iglesia ese d\u00eda en la Asociaci\u00f3n Dominicana Oriental, lo que llev\u00f3 el n\u00famero total de iglesias nuevas el a\u00f1o pasado a 47.<\/p>\n<p>\u201cNuestros miembros de iglesia est\u00e1n compartiendo el evangelio con decisi\u00f3n en sus comunidades, y tambi\u00e9n est\u00e1n contribuyendo fielmente con la construcci\u00f3n de templos en la isla\u201d, dijo Acevedo.<\/p>\n<p>Durante la \u00faltima d\u00e9cada, cada a\u00f1o se han construido un promedio de 30 a 35 iglesias. No son iglesias endebles, sino edificaciones de concreto llenas de esperanza en Jes\u00fas en todas las comunidades, explic\u00f3 Acevedo. Muchas iglesias han sido construidas con un plano especial preparado por Maranatha Volunteers International, dijeron los l\u00edderes de la iglesia.<\/p>\n<p>Tambi\u00e9n se inaugur\u00f3 una nueva escuela adventista en Miches, en la regi\u00f3n oriental de la isla, lo que llev\u00f3 a sesenta el n\u00famero de escuelas primarias y secundarias operadas por la iglesia en la isla.<\/p>\n<p>Tiene que ver con celebrar el mensaje adventista en las escuelas, lo que ha sido una obra real para el crecimiento de la iglesia, dijo Alejandra Casillas, directora de educaci\u00f3n de la Iglesia Adventista en la Rep\u00fablica Dominicana. Alrededor del 65 por ciento de los estudiantes que asisten al sistema educativo adventista en la isla no pertenecen a la denominaci\u00f3n, explic\u00f3 Casillas. Sin embargo, la obra de evangelizaci\u00f3n en las escuelas est\u00e1 cambiando ese porcentaje, y m\u00e1s familias se est\u00e1n uniendo a la iglesia.<\/p>\n<div id=\"attachment_33306\" class=\"wp-caption alignright\">\n<div id=\"attachment_33306\" style=\"width: 408px\" class=\"wp-caption alignright\"><a title=\"Iglesia Adventista celebra cien a\u00f1os de crecimiento en la Rep\u00fablica Dominicana\" href=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/02\/DOMU-Miches-school.gif\" rel=\"fancybox\" title=\"Iglesia Adventista celebra cien a\u00f1os de crecimiento en la Rep\u00fablica Dominicana\" rel=\"fancybox\"><img decoding=\"async\" aria-describedby=\"caption-attachment-33306\" class=\"wp-image-33306\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/02\/DOMU-Miches-school.gif\" alt=\"\" width=\"398\" height=\"249\" \/><\/a><p id=\"caption-attachment-33306\" class=\"wp-caption-text\">De izquierda a derecha: Alejandra Casillas, directora de educaci\u00f3n, y el pastor Cesario Acevedo, presidente de la Iglesia Adventista en la Rep\u00fablica Dominicana, cortan las cintas del flamante edificio escolar en Miches.\u00a0 Imagen por cortes\u00eda de la Uni\u00f3n Dominicana\/DIA<\/p><\/div>\n<\/div>\n<p>Solo durante los \u00faltimos tres a\u00f1os, se ha bautizado a 1250 estudiantes y padres, lo que representa un promedio de 416 por a\u00f1o\u201d, inform\u00f3 Casillas.<\/p>\n<p>El evangelio tambi\u00e9n se ha expandido de manera significativa mediante el ministerio radial en la isla. La estaci\u00f3n adventista llamada Radio Amanecer ha estado proclamando el mensaje de esperanza y salvaci\u00f3n durante ya 35 a\u00f1os. La estaci\u00f3n cubre el noventa por ciento del pa\u00eds, gracias a sus 23 repetidoras en la isla.<\/p>\n<p>\u201cRadio Amanecer se ha convertido en una herramienta que promueve la unidad de la Iglesia Adventista del S\u00e9ptimo D\u00eda, su crecimiento y su inter\u00e9s en beneficiar a la comunidad, promoviendo la educaci\u00f3n y gracias a su obra social\u201d, dijo Miqueas Fortunato, gerente general de Radio Amanecer. \u201cEsto ha hecho que la radio sea el medio m\u00e1s poderoso de evangelismo para traer a las personas a la iglesia por medio del bautismo\u201d, a\u00f1adi\u00f3.<\/p>\n<p>Seg\u00fan Fortunato, Radio Amanecer es la \u00fanica estaci\u00f3n que m\u00e1s cobertura tiene en la isla.<\/p>\n<p>El crecimiento en la isla tambi\u00e9n ha hecho que dos regiones que ten\u00edan la categor\u00eda de \u201cmisi\u00f3n\u201d hayan pasado a ser \u201casociaci\u00f3n\u201d.<\/p>\n<p>Gracias al Hospital y Centro M\u00e9dico Adventista \u201cVista del Jard\u00edn\u201d, en Santo Domingo, la iglesia se ha conectado con la comunidad mediante servicios de salud, desde su apertura en 2007. La instituci\u00f3n, que cuenta con 51 camas, ha estado ofreciendo atenci\u00f3n ambulatoria y a pacientes internados, as\u00ed como ofreciendo exposiciones y brigadas de salud a las comunidades necesitadas de la capital del pa\u00eds.<\/p>\n<p>El hospital inaugur\u00f3 hace poco un nuevo centro de di\u00e1lisis, dijeron los l\u00edderes de la iglesia.<\/p>\n<p>La Iglesia Adventista tambi\u00e9n opera la hist\u00f3rica Universidad Adventista Dominicana, donde ofrece programas de grado y posgrado, y est\u00e1 acreditada por la Asociaci\u00f3n Adventista de Acreditaci\u00f3n.<\/p>\n<p>En la Rep\u00fablica Dominicana, hay m\u00e1s de 334 mil adventistas que se re\u00fanen en 1338 iglesias y congregaciones.<\/p>\n<p>Para saber m\u00e1s de la Iglesia Adventista en la Rep\u00fablica Dominicana, visite\u00a0<a href=\"mailto:https:\/\/adventistasrd.interamerica.org\/\">adventistasrd.org<\/a><\/p>\n<p><em>Bernardo Medina colabor\u00f3 con este informe.<\/em><\/p>\n<p>Traducci\u00f3n de Marcos Paseggi<\/p>\n","protected":false},"excerpt":{"rendered":"<p>8 de febrero de 2018 | Santo Domingo, Rep\u00fablica Dominicana [Libna Stevens\/DIA] Los adventistas del s\u00e9ptimo d\u00eda en la Rep\u00fablica Dominicana celebraron hace poco el cent\u00e9simo aniversario de la iglesia&#8230;.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17,15],"tags":[],"class_list":["post-38512","post","type-post","status-publish","format-standard","hentry","category-desde-el-campo","category-rss-espanol"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Iglesia Adventista celebra cien a\u00f1os de crecimiento en la Rep\u00fablica Dominicana - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/interamerica.org\/es\/2018\/02\/iglesia-adventista-celebra-cien-anos-de-crecimiento-en-la-republica-dominicana\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Iglesia Adventista celebra cien a\u00f1os de crecimiento en la Rep\u00fablica Dominicana - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana\" \/>\n<meta property=\"og:description\" content=\"8 de febrero de 2018 | Santo Domingo, Rep\u00fablica Dominicana [Libna Stevens\/DIA] Los adventistas del s\u00e9ptimo d\u00eda en la Rep\u00fablica Dominicana celebraron hace poco el cent\u00e9simo aniversario de la iglesia....\" \/>\n<meta property=\"og:url\" content=\"https:\/\/interamerica.org\/es\/2018\/02\/iglesia-adventista-celebra-cien-anos-de-crecimiento-en-la-republica-dominicana\/\" \/>\n<meta property=\"og:site_name\" content=\"Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-08T18:04:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-02-20T18:05:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/02\/DOMU-MellaChurch.gif\" \/>\n<meta name=\"author\" content=\"Lorenzo Verduzco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lorenzo Verduzco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/02\\\/iglesia-adventista-celebra-cien-anos-de-crecimiento-en-la-republica-dominicana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/02\\\/iglesia-adventista-celebra-cien-anos-de-crecimiento-en-la-republica-dominicana\\\/\"},\"author\":{\"name\":\"Lorenzo Verduzco\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#\\\/schema\\\/person\\\/68ede8bdc292885bb76c1e3810e73c39\"},\"headline\":\"Iglesia Adventista celebra cien a\u00f1os de crecimiento en la Rep\u00fablica Dominicana\",\"datePublished\":\"2018-02-08T18:04:34+00:00\",\"dateModified\":\"2018-02-20T18:05:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/02\\\/iglesia-adventista-celebra-cien-anos-de-crecimiento-en-la-republica-dominicana\\\/\"},\"wordCount\":1008,\"image\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/02\\\/iglesia-adventista-celebra-cien-anos-de-crecimiento-en-la-republica-dominicana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/recursing-golick.147-182-135-0.plesk.page\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/DOMU-MellaChurch.gif\",\"articleSection\":[\"Desde el campo\",\"RSS Espa\u00f1ol\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/02\\\/iglesia-adventista-celebra-cien-anos-de-crecimiento-en-la-republica-dominicana\\\/\",\"url\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/02\\\/iglesia-adventista-celebra-cien-anos-de-crecimiento-en-la-republica-dominicana\\\/\",\"name\":\"Iglesia Adventista celebra cien a\u00f1os de crecimiento en la Rep\u00fablica Dominicana - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/02\\\/iglesia-adventista-celebra-cien-anos-de-crecimiento-en-la-republica-dominicana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/02\\\/iglesia-adventista-celebra-cien-anos-de-crecimiento-en-la-republica-dominicana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/recursing-golick.147-182-135-0.plesk.page\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/DOMU-MellaChurch.gif\",\"datePublished\":\"2018-02-08T18:04:34+00:00\",\"dateModified\":\"2018-02-20T18:05:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#\\\/schema\\\/person\\\/68ede8bdc292885bb76c1e3810e73c39\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/02\\\/iglesia-adventista-celebra-cien-anos-de-crecimiento-en-la-republica-dominicana\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/02\\\/iglesia-adventista-celebra-cien-anos-de-crecimiento-en-la-republica-dominicana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/02\\\/iglesia-adventista-celebra-cien-anos-de-crecimiento-en-la-republica-dominicana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/recursing-golick.147-182-135-0.plesk.page\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/DOMU-MellaChurch.gif\",\"contentUrl\":\"https:\\\/\\\/recursing-golick.147-182-135-0.plesk.page\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/DOMU-MellaChurch.gif\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/02\\\/iglesia-adventista-celebra-cien-anos-de-crecimiento-en-la-republica-dominicana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/interamerica.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Iglesia Adventista celebra cien a\u00f1os de crecimiento en la Rep\u00fablica Dominicana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/interamerica.org\\\/es\\\/\",\"name\":\"Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/interamerica.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#\\\/schema\\\/person\\\/68ede8bdc292885bb76c1e3810e73c39\",\"name\":\"Lorenzo Verduzco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g\",\"caption\":\"Lorenzo Verduzco\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Iglesia Adventista celebra cien a\u00f1os de crecimiento en la Rep\u00fablica Dominicana - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/interamerica.org\/es\/2018\/02\/iglesia-adventista-celebra-cien-anos-de-crecimiento-en-la-republica-dominicana\/","og_locale":"es_ES","og_type":"article","og_title":"Iglesia Adventista celebra cien a\u00f1os de crecimiento en la Rep\u00fablica Dominicana - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","og_description":"8 de febrero de 2018 | Santo Domingo, Rep\u00fablica Dominicana [Libna Stevens\/DIA] Los adventistas del s\u00e9ptimo d\u00eda en la Rep\u00fablica Dominicana celebraron hace poco el cent\u00e9simo aniversario de la iglesia....","og_url":"https:\/\/interamerica.org\/es\/2018\/02\/iglesia-adventista-celebra-cien-anos-de-crecimiento-en-la-republica-dominicana\/","og_site_name":"Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","article_published_time":"2018-02-08T18:04:34+00:00","article_modified_time":"2018-02-20T18:05:32+00:00","og_image":[{"url":"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/02\/DOMU-MellaChurch.gif","type":"","width":"","height":""}],"author":"Lorenzo Verduzco","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Lorenzo Verduzco","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/interamerica.org\/es\/2018\/02\/iglesia-adventista-celebra-cien-anos-de-crecimiento-en-la-republica-dominicana\/#article","isPartOf":{"@id":"https:\/\/interamerica.org\/es\/2018\/02\/iglesia-adventista-celebra-cien-anos-de-crecimiento-en-la-republica-dominicana\/"},"author":{"name":"Lorenzo Verduzco","@id":"https:\/\/interamerica.org\/es\/#\/schema\/person\/68ede8bdc292885bb76c1e3810e73c39"},"headline":"Iglesia Adventista celebra cien a\u00f1os de crecimiento en la Rep\u00fablica Dominicana","datePublished":"2018-02-08T18:04:34+00:00","dateModified":"2018-02-20T18:05:32+00:00","mainEntityOfPage":{"@id":"https:\/\/interamerica.org\/es\/2018\/02\/iglesia-adventista-celebra-cien-anos-de-crecimiento-en-la-republica-dominicana\/"},"wordCount":1008,"image":{"@id":"https:\/\/interamerica.org\/es\/2018\/02\/iglesia-adventista-celebra-cien-anos-de-crecimiento-en-la-republica-dominicana\/#primaryimage"},"thumbnailUrl":"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/02\/DOMU-MellaChurch.gif","articleSection":["Desde el campo","RSS Espa\u00f1ol"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/interamerica.org\/es\/2018\/02\/iglesia-adventista-celebra-cien-anos-de-crecimiento-en-la-republica-dominicana\/","url":"https:\/\/interamerica.org\/es\/2018\/02\/iglesia-adventista-celebra-cien-anos-de-crecimiento-en-la-republica-dominicana\/","name":"Iglesia Adventista celebra cien a\u00f1os de crecimiento en la Rep\u00fablica Dominicana - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","isPartOf":{"@id":"https:\/\/interamerica.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/interamerica.org\/es\/2018\/02\/iglesia-adventista-celebra-cien-anos-de-crecimiento-en-la-republica-dominicana\/#primaryimage"},"image":{"@id":"https:\/\/interamerica.org\/es\/2018\/02\/iglesia-adventista-celebra-cien-anos-de-crecimiento-en-la-republica-dominicana\/#primaryimage"},"thumbnailUrl":"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/02\/DOMU-MellaChurch.gif","datePublished":"2018-02-08T18:04:34+00:00","dateModified":"2018-02-20T18:05:32+00:00","author":{"@id":"https:\/\/interamerica.org\/es\/#\/schema\/person\/68ede8bdc292885bb76c1e3810e73c39"},"breadcrumb":{"@id":"https:\/\/interamerica.org\/es\/2018\/02\/iglesia-adventista-celebra-cien-anos-de-crecimiento-en-la-republica-dominicana\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/interamerica.org\/es\/2018\/02\/iglesia-adventista-celebra-cien-anos-de-crecimiento-en-la-republica-dominicana\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/interamerica.org\/es\/2018\/02\/iglesia-adventista-celebra-cien-anos-de-crecimiento-en-la-republica-dominicana\/#primaryimage","url":"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/02\/DOMU-MellaChurch.gif","contentUrl":"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/02\/DOMU-MellaChurch.gif"},{"@type":"BreadcrumbList","@id":"https:\/\/interamerica.org\/es\/2018\/02\/iglesia-adventista-celebra-cien-anos-de-crecimiento-en-la-republica-dominicana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/interamerica.org\/es\/"},{"@type":"ListItem","position":2,"name":"Iglesia Adventista celebra cien a\u00f1os de crecimiento en la Rep\u00fablica Dominicana"}]},{"@type":"WebSite","@id":"https:\/\/interamerica.org\/es\/#website","url":"https:\/\/interamerica.org\/es\/","name":"Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/interamerica.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/interamerica.org\/es\/#\/schema\/person\/68ede8bdc292885bb76c1e3810e73c39","name":"Lorenzo Verduzco","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g","caption":"Lorenzo Verduzco"}}]}},"_links":{"self":[{"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/posts\/38512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/comments?post=38512"}],"version-history":[{"count":0,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/posts\/38512\/revisions"}],"wp:attachment":[{"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/media?parent=38512"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/categories?post=38512"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/tags?post=38512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}