{"id":39720,"date":"2018-03-08T00:00:00","date_gmt":"2018-03-08T04:00:00","guid":{"rendered":"http:\/\/192.81.217.108\/2018\/03\/las-bebidas-gaseosas-son-malas-pero-quiza-no-es-lo-que-nos-esta-engordando\/"},"modified":"2018-12-03T22:00:22","modified_gmt":"2018-12-04T02:00:22","slug":"las-bebidas-gaseosas-son-malas-pero-quiza-no-es-lo-que-nos-esta-engordando","status":"publish","type":"post","link":"https:\/\/interamerica.org\/es\/2018\/03\/las-bebidas-gaseosas-son-malas-pero-quiza-no-es-lo-que-nos-esta-engordando\/","title":{"rendered":"Las bebidas gaseosas son malas, pero quiz\u00e1 no es lo que nos est\u00e1 engordando"},"content":{"rendered":"<div id=\"attachment_33835\" style=\"width: 770px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/03\/soda-bad-for-health-but-may-not-be-making-us-fat-1.jpg\" rel=\"fancybox\" title=\"Las bebidas gaseosas son malas, pero quiz\u00e1 no es lo que nos est\u00e1 engordando\"><img fetchpriority=\"high\" decoding=\"async\" aria-describedby=\"caption-attachment-33835\" class=\" wp-image-33835\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/03\/soda-bad-for-health-but-may-not-be-making-us-fat-1.jpg\" alt=\"\" width=\"760\" height=\"380\" \/><\/a><p id=\"caption-attachment-33835\" class=\"wp-caption-text\"><br \/> El expert en medicina preventiva Neal Barnard dijo que en lo que respecta a la epidemia de obesidad, el queso ha llegado a ser un peligro mayor que las bebidas gaseosas. Imagen de Salud de la Universidad de Loma Linda<\/p><\/div>\n<p><span class=\"byline-news\"> 7 de marzo de 2018 | Loma Linda, California, Estados Unidos | Marcos Paseggi, <em>Adventist Review<\/em><\/span><\/p>\n<p>\u201cNo me entiendan mal\u201d, dijo el experto en medicina preventiva Neal Barnard en su presentaci\u00f3n en el Congreso Internacional de Nutrici\u00f3n Vegetariana el 27 de febrero de 2018. \u201cLas sodas o bebidas gaseosas son muy malas para la salud. No hay siquiera que cuestionarlo. Pero la verdad es que acaso no sean lo que nos est\u00e1 engordando\u201d.<\/p>\n<div id=\"attachment_33838\" style=\"width: 408px\" class=\"wp-caption alignright\"><a href=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/03\/LLU-cooking-demonstrations.jpg\" rel=\"fancybox\" title=\"Las bebidas gaseosas son malas, pero quiz\u00e1 no es lo que nos est\u00e1 engordando\"><img decoding=\"async\" aria-describedby=\"caption-attachment-33838\" class=\" wp-image-33838\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/03\/LLU-cooking-demonstrations.jpg\" alt=\"\" width=\"398\" height=\"265\" \/><\/a><p id=\"caption-attachment-33838\" class=\"wp-caption-text\">Como parte del programa, los participantes que asisten al VII Congreso Internacional sobre Nutrici\u00f3n Vegetariana en Loma Linda disfrutaron de demostraciones de cocina en el campus. Imagen de Salud de la Universidad de Loma Linda<\/p><\/div>\n<p>Barnard, que ense\u00f1a en la Escuela de Medicina de la Universidad George Washington y preside la Comisi\u00f3n de M\u00e9dicos por una Medicina Responsable en Washington D.C., hizo esa llamativa observaci\u00f3n al analizar de qu\u00e9 manera las dietas basadas en plantas pueden apoyar los esfuerzos de tratamiento contra la obesidad.<\/p>\n<p><strong>Las dietas basadas en plantas y la obesidad<\/strong><\/p>\n<p>Barnard revel\u00f3 que en estudios de observaci\u00f3n, \u201clos individuos que siguieron una dieta vegetariana, y en particular vegana, mostraron un peso corporal m\u00e1s saludable, en promedio, en comparaci\u00f3n con los que siguen dietas omn\u00edvoras\u201d. A\u00f1adi\u00f3 que \u201cen las pruebas cl\u00ednicas, las dietas vegetarianas y veganas llevaron a una significativa p\u00e9rdida de peso, aun ante la ausencia de ejercicio f\u00edsico o la falta de l\u00edmites en la ingesta de energ\u00eda\u201d.<\/p>\n<p>A\u00fan no se comprende cada detalle del mecanismo de p\u00e9rdida de peso en el caso de las dietas basadas en plantas, pero Barnard dijo que los contenidos de alto contenido de fibra y bajo contenido graso parecen reducir la densidad de la energ\u00eda diet\u00e9tica. Tambi\u00e9n explic\u00f3 que aparentemente, se produce un incremento en el uso de energ\u00eda postprandial (despu\u00e9s de comer).<\/p>\n<p>Los cambios hacia una dieta basada en plantas no son solo efectivos, sino que producen modificaciones positivas en otros indicadores de salud. Entre otros, los investigadores han observado cambios favorables en la nutrici\u00f3n general, las concentraciones de l\u00edpidos en la sangre y la presi\u00f3n arterial, revel\u00f3.<\/p>\n<p><strong> El culpable de la obesidad<\/strong><strong>rit<\/strong><\/p>\n<p>Pero entonces, una vez m\u00e1s, \u00bfcu\u00e1l es la relaci\u00f3n entre el consumo de bebidas gaseosas y la obesidad?<\/p>\n<div id=\"attachment_33841\" style=\"width: 403px\" class=\"wp-caption alignright\"><a href=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/03\/LLU-participant.jpg\" rel=\"fancybox\" title=\"Las bebidas gaseosas son malas, pero quiz\u00e1 no es lo que nos est\u00e1 engordando\"><img decoding=\"async\" aria-describedby=\"caption-attachment-33841\" class=\" wp-image-33841\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/03\/LLU-participant.jpg\" alt=\"\" width=\"393\" height=\"262\" \/><\/a><p id=\"caption-attachment-33841\" class=\"wp-caption-text\">Una de las participantes del congreso sonr\u00ede junto a su p\u00f3ster de investigaci\u00f3n. Los estudiantes y los profesionales de nutrici\u00f3n presentaron cientos de p\u00f3steres sobre diversos temas relacionados con la dieta y la salud. Imagen de Salud de la Universidad de Loma Linda<\/p><\/div>\n<p>Barnard mostr\u00f3 que en a\u00f1os recientes, el consumo de gaseosas en general ha disminuido, mientras que las opciones \u201cdiet\u00e9ticas\u201d o de \u201ccero az\u00facar\u201d se han disparado. Estas bebidas no necesariamente a\u00f1aden una cantidad sustancial de calor\u00edas a la dieta de sus consumidores. \u201cSiguen siendo muy malas para la salud, pero no disparan la obesidad\u201d, explic\u00f3.<\/p>\n<p>Si consideramos la tendencia de que hay menos personas que beben gaseosas y que si lo hacen, es muy probable que sean diet\u00e9ticas o sin az\u00facar, Barnard indic\u00f3 que en el presente hay otros alimentos que est\u00e1n contribuyendo m\u00e1s que las gaseosas al aumento de peso. Hay otros art\u00edculos alimentarios, cree \u00e9l, que son mucho peores a la hora de prevenir la epidemia de obesidad que estamos viendo a nuestro alrededor.<\/p>\n<p>\u201c\u00bfCu\u00e1l es el art\u00edculo alimentario que r\u00e1pida y f\u00e1cilmente a\u00f1ade grasa a nuestro cuerpo?\u201d, pregunt\u00f3, antes de responder. \u201c\u00a1Es el queso!\u201d<\/p>\n<p>A diferencia de los carbohidratos, Barnard explic\u00f3 que el cuerpo almacena el queso muy f\u00e1cilmente en forma de grasa. Y mostr\u00f3 gr\u00e1ficos donde parece haber una relaci\u00f3n entre el astron\u00f3mico aumento del consumo de queso y la epidemia de obesidad.<\/p>\n<p>Barnard tambi\u00e9n se refiri\u00f3 a estudios que muestran que una dieta grasa desregula los genes que se requieren para la biog\u00e9nesis mitocondrial. \u201cEsto significa que la grasa interfiere con la quema de calor\u00edas\u201d, dijo. \u201cLos alimentos grasos tambi\u00e9n alteran la oxidaci\u00f3n celular. \u201cUna dieta elevada en contenidos grasos altera las barreras intestinales, y la grasa env\u00eda endotoxinas al flujo sangu\u00edneo\u201d, dijo. En algunos estudios, los investigadores observaron esos efectos adversos solo cinco d\u00edas despu\u00e9s de que se administr\u00f3 a los sujetos una dieta alta en contenidos grasos.<\/p>\n<p><strong>Qu\u00e9 podemos hacer<\/strong><\/p>\n<p>En su pr\u00e1ctica profesional, Barnard dijo que invita a las personas que est\u00e1n considerando comenzar una dieta m\u00e1s sana a que primero eval\u00faen las posibilidades. \u201cNo se ponga a discutir con sus pacientes\u201d, les dijo a los profesionales de nutrici\u00f3n que lo escuchaban. \u201cInv\u00edtelos a evaluar qu\u00e9 opciones tienen\u201d. Y entonces, a\u00f1adi\u00f3, inv\u00edtelos a hacer una prueba durante dos a tres semanas\u201d. \u201cSean buenos instructores\u201d, les aconsej\u00f3.<\/p>\n<div id=\"attachment_33844\" style=\"width: 408px\" class=\"wp-caption alignright\"><a href=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/03\/LLU-Chef-Cory.jpg\" rel=\"fancybox\" title=\"Las bebidas gaseosas son malas, pero quiz\u00e1 no es lo que nos est\u00e1 engordando\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-33844\" class=\" wp-image-33844\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/03\/LLU-Chef-Cory.jpg\" alt=\"\" width=\"398\" height=\"264\" \/><\/a><p id=\"caption-attachment-33844\" class=\"wp-caption-text\">El chef Cory Gheen hace una demostraci\u00f3n de c\u00f3mo preparar uno de los platos que formaron parte de la demostraci\u00f3n de cocina y almuerzo \u201cUna aventura culinaria vegetariana\u201d, el 26 de febrero de 2018. Imagen de la Universidad de Loma Linda<\/p><\/div>\n<p>Hay numerosos ejemplos de c\u00f3mo la adopci\u00f3n de una dieta basada en plantas ha beneficiado a las personas, dijo Barnard. Cuando peor es el estado inicial de la persona, m\u00e1s r\u00e1pidos parecen comenzar a verse los efectos positivos.<\/p>\n<p>Barnard dijo que una dieta basada en plantas tiene el potencial de mejorar la calidad de vida de los pacientes que sufren de varias enfermedades, lo que incluye las afecciones card\u00edacas, la diabetes tipo 2, y el sobrepeso de las mujeres despu\u00e9s de la menopausia. Fue una declaraci\u00f3n repetida una y otra vez tambi\u00e9n por varios otros expositores.<\/p>\n<p>Pensemos, por ejemplo, en Brenda Davis. Davis una consultora nutricional de Columbia Brit\u00e1nica, Canad\u00e1, que ha escrito m\u00e1s de una decena de libros sobre nutrici\u00f3n basada en plantas, analiz\u00f3 estudios de casos en los que un cambio en la dieta signific\u00f3 mejoras en la salud, un mejor control y hasta la reversi\u00f3n de los efectos resultantes de enfermedades cr\u00f3nicas.<\/p>\n<p>\u201cSufrir una enfermedad es como tener incendiada la casa\u201d, dijo. \u201cAseg\u00farense de no a\u00f1adir ning\u00fan tipo de gasolina \u2014elecciones de alimentos no saludables\u2014 a ese fuego\u201d.<\/p>\n<p>Davis, que tuvo a su cargo una presentaci\u00f3n el \u00faltimo d\u00eda del congreso, dijo que aun cambios moderados pueden producir mejoras cl\u00ednicas valiosas. \u201cY cuanto m\u00e1s cambia el paciente, m\u00e1s grandes son los resultados esperados\u201d, expres\u00f3.<\/p>\n<p>Por su parte Wes Youngberg, profesor de Medicina Preventiva de la Universidad de Loma Linda concord\u00f3 con Davis al expresar que algunas afecciones relacionadas con la dieta pueden experimentar cambios positivos. \u201cDios cre\u00f3 el cuerpo de manera tal que, con tiempo y el proceso correcto, un estado determinado puede ser revertido\u201d, dijo. \u201cLa funci\u00f3n de ustedes \u2014les dijo a los profesionales de nutrici\u00f3n presentes en el congreso\u2014 es invitar [a sus pacientes] a que adopten un programa que les permita un camino hacia la sanaci\u00f3n\u201d.<\/p>\n<p>Ese camino hacia la salud puede resultar dif\u00edcil y arduo en un comienzo, pero las instrucciones para avanzar en \u00e9l son simples, dijo Davis. \u201cHagan que los alimentos basados en plantas lleguen a ser la base de la dieta, y quiten los az\u00facares y los almidones refinados\u201d, aconsej\u00f3.<\/p>\n<p>Y por supuesto, \u00a1olv\u00eddense de las gaseosas!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cNo me entiendan mal\u201d, dijo el experto en medicina preventiva Neal Barnard en su presentaci\u00f3n en el Congreso Internacional de Nutrici\u00f3n Vegetariana el 27 de febrero de 2018. \u201cLas sodas o bebidas gaseosas son muy malas para la salud. No hay siquiera que cuestionarlo. Pero la verdad es que acaso no sean lo que nos est\u00e1 engordando\u201d.<\/p>\n<p>Barnard, que ense\u00f1a en la Escuela de Medicina de la Universidad George Washington y preside la Comisi\u00f3n de M\u00e9dicos por una Medicina Responsable en Washington D.C., hizo esa llamativa observaci\u00f3n al analizar de qu\u00e9 manera las dietas basadas en plantas pueden apoyar los esfuerzos de tratamiento contra la obesidad.<\/p>\n","protected":false},"author":1,"featured_media":40165,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[14,15],"tags":[],"class_list":["post-39720","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-de-la-iglesia-mundial","category-rss-espanol"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Las bebidas gaseosas son malas, pero quiz\u00e1 no es lo que nos est\u00e1 engordando - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/interamerica.org\/es\/2018\/03\/las-bebidas-gaseosas-son-malas-pero-quiza-no-es-lo-que-nos-esta-engordando\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las bebidas gaseosas son malas, pero quiz\u00e1 no es lo que nos est\u00e1 engordando - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana\" \/>\n<meta property=\"og:description\" content=\"\u201cNo me entiendan mal\u201d, dijo el experto en medicina preventiva Neal Barnard en su presentaci\u00f3n en el Congreso Internacional de Nutrici\u00f3n Vegetariana el 27 de febrero de 2018. \u201cLas sodas o bebidas gaseosas son muy malas para la salud. No hay siquiera que cuestionarlo. Pero la verdad es que acaso no sean lo que nos est\u00e1 engordando\u201d.  Barnard, que ense\u00f1a en la Escuela de Medicina de la Universidad George Washington y preside la Comisi\u00f3n de M\u00e9dicos por una Medicina Responsable en Washington D.C., hizo esa llamativa observaci\u00f3n al analizar de qu\u00e9 manera las dietas basadas en plantas pueden apoyar los esfuerzos de tratamiento contra la obesidad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/interamerica.org\/es\/2018\/03\/las-bebidas-gaseosas-son-malas-pero-quiza-no-es-lo-que-nos-esta-engordando\/\" \/>\n<meta property=\"og:site_name\" content=\"Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-08T04:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-04T02:00:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/03\/soda-686984-1280.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lorenzo Verduzco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lorenzo Verduzco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/03\\\/las-bebidas-gaseosas-son-malas-pero-quiza-no-es-lo-que-nos-esta-engordando\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/03\\\/las-bebidas-gaseosas-son-malas-pero-quiza-no-es-lo-que-nos-esta-engordando\\\/\"},\"author\":{\"name\":\"Lorenzo Verduzco\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#\\\/schema\\\/person\\\/68ede8bdc292885bb76c1e3810e73c39\"},\"headline\":\"Las bebidas gaseosas son malas, pero quiz\u00e1 no es lo que nos est\u00e1 engordando\",\"datePublished\":\"2018-03-08T04:00:00+00:00\",\"dateModified\":\"2018-12-04T02:00:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/03\\\/las-bebidas-gaseosas-son-malas-pero-quiza-no-es-lo-que-nos-esta-engordando\\\/\"},\"wordCount\":1325,\"image\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/03\\\/las-bebidas-gaseosas-son-malas-pero-quiza-no-es-lo-que-nos-esta-engordando\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/soda-686984-1280.jpg\",\"articleSection\":[\"Desde la iglesia mundial\",\"RSS Espa\u00f1ol\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/03\\\/las-bebidas-gaseosas-son-malas-pero-quiza-no-es-lo-que-nos-esta-engordando\\\/\",\"url\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/03\\\/las-bebidas-gaseosas-son-malas-pero-quiza-no-es-lo-que-nos-esta-engordando\\\/\",\"name\":\"Las bebidas gaseosas son malas, pero quiz\u00e1 no es lo que nos est\u00e1 engordando - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/03\\\/las-bebidas-gaseosas-son-malas-pero-quiza-no-es-lo-que-nos-esta-engordando\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/03\\\/las-bebidas-gaseosas-son-malas-pero-quiza-no-es-lo-que-nos-esta-engordando\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/soda-686984-1280.jpg\",\"datePublished\":\"2018-03-08T04:00:00+00:00\",\"dateModified\":\"2018-12-04T02:00:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#\\\/schema\\\/person\\\/68ede8bdc292885bb76c1e3810e73c39\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/03\\\/las-bebidas-gaseosas-son-malas-pero-quiza-no-es-lo-que-nos-esta-engordando\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/03\\\/las-bebidas-gaseosas-son-malas-pero-quiza-no-es-lo-que-nos-esta-engordando\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/03\\\/las-bebidas-gaseosas-son-malas-pero-quiza-no-es-lo-que-nos-esta-engordando\\\/#primaryimage\",\"url\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/soda-686984-1280.jpg\",\"contentUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/soda-686984-1280.jpg\",\"width\":1280,\"height\":853},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/03\\\/las-bebidas-gaseosas-son-malas-pero-quiza-no-es-lo-que-nos-esta-engordando\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/interamerica.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las bebidas gaseosas son malas, pero quiz\u00e1 no es lo que nos est\u00e1 engordando\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/interamerica.org\\\/es\\\/\",\"name\":\"Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/interamerica.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#\\\/schema\\\/person\\\/68ede8bdc292885bb76c1e3810e73c39\",\"name\":\"Lorenzo Verduzco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g\",\"caption\":\"Lorenzo Verduzco\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las bebidas gaseosas son malas, pero quiz\u00e1 no es lo que nos est\u00e1 engordando - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/interamerica.org\/es\/2018\/03\/las-bebidas-gaseosas-son-malas-pero-quiza-no-es-lo-que-nos-esta-engordando\/","og_locale":"es_ES","og_type":"article","og_title":"Las bebidas gaseosas son malas, pero quiz\u00e1 no es lo que nos est\u00e1 engordando - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","og_description":"\u201cNo me entiendan mal\u201d, dijo el experto en medicina preventiva Neal Barnard en su presentaci\u00f3n en el Congreso Internacional de Nutrici\u00f3n Vegetariana el 27 de febrero de 2018. \u201cLas sodas o bebidas gaseosas son muy malas para la salud. No hay siquiera que cuestionarlo. Pero la verdad es que acaso no sean lo que nos est\u00e1 engordando\u201d.  Barnard, que ense\u00f1a en la Escuela de Medicina de la Universidad George Washington y preside la Comisi\u00f3n de M\u00e9dicos por una Medicina Responsable en Washington D.C., hizo esa llamativa observaci\u00f3n al analizar de qu\u00e9 manera las dietas basadas en plantas pueden apoyar los esfuerzos de tratamiento contra la obesidad.","og_url":"https:\/\/interamerica.org\/es\/2018\/03\/las-bebidas-gaseosas-son-malas-pero-quiza-no-es-lo-que-nos-esta-engordando\/","og_site_name":"Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","article_published_time":"2018-03-08T04:00:00+00:00","article_modified_time":"2018-12-04T02:00:22+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/03\/soda-686984-1280.jpg","type":"image\/jpeg"}],"author":"Lorenzo Verduzco","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Lorenzo Verduzco","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/interamerica.org\/es\/2018\/03\/las-bebidas-gaseosas-son-malas-pero-quiza-no-es-lo-que-nos-esta-engordando\/#article","isPartOf":{"@id":"https:\/\/interamerica.org\/es\/2018\/03\/las-bebidas-gaseosas-son-malas-pero-quiza-no-es-lo-que-nos-esta-engordando\/"},"author":{"name":"Lorenzo Verduzco","@id":"https:\/\/interamerica.org\/es\/#\/schema\/person\/68ede8bdc292885bb76c1e3810e73c39"},"headline":"Las bebidas gaseosas son malas, pero quiz\u00e1 no es lo que nos est\u00e1 engordando","datePublished":"2018-03-08T04:00:00+00:00","dateModified":"2018-12-04T02:00:22+00:00","mainEntityOfPage":{"@id":"https:\/\/interamerica.org\/es\/2018\/03\/las-bebidas-gaseosas-son-malas-pero-quiza-no-es-lo-que-nos-esta-engordando\/"},"wordCount":1325,"image":{"@id":"https:\/\/interamerica.org\/es\/2018\/03\/las-bebidas-gaseosas-son-malas-pero-quiza-no-es-lo-que-nos-esta-engordando\/#primaryimage"},"thumbnailUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/03\/soda-686984-1280.jpg","articleSection":["Desde la iglesia mundial","RSS Espa\u00f1ol"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/interamerica.org\/es\/2018\/03\/las-bebidas-gaseosas-son-malas-pero-quiza-no-es-lo-que-nos-esta-engordando\/","url":"https:\/\/interamerica.org\/es\/2018\/03\/las-bebidas-gaseosas-son-malas-pero-quiza-no-es-lo-que-nos-esta-engordando\/","name":"Las bebidas gaseosas son malas, pero quiz\u00e1 no es lo que nos est\u00e1 engordando - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","isPartOf":{"@id":"https:\/\/interamerica.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/interamerica.org\/es\/2018\/03\/las-bebidas-gaseosas-son-malas-pero-quiza-no-es-lo-que-nos-esta-engordando\/#primaryimage"},"image":{"@id":"https:\/\/interamerica.org\/es\/2018\/03\/las-bebidas-gaseosas-son-malas-pero-quiza-no-es-lo-que-nos-esta-engordando\/#primaryimage"},"thumbnailUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/03\/soda-686984-1280.jpg","datePublished":"2018-03-08T04:00:00+00:00","dateModified":"2018-12-04T02:00:22+00:00","author":{"@id":"https:\/\/interamerica.org\/es\/#\/schema\/person\/68ede8bdc292885bb76c1e3810e73c39"},"breadcrumb":{"@id":"https:\/\/interamerica.org\/es\/2018\/03\/las-bebidas-gaseosas-son-malas-pero-quiza-no-es-lo-que-nos-esta-engordando\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/interamerica.org\/es\/2018\/03\/las-bebidas-gaseosas-son-malas-pero-quiza-no-es-lo-que-nos-esta-engordando\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/interamerica.org\/es\/2018\/03\/las-bebidas-gaseosas-son-malas-pero-quiza-no-es-lo-que-nos-esta-engordando\/#primaryimage","url":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/03\/soda-686984-1280.jpg","contentUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/03\/soda-686984-1280.jpg","width":1280,"height":853},{"@type":"BreadcrumbList","@id":"https:\/\/interamerica.org\/es\/2018\/03\/las-bebidas-gaseosas-son-malas-pero-quiza-no-es-lo-que-nos-esta-engordando\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/interamerica.org\/es\/"},{"@type":"ListItem","position":2,"name":"Las bebidas gaseosas son malas, pero quiz\u00e1 no es lo que nos est\u00e1 engordando"}]},{"@type":"WebSite","@id":"https:\/\/interamerica.org\/es\/#website","url":"https:\/\/interamerica.org\/es\/","name":"Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/interamerica.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/interamerica.org\/es\/#\/schema\/person\/68ede8bdc292885bb76c1e3810e73c39","name":"Lorenzo Verduzco","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g","caption":"Lorenzo Verduzco"}}]}},"_links":{"self":[{"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/posts\/39720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/comments?post=39720"}],"version-history":[{"count":0,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/posts\/39720\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/media\/40165"}],"wp:attachment":[{"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/media?parent=39720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/categories?post=39720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/tags?post=39720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}