{"id":39732,"date":"2018-03-23T00:00:00","date_gmt":"2018-03-23T04:00:00","guid":{"rendered":"http:\/\/192.81.217.108\/2018\/03\/en-puerto-rico-universidad-adventista-inaugura-nuevo-centro-de-simulacion-de-ciencias-de-la-salud\/"},"modified":"2018-04-06T16:26:59","modified_gmt":"2018-04-06T20:26:59","slug":"en-puerto-rico-universidad-adventista-inaugura-nuevo-centro-de-simulacion-de-ciencias-de-la-salud","status":"publish","type":"post","link":"https:\/\/interamerica.org\/es\/2018\/03\/en-puerto-rico-universidad-adventista-inaugura-nuevo-centro-de-simulacion-de-ciencias-de-la-salud\/","title":{"rendered":"En Puerto Rico, universidad adventista inaugura nuevo centro de simulaci\u00f3n de ciencias de la salud"},"content":{"rendered":"<div id=\"attachment_34106\" style=\"width: 752px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/03\/AAU-BAH_6763.jpg\" rel=\"fancybox\" title=\"En Puerto Rico, universidad adventista inaugura nuevo centro de simulaci\u00f3n de ciencias de la salud\"><img fetchpriority=\"high\" decoding=\"async\" aria-describedby=\"caption-attachment-34106\" class=\" wp-image-34106\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/03\/AAU-BAH_6763.jpg\" alt=\"\" width=\"742\" height=\"464\" \/><\/a><p id=\"caption-attachment-34106\" class=\"wp-caption-text\">Estudiantes de enfermer\u00eda de la Universidad Adventista de las Antillas demuestran sus habilidades durante un recorrido del nuevo Centro de Simulaci\u00f3n de Ciencias de la Salud despu\u00e9s de la ceremonia de inauguraci\u00f3n el 14 de marzo de 2018 en Mayag\u00fcez, Puerto Rico. Imagen por cortes\u00eda de la Universidad Adventista de las Antillas.<\/p><\/div>\n<p>23 de mayo de 2018 | Mayag\u00fcez, Puerto Rico | Lorell Varela\/DIA<\/p>\n<p>La Universidad Adventista de las Antillas (AAU), una instituci\u00f3n operada por la Iglesia Adventista del S\u00e9ptimo D\u00eda en Puerto Rico, inaugur\u00f3 hace poco un nuevo Centro de Simulaci\u00f3n de Ciencias de la Salud. El centro de \u00faltima generaci\u00f3n beneficiar\u00e1 a los futuros profesionales de salud con la tecnolog\u00eda m\u00e1s avanzada en el \u00e1rea, dijeron los l\u00edderes de la universidad.<\/p>\n<div id=\"attachment_34109\" style=\"width: 423px\" class=\"wp-caption alignright\"><a href=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/03\/AAU-ribbonBAH_6694.jpg\" rel=\"fancybox\" title=\"En Puerto Rico, universidad adventista inaugura nuevo centro de simulaci\u00f3n de ciencias de la salud\"><img decoding=\"async\" aria-describedby=\"caption-attachment-34109\" class=\" wp-image-34109\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/03\/AAU-ribbonBAH_6694.jpg\" alt=\"\" width=\"413\" height=\"258\" \/><\/a><p id=\"caption-attachment-34109\" class=\"wp-caption-text\">Maricamen Mass (izquierda), representante del distrito occidental de Mayag\u00fcez, el doctor Obed Jim\u00e9nez (centro), presidente de la Universidad Adventista de las Antillas, y Jos\u00e9 Guillermo Rodr\u00edguez (derecho), alcalde de Mayag\u00fcez, cortan las cintas del nuevo Centro de Simulaci\u00f3n de Ciencias de la Salud. Imagen por cortes\u00eda de la Universidad Adventista de las Antillas<\/p><\/div>\n<p>El alcalde de Mayag\u00fcez Jos\u00e9 Guillermo Rodr\u00edguez felicit\u00f3 a la iglesia y a los l\u00edderes de la universidad por abrir el m\u00e1s moderno centro de simulaci\u00f3n en ciencias de la salud de la isla. La ceremonia se llev\u00f3 a cabo el 13 de marzo de 2018.<\/p>\n<p>\u201cLos estudiantes van a poder realizar sus pr\u00e1cticas de procedimientos de forma en que puedan minimizar errores y afinar sus destrezas antes de visitar una facilidad hospitalaria con pacientes reales\u201d, dijo el doctor Obed Jim\u00e9nez, presidente de la instituci\u00f3n.<\/p>\n<p>El centro de simulaci\u00f3n de m\u00e1s de 500 metros cuadrados cuenta con una unidad de maternidad, una sala de emergencias, dos salas de operaciones y una zona de cuidados cr\u00edticos. Asimismo, tiene una sala de suministros, un lavadero, \u00e1reas t\u00e9cnicas para cada sala, y dos oficinas administrativas, adem\u00e1s de un sal\u00f3n de clases. El centro fue certificado por la Gaumard Scientific Company, Inc., que produce simuladores de pol\u00edmeros para la educaci\u00f3n en el \u00e1rea de salud.<\/p>\n<p>Adyacentes al centro de simulaci\u00f3n se encuentra un centro de recursos matem\u00e1ticos para el desarrollo de habilidades en al \u00e1rea de farmacolog\u00eda, que es parte de una extensi\u00f3n del Edificio de Ciencias Benjam\u00edn P\u00e9rez Soto.<\/p>\n<p>Gracias a un acuerdo con el Hospital Bella Vista, el centro de simulaci\u00f3n tendr\u00e1 acceso a la plataforma MediTech en los m\u00f3dulos del expediente electr\u00f3nico, lo que brindar\u00e1 experiencias reales a los estudiantes relacionadas con los procesos de documentaci\u00f3n cl\u00ednica, explic\u00f3 Jim\u00e9nez.<\/p>\n<p>El Centro de Simulaci\u00f3n de Ciencias de la Salud remplaza a un laboratorio de salud m\u00e1s peque\u00f1o y fortalecer\u00e1 el programa de enfermer\u00eda de la universidad, que actualmente es el programa m\u00e1s grande y s\u00f3lido con el que cuenta la instituci\u00f3n. En el presente hay 641 estudiantes en la carrera de enfermer\u00eda, adem\u00e1s de 64 estudiantes que cursan la carrera de terapia respiratoria, dijeron los directivos de la universidad. Eso significa que m\u00e1s de la mitad de los estudiantes de la universidad se beneficiar\u00e1n con este nuevo centro de recursos.<\/p>\n<div id=\"attachment_34103\" style=\"width: 421px\" class=\"wp-caption alignright\"><a href=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/03\/AAU-BAH_2667.jpg\" rel=\"fancybox\" title=\"En Puerto Rico, universidad adventista inaugura nuevo centro de simulaci\u00f3n de ciencias de la salud\"><img decoding=\"async\" aria-describedby=\"caption-attachment-34103\" class=\" wp-image-34103\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/03\/AAU-BAH_2667.jpg\" alt=\"\" width=\"411\" height=\"257\" \/><\/a><p id=\"caption-attachment-34103\" class=\"wp-caption-text\">El nuevo centro de simulaci\u00f3n cuenta con una unidad de maternidad, una sala de emergencias, dos salas de operaciones, un \u00e1rea de cuidados intensivos y estaciones de trabajo adicionales. Imagen por cortes\u00eda de la Universidad Adventista de las Antillas<\/p><\/div>\n<p>\u201cLos graduandos de ciencias cardiopulmonares y de enfermer\u00eda se distinguen por tener las calificaciones m\u00e1s altas en los ex\u00e1menes nacionales para obtener su licencia\u201d, dijo Jim\u00e9nez.<\/p>\n<p>La Universidad Adventista de las Antillas ha sido acreditada por la Comisi\u00f3n de Acreditaci\u00f3n de Educaci\u00f3n (ACEN), la Comisi\u00f3n sobre Educaci\u00f3n Superior en Enfermer\u00eda (CCNE), la Comisi\u00f3n de Acreditaci\u00f3n en Anestesia (COA), y la Comisi\u00f3n de Acreditaci\u00f3n de Cuidados Respiratorios (CoARC), entre otras entidades.<\/p>\n<p>Asimismo, la Universidad Adventista de las Antillas est\u00e1 afiliada con la Universidad de Loma Linda en California, para ofrecer un t\u00edtulo doctoral en terapia f\u00edsica. Este programa postprofesional es el \u00fanico en la isla que permite que los terapeutas f\u00edsicos completen su nivel doctoral de educaci\u00f3n en persona, adquiriendo habilidades avanzadas en su \u00e1rea de especializaci\u00f3n.<\/p>\n<p>Para saber m\u00e1s sobre la Universidad Adventista de las Antillas y sus programas, visite <a href=\"mailto:https:\/\/www.uaa.edu\/esp\/\">uaa.edu<\/a><\/p>\n<p>Traducci\u00f3n de Marcos Paseggi<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Universidad Adventista de las Antillas (AAU), una instituci\u00f3n operada por la Iglesia Adventista del S\u00e9ptimo D\u00eda en Puerto Rico, inaugur\u00f3 hace poco un nuevo Centro de Simulaci\u00f3n de Ciencias de la Salud. El centro de \u00faltima generaci\u00f3n beneficiar\u00e1 a los futuros profesionales de salud con la tecnolog\u00eda m\u00e1s avanzada en el \u00e1rea, dijeron los l\u00edderes de la universidad.<\/p>\n<p>El alcalde de Mayag\u00fcez Jos\u00e9 Guillermo Rodr\u00edguez felicit\u00f3 a la iglesia y a los l\u00edderes de la universidad por abrir el m\u00e1s moderno centro de simulaci\u00f3n en ciencias de la salud de la isla. La ceremonia se llev\u00f3 a cabo el 13 de marzo de 2018.<\/p>\n","protected":false},"author":1,"featured_media":39649,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17,15],"tags":[],"class_list":["post-39732","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-desde-el-campo","category-rss-espanol"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>En Puerto Rico, universidad adventista inaugura nuevo centro de simulaci\u00f3n de ciencias de la salud - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/interamerica.org\/es\/2018\/03\/en-puerto-rico-universidad-adventista-inaugura-nuevo-centro-de-simulacion-de-ciencias-de-la-salud\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En Puerto Rico, universidad adventista inaugura nuevo centro de simulaci\u00f3n de ciencias de la salud - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana\" \/>\n<meta property=\"og:description\" content=\"La Universidad Adventista de las Antillas (AAU), una instituci\u00f3n operada por la Iglesia Adventista del S\u00e9ptimo D\u00eda en Puerto Rico, inaugur\u00f3 hace poco un nuevo Centro de Simulaci\u00f3n de Ciencias de la Salud. El centro de \u00faltima generaci\u00f3n beneficiar\u00e1 a los futuros profesionales de salud con la tecnolog\u00eda m\u00e1s avanzada en el \u00e1rea, dijeron los l\u00edderes de la universidad.  El alcalde de Mayag\u00fcez Jos\u00e9 Guillermo Rodr\u00edguez felicit\u00f3 a la iglesia y a los l\u00edderes de la universidad por abrir el m\u00e1s moderno centro de simulaci\u00f3n en ciencias de la salud de la isla. La ceremonia se llev\u00f3 a cabo el 13 de marzo de 2018.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/interamerica.org\/es\/2018\/03\/en-puerto-rico-universidad-adventista-inaugura-nuevo-centro-de-simulacion-de-ciencias-de-la-salud\/\" \/>\n<meta property=\"og:site_name\" content=\"Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-23T04:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-04-06T20:26:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/04\/aau-bah-6763.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lorenzo Verduzco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lorenzo Verduzco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/03\\\/en-puerto-rico-universidad-adventista-inaugura-nuevo-centro-de-simulacion-de-ciencias-de-la-salud\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/03\\\/en-puerto-rico-universidad-adventista-inaugura-nuevo-centro-de-simulacion-de-ciencias-de-la-salud\\\/\"},\"author\":{\"name\":\"Lorenzo Verduzco\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#\\\/schema\\\/person\\\/68ede8bdc292885bb76c1e3810e73c39\"},\"headline\":\"En Puerto Rico, universidad adventista inaugura nuevo centro de simulaci\u00f3n de ciencias de la salud\",\"datePublished\":\"2018-03-23T04:00:00+00:00\",\"dateModified\":\"2018-04-06T20:26:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/03\\\/en-puerto-rico-universidad-adventista-inaugura-nuevo-centro-de-simulacion-de-ciencias-de-la-salud\\\/\"},\"wordCount\":799,\"image\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/03\\\/en-puerto-rico-universidad-adventista-inaugura-nuevo-centro-de-simulacion-de-ciencias-de-la-salud\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/aau-bah-6763.jpg\",\"articleSection\":[\"Desde el campo\",\"RSS Espa\u00f1ol\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/03\\\/en-puerto-rico-universidad-adventista-inaugura-nuevo-centro-de-simulacion-de-ciencias-de-la-salud\\\/\",\"url\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/03\\\/en-puerto-rico-universidad-adventista-inaugura-nuevo-centro-de-simulacion-de-ciencias-de-la-salud\\\/\",\"name\":\"En Puerto Rico, universidad adventista inaugura nuevo centro de simulaci\u00f3n de ciencias de la salud - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/03\\\/en-puerto-rico-universidad-adventista-inaugura-nuevo-centro-de-simulacion-de-ciencias-de-la-salud\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/03\\\/en-puerto-rico-universidad-adventista-inaugura-nuevo-centro-de-simulacion-de-ciencias-de-la-salud\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/aau-bah-6763.jpg\",\"datePublished\":\"2018-03-23T04:00:00+00:00\",\"dateModified\":\"2018-04-06T20:26:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#\\\/schema\\\/person\\\/68ede8bdc292885bb76c1e3810e73c39\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/03\\\/en-puerto-rico-universidad-adventista-inaugura-nuevo-centro-de-simulacion-de-ciencias-de-la-salud\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/03\\\/en-puerto-rico-universidad-adventista-inaugura-nuevo-centro-de-simulacion-de-ciencias-de-la-salud\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/03\\\/en-puerto-rico-universidad-adventista-inaugura-nuevo-centro-de-simulacion-de-ciencias-de-la-salud\\\/#primaryimage\",\"url\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/aau-bah-6763.jpg\",\"contentUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/aau-bah-6763.jpg\",\"width\":1280,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/03\\\/en-puerto-rico-universidad-adventista-inaugura-nuevo-centro-de-simulacion-de-ciencias-de-la-salud\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/interamerica.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En Puerto Rico, universidad adventista inaugura nuevo centro de simulaci\u00f3n de ciencias de la salud\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/interamerica.org\\\/es\\\/\",\"name\":\"Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/interamerica.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#\\\/schema\\\/person\\\/68ede8bdc292885bb76c1e3810e73c39\",\"name\":\"Lorenzo Verduzco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g\",\"caption\":\"Lorenzo Verduzco\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En Puerto Rico, universidad adventista inaugura nuevo centro de simulaci\u00f3n de ciencias de la salud - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/interamerica.org\/es\/2018\/03\/en-puerto-rico-universidad-adventista-inaugura-nuevo-centro-de-simulacion-de-ciencias-de-la-salud\/","og_locale":"es_ES","og_type":"article","og_title":"En Puerto Rico, universidad adventista inaugura nuevo centro de simulaci\u00f3n de ciencias de la salud - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","og_description":"La Universidad Adventista de las Antillas (AAU), una instituci\u00f3n operada por la Iglesia Adventista del S\u00e9ptimo D\u00eda en Puerto Rico, inaugur\u00f3 hace poco un nuevo Centro de Simulaci\u00f3n de Ciencias de la Salud. El centro de \u00faltima generaci\u00f3n beneficiar\u00e1 a los futuros profesionales de salud con la tecnolog\u00eda m\u00e1s avanzada en el \u00e1rea, dijeron los l\u00edderes de la universidad.  El alcalde de Mayag\u00fcez Jos\u00e9 Guillermo Rodr\u00edguez felicit\u00f3 a la iglesia y a los l\u00edderes de la universidad por abrir el m\u00e1s moderno centro de simulaci\u00f3n en ciencias de la salud de la isla. La ceremonia se llev\u00f3 a cabo el 13 de marzo de 2018.","og_url":"https:\/\/interamerica.org\/es\/2018\/03\/en-puerto-rico-universidad-adventista-inaugura-nuevo-centro-de-simulacion-de-ciencias-de-la-salud\/","og_site_name":"Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","article_published_time":"2018-03-23T04:00:00+00:00","article_modified_time":"2018-04-06T20:26:59+00:00","og_image":[{"width":1280,"height":800,"url":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/04\/aau-bah-6763.jpg","type":"image\/jpeg"}],"author":"Lorenzo Verduzco","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Lorenzo Verduzco","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/interamerica.org\/es\/2018\/03\/en-puerto-rico-universidad-adventista-inaugura-nuevo-centro-de-simulacion-de-ciencias-de-la-salud\/#article","isPartOf":{"@id":"https:\/\/interamerica.org\/es\/2018\/03\/en-puerto-rico-universidad-adventista-inaugura-nuevo-centro-de-simulacion-de-ciencias-de-la-salud\/"},"author":{"name":"Lorenzo Verduzco","@id":"https:\/\/interamerica.org\/es\/#\/schema\/person\/68ede8bdc292885bb76c1e3810e73c39"},"headline":"En Puerto Rico, universidad adventista inaugura nuevo centro de simulaci\u00f3n de ciencias de la salud","datePublished":"2018-03-23T04:00:00+00:00","dateModified":"2018-04-06T20:26:59+00:00","mainEntityOfPage":{"@id":"https:\/\/interamerica.org\/es\/2018\/03\/en-puerto-rico-universidad-adventista-inaugura-nuevo-centro-de-simulacion-de-ciencias-de-la-salud\/"},"wordCount":799,"image":{"@id":"https:\/\/interamerica.org\/es\/2018\/03\/en-puerto-rico-universidad-adventista-inaugura-nuevo-centro-de-simulacion-de-ciencias-de-la-salud\/#primaryimage"},"thumbnailUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/04\/aau-bah-6763.jpg","articleSection":["Desde el campo","RSS Espa\u00f1ol"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/interamerica.org\/es\/2018\/03\/en-puerto-rico-universidad-adventista-inaugura-nuevo-centro-de-simulacion-de-ciencias-de-la-salud\/","url":"https:\/\/interamerica.org\/es\/2018\/03\/en-puerto-rico-universidad-adventista-inaugura-nuevo-centro-de-simulacion-de-ciencias-de-la-salud\/","name":"En Puerto Rico, universidad adventista inaugura nuevo centro de simulaci\u00f3n de ciencias de la salud - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","isPartOf":{"@id":"https:\/\/interamerica.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/interamerica.org\/es\/2018\/03\/en-puerto-rico-universidad-adventista-inaugura-nuevo-centro-de-simulacion-de-ciencias-de-la-salud\/#primaryimage"},"image":{"@id":"https:\/\/interamerica.org\/es\/2018\/03\/en-puerto-rico-universidad-adventista-inaugura-nuevo-centro-de-simulacion-de-ciencias-de-la-salud\/#primaryimage"},"thumbnailUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/04\/aau-bah-6763.jpg","datePublished":"2018-03-23T04:00:00+00:00","dateModified":"2018-04-06T20:26:59+00:00","author":{"@id":"https:\/\/interamerica.org\/es\/#\/schema\/person\/68ede8bdc292885bb76c1e3810e73c39"},"breadcrumb":{"@id":"https:\/\/interamerica.org\/es\/2018\/03\/en-puerto-rico-universidad-adventista-inaugura-nuevo-centro-de-simulacion-de-ciencias-de-la-salud\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/interamerica.org\/es\/2018\/03\/en-puerto-rico-universidad-adventista-inaugura-nuevo-centro-de-simulacion-de-ciencias-de-la-salud\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/interamerica.org\/es\/2018\/03\/en-puerto-rico-universidad-adventista-inaugura-nuevo-centro-de-simulacion-de-ciencias-de-la-salud\/#primaryimage","url":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/04\/aau-bah-6763.jpg","contentUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/04\/aau-bah-6763.jpg","width":1280,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/interamerica.org\/es\/2018\/03\/en-puerto-rico-universidad-adventista-inaugura-nuevo-centro-de-simulacion-de-ciencias-de-la-salud\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/interamerica.org\/es\/"},{"@type":"ListItem","position":2,"name":"En Puerto Rico, universidad adventista inaugura nuevo centro de simulaci\u00f3n de ciencias de la salud"}]},{"@type":"WebSite","@id":"https:\/\/interamerica.org\/es\/#website","url":"https:\/\/interamerica.org\/es\/","name":"Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/interamerica.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/interamerica.org\/es\/#\/schema\/person\/68ede8bdc292885bb76c1e3810e73c39","name":"Lorenzo Verduzco","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g","caption":"Lorenzo Verduzco"}}]}},"_links":{"self":[{"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/posts\/39732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/comments?post=39732"}],"version-history":[{"count":0,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/posts\/39732\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/media\/39649"}],"wp:attachment":[{"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/media?parent=39732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/categories?post=39732"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/tags?post=39732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}