{"id":39736,"date":"2018-03-28T00:00:00","date_gmt":"2018-03-28T04:00:00","guid":{"rendered":"http:\/\/192.81.217.108\/2018\/03\/en-mexico-iglesia-adventista-ayuda-a-los-creyentes-afectados-por-la-intolerancia-religiosa\/"},"modified":"2018-05-01T21:55:59","modified_gmt":"2018-05-02T01:55:59","slug":"en-mexico-iglesia-adventista-ayuda-a-los-creyentes-afectados-por-la-intolerancia-religiosa","status":"publish","type":"post","link":"https:\/\/interamerica.org\/es\/2018\/03\/en-mexico-iglesia-adventista-ayuda-a-los-creyentes-afectados-por-la-intolerancia-religiosa\/","title":{"rendered":"En M\u00e9xico, Iglesia Adventista ayuda a los creyentes afectados por la intolerancia religiosa"},"content":{"rendered":"<div id=\"attachment_34217\" style=\"width: 781px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/03\/Navarro-chiapas.jpg\" rel=\"fancybox\" title=\"En M\u00e9xico, Iglesia Adventista ayuda a los creyentes afectados por la intolerancia religiosa\"><img fetchpriority=\"high\" decoding=\"async\" aria-describedby=\"caption-attachment-34217\" class=\" wp-image-34217\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/03\/Navarro-chiapas.jpg\" alt=\"\" width=\"771\" height=\"482\" \/><\/a><p id=\"caption-attachment-34217\" class=\"wp-caption-text\">El pastor Ignacio Navarro, presidente de la Iglesia Adventista en Chiapas, M\u00e9xico, se\u00f1ala a los cuatros nuevos creyentes que hace poco fueron expulsados de su comunidad en San Miguel Chiptip como resultado de la intolerancia religiosa en la regi\u00f3n. El pastor Ted N.C. Wilson, presidente de la Iglesia Adventista mundial, y el pastor Israel Leito, presidente de la Divisi\u00f3n Interamericana, est\u00e1n cerca de ellos mientras los presentan a los miembros de iglesia sobre el escenario, durante una celebraci\u00f3n de impacto joven llevada a cabo en Tuxtla Gutierrez, Chiapas, el 24 de marzo de 2018. Image de Miriam Clemente\/Uni\u00f3n Mexicana de Chiapas<\/p><\/div>\n<p>28 de marzo de 2018 | Tuxtla Guti\u00e9rrez, Chiapas, M\u00e9xico | Libna Stevens\/DIA<\/p>\n<p>La Iglesia Adventista del S\u00e9ptimo D\u00eda en Chiapas, M\u00e9xico, est\u00e1 ayudando a las v\u00edctimas de la intolerancia religiosa, despu\u00e9s de que cuatro familias fueron forzadas a salir de sus hogares por residentes de la comunidad San Miguel Chiptip en Chiapas.<\/p>\n<div id=\"attachment_34205\" style=\"width: 391px\" class=\"wp-caption alignright\"><a href=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/03\/WhatsApp-Image-2018-03-28-at-10.30.01-AM.jpeg\" rel=\"fancybox\" title=\"En M\u00e9xico, Iglesia Adventista ayuda a los creyentes afectados por la intolerancia religiosa\"><img decoding=\"async\" aria-describedby=\"caption-attachment-34205\" class=\" wp-image-34205\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/03\/WhatsApp-Image-2018-03-28-at-10.30.01-AM.jpeg\" alt=\"\" width=\"381\" height=\"286\" \/><\/a><p id=\"caption-attachment-34205\" class=\"wp-caption-text\">Uno de los cuatro hogares destruidos hace unos d\u00edas por residentes de San Miguel Chiptip. Imagen de cortes\u00eda de la Uni\u00f3n Mexicana de Chiapas<\/p><\/div>\n<p>Agust\u00edn Alv\u00e1rez, miembro bautizado y otros tres hombres fueron expulsados de sus comunidades el 15 de marzo despu\u00e9s de asistir a una campa\u00f1a de evangelizaci\u00f3n en otra comunidad. Sus esposas e hijos fueron forzados a permanecer en Chiptip, seg\u00fan el pastor Ignacio Navarro, presidente de la Iglesia Adventista en Chiapas.<\/p>\n<p>\u201cEstas familias han estado aprendiendo de las verdades b\u00edblicas, y esto hizo que algunos se enojaran\u201d, dijo Navarro. Despu\u00e9s de nueve d\u00edas de apelar a los residentes locales, los hombres se reunieron con sus familias, y ahora est\u00e1n alojados con familiares en otra parte.<\/p>\n<p>\u201cHemos estado trabajando con los l\u00edderes municipales y funcionarios del gobierno estatal en una apelaci\u00f3n para que se cumplan las leyes de libertad religiosa\u201d, dijo el pastor Ignacio Navarro, presidente de la Iglesia Adventista en Chiapas. \u201cLos hogares de estas familias fueron destruidos. No tienen ning\u00fan lugar al cual regresar\u201d.<\/p>\n<p>No es la primera vez que \u00c1lvarez y su familia se ven forzados a dejar su comunidad de Chiptip. Hace cuatro a\u00f1os, cuando \u00e9l y su familia se unieron a la Iglesia Adventista, fueron condenados al ostracismo y tuvieron que mudarse a una comunidad cercana. \u00c1lvarez y su familia continuaron compartiendo el mensaje del evangelio.<\/p>\n<div id=\"attachment_34211\" style=\"width: 398px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/03\/WhatsApp-Image-2018-03-28-at-10.31.32-AM.jpeg\" rel=\"fancybox\" title=\"En M\u00e9xico, Iglesia Adventista ayuda a los creyentes afectados por la intolerancia religiosa\"><img decoding=\"async\" aria-describedby=\"caption-attachment-34211\" class=\" wp-image-34211\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/03\/WhatsApp-Image-2018-03-28-at-10.31.32-AM.jpeg\" alt=\"\" width=\"388\" height=\"218\" \/><\/a><p id=\"caption-attachment-34211\" class=\"wp-caption-text\">Los escombros que quedaron despu\u00e9s de que residentes locales destruyeron los hogares de cuatro familias en San Miguel Chiptip, Chiapas, hace unos d\u00edas. Imagen por cortes\u00eda de la Uni\u00f3n Mexicana de Chiapas<\/p><\/div>\n<p>\u201cLa asociaci\u00f3n y la uni\u00f3n locales est\u00e1n tomando las previsiones necesarias para ayudar a que estas familias puedan restaurar sus vidas\u201d, dijo Navarro. No est\u00e1 claro si sus hogares ser\u00e1n reconstruidos, o si las familias tendr\u00e1n que ser reubicadas, dijo Navarro, pero los l\u00edderes de la iglesia est\u00e1n analizando la situaci\u00f3n y brind\u00e1ndoles alimento f\u00edsico y espiritual.<\/p>\n<p>El presidente de la Iglesia Adventista mundial, Ted N.C. Wilson, que estuvo en Chiapas el \u00faltimo fin de semana para el relanzamiento del programa joven \u201cUn a\u00f1o en misi\u00f3n\u201d, anim\u00f3 a las familias.<\/p>\n<p>\u201cUstedes son en verdad gigantes de Jes\u00fas, porque han aceptado la verdad plena y est\u00e1n dispuestos a morir por la verdad\u201d, dijo el pastor Wilson. \u201cMi coraz\u00f3n se regocija de verlos, de ver la fidelidad que tienen por la Palabra de Dios\u201d.<\/p>\n<p>El pastor Wilson dijo que la iglesia mundial, que tiene su sede en Washington D.C., los ha tenido presentes en oraci\u00f3n desde que el pastor Israel Leito, presidente de la Divisi\u00f3n Interamericana, le comunic\u00f3 la noticia.<\/p>\n<p>Las familias fueron llevadas al Centro de Convenciones Polyforum en Tuxtla Guti\u00e9rrez mientras se estaba llevando a cabo la celebraci\u00f3n del impacto joven de la iglesia en todo el estado, el s\u00e1bado 24 de marzo. M\u00e1s de cuatro mil l\u00edderes y j\u00f3venes adventistas dieron la bienvenida a las familias y aplaudieron la fidelidad que han demostrado.<\/p>\n<div id=\"attachment_34214\" style=\"width: 396px\" class=\"wp-caption alignright\"><a href=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/03\/Wilson-Chiapas.jpg\" rel=\"fancybox\" title=\"En M\u00e9xico, Iglesia Adventista ayuda a los creyentes afectados por la intolerancia religiosa\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-34214\" class=\" wp-image-34214\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/03\/Wilson-Chiapas.jpg\" alt=\"\" width=\"386\" height=\"241\" \/><\/a><p id=\"caption-attachment-34214\" class=\"wp-caption-text\">Ted N.C. Wilson, presidente de la Iglesia Adventista mundial, anima a las familias cuyos hogares fueron destruidos el 15 de marzo de 2018, como resultado de la intolerancia religiosa. Imagen de Miriam Clemente\/Uni\u00f3n Mexicana de Chiapas<\/p><\/div>\n<p>\u201cQueremos que estos hermanos sepan que tienen la iglesia mundial apoy\u00e1ndolos, que cuentan con una gran familia de m\u00e1s de veinte millones de personas y que les damos la bienvenida a la iglesia\u201d, dijo Navarro.<\/p>\n<p>Las familias recibieron Biblias y presentes. Adem\u00e1s, durante el programa se or\u00f3 especialmente por ellos.<\/p>\n<p>La Iglesia Adventista mundial en la Divisi\u00f3n Interamericana ya ha puesto fondos a disposici\u00f3n para reconstruir la vida de estas familias, dijo el pastor Leito.<\/p>\n<p>Gracias al testimonio de estas familias, otras tres familias de la comunidad de Chiptip las han defendido y est\u00e1n interesadas en saber m\u00e1s sobre sus creencias, dijo el pastor Navarro.<\/p>\n<p>La iglesia seguir\u00e1 monitorizando a las familias y buscando soluciones que permitan cumplir con los derechos de libertad religiosa en la regi\u00f3n.<\/p>\n<p>La Iglesia Adventista del S\u00e9ptimo D\u00eda en Chiapas, M\u00e9xico, cuenta con m\u00e1s de 230 mil miembros que se re\u00fanen en 3087 iglesias y congregaciones. La iglesia supervisa ocho asociaciones y misiones, cuenta con una universidad, y con 51 escuelas primarias y secundarias.<\/p>\n<p>Si desea saber m\u00e1s sobre la Iglesia Adventista de Chiapas, M\u00e9xico, visite <a href=\"mailto:http:\/\/umch.org.mx\/\">umch.org.mx<\/a><\/p>\n<p>Traducci\u00f3n de Marcos Paseggi<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Iglesia Adventista del S\u00e9ptimo D\u00eda en Chiapas, M\u00e9xico, est\u00e1 ayudando a las v\u00edctimas de la intolerancia religiosa, despu\u00e9s de que cuatro familias fueron forzadas a salir de sus hogares por residentes de la comunidad San Miguel Chiptip en Chiapas.<\/p>\n<p>Agust\u00edn Alv\u00e1rez, miembro bautizado y otros tres hombres fueron expulsados de sus comunidades el 15 de marzo despu\u00e9s de asistir a una campa\u00f1a de evangelizaci\u00f3n en otra comunidad. Sus esposas e hijos fueron forzados a permanecer en Chiptip, seg\u00fan el pastor Ignacio Navarro, presidente de la Iglesia Adventista en Chiapas.<\/p>\n","protected":false},"author":1,"featured_media":39667,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17,15],"tags":[],"class_list":["post-39736","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-desde-el-campo","category-rss-espanol"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>En M\u00e9xico, Iglesia Adventista ayuda a los creyentes afectados por la intolerancia religiosa - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/interamerica.org\/es\/2018\/03\/en-mexico-iglesia-adventista-ayuda-a-los-creyentes-afectados-por-la-intolerancia-religiosa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En M\u00e9xico, Iglesia Adventista ayuda a los creyentes afectados por la intolerancia religiosa - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana\" \/>\n<meta property=\"og:description\" content=\"La Iglesia Adventista del S\u00e9ptimo D\u00eda en Chiapas, M\u00e9xico, est\u00e1 ayudando a las v\u00edctimas de la intolerancia religiosa, despu\u00e9s de que cuatro familias fueron forzadas a salir de sus hogares por residentes de la comunidad San Miguel Chiptip en Chiapas.  Agust\u00edn Alv\u00e1rez, miembro bautizado y otros tres hombres fueron expulsados de sus comunidades el 15 de marzo despu\u00e9s de asistir a una campa\u00f1a de evangelizaci\u00f3n en otra comunidad. Sus esposas e hijos fueron forzados a permanecer en Chiptip, seg\u00fan el pastor Ignacio Navarro, presidente de la Iglesia Adventista en Chiapas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/interamerica.org\/es\/2018\/03\/en-mexico-iglesia-adventista-ayuda-a-los-creyentes-afectados-por-la-intolerancia-religiosa\/\" \/>\n<meta property=\"og:site_name\" content=\"Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-28T04:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-05-02T01:55:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/04\/navarro-chiapas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lorenzo Verduzco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lorenzo Verduzco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/03\\\/en-mexico-iglesia-adventista-ayuda-a-los-creyentes-afectados-por-la-intolerancia-religiosa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/03\\\/en-mexico-iglesia-adventista-ayuda-a-los-creyentes-afectados-por-la-intolerancia-religiosa\\\/\"},\"author\":{\"name\":\"Lorenzo Verduzco\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#\\\/schema\\\/person\\\/68ede8bdc292885bb76c1e3810e73c39\"},\"headline\":\"En M\u00e9xico, Iglesia Adventista ayuda a los creyentes afectados por la intolerancia religiosa\",\"datePublished\":\"2018-03-28T04:00:00+00:00\",\"dateModified\":\"2018-05-02T01:55:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/03\\\/en-mexico-iglesia-adventista-ayuda-a-los-creyentes-afectados-por-la-intolerancia-religiosa\\\/\"},\"wordCount\":968,\"image\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/03\\\/en-mexico-iglesia-adventista-ayuda-a-los-creyentes-afectados-por-la-intolerancia-religiosa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/navarro-chiapas.jpg\",\"articleSection\":[\"Desde el campo\",\"RSS Espa\u00f1ol\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/03\\\/en-mexico-iglesia-adventista-ayuda-a-los-creyentes-afectados-por-la-intolerancia-religiosa\\\/\",\"url\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/03\\\/en-mexico-iglesia-adventista-ayuda-a-los-creyentes-afectados-por-la-intolerancia-religiosa\\\/\",\"name\":\"En M\u00e9xico, Iglesia Adventista ayuda a los creyentes afectados por la intolerancia religiosa - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/03\\\/en-mexico-iglesia-adventista-ayuda-a-los-creyentes-afectados-por-la-intolerancia-religiosa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/03\\\/en-mexico-iglesia-adventista-ayuda-a-los-creyentes-afectados-por-la-intolerancia-religiosa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/navarro-chiapas.jpg\",\"datePublished\":\"2018-03-28T04:00:00+00:00\",\"dateModified\":\"2018-05-02T01:55:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#\\\/schema\\\/person\\\/68ede8bdc292885bb76c1e3810e73c39\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/03\\\/en-mexico-iglesia-adventista-ayuda-a-los-creyentes-afectados-por-la-intolerancia-religiosa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/03\\\/en-mexico-iglesia-adventista-ayuda-a-los-creyentes-afectados-por-la-intolerancia-religiosa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/03\\\/en-mexico-iglesia-adventista-ayuda-a-los-creyentes-afectados-por-la-intolerancia-religiosa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/navarro-chiapas.jpg\",\"contentUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/navarro-chiapas.jpg\",\"width\":1280,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/03\\\/en-mexico-iglesia-adventista-ayuda-a-los-creyentes-afectados-por-la-intolerancia-religiosa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/interamerica.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En M\u00e9xico, Iglesia Adventista ayuda a los creyentes afectados por la intolerancia religiosa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/interamerica.org\\\/es\\\/\",\"name\":\"Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/interamerica.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#\\\/schema\\\/person\\\/68ede8bdc292885bb76c1e3810e73c39\",\"name\":\"Lorenzo Verduzco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g\",\"caption\":\"Lorenzo Verduzco\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En M\u00e9xico, Iglesia Adventista ayuda a los creyentes afectados por la intolerancia religiosa - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/interamerica.org\/es\/2018\/03\/en-mexico-iglesia-adventista-ayuda-a-los-creyentes-afectados-por-la-intolerancia-religiosa\/","og_locale":"es_ES","og_type":"article","og_title":"En M\u00e9xico, Iglesia Adventista ayuda a los creyentes afectados por la intolerancia religiosa - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","og_description":"La Iglesia Adventista del S\u00e9ptimo D\u00eda en Chiapas, M\u00e9xico, est\u00e1 ayudando a las v\u00edctimas de la intolerancia religiosa, despu\u00e9s de que cuatro familias fueron forzadas a salir de sus hogares por residentes de la comunidad San Miguel Chiptip en Chiapas.  Agust\u00edn Alv\u00e1rez, miembro bautizado y otros tres hombres fueron expulsados de sus comunidades el 15 de marzo despu\u00e9s de asistir a una campa\u00f1a de evangelizaci\u00f3n en otra comunidad. Sus esposas e hijos fueron forzados a permanecer en Chiptip, seg\u00fan el pastor Ignacio Navarro, presidente de la Iglesia Adventista en Chiapas.","og_url":"https:\/\/interamerica.org\/es\/2018\/03\/en-mexico-iglesia-adventista-ayuda-a-los-creyentes-afectados-por-la-intolerancia-religiosa\/","og_site_name":"Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","article_published_time":"2018-03-28T04:00:00+00:00","article_modified_time":"2018-05-02T01:55:59+00:00","og_image":[{"width":1280,"height":800,"url":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/04\/navarro-chiapas.jpg","type":"image\/jpeg"}],"author":"Lorenzo Verduzco","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Lorenzo Verduzco","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/interamerica.org\/es\/2018\/03\/en-mexico-iglesia-adventista-ayuda-a-los-creyentes-afectados-por-la-intolerancia-religiosa\/#article","isPartOf":{"@id":"https:\/\/interamerica.org\/es\/2018\/03\/en-mexico-iglesia-adventista-ayuda-a-los-creyentes-afectados-por-la-intolerancia-religiosa\/"},"author":{"name":"Lorenzo Verduzco","@id":"https:\/\/interamerica.org\/es\/#\/schema\/person\/68ede8bdc292885bb76c1e3810e73c39"},"headline":"En M\u00e9xico, Iglesia Adventista ayuda a los creyentes afectados por la intolerancia religiosa","datePublished":"2018-03-28T04:00:00+00:00","dateModified":"2018-05-02T01:55:59+00:00","mainEntityOfPage":{"@id":"https:\/\/interamerica.org\/es\/2018\/03\/en-mexico-iglesia-adventista-ayuda-a-los-creyentes-afectados-por-la-intolerancia-religiosa\/"},"wordCount":968,"image":{"@id":"https:\/\/interamerica.org\/es\/2018\/03\/en-mexico-iglesia-adventista-ayuda-a-los-creyentes-afectados-por-la-intolerancia-religiosa\/#primaryimage"},"thumbnailUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/04\/navarro-chiapas.jpg","articleSection":["Desde el campo","RSS Espa\u00f1ol"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/interamerica.org\/es\/2018\/03\/en-mexico-iglesia-adventista-ayuda-a-los-creyentes-afectados-por-la-intolerancia-religiosa\/","url":"https:\/\/interamerica.org\/es\/2018\/03\/en-mexico-iglesia-adventista-ayuda-a-los-creyentes-afectados-por-la-intolerancia-religiosa\/","name":"En M\u00e9xico, Iglesia Adventista ayuda a los creyentes afectados por la intolerancia religiosa - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","isPartOf":{"@id":"https:\/\/interamerica.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/interamerica.org\/es\/2018\/03\/en-mexico-iglesia-adventista-ayuda-a-los-creyentes-afectados-por-la-intolerancia-religiosa\/#primaryimage"},"image":{"@id":"https:\/\/interamerica.org\/es\/2018\/03\/en-mexico-iglesia-adventista-ayuda-a-los-creyentes-afectados-por-la-intolerancia-religiosa\/#primaryimage"},"thumbnailUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/04\/navarro-chiapas.jpg","datePublished":"2018-03-28T04:00:00+00:00","dateModified":"2018-05-02T01:55:59+00:00","author":{"@id":"https:\/\/interamerica.org\/es\/#\/schema\/person\/68ede8bdc292885bb76c1e3810e73c39"},"breadcrumb":{"@id":"https:\/\/interamerica.org\/es\/2018\/03\/en-mexico-iglesia-adventista-ayuda-a-los-creyentes-afectados-por-la-intolerancia-religiosa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/interamerica.org\/es\/2018\/03\/en-mexico-iglesia-adventista-ayuda-a-los-creyentes-afectados-por-la-intolerancia-religiosa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/interamerica.org\/es\/2018\/03\/en-mexico-iglesia-adventista-ayuda-a-los-creyentes-afectados-por-la-intolerancia-religiosa\/#primaryimage","url":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/04\/navarro-chiapas.jpg","contentUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/04\/navarro-chiapas.jpg","width":1280,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/interamerica.org\/es\/2018\/03\/en-mexico-iglesia-adventista-ayuda-a-los-creyentes-afectados-por-la-intolerancia-religiosa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/interamerica.org\/es\/"},{"@type":"ListItem","position":2,"name":"En M\u00e9xico, Iglesia Adventista ayuda a los creyentes afectados por la intolerancia religiosa"}]},{"@type":"WebSite","@id":"https:\/\/interamerica.org\/es\/#website","url":"https:\/\/interamerica.org\/es\/","name":"Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/interamerica.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/interamerica.org\/es\/#\/schema\/person\/68ede8bdc292885bb76c1e3810e73c39","name":"Lorenzo Verduzco","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g","caption":"Lorenzo Verduzco"}}]}},"_links":{"self":[{"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/posts\/39736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/comments?post=39736"}],"version-history":[{"count":0,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/posts\/39736\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/media\/39667"}],"wp:attachment":[{"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/media?parent=39736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/categories?post=39736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/tags?post=39736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}