{"id":45822,"date":"2018-12-12T12:04:03","date_gmt":"2018-12-12T16:04:03","guid":{"rendered":"https:\/\/recursing-golick.147-182-135-0.plesk.page\/?p=45822"},"modified":"2018-12-13T09:54:56","modified_gmt":"2018-12-13T13:54:56","slug":"muy-pronto-estara-en-linea-la-enciclopedia-adventista-del-septimo-dia","status":"publish","type":"post","link":"https:\/\/interamerica.org\/es\/2018\/12\/muy-pronto-estara-en-linea-la-enciclopedia-adventista-del-septimo-dia\/","title":{"rendered":"Muy pronto estar\u00e1 en l\u00ednea la Enciclopedia Adventista del S\u00e9ptimo D\u00eda"},"content":{"rendered":"<p>11 de diciembre de 2018 | Silver Spring Maryland, Estados Unidos |\u00a0 Dragoslava Santrac<\/p>\n<p>Mi hija hizo recientemente una investigaci\u00f3n acerca de la historia de la Iglesia Adventista, como parte de un proyecto en su escuela p\u00fablica de nivel secundario. Consider\u00f3 el proyecto como una excelente oportunidad para dar a conocer a su clase el legado adventista. Inmediatamente le suger\u00ed varios libros de historia adventista que tenemos en nuestra biblioteca familiar. Como madre y maestra me esfuerzo siempre por compartir con mis hijos y estudiantes, informaci\u00f3n que sea siempre fidedigna y veraz, porque la informaci\u00f3n confiable moldea en forma significativa tanto los h\u00e1bitos, como la cosmovisi\u00f3n y elecciones de las personas. \u00bfComo pude haberme olvidado de que la generaci\u00f3n de mi hija consulta primero al \u201cDr. Google\u201d?<\/p>\n<p>Mi hija se sinti\u00f3 abatida y consternada por la cantidad de informaci\u00f3n falsa y difamatoria que encontr\u00f3 en l\u00ednea acerca de la Iglesia Adventista. Descorazonada, me pidi\u00f3 que le recomendara recursos en l\u00ednea que fuesen aut\u00e9nticos acerca de la historia adventista. Ese d\u00eda, anhel\u00e9 contar con una cautivadora publicaci\u00f3n como la nueva <em>Enciclopedia Adventista del S\u00e9ptimo D\u00eda, <\/em>en l\u00ednea.<\/p>\n<p>Me pregunto cu\u00e1ntos padres, maestros y personas adventistas de todas las edades enfrentan este mismo desaf\u00edo.<\/p>\n<p>La <em>Enciclopedia Adventista del S\u00e9ptimo D\u00eda <\/em>(ESDA por sus siglas en ingl\u00e9s) es una publicaci\u00f3n y registro oficial de la historia de la obra adventista del s\u00e9ptimo d\u00eda. Este proyecto global de la iglesia va a producir aproximadamente 10,000 art\u00edculos sobre historia adventista, acerca de eventos y temas cruciales y, sobre organizaciones, entidades, instituciones y personas en particular, con sus respectivas fotograf\u00edas, medios y documentos originales acompa\u00f1antes. La nueva enciclopedia va a reflejar el incre\u00edble crecimiento producido en la iglesia en los \u00faltimos cincuenta a\u00f1os o m\u00e1s, desde la publicaci\u00f3n de la primera edici\u00f3n de la <em>Enciclopedia Adventista del S\u00e9ptimo D\u00eda. <\/em><\/p>\n<p>ESDA en L\u00ednea, la primera obra de referencia de la iglesia, facilitada en l\u00ednea, har\u00e1 su debut oficial en la sesi\u00f3n de 2020 de la Asociaci\u00f3n General. ESDA en L\u00ednea va a ser un sitio electr\u00f3nico gratuito, asegurando as\u00ed la diseminaci\u00f3n global de su contenido. La versi\u00f3n impresa de la enciclopedia se producir\u00e1 despu\u00e9s de la primera edici\u00f3n en l\u00ednea.<\/p>\n<p>Los editores invitan no solamente a los historiadores y te\u00f3logos, sino tambi\u00e9n a los investigadores, maestros, estudiantes y miembros en general, expertos en alg\u00fan tema o asunto, a contribuir con art\u00edculos sobre temas todav\u00eda no cubiertos en la invitaci\u00f3n inicial dentro del proceso editorial.<\/p>\n<p>ESDA hace \u00a0un llamado especial a los escritores en todo el mundo a recolectar datos pertinentes a sus regiones locales acerca de misioneros, evangelizadores, educadores, obreros m\u00e9dicos, predicadores y dirigentes de la iglesia que contribuyeron en el pasado al crecimiento de la iglesia adventista en su territorio. Algunos buenos lugares en donde los autores pueden comenzar a hacer sus investigaciones son los archivos de las iglesias locales, obituarios, anuarios adventistas (yearbooks), boletines de informaci\u00f3n, publicaciones de la iglesia, colecciones privadas de cartas y diarios misioneros, materiales audiovisuales, videograbaciones y entrevistas con el fin de reunir datos hist\u00f3ricos a partir de tradiciones orales.<\/p>\n<p>Cada art\u00edculo en la Enciclopedia va a poder calificar como una publicaci\u00f3n especializada o erudita, en la que el autor recibir\u00e1 pleno reconocimiento. Los autores deben revisar la p\u00e1gina dedicada a <a href=\"http:\/\/www.adventistarchives.org\/author-materials\">Author Materials<\/a> (materiales usados por el autor) en busca de informaci\u00f3n detallada, y la p\u00e1gina <a href=\"http:\/\/www.adventistarchives.org\/assistant-editors\">Assistant Editors<\/a> (editores asistentes), con el fin de enterarse de formas para ponerse en contacto con los editores responsables en la divisi\u00f3n y tambi\u00e9n respecto a los temas disponibles. Deben adem\u00e1s visitar la p\u00e1gina web de la Enciclopedia para las divisiones <a href=\"https:\/\/www.esda-europe.org\/\">EUD y ESD<\/a>, la p\u00e1gina para la <a href=\"http:\/\/www.esdana.org\/\">NAD<\/a>, y la p\u00e1gina para la <a href=\"http:\/\/esda-nsd.weebly.com\/\">NSD<\/a>.<\/p>\n<p>Los editores est\u00e1n dispuestos a considerar nuevas investigaciones y art\u00edculos no antes planificados, si los hay disponibles. Los autores pueden considerar sobre qu\u00e9 escribir y pueden ponerse en contacto con la oficina de Estad\u00edsticas y Archivos de la Asociaci\u00f3n General con sus sugerencias. Pueden adem\u00e1s darle seguimiento al proyecto a trav\u00e9s de Twitter, en \u00a0@EncyclopediaSDA.<\/p>\n<p>Juntos podemos hacer de la ESDA una bendici\u00f3n para el mundo y alabar a Dios por la maravillosa gu\u00eda que ha brindado siempre a su pueblo.<\/p>\n<p>Acerca de la editora de la Enciclopedia<\/p>\n<p><em>Dragoslava Santrac es directora editorial de la <\/em>Enciclopedia Adventista del S\u00e9ptimo D\u00eda. Posee un <em>PhD en Antiguo Testamento (North-West University, Sud\u00e1frica\/Escuela de Teolog\u00eda Greenwich, Reino Unido) y una Maestr\u00eda en Idiomas B\u00edblicos y Antiguo Testamento (Andrews University). Ha ense\u00f1ado clases b\u00edblicas por los \u00faltimos 15 a\u00f1os en el Seminario Teol\u00f3gico de Belgrado (Serbia) y en la Universidad del Sur del Caribe (Trinidad). Actualmente presta sus servicios como profesora adjunta de Religi\u00f3n en la Universidad Adventista de Washington \u00a0(Estados Unidos).<\/em><\/p>\n<p><em>Dragoslava Santrac<\/em> <em>ha prestado adem\u00e1s sus servicios como editora de la Uni\u00f3n Europea del Sureste y del Instituto de Investigaci\u00f3n B\u00edblica <\/em>(BRI). Es autora de varios libros y art\u00edculos sobre teolog\u00eda del Antiguo Testamento, el libro de Salmos y otros temas b\u00edblicos.<\/p>\n<p><em>La versi\u00f3n <\/em><a href=\"https:\/\/educators.adventist.org\/2018\/12\/encyclopedia-adventist\/?fbclid=IwAR1HQQ06v6jSJqwODfXyZHqEgaY7s4deO41W6JNWHayRZ0GuqmAG-PrcNoM\"><em>original de este comentario se public\u00f3 en el sitio de Educadores Adventistas del S\u00e9ptimo D\u00eda. <\/em><\/a><\/p>\n<p>Traducci\u00f3n \u2013 Gloria A Castrej\u00f3n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>11 de diciembre de 2018 | Silver Spring Maryland, Estados Unidos |\u00a0 Dragoslava Santrac Mi hija hizo recientemente una investigaci\u00f3n acerca de la historia de la Iglesia Adventista, como parte&#8230;<\/p>\n","protected":false},"author":3,"featured_media":45775,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[14,15],"tags":[],"class_list":["post-45822","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-de-la-iglesia-mundial","category-rss-espanol"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Muy pronto estar\u00e1 en l\u00ednea la Enciclopedia Adventista del S\u00e9ptimo D\u00eda - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/interamerica.org\/es\/2018\/12\/muy-pronto-estara-en-linea-la-enciclopedia-adventista-del-septimo-dia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Muy pronto estar\u00e1 en l\u00ednea la Enciclopedia Adventista del S\u00e9ptimo D\u00eda - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana\" \/>\n<meta property=\"og:description\" content=\"11 de diciembre de 2018 | Silver Spring Maryland, Estados Unidos |\u00a0 Dragoslava Santrac Mi hija hizo recientemente una investigaci\u00f3n acerca de la historia de la Iglesia Adventista, como parte...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/interamerica.org\/es\/2018\/12\/muy-pronto-estara-en-linea-la-enciclopedia-adventista-del-septimo-dia\/\" \/>\n<meta property=\"og:site_name\" content=\"Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-12T16:04:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-13T13:54:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/12\/online-keyboard1280.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"libna\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"libna\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/12\\\/muy-pronto-estara-en-linea-la-enciclopedia-adventista-del-septimo-dia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/12\\\/muy-pronto-estara-en-linea-la-enciclopedia-adventista-del-septimo-dia\\\/\"},\"author\":{\"name\":\"libna\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#\\\/schema\\\/person\\\/29998f2bc2d8bd0d38662909289b54f1\"},\"headline\":\"Muy pronto estar\u00e1 en l\u00ednea la Enciclopedia Adventista del S\u00e9ptimo D\u00eda\",\"datePublished\":\"2018-12-12T16:04:03+00:00\",\"dateModified\":\"2018-12-13T13:54:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/12\\\/muy-pronto-estara-en-linea-la-enciclopedia-adventista-del-septimo-dia\\\/\"},\"wordCount\":944,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/12\\\/muy-pronto-estara-en-linea-la-enciclopedia-adventista-del-septimo-dia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/online-keyboard1280.jpg\",\"articleSection\":[\"Desde la iglesia mundial\",\"RSS Espa\u00f1ol\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/12\\\/muy-pronto-estara-en-linea-la-enciclopedia-adventista-del-septimo-dia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/12\\\/muy-pronto-estara-en-linea-la-enciclopedia-adventista-del-septimo-dia\\\/\",\"url\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/12\\\/muy-pronto-estara-en-linea-la-enciclopedia-adventista-del-septimo-dia\\\/\",\"name\":\"Muy pronto estar\u00e1 en l\u00ednea la Enciclopedia Adventista del S\u00e9ptimo D\u00eda - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/12\\\/muy-pronto-estara-en-linea-la-enciclopedia-adventista-del-septimo-dia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/12\\\/muy-pronto-estara-en-linea-la-enciclopedia-adventista-del-septimo-dia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/online-keyboard1280.jpg\",\"datePublished\":\"2018-12-12T16:04:03+00:00\",\"dateModified\":\"2018-12-13T13:54:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#\\\/schema\\\/person\\\/29998f2bc2d8bd0d38662909289b54f1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/12\\\/muy-pronto-estara-en-linea-la-enciclopedia-adventista-del-septimo-dia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/12\\\/muy-pronto-estara-en-linea-la-enciclopedia-adventista-del-septimo-dia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/12\\\/muy-pronto-estara-en-linea-la-enciclopedia-adventista-del-septimo-dia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/online-keyboard1280.jpg\",\"contentUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/online-keyboard1280.jpg\",\"width\":1280,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2018\\\/12\\\/muy-pronto-estara-en-linea-la-enciclopedia-adventista-del-septimo-dia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/interamerica.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Muy pronto estar\u00e1 en l\u00ednea la Enciclopedia Adventista del S\u00e9ptimo D\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/interamerica.org\\\/es\\\/\",\"name\":\"Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/interamerica.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#\\\/schema\\\/person\\\/29998f2bc2d8bd0d38662909289b54f1\",\"name\":\"libna\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7c5bd30ae4b47a9ba3c856590957fd1d96dc588bf3ac05719d247e126840331f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7c5bd30ae4b47a9ba3c856590957fd1d96dc588bf3ac05719d247e126840331f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7c5bd30ae4b47a9ba3c856590957fd1d96dc588bf3ac05719d247e126840331f?s=96&d=mm&r=g\",\"caption\":\"libna\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Muy pronto estar\u00e1 en l\u00ednea la Enciclopedia Adventista del S\u00e9ptimo D\u00eda - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/interamerica.org\/es\/2018\/12\/muy-pronto-estara-en-linea-la-enciclopedia-adventista-del-septimo-dia\/","og_locale":"es_ES","og_type":"article","og_title":"Muy pronto estar\u00e1 en l\u00ednea la Enciclopedia Adventista del S\u00e9ptimo D\u00eda - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","og_description":"11 de diciembre de 2018 | Silver Spring Maryland, Estados Unidos |\u00a0 Dragoslava Santrac Mi hija hizo recientemente una investigaci\u00f3n acerca de la historia de la Iglesia Adventista, como parte...","og_url":"https:\/\/interamerica.org\/es\/2018\/12\/muy-pronto-estara-en-linea-la-enciclopedia-adventista-del-septimo-dia\/","og_site_name":"Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","article_published_time":"2018-12-12T16:04:03+00:00","article_modified_time":"2018-12-13T13:54:56+00:00","og_image":[{"width":1280,"height":800,"url":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/12\/online-keyboard1280.jpg","type":"image\/jpeg"}],"author":"libna","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"libna","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/interamerica.org\/es\/2018\/12\/muy-pronto-estara-en-linea-la-enciclopedia-adventista-del-septimo-dia\/#article","isPartOf":{"@id":"https:\/\/interamerica.org\/es\/2018\/12\/muy-pronto-estara-en-linea-la-enciclopedia-adventista-del-septimo-dia\/"},"author":{"name":"libna","@id":"https:\/\/interamerica.org\/es\/#\/schema\/person\/29998f2bc2d8bd0d38662909289b54f1"},"headline":"Muy pronto estar\u00e1 en l\u00ednea la Enciclopedia Adventista del S\u00e9ptimo D\u00eda","datePublished":"2018-12-12T16:04:03+00:00","dateModified":"2018-12-13T13:54:56+00:00","mainEntityOfPage":{"@id":"https:\/\/interamerica.org\/es\/2018\/12\/muy-pronto-estara-en-linea-la-enciclopedia-adventista-del-septimo-dia\/"},"wordCount":944,"commentCount":0,"image":{"@id":"https:\/\/interamerica.org\/es\/2018\/12\/muy-pronto-estara-en-linea-la-enciclopedia-adventista-del-septimo-dia\/#primaryimage"},"thumbnailUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/12\/online-keyboard1280.jpg","articleSection":["Desde la iglesia mundial","RSS Espa\u00f1ol"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/interamerica.org\/es\/2018\/12\/muy-pronto-estara-en-linea-la-enciclopedia-adventista-del-septimo-dia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/interamerica.org\/es\/2018\/12\/muy-pronto-estara-en-linea-la-enciclopedia-adventista-del-septimo-dia\/","url":"https:\/\/interamerica.org\/es\/2018\/12\/muy-pronto-estara-en-linea-la-enciclopedia-adventista-del-septimo-dia\/","name":"Muy pronto estar\u00e1 en l\u00ednea la Enciclopedia Adventista del S\u00e9ptimo D\u00eda - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","isPartOf":{"@id":"https:\/\/interamerica.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/interamerica.org\/es\/2018\/12\/muy-pronto-estara-en-linea-la-enciclopedia-adventista-del-septimo-dia\/#primaryimage"},"image":{"@id":"https:\/\/interamerica.org\/es\/2018\/12\/muy-pronto-estara-en-linea-la-enciclopedia-adventista-del-septimo-dia\/#primaryimage"},"thumbnailUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/12\/online-keyboard1280.jpg","datePublished":"2018-12-12T16:04:03+00:00","dateModified":"2018-12-13T13:54:56+00:00","author":{"@id":"https:\/\/interamerica.org\/es\/#\/schema\/person\/29998f2bc2d8bd0d38662909289b54f1"},"breadcrumb":{"@id":"https:\/\/interamerica.org\/es\/2018\/12\/muy-pronto-estara-en-linea-la-enciclopedia-adventista-del-septimo-dia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/interamerica.org\/es\/2018\/12\/muy-pronto-estara-en-linea-la-enciclopedia-adventista-del-septimo-dia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/interamerica.org\/es\/2018\/12\/muy-pronto-estara-en-linea-la-enciclopedia-adventista-del-septimo-dia\/#primaryimage","url":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/12\/online-keyboard1280.jpg","contentUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/12\/online-keyboard1280.jpg","width":1280,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/interamerica.org\/es\/2018\/12\/muy-pronto-estara-en-linea-la-enciclopedia-adventista-del-septimo-dia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/interamerica.org\/es\/"},{"@type":"ListItem","position":2,"name":"Muy pronto estar\u00e1 en l\u00ednea la Enciclopedia Adventista del S\u00e9ptimo D\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/interamerica.org\/es\/#website","url":"https:\/\/interamerica.org\/es\/","name":"Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/interamerica.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/interamerica.org\/es\/#\/schema\/person\/29998f2bc2d8bd0d38662909289b54f1","name":"libna","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/7c5bd30ae4b47a9ba3c856590957fd1d96dc588bf3ac05719d247e126840331f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7c5bd30ae4b47a9ba3c856590957fd1d96dc588bf3ac05719d247e126840331f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7c5bd30ae4b47a9ba3c856590957fd1d96dc588bf3ac05719d247e126840331f?s=96&d=mm&r=g","caption":"libna"}}]}},"_links":{"self":[{"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/posts\/45822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/comments?post=45822"}],"version-history":[{"count":0,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/posts\/45822\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/media\/45775"}],"wp:attachment":[{"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/media?parent=45822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/categories?post=45822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/tags?post=45822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}