{"id":48499,"date":"2019-04-23T14:54:22","date_gmt":"2019-04-23T18:54:22","guid":{"rendered":"https:\/\/recursing-golick.147-182-135-0.plesk.page\/?p=48499"},"modified":"2019-04-23T17:08:16","modified_gmt":"2019-04-23T21:08:16","slug":"en-interamerica-miles-de-conquistadores-clavan-sus-tiendas-para-el-receso-de-primavera","status":"publish","type":"post","link":"https:\/\/interamerica.org\/es\/2019\/04\/en-interamerica-miles-de-conquistadores-clavan-sus-tiendas-para-el-receso-de-primavera\/","title":{"rendered":"En Interam\u00e9rica, miles de Conquistadores clavan sus tiendas para el Receso de Primavera"},"content":{"rendered":"<div id=\"attachment_48474\" style=\"width: 810px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" aria-describedby=\"caption-attachment-48474\" class=\" wp-image-48472\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2019\/04\/chiapas-tents.jpg\" alt=\"\" width=\"800\" height=\"533\" srcset=\"https:\/\/interamerica.org\/wp-content\/uploads\/2019\/04\/chiapas-tents.jpg 1000w, https:\/\/interamerica.org\/wp-content\/uploads\/2019\/04\/chiapas-tents-300x200.jpg 300w, https:\/\/interamerica.org\/wp-content\/uploads\/2019\/04\/chiapas-tents-768x511.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><p id=\"caption-attachment-48474\" class=\"wp-caption-text\">Un grupo de Conquistadores y l\u00edderes armaron un campamento en el d\u00eda del Primer Campor\u00ed de la Uni\u00f3n Mexicana de Chiapas llevado a cabo en el Campamento Ebenezer en Chiapas, M\u00e9xico, el 17 de abril de 2019. Fue el campor\u00ed de uni\u00f3n m\u00e1s grande que se llev\u00f3 a cabo en el territorio de la Divisi\u00f3n Interamericana, con m\u00e1s de 10.600 campistas. Fotograf\u00eda de Daniel Gallardo\/DIA<\/p><\/div>\n<p>22 de abril de 2019 | Miami, Florida, Estados Unidos | Libna Stevens\/DIA<\/p>\n<p>Para miles de j\u00f3venes adventistas del s\u00e9ptimo d\u00eda en el territorio de la Divisi\u00f3n Interamericana (DIA), la semana del receso de primavera en abril es tiempo para un campor\u00ed de Conquistadores, un momento para ir a acampar con sus compa\u00f1eros, adquirir nuevas habilidades y participar de actividades comunitarias.<\/p>\n<p>Un campor\u00ed de Conquistadores es un evento que re\u00fane a decenas o en algunos casos a clubes internacionales de Conquistadores cada a\u00f1o para reafirmar su lugar en este mundo como j\u00f3venes que aman a Cristo y est\u00e1n listo para servir dondequiera est\u00e9n. Los campor\u00edes atraen a cientos, y a veces a miles de j\u00f3venes en un lugar.<\/p>\n<p>Los l\u00edderes de la iglesia estiman que cerca de 80 mil Conquistadores y Gu\u00edas Mayores (que son j\u00f3venes que est\u00e1n prepar\u00e1ndose para dirigir a los Conquistadores) participaron en campor\u00edes a lo largo y a lo ancho del territorio la semana pasada.<\/p>\n<div id=\"attachment_48494\" style=\"width: 811px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" aria-describedby=\"caption-attachment-48494\" class=\"wp-image-48492\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2019\/04\/al-powell-chiapas-camporee.jpg\" alt=\"\" width=\"801\" height=\"601\" srcset=\"https:\/\/interamerica.org\/wp-content\/uploads\/2019\/04\/al-powell-chiapas-camporee.jpg 900w, https:\/\/interamerica.org\/wp-content\/uploads\/2019\/04\/al-powell-chiapas-camporee-300x225.jpg 300w, https:\/\/interamerica.org\/wp-content\/uploads\/2019\/04\/al-powell-chiapas-camporee-768x576.jpg 768w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><p id=\"caption-attachment-48494\" class=\"wp-caption-text\">El pastor Al Powell, director de ministerios j\u00f3venes de la Iglesia Adventista en Interam\u00e9rica, habla a los Conquistadores durante la noche de apertura del gran campor\u00ed en Chiapas, M\u00e9xico, el 17 de abril de 2019. Fotograf\u00eda de Daniel Gallardo\/DIA<\/p><\/div>\n<p>\u201cSabemos que m\u00e1s de treinta mil j\u00f3venes de ocho uniones de Interam\u00e9rica acamparon en Belice, Chiapas, la regi\u00f3n Interoce\u00e1nica de M\u00e9xico, Jamaica, Panam\u00e1, Am\u00e9rica Central Sur y Venezuela Occidental, reuniendo a Conquistadores y Gu\u00edas Mayores en grandes campor\u00edes\u201d, dijo el pastor Al Powell, director de ministerios j\u00f3venes de la Iglesia Adventista en Interam\u00e9rica.<\/p>\n<p>Powell, que pas\u00f3 el \u00faltimo fin de semana con unos 10.600 campistas en Chiapas, M\u00e9xico, dijo que ver el entusiasmo y el compromiso de tantos j\u00f3venes por el Se\u00f1or confirma una y otra vez por qu\u00e9 las iglesia financia esos eventos que tanto empoderan a los j\u00f3venes. Chiapas organiz\u00f3 el campamento m\u00e1s grande a nivel de uni\u00f3n este a\u00f1o.<\/p>\n<p>\u201cEste [campor\u00ed] implica preparar a los j\u00f3venes para que reconsagren sus vidas a Dios, ayud\u00e1ndolos a formar su car\u00e1cter y brind\u00e1ndoles oportunidades de que se dediquen a testificar y a la misi\u00f3n de servir para marcar una diferencia en sus comunidades\u201d, dijo Powell. S\u00ed, la iglesia gasta muchos recursos para financiar estos tipos de eventos, dijo Powell, pero esto implica invertir en los j\u00f3venes, la comunidad y el futuro de la iglesia, a\u00f1adi\u00f3.<\/p>\n<div id=\"attachment_48487\" style=\"width: 811px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" aria-describedby=\"caption-attachment-48487\" class=\" wp-image-48485\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2019\/04\/jamu-camporee2019.jpg\" alt=\"\" width=\"801\" height=\"535\" srcset=\"https:\/\/interamerica.org\/wp-content\/uploads\/2019\/04\/jamu-camporee2019.jpg 1000w, https:\/\/interamerica.org\/wp-content\/uploads\/2019\/04\/jamu-camporee2019-300x200.jpg 300w, https:\/\/interamerica.org\/wp-content\/uploads\/2019\/04\/jamu-camporee2019-768x513.jpg 768w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><p id=\"caption-attachment-48487\" class=\"wp-caption-text\">Los Conquistadores usan sus redoblantes meintras se abren paso al estadio principal en el Complejo Multiprop\u00f3sito de Trelawny, durante el Campor\u00ed de J\u00f3venes de la Uni\u00f3n Jamaiquina, llevado a cabo del 18 al 22 de abril de 2019. M\u00e1s de 4000 j\u00f3venes se reunieron para el evento de cuatro d\u00edas bajo el lema \u201cYEA4Jesus, Youth Engaged in Action for Jesus\u201d. Fotograf\u00eda de Michael Fletcher\/JAMU\/DIA<\/p><\/div>\n<p>Durante un campor\u00ed, los Conquistadores participan de una amplia gama de actividades como cultos, aprendizaje de t\u00e9cnicas de supervivencia, actividades f\u00edsicas, competiciones de habilidades, intercambio de pines, establecimiento de conexiones profesionales y clases progresivas, entre otros.<\/p>\n<p>Los campor\u00edes tambi\u00e9n son una oportunidad de alcanzar a los adolescentes que a\u00fan no han entregado su vida a Cristo, ayud\u00e1ndolos a crecer espiritualmente y aprender de la Biblia y el amor de Jes\u00fas, explic\u00f3 Powell. En total, en los ocho campor\u00edes a nivel de union llevados a cabo la semana pasada, se bautizaron 930 j\u00f3venes, inform\u00f3 Powell.<br \/>\nAsimismo, otras asociaciones y misiones de la Divisi\u00f3n Interamericana, que llevaron a cabo campor\u00edes menores la semana pasada, informaron un total de m\u00e1s de mil bautismos seg\u00fan los datos preliminares, a\u00f1adi\u00f3.<\/p>\n<div id=\"attachment_48477\" style=\"width: 811px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-48477\" class=\" wp-image-48475\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2019\/04\/inaguracion-camporee-sin-logos-1024x592.jpg\" alt=\"\" width=\"801\" height=\"463\" srcset=\"https:\/\/interamerica.org\/wp-content\/uploads\/2019\/04\/inaguracion-camporee-sin-logos-1024x592.jpg 1024w, https:\/\/interamerica.org\/wp-content\/uploads\/2019\/04\/inaguracion-camporee-sin-logos-300x173.jpg 300w, https:\/\/interamerica.org\/wp-content\/uploads\/2019\/04\/inaguracion-camporee-sin-logos-768x444.jpg 768w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><p id=\"caption-attachment-48477\" class=\"wp-caption-text\">La Uni\u00f3n Mexicana de Chiapas da la bienvenida a los campistas con fuegos artificiales, durante la noche de apertura del programa del campor\u00ed, el 17 de abril de 2019. Fotograf\u00eda de Daniel Gallardo\/DIA<\/p><\/div>\n<p>En el campor\u00ed de la Uni\u00f3n Mexicana de Chiapas se bautizaron 324 j\u00f3venes. En la Uni\u00f3n Paname\u00f1a hubo 264 bautismos y en Venezuela Oriental, 427 bautismos en sus campor\u00edes de asociaci\u00f3n y misi\u00f3n.<\/p>\n<p>En Venezuela Occidental, una multitud de m\u00e1s de 6780 Conquistadores y Gu\u00edas Mayores se reunieron en el Parque Bosque Macuto en Barquisimeto para el campor\u00ed. El evento casi tuvo que ser cancelado, dijo el pastor Orlando Ram\u00edrez, secretario ejecutivo de la Iglesia Adventista en Venezuela Occidental. A pesar de algunos desaf\u00edos financieros y de transporte, el campor\u00ed sigui\u00f3 adelante sin complicaciones.<\/p>\n<p>\u201cEste evento fue una gran bendici\u00f3n\u201d, dijo Ram\u00edrez. \u201cSe pod\u00eda notar el gozo\u201d. El evento se hizo posible gracias a las muchas contribuciones enviadas por otros venezolanos que viven fuera del pa\u00eds, dijo Ram\u00edrez.<\/p>\n<div id=\"attachment_48480\" style=\"width: 810px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-48480\" class=\" wp-image-48478\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2019\/04\/wevu-camporee-1024x768.jpg\" alt=\"\" width=\"800\" height=\"600\" srcset=\"https:\/\/interamerica.org\/wp-content\/uploads\/2019\/04\/wevu-camporee-1024x768.jpg 1024w, https:\/\/interamerica.org\/wp-content\/uploads\/2019\/04\/wevu-camporee-300x225.jpg 300w, https:\/\/interamerica.org\/wp-content\/uploads\/2019\/04\/wevu-camporee-768x576.jpg 768w, https:\/\/interamerica.org\/wp-content\/uploads\/2019\/04\/wevu-camporee.jpg 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><p id=\"caption-attachment-48480\" class=\"wp-caption-text\">Los Conquistadores de Venezuela Occidental se alistan para una actividad durante un campor\u00ed de su territorio, del 14 al 20 de abril de 2019 en el Parque Bosque Macuto en Barquisimeto, Venezuela. M\u00e1s de 6500 campistas participaron de los seis d\u00edas del evento. Fotograf\u00eda de Orlando Ram\u00edrez\/DIA<\/p><\/div>\n<p>Como parte de su impacto comunitario, los Conquistadores limpiaron el parque, pintaron canchas de b\u00e1squetbol y dejaron libros de pintura para embellecer la zona de la piscina, a\u00f1adi\u00f3 Ram\u00edrez.<\/p>\n<p>No se produjeron mayores incidentes durante la semana, excepto por unos campistas que tuvieron que ser evacuados en Guatemala debido a las bajas temperaturas.<\/p>\n<p>\u201cAlabamos a Dios por el impacto que estas actividades de los j\u00f3venes han tenido en sus vidas, porque su prop\u00f3sito es inspirar a los j\u00f3venes para que testifiquen por Cristo y mostrar su amor con toda persona con quien se encuentren\u201d, dijo Powell.<\/p>\n<p>Traducci\u00f3n de Marcos Paseggi<\/p>\n","protected":false},"excerpt":{"rendered":"<p>22 de abril de 2019 | Miami, Florida, Estados Unidos | Libna Stevens\/DIA Para miles de j\u00f3venes adventistas del s\u00e9ptimo d\u00eda en el territorio de la Divisi\u00f3n Interamericana (DIA), la&#8230;<\/p>\n","protected":false},"author":3,"featured_media":48474,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16,15],"tags":[],"class_list":["post-48499","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-desde-la-sede","category-rss-espanol"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>En Interam\u00e9rica, miles de Conquistadores clavan sus tiendas para el Receso de Primavera - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/interamerica.org\/es\/2019\/04\/en-interamerica-miles-de-conquistadores-clavan-sus-tiendas-para-el-receso-de-primavera\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En Interam\u00e9rica, miles de Conquistadores clavan sus tiendas para el Receso de Primavera - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana\" \/>\n<meta property=\"og:description\" content=\"22 de abril de 2019 | Miami, Florida, Estados Unidos | Libna Stevens\/DIA Para miles de j\u00f3venes adventistas del s\u00e9ptimo d\u00eda en el territorio de la Divisi\u00f3n Interamericana (DIA), la...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/interamerica.org\/es\/2019\/04\/en-interamerica-miles-de-conquistadores-clavan-sus-tiendas-para-el-receso-de-primavera\/\" \/>\n<meta property=\"og:site_name\" content=\"Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-23T18:54:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-23T21:08:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/interamerica.org\/wp-content\/uploads\/2019\/04\/chiapas-tents.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"666\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"libna\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"libna\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2019\\\/04\\\/en-interamerica-miles-de-conquistadores-clavan-sus-tiendas-para-el-receso-de-primavera\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2019\\\/04\\\/en-interamerica-miles-de-conquistadores-clavan-sus-tiendas-para-el-receso-de-primavera\\\/\"},\"author\":{\"name\":\"libna\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#\\\/schema\\\/person\\\/29998f2bc2d8bd0d38662909289b54f1\"},\"headline\":\"En Interam\u00e9rica, miles de Conquistadores clavan sus tiendas para el Receso de Primavera\",\"datePublished\":\"2019-04-23T18:54:22+00:00\",\"dateModified\":\"2019-04-23T21:08:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2019\\\/04\\\/en-interamerica-miles-de-conquistadores-clavan-sus-tiendas-para-el-receso-de-primavera\\\/\"},\"wordCount\":1082,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2019\\\/04\\\/en-interamerica-miles-de-conquistadores-clavan-sus-tiendas-para-el-receso-de-primavera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/chiapas-tents.jpg\",\"articleSection\":[\"Desde la sede\",\"RSS Espa\u00f1ol\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/interamerica.org\\\/es\\\/2019\\\/04\\\/en-interamerica-miles-de-conquistadores-clavan-sus-tiendas-para-el-receso-de-primavera\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2019\\\/04\\\/en-interamerica-miles-de-conquistadores-clavan-sus-tiendas-para-el-receso-de-primavera\\\/\",\"url\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2019\\\/04\\\/en-interamerica-miles-de-conquistadores-clavan-sus-tiendas-para-el-receso-de-primavera\\\/\",\"name\":\"En Interam\u00e9rica, miles de Conquistadores clavan sus tiendas para el Receso de Primavera - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2019\\\/04\\\/en-interamerica-miles-de-conquistadores-clavan-sus-tiendas-para-el-receso-de-primavera\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2019\\\/04\\\/en-interamerica-miles-de-conquistadores-clavan-sus-tiendas-para-el-receso-de-primavera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/chiapas-tents.jpg\",\"datePublished\":\"2019-04-23T18:54:22+00:00\",\"dateModified\":\"2019-04-23T21:08:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#\\\/schema\\\/person\\\/29998f2bc2d8bd0d38662909289b54f1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2019\\\/04\\\/en-interamerica-miles-de-conquistadores-clavan-sus-tiendas-para-el-receso-de-primavera\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/interamerica.org\\\/es\\\/2019\\\/04\\\/en-interamerica-miles-de-conquistadores-clavan-sus-tiendas-para-el-receso-de-primavera\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2019\\\/04\\\/en-interamerica-miles-de-conquistadores-clavan-sus-tiendas-para-el-receso-de-primavera\\\/#primaryimage\",\"url\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/chiapas-tents.jpg\",\"contentUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/chiapas-tents.jpg\",\"width\":1000,\"height\":666,\"caption\":\"Fotograf\u00eda de Daniel Gallardo\\\/DIA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2019\\\/04\\\/en-interamerica-miles-de-conquistadores-clavan-sus-tiendas-para-el-receso-de-primavera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/interamerica.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En Interam\u00e9rica, miles de Conquistadores clavan sus tiendas para el Receso de Primavera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/interamerica.org\\\/es\\\/\",\"name\":\"Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/interamerica.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#\\\/schema\\\/person\\\/29998f2bc2d8bd0d38662909289b54f1\",\"name\":\"libna\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7c5bd30ae4b47a9ba3c856590957fd1d96dc588bf3ac05719d247e126840331f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7c5bd30ae4b47a9ba3c856590957fd1d96dc588bf3ac05719d247e126840331f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7c5bd30ae4b47a9ba3c856590957fd1d96dc588bf3ac05719d247e126840331f?s=96&d=mm&r=g\",\"caption\":\"libna\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En Interam\u00e9rica, miles de Conquistadores clavan sus tiendas para el Receso de Primavera - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/interamerica.org\/es\/2019\/04\/en-interamerica-miles-de-conquistadores-clavan-sus-tiendas-para-el-receso-de-primavera\/","og_locale":"es_ES","og_type":"article","og_title":"En Interam\u00e9rica, miles de Conquistadores clavan sus tiendas para el Receso de Primavera - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","og_description":"22 de abril de 2019 | Miami, Florida, Estados Unidos | Libna Stevens\/DIA Para miles de j\u00f3venes adventistas del s\u00e9ptimo d\u00eda en el territorio de la Divisi\u00f3n Interamericana (DIA), la...","og_url":"https:\/\/interamerica.org\/es\/2019\/04\/en-interamerica-miles-de-conquistadores-clavan-sus-tiendas-para-el-receso-de-primavera\/","og_site_name":"Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","article_published_time":"2019-04-23T18:54:22+00:00","article_modified_time":"2019-04-23T21:08:16+00:00","og_image":[{"width":1000,"height":666,"url":"https:\/\/interamerica.org\/wp-content\/uploads\/2019\/04\/chiapas-tents.jpg","type":"image\/jpeg"}],"author":"libna","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"libna","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/interamerica.org\/es\/2019\/04\/en-interamerica-miles-de-conquistadores-clavan-sus-tiendas-para-el-receso-de-primavera\/#article","isPartOf":{"@id":"https:\/\/interamerica.org\/es\/2019\/04\/en-interamerica-miles-de-conquistadores-clavan-sus-tiendas-para-el-receso-de-primavera\/"},"author":{"name":"libna","@id":"https:\/\/interamerica.org\/es\/#\/schema\/person\/29998f2bc2d8bd0d38662909289b54f1"},"headline":"En Interam\u00e9rica, miles de Conquistadores clavan sus tiendas para el Receso de Primavera","datePublished":"2019-04-23T18:54:22+00:00","dateModified":"2019-04-23T21:08:16+00:00","mainEntityOfPage":{"@id":"https:\/\/interamerica.org\/es\/2019\/04\/en-interamerica-miles-de-conquistadores-clavan-sus-tiendas-para-el-receso-de-primavera\/"},"wordCount":1082,"commentCount":0,"image":{"@id":"https:\/\/interamerica.org\/es\/2019\/04\/en-interamerica-miles-de-conquistadores-clavan-sus-tiendas-para-el-receso-de-primavera\/#primaryimage"},"thumbnailUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2019\/04\/chiapas-tents.jpg","articleSection":["Desde la sede","RSS Espa\u00f1ol"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/interamerica.org\/es\/2019\/04\/en-interamerica-miles-de-conquistadores-clavan-sus-tiendas-para-el-receso-de-primavera\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/interamerica.org\/es\/2019\/04\/en-interamerica-miles-de-conquistadores-clavan-sus-tiendas-para-el-receso-de-primavera\/","url":"https:\/\/interamerica.org\/es\/2019\/04\/en-interamerica-miles-de-conquistadores-clavan-sus-tiendas-para-el-receso-de-primavera\/","name":"En Interam\u00e9rica, miles de Conquistadores clavan sus tiendas para el Receso de Primavera - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","isPartOf":{"@id":"https:\/\/interamerica.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/interamerica.org\/es\/2019\/04\/en-interamerica-miles-de-conquistadores-clavan-sus-tiendas-para-el-receso-de-primavera\/#primaryimage"},"image":{"@id":"https:\/\/interamerica.org\/es\/2019\/04\/en-interamerica-miles-de-conquistadores-clavan-sus-tiendas-para-el-receso-de-primavera\/#primaryimage"},"thumbnailUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2019\/04\/chiapas-tents.jpg","datePublished":"2019-04-23T18:54:22+00:00","dateModified":"2019-04-23T21:08:16+00:00","author":{"@id":"https:\/\/interamerica.org\/es\/#\/schema\/person\/29998f2bc2d8bd0d38662909289b54f1"},"breadcrumb":{"@id":"https:\/\/interamerica.org\/es\/2019\/04\/en-interamerica-miles-de-conquistadores-clavan-sus-tiendas-para-el-receso-de-primavera\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/interamerica.org\/es\/2019\/04\/en-interamerica-miles-de-conquistadores-clavan-sus-tiendas-para-el-receso-de-primavera\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/interamerica.org\/es\/2019\/04\/en-interamerica-miles-de-conquistadores-clavan-sus-tiendas-para-el-receso-de-primavera\/#primaryimage","url":"https:\/\/interamerica.org\/wp-content\/uploads\/2019\/04\/chiapas-tents.jpg","contentUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2019\/04\/chiapas-tents.jpg","width":1000,"height":666,"caption":"Fotograf\u00eda de Daniel Gallardo\/DIA"},{"@type":"BreadcrumbList","@id":"https:\/\/interamerica.org\/es\/2019\/04\/en-interamerica-miles-de-conquistadores-clavan-sus-tiendas-para-el-receso-de-primavera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/interamerica.org\/es\/"},{"@type":"ListItem","position":2,"name":"En Interam\u00e9rica, miles de Conquistadores clavan sus tiendas para el Receso de Primavera"}]},{"@type":"WebSite","@id":"https:\/\/interamerica.org\/es\/#website","url":"https:\/\/interamerica.org\/es\/","name":"Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/interamerica.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/interamerica.org\/es\/#\/schema\/person\/29998f2bc2d8bd0d38662909289b54f1","name":"libna","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/7c5bd30ae4b47a9ba3c856590957fd1d96dc588bf3ac05719d247e126840331f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7c5bd30ae4b47a9ba3c856590957fd1d96dc588bf3ac05719d247e126840331f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7c5bd30ae4b47a9ba3c856590957fd1d96dc588bf3ac05719d247e126840331f?s=96&d=mm&r=g","caption":"libna"}}]}},"_links":{"self":[{"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/posts\/48499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/comments?post=48499"}],"version-history":[{"count":0,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/posts\/48499\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/media\/48474"}],"wp:attachment":[{"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/media?parent=48499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/categories?post=48499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/tags?post=48499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}