{"id":86947,"date":"2022-06-28T10:45:55","date_gmt":"2022-06-28T14:45:55","guid":{"rendered":"https:\/\/recursing-golick.147-182-135-0.plesk.page\/?p=86947"},"modified":"2022-06-29T14:16:36","modified_gmt":"2022-06-29T18:16:36","slug":"en-mexico-iglesia-adventista-capacita-a-ninos-y-adolescentes-para-que-sean-futuros-lideres","status":"publish","type":"post","link":"https:\/\/interamerica.org\/es\/2022\/06\/en-mexico-iglesia-adventista-capacita-a-ninos-y-adolescentes-para-que-sean-futuros-lideres\/","title":{"rendered":"En M\u00e9xico, Iglesia Adventista capacita a ni\u00f1os y adolescentes para que sean futuros l\u00edderes"},"content":{"rendered":"<p>27 de junio de 2022 | Chihuahua, Chihuahua, M\u00e9xico | Keila Urbano y Noticias de la Divisi\u00f3n Interamericana<\/p>\n<p>L\u00edderes adventistas del norte, centro y la zona monta\u00f1osa de Chihuahua en M\u00e9xico ofrecieron hace poco capacitaci\u00f3n en liderazgo a decenas de ni\u00f1os y adolescentes de la regi\u00f3n, con un programa especial que han denominado \u201cLa Asociaci\u00f3n del Ma\u00f1ana\u201d. El programa busca involucrar a los miembros j\u00f3venes de entre 10 y 15 a\u00f1os para que dirijan en diversos niveles de la iglesia, lo que incluye la parte administrativa, de departamentos, pastoral y la iglesia local, durante una semana.<\/p>\n<p><strong>Iniciativa de capacitaci\u00f3n en el liderazgo<\/strong><\/p>\n<p>Es el primer a\u00f1o que la iniciativa ha atra\u00eddo a los jovencitos para que experimenten de primera mano la manera en que la iglesia opera desde el nivel de iglesia local al nivel de asociaci\u00f3n, dijeron los l\u00edderes de la iglesia. El programa abarc\u00f3 las localidades de Ciudad Ju\u00e1rez, Chihuahua, Delicias, Cuaubt\u00e9moc, Parral, Valle De Zaragoza, Nuevo Casas Grandes, El Terrero y Creel del 14-21 de mayo.<\/p>\n<p><div id=\"attachment_86930\" style=\"width: 910px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" aria-describedby=\"caption-attachment-86930\" class=\"size-full wp-image-86930\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2022\/06\/nomu-chihuahua-pews-2.jpeg\" alt=\"\" width=\"900\" height=\"675\" srcset=\"https:\/\/interamerica.org\/wp-content\/uploads\/2022\/06\/nomu-chihuahua-pews-2.jpeg 900w, https:\/\/interamerica.org\/wp-content\/uploads\/2022\/06\/nomu-chihuahua-pews-2-300x225.jpeg 300w, https:\/\/interamerica.org\/wp-content\/uploads\/2022\/06\/nomu-chihuahua-pews-2-768x576.jpeg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><p id=\"caption-attachment-86930\" class=\"wp-caption-text\">El pastor Jaime Vega (derecha), secretario ejecutivo de la Asociaci\u00f3n Mexicana de Chihuahua, habla con David Ochoa (izquierda) sobre sus responsabilidades laborales, durante la capacitaci\u00f3n en liderazgo para ni\u00f1os y adolescentes que participaron de la iniciativa \u201cAsociaci\u00f3n del Ma\u00f1ana\u201d, llevada a cabo en la regi\u00f3n del 14-21 de mayo de 2022. Atr\u00e1s, el pastor Marco Ortega (a la derecha), director de ministerios personales de la asociaci\u00f3n, repasa los planes con Johan Jimenez, un joven de la ciudad de Chihuahua. [Fotograf\u00eda: Asociaci\u00f3n de Chihuahua]<\/p><\/div>\u201cNuestro principal objetivo es promover el desarrollo del liderazgo de la iglesia entre los ni\u00f1os y los adolescentes, y prepararlos para que sean futuros l\u00edderes de la iglesia\u201d, dijo el pastor Iv\u00e1n Orozco, director de ministerios j\u00f3venes de la Iglesia Adventista en la Asociaci\u00f3n Mexicana de Chihuahua. Cada cargo fue cubierto a nivel local, lo que incluye al pastor, el tesorero y los ancianos. Cada l\u00edder de departamento o ministerio fue \u201celegido\u201d, dijo.<\/p>\n<p>Los ni\u00f1os, los adolescentes y los j\u00f3venes tambi\u00e9n fueron seleccionados para ser parte de la capacitaci\u00f3n en liderazgo en la sede de la asociaci\u00f3n, para acompa\u00f1ar a los l\u00edderes y formar parte de las decisiones y las reuniones, explic\u00f3 Orozco. \u201cCada ni\u00f1o o adolescente cumpli\u00f3 con sus responsabilidades en persona, pasando d\u00edas en las oficinas o en la iglesia y organizando actividades\u201d, dijo.<\/p>\n<p><strong>Aprendieron numerosas responsabilidades<\/strong><\/p>\n<p>En la mayor\u00eda de las iglesias que participaron del programa de desarrollo de liderazgo, los j\u00f3venes trataron con numerosas cuestiones y responsabilidades, dijo Alma Ibuado, directora de ministerios del ni\u00f1o y el adolescente de la Asociaci\u00f3n Mexicana de Chihuahua. \u201cCada iglesia participante eligi\u00f3 sus pastores y juntas de iglesia, junto con los participantes, para organizar las actividades de la semana mientras fueron acompa\u00f1ados por mentores, visitaron familias y se reunieron con los pastores distritales, entre otras actividades\u201d, dijo Ibuado.<\/p>\n<p><div id=\"attachment_86933\" style=\"width: 889px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" aria-describedby=\"caption-attachment-86933\" class=\" wp-image-86933\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2022\/06\/nomu-chihuahua-office1.jpeg\" alt=\"\" width=\"879\" height=\"549\" srcset=\"https:\/\/interamerica.org\/wp-content\/uploads\/2022\/06\/nomu-chihuahua-office1.jpeg 1000w, https:\/\/interamerica.org\/wp-content\/uploads\/2022\/06\/nomu-chihuahua-office1-300x188.jpeg 300w, https:\/\/interamerica.org\/wp-content\/uploads\/2022\/06\/nomu-chihuahua-office1-768x480.jpeg 768w\" sizes=\"(max-width: 879px) 100vw, 879px\" \/><p id=\"caption-attachment-86933\" class=\"wp-caption-text\">Como directora de diaconisas, Melissa Caldelas, una adolescente, ayuda a preparar certificados para reconocer a los ancianos de la iglesia local, durante un congreso especial en Ciudad Ju\u00e1rez, al norte del territorio. [Fotograf\u00eda: Uni\u00f3n Mexicana de Chihuahua]<\/p><\/div>Dado que el Estado de Chihuahua es tan grande, se organizaron dos grupos de la \u201cAsociaci\u00f3n del Ma\u00f1ana\u201d, para que los ni\u00f1os tuvieran la oportunidad de participar de la experiencia en Ciudad Ju\u00e1rez y Chihuahua, donde se encuentra la sede del territorio, explic\u00f3 Ibuado. El grupo incluy\u00f3 la elecci\u00f3n de dos conjuntos de administradores de la asociaci\u00f3n y equipos de los departamentos\u201d, dijo.<\/p>\n<p>La primera parte de la capacitaci\u00f3n a nivel de la asociaci\u00f3n comenz\u00f3 en Ciudad Ju\u00e1rez, donde los participantes estuvieron al frente del programa durante el congreso de ancianos de iglesia.<\/p>\n<p>El segundo equipo de ni\u00f1os y adolescentes de la asociaci\u00f3n visit\u00f3 la sede en la ciudad de Chihuahua para recibir orientaci\u00f3n y trabajar en la sede. \u201cLes dimos las claves de las oficinas, y cada l\u00edder les explic\u00f3 la funci\u00f3n de los departamentos, cu\u00e1les eran sus responsabilidades, hicieron llamadas, participaron de dirigir reuniones, y entonces se reunieron por Zoom para hablar a los \u2018pastores del ma\u00f1ana\u2019\u201d, dijo Ibuado.<\/p>\n<p><div id=\"attachment_86924\" style=\"width: 907px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" aria-describedby=\"caption-attachment-86924\" class=\" wp-image-86924\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2022\/06\/nomu-ciudad-juarez-leaders-1024x640.jpg\" alt=\"\" width=\"897\" height=\"560\" srcset=\"https:\/\/interamerica.org\/wp-content\/uploads\/2022\/06\/nomu-ciudad-juarez-leaders-1024x640.jpg 1024w, https:\/\/interamerica.org\/wp-content\/uploads\/2022\/06\/nomu-ciudad-juarez-leaders-300x188.jpg 300w, https:\/\/interamerica.org\/wp-content\/uploads\/2022\/06\/nomu-ciudad-juarez-leaders-768x480.jpg 768w, https:\/\/interamerica.org\/wp-content\/uploads\/2022\/06\/nomu-ciudad-juarez-leaders.jpg 1280w\" sizes=\"(max-width: 897px) 100vw, 897px\" \/><p id=\"caption-attachment-86924\" class=\"wp-caption-text\">El grupo de j\u00f3venes seleccionados presenta un reconocimiento a los ancianos de iglesia, durante un congreso especial de ancianos en Ciudad Ju\u00e1rez el mes pasado. [Fotograf\u00eda: Asociaci\u00f3n de Chihuahua]<\/p><\/div>Se propusieron varias actividades misioneras que estuvieron a cargo de los j\u00f3venes, entre ellas, planes de llevar a cabo una gran brigada de salud en Ciudad Ju\u00e1rez, y una iniciativa de invitar a los j\u00f3venes que no son de la iglesia a un programa especial en el D\u00eda del Estudiante que se celebra en el pa\u00eds.<\/p>\n<p>Adem\u00e1s de ello, el grupo joven se ocup\u00f3 de atender las llamadas, llevaron a cabo reuniones con pastores y l\u00edderes de la iglesia, participaron de una sesi\u00f3n de planificaci\u00f3n sobre una iniciativa detallada propuesta denominada \u201cAsociaci\u00f3n o Iglesia del Ma\u00f1ana\u201d, para que sea estudiada por la Uni\u00f3n Mexicana del Norte, votaron, y m\u00e1s tarde lo informaron al resto de las asociaciones del territorio.<\/p>\n<p>En a\u00f1os anteriores, muchas las iglesias locales contaron con ni\u00f1os y adolescentes en un programa similar de liderazgo, como parte de un requisito para una especialidad del Club de Conquistadores, pero pronto fue adoptada para que fuera una iniciativa en toda la asociaci\u00f3n, a\u00f1adi\u00f3 Ibuado.<\/p>\n<p><div id=\"attachment_86936\" style=\"width: 882px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-86936\" class=\" wp-image-86936\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2022\/06\/nomu-ciudadjuarez-team.jpg\" alt=\"\" width=\"872\" height=\"581\" srcset=\"https:\/\/interamerica.org\/wp-content\/uploads\/2022\/06\/nomu-ciudadjuarez-team.jpg 1000w, https:\/\/interamerica.org\/wp-content\/uploads\/2022\/06\/nomu-ciudadjuarez-team-300x200.jpg 300w, https:\/\/interamerica.org\/wp-content\/uploads\/2022\/06\/nomu-ciudadjuarez-team-768x511.jpg 768w\" sizes=\"(max-width: 872px) 100vw, 872px\" \/><p id=\"caption-attachment-86936\" class=\"wp-caption-text\">El grupo de l\u00edderes j\u00f3venes elegido, que particip\u00f3 de la iniciativa \u201cAsociaci\u00f3n del Ma\u00f1ana\u201d, con la Asociaci\u00f3n Mexicana de Chihuahua. [Fotograf\u00eda: Asociaci\u00f3n Mexicana de Chihuahua]<\/p><\/div><strong>Experiencias de liderazgo joven<\/strong><\/p>\n<p>Valeria Orozco fue elegida tesorera de la iglesia adventista de Chihuahua Centro. \u201cRealmente me gust\u00f3 de qu\u00e9 manera la iglesia est\u00e1 bien organizada\u201d, dijo. \u201cCuando los di\u00e1conos juntaron los diezmos y ofrendas, tuve que verificar que los fondos recolectados fueran correctos, y tuvo que publicarlo en una planilla de Excel. Tambi\u00e9n tuve que hacer algunos pagos\u201d.<\/p>\n<p>H\u00e9ctor Olivares, quien fue nombrado presidente de la asociaci\u00f3n durante el programa, comparti\u00f3 que la experiencia le ense\u00f1\u00f3 mucho sobre el liderazgo de la iglesia. \u201cAprend\u00ed que, como presidente de la asociaci\u00f3n, uno tiene que mantener buenas relaciones con la administraci\u00f3n y el liderazgo, y que la presencia de uno es muy importante para mantener el orden\u201d, dijo Olivares. \u201cLo que m\u00e1s disfrut\u00e9 fue liderar a las personas y coordinar y ayudar a otros\u201d.<\/p>\n<p>El pastor Arturo King, presidente de la Uni\u00f3n Mexicana del Norte, celebr\u00f3 los esfuerzos de los l\u00edderes de la asociaci\u00f3n en esta iniciativa de desarrollo del liderazgo joven. Hay otros campos que han capacitado a los ni\u00f1os y adolescentes a nivel de iglesias locales, pero la Asociaci\u00f3n de Chihuahua es el primer territorio de la uni\u00f3n que lleva a cabo la actividad en diversos niveles, dijo King.<\/p>\n<img loading=\"lazy\" decoding=\"async\" class=\"wp-image-86921 aligncenter\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2022\/06\/nomu-chihuahua-zoom-meeting-1024x640.jpg\" alt=\"\" width=\"838\" height=\"524\" srcset=\"https:\/\/interamerica.org\/wp-content\/uploads\/2022\/06\/nomu-chihuahua-zoom-meeting-1024x640.jpg 1024w, https:\/\/interamerica.org\/wp-content\/uploads\/2022\/06\/nomu-chihuahua-zoom-meeting-300x188.jpg 300w, https:\/\/interamerica.org\/wp-content\/uploads\/2022\/06\/nomu-chihuahua-zoom-meeting-768x480.jpg 768w, https:\/\/interamerica.org\/wp-content\/uploads\/2022\/06\/nomu-chihuahua-zoom-meeting.jpg 1280w\" sizes=\"(max-width: 838px) 100vw, 838px\" \/>\n<p><div id=\"attachment_86918\" style=\"width: 855px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-86918\" class=\" wp-image-86918\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2022\/06\/nomu-chihuahua-zoom-young-leaders.jpg\" alt=\"\" width=\"845\" height=\"566\" srcset=\"https:\/\/interamerica.org\/wp-content\/uploads\/2022\/06\/nomu-chihuahua-zoom-young-leaders.jpg 1024w, https:\/\/interamerica.org\/wp-content\/uploads\/2022\/06\/nomu-chihuahua-zoom-young-leaders-300x201.jpg 300w, https:\/\/interamerica.org\/wp-content\/uploads\/2022\/06\/nomu-chihuahua-zoom-young-leaders-768x515.jpg 768w\" sizes=\"(max-width: 845px) 100vw, 845px\" \/><p id=\"caption-attachment-86918\" class=\"wp-caption-text\">La fotograf\u00eda de arriba muestra al grupo de ni\u00f1os y adolescentes reunidos en la Asociaci\u00f3n Mexicana de Chihuahua por medio de Zoom, con los l\u00edderes j\u00f3venes elegidos, para analizar planes e iniciativas que beneficiar\u00e1n a la comunidad en el territorio. [Fotograf\u00eda: Asociaci\u00f3n Mexicana de Chihuahua]<\/p><\/div>\u201cAnimamos a los ni\u00f1os y a los j\u00f3venes a que presten servicio en sus iglesias\u201d, dijo King. \u201cSi su creatividad, entusiasmo y fuerza, muchas iglesias comenzar\u00e1n a morir. Cada uno tiene que poner sus dones y talentos al servicio del Se\u00f1or\u201d.<\/p>\n<p>Los l\u00edderes de la asociaci\u00f3n dijeron que planean continuar con la iniciativa como un programa anual en todo el territorio.<\/p>\n<p>Traducci\u00f3n de Marcos Paseggi<\/p>\n","protected":false},"excerpt":{"rendered":"<p>27 de junio de 2022 | Chihuahua, Chihuahua, M\u00e9xico | Keila Urbano y Noticias de la Divisi\u00f3n Interamericana L\u00edderes adventistas del norte, centro y la zona monta\u00f1osa de Chihuahua en&#8230;<\/p>\n","protected":false},"author":3,"featured_media":86930,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17,15],"tags":[],"class_list":["post-86947","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-desde-el-campo","category-rss-espanol"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>En M\u00e9xico, Iglesia Adventista capacita a ni\u00f1os y adolescentes para que sean futuros l\u00edderes - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/interamerica.org\/es\/2022\/06\/en-mexico-iglesia-adventista-capacita-a-ninos-y-adolescentes-para-que-sean-futuros-lideres\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En M\u00e9xico, Iglesia Adventista capacita a ni\u00f1os y adolescentes para que sean futuros l\u00edderes - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana\" \/>\n<meta property=\"og:description\" content=\"27 de junio de 2022 | Chihuahua, Chihuahua, M\u00e9xico | Keila Urbano y Noticias de la Divisi\u00f3n Interamericana L\u00edderes adventistas del norte, centro y la zona monta\u00f1osa de Chihuahua en...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/interamerica.org\/es\/2022\/06\/en-mexico-iglesia-adventista-capacita-a-ninos-y-adolescentes-para-que-sean-futuros-lideres\/\" \/>\n<meta property=\"og:site_name\" content=\"Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-28T14:45:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-29T18:16:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/interamerica.org\/wp-content\/uploads\/2022\/06\/nomu-chihuahua-pews-2.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"libna\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"libna\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2022\\\/06\\\/en-mexico-iglesia-adventista-capacita-a-ninos-y-adolescentes-para-que-sean-futuros-lideres\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2022\\\/06\\\/en-mexico-iglesia-adventista-capacita-a-ninos-y-adolescentes-para-que-sean-futuros-lideres\\\/\"},\"author\":{\"name\":\"libna\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#\\\/schema\\\/person\\\/29998f2bc2d8bd0d38662909289b54f1\"},\"headline\":\"En M\u00e9xico, Iglesia Adventista capacita a ni\u00f1os y adolescentes para que sean futuros l\u00edderes\",\"datePublished\":\"2022-06-28T14:45:55+00:00\",\"dateModified\":\"2022-06-29T18:16:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2022\\\/06\\\/en-mexico-iglesia-adventista-capacita-a-ninos-y-adolescentes-para-que-sean-futuros-lideres\\\/\"},\"wordCount\":1366,\"image\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2022\\\/06\\\/en-mexico-iglesia-adventista-capacita-a-ninos-y-adolescentes-para-que-sean-futuros-lideres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/nomu-chihuahua-pews-2.jpeg\",\"articleSection\":[\"Desde el campo\",\"RSS Espa\u00f1ol\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2022\\\/06\\\/en-mexico-iglesia-adventista-capacita-a-ninos-y-adolescentes-para-que-sean-futuros-lideres\\\/\",\"url\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2022\\\/06\\\/en-mexico-iglesia-adventista-capacita-a-ninos-y-adolescentes-para-que-sean-futuros-lideres\\\/\",\"name\":\"En M\u00e9xico, Iglesia Adventista capacita a ni\u00f1os y adolescentes para que sean futuros l\u00edderes - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2022\\\/06\\\/en-mexico-iglesia-adventista-capacita-a-ninos-y-adolescentes-para-que-sean-futuros-lideres\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2022\\\/06\\\/en-mexico-iglesia-adventista-capacita-a-ninos-y-adolescentes-para-que-sean-futuros-lideres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/nomu-chihuahua-pews-2.jpeg\",\"datePublished\":\"2022-06-28T14:45:55+00:00\",\"dateModified\":\"2022-06-29T18:16:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#\\\/schema\\\/person\\\/29998f2bc2d8bd0d38662909289b54f1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2022\\\/06\\\/en-mexico-iglesia-adventista-capacita-a-ninos-y-adolescentes-para-que-sean-futuros-lideres\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/interamerica.org\\\/es\\\/2022\\\/06\\\/en-mexico-iglesia-adventista-capacita-a-ninos-y-adolescentes-para-que-sean-futuros-lideres\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2022\\\/06\\\/en-mexico-iglesia-adventista-capacita-a-ninos-y-adolescentes-para-que-sean-futuros-lideres\\\/#primaryimage\",\"url\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/nomu-chihuahua-pews-2.jpeg\",\"contentUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/nomu-chihuahua-pews-2.jpeg\",\"width\":900,\"height\":675,\"caption\":\"[Fotograf\u00eda: Asociaci\u00f3n Mexicana de Chihuahua]\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/2022\\\/06\\\/en-mexico-iglesia-adventista-capacita-a-ninos-y-adolescentes-para-que-sean-futuros-lideres\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/interamerica.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En M\u00e9xico, Iglesia Adventista capacita a ni\u00f1os y adolescentes para que sean futuros l\u00edderes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/interamerica.org\\\/es\\\/\",\"name\":\"Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/interamerica.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/es\\\/#\\\/schema\\\/person\\\/29998f2bc2d8bd0d38662909289b54f1\",\"name\":\"libna\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7c5bd30ae4b47a9ba3c856590957fd1d96dc588bf3ac05719d247e126840331f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7c5bd30ae4b47a9ba3c856590957fd1d96dc588bf3ac05719d247e126840331f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7c5bd30ae4b47a9ba3c856590957fd1d96dc588bf3ac05719d247e126840331f?s=96&d=mm&r=g\",\"caption\":\"libna\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En M\u00e9xico, Iglesia Adventista capacita a ni\u00f1os y adolescentes para que sean futuros l\u00edderes - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/interamerica.org\/es\/2022\/06\/en-mexico-iglesia-adventista-capacita-a-ninos-y-adolescentes-para-que-sean-futuros-lideres\/","og_locale":"es_ES","og_type":"article","og_title":"En M\u00e9xico, Iglesia Adventista capacita a ni\u00f1os y adolescentes para que sean futuros l\u00edderes - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","og_description":"27 de junio de 2022 | Chihuahua, Chihuahua, M\u00e9xico | Keila Urbano y Noticias de la Divisi\u00f3n Interamericana L\u00edderes adventistas del norte, centro y la zona monta\u00f1osa de Chihuahua en...","og_url":"https:\/\/interamerica.org\/es\/2022\/06\/en-mexico-iglesia-adventista-capacita-a-ninos-y-adolescentes-para-que-sean-futuros-lideres\/","og_site_name":"Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","article_published_time":"2022-06-28T14:45:55+00:00","article_modified_time":"2022-06-29T18:16:36+00:00","og_image":[{"width":900,"height":675,"url":"https:\/\/interamerica.org\/wp-content\/uploads\/2022\/06\/nomu-chihuahua-pews-2.jpeg","type":"image\/jpeg"}],"author":"libna","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"libna","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/interamerica.org\/es\/2022\/06\/en-mexico-iglesia-adventista-capacita-a-ninos-y-adolescentes-para-que-sean-futuros-lideres\/#article","isPartOf":{"@id":"https:\/\/interamerica.org\/es\/2022\/06\/en-mexico-iglesia-adventista-capacita-a-ninos-y-adolescentes-para-que-sean-futuros-lideres\/"},"author":{"name":"libna","@id":"https:\/\/interamerica.org\/es\/#\/schema\/person\/29998f2bc2d8bd0d38662909289b54f1"},"headline":"En M\u00e9xico, Iglesia Adventista capacita a ni\u00f1os y adolescentes para que sean futuros l\u00edderes","datePublished":"2022-06-28T14:45:55+00:00","dateModified":"2022-06-29T18:16:36+00:00","mainEntityOfPage":{"@id":"https:\/\/interamerica.org\/es\/2022\/06\/en-mexico-iglesia-adventista-capacita-a-ninos-y-adolescentes-para-que-sean-futuros-lideres\/"},"wordCount":1366,"image":{"@id":"https:\/\/interamerica.org\/es\/2022\/06\/en-mexico-iglesia-adventista-capacita-a-ninos-y-adolescentes-para-que-sean-futuros-lideres\/#primaryimage"},"thumbnailUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2022\/06\/nomu-chihuahua-pews-2.jpeg","articleSection":["Desde el campo","RSS Espa\u00f1ol"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/interamerica.org\/es\/2022\/06\/en-mexico-iglesia-adventista-capacita-a-ninos-y-adolescentes-para-que-sean-futuros-lideres\/","url":"https:\/\/interamerica.org\/es\/2022\/06\/en-mexico-iglesia-adventista-capacita-a-ninos-y-adolescentes-para-que-sean-futuros-lideres\/","name":"En M\u00e9xico, Iglesia Adventista capacita a ni\u00f1os y adolescentes para que sean futuros l\u00edderes - Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","isPartOf":{"@id":"https:\/\/interamerica.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/interamerica.org\/es\/2022\/06\/en-mexico-iglesia-adventista-capacita-a-ninos-y-adolescentes-para-que-sean-futuros-lideres\/#primaryimage"},"image":{"@id":"https:\/\/interamerica.org\/es\/2022\/06\/en-mexico-iglesia-adventista-capacita-a-ninos-y-adolescentes-para-que-sean-futuros-lideres\/#primaryimage"},"thumbnailUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2022\/06\/nomu-chihuahua-pews-2.jpeg","datePublished":"2022-06-28T14:45:55+00:00","dateModified":"2022-06-29T18:16:36+00:00","author":{"@id":"https:\/\/interamerica.org\/es\/#\/schema\/person\/29998f2bc2d8bd0d38662909289b54f1"},"breadcrumb":{"@id":"https:\/\/interamerica.org\/es\/2022\/06\/en-mexico-iglesia-adventista-capacita-a-ninos-y-adolescentes-para-que-sean-futuros-lideres\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/interamerica.org\/es\/2022\/06\/en-mexico-iglesia-adventista-capacita-a-ninos-y-adolescentes-para-que-sean-futuros-lideres\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/interamerica.org\/es\/2022\/06\/en-mexico-iglesia-adventista-capacita-a-ninos-y-adolescentes-para-que-sean-futuros-lideres\/#primaryimage","url":"https:\/\/interamerica.org\/wp-content\/uploads\/2022\/06\/nomu-chihuahua-pews-2.jpeg","contentUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2022\/06\/nomu-chihuahua-pews-2.jpeg","width":900,"height":675,"caption":"[Fotograf\u00eda: Asociaci\u00f3n Mexicana de Chihuahua]"},{"@type":"BreadcrumbList","@id":"https:\/\/interamerica.org\/es\/2022\/06\/en-mexico-iglesia-adventista-capacita-a-ninos-y-adolescentes-para-que-sean-futuros-lideres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/interamerica.org\/es\/"},{"@type":"ListItem","position":2,"name":"En M\u00e9xico, Iglesia Adventista capacita a ni\u00f1os y adolescentes para que sean futuros l\u00edderes"}]},{"@type":"WebSite","@id":"https:\/\/interamerica.org\/es\/#website","url":"https:\/\/interamerica.org\/es\/","name":"Iglesia Adventista del S\u00e9ptimo D\u00eda - Divisi\u00f3n Interamericana","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/interamerica.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/interamerica.org\/es\/#\/schema\/person\/29998f2bc2d8bd0d38662909289b54f1","name":"libna","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/7c5bd30ae4b47a9ba3c856590957fd1d96dc588bf3ac05719d247e126840331f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7c5bd30ae4b47a9ba3c856590957fd1d96dc588bf3ac05719d247e126840331f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7c5bd30ae4b47a9ba3c856590957fd1d96dc588bf3ac05719d247e126840331f?s=96&d=mm&r=g","caption":"libna"}}]}},"_links":{"self":[{"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/posts\/86947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/comments?post=86947"}],"version-history":[{"count":0,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/posts\/86947\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/media\/86930"}],"wp:attachment":[{"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/media?parent=86947"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/categories?post=86947"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/interamerica.org\/es\/wp-json\/wp\/v2\/tags?post=86947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}