{"id":121602,"date":"2024-10-30T12:26:31","date_gmt":"2024-10-30T16:26:31","guid":{"rendered":"https:\/\/interamerica.org\/?p=121602"},"modified":"2024-11-01T10:31:22","modified_gmt":"2024-11-01T14:31:22","slug":"toujours-le-moment-parfait","status":"publish","type":"post","link":"https:\/\/interamerica.org\/fr\/2024\/10\/toujours-le-moment-parfait\/","title":{"rendered":"Toujours le moment parfait"},"content":{"rendered":"<p><i><span style=\"font-weight: 400;\">Lorsque nous nous soumettons \u00e0 Dieu, il s\u2019occupe du reste.<\/span><\/i><\/p>\n<p><span style=\"font-weight: 400;\">Le 30 octobre 2024 | Silver Spring, Maryland, \u00c9tats-Unis | Howard Williams pour <\/span><i><span style=\"font-weight: 400;\">Adventist Review<\/span><\/i><\/p>\n<p><span style=\"font-weight: 400;\">C\u2019\u00e9tait un soir d\u2019automne 1974. Mon p\u00e8re a invit\u00e9 ma jeune femme et moi \u00e0 la maison pour nous pr\u00e9senter une famille qui faisait du travail missionnaire en Colombie. Comme je voulais \u00eatre missionnaire, nous avons accept\u00e9 son invitation. Bref, environ un mois et demi plus tard, nous nous sommes retrouv\u00e9s en Colombie \u00e0 travailler comme b\u00e9n\u00e9voles pour l\u2019hiver.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Conform\u00e9ment aux instructions re\u00e7ues, nous n\u2019avions pas apport\u00e9 beaucoup d\u2019argent. \u00c0 la place, mes parents nous envoyaient un ch\u00e8que tous les deux mois, que nous encaissions au bureau de la f\u00e9d\u00e9ration \u00e0 Bogota. Le premier ch\u00e8que est arriv\u00e9 au moment o\u00f9 nous commencions \u00e0 manquer d\u2019argent, nous avons donc fait le long voyage jusqu\u2019\u00e0 la capitale, n\u2019arrivant qu\u2019avec quelques pesos. Quand j\u2019avais ouvert l\u2019enveloppe contenant le ch\u00e8que, j\u2019avais plac\u00e9 le ch\u00e8que dans ma poche de chemise pendant que je lisais la lettre. Le lendemain, quand j\u2019ai demand\u00e9 \u00e0 ma femme o\u00f9 \u00e9tait ma chemise, elle a dit qu\u2019elle l\u2019avait lav\u00e9e dans la rivi\u00e8re et qu\u2019elle \u00e9tait en train de s\u00e9cher sur la corde. Quand nous avons pr\u00e9sent\u00e9 le ch\u00e8que d\u00e9lav\u00e9 au caissier, il y a jet\u00e9 un coup d\u2019\u0153il avant de m\u2019annoncer que la banque ne l\u2019accepterait pas, parce que l\u2019un des chiffres \u00e9tait endommag\u00e9. Nous le voyions bien, mais nous \u00e9tions incapables de le convaincre de l\u2019accepter.\u00a0<\/span><\/p>\n<p><b>Enti\u00e8re soumission<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Nous avons manifest\u00e9 notre m\u00e9contentement et nous sommes assis sur les marches pour r\u00e9fl\u00e9chir \u00e0 notre situation d\u00e9sesp\u00e9r\u00e9e. Nous voil\u00e0, deux jeunes campagnards dans une ville d\u2019environ trois millions de personnes. Nous ne connaissions personne. Nous n\u2019avions m\u00eame pas assez d\u2019argent pour nous acheter un repas pour la journ\u00e9e. En prenant conscience de la gravit\u00e9 de notre situation, ma femme s\u2019est mise \u00e0 pleurer et, lorsqu\u2019un homme bien v\u00eatu est pass\u00e9 devant nous, je suis certain que mon expression faciale en disait long \u00e9galement. En atteignant le haut de l\u2019escalier, il s\u2019est retourn\u00e9 et nous a demand\u00e9, \u00ab\u00a0Est-ce que \u00e7a va?\u00a0\u00bb Nous lui avons tout d\u00e9ball\u00e9 avec quelques larmes. \u00ab\u00a0Ne vous inqui\u00e9tez pas, nous a-t-il dit. Donnez-moi 15 minutes et je vous emm\u00e8ne chez moi. Vous pourrez y rester jusqu\u2019\u00e0 ce que vous receviez plus d\u2019argent. En passant, je m\u2019appelle Henry Niemann, je suis le pr\u00e9sident de la f\u00e9d\u00e9ration.\u00a0\u00bb\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Il nous a emmen\u00e9s chez lui, nous a trait\u00e9s comme ses propres enfants, nous a pr\u00eat\u00e9 de l\u2019argent pour nous permettre de nous d\u00e9placer dans la ville et nous a m\u00eame invit\u00e9s \u00e0 l\u2019accompagner dans un voyage pour visiter la campagne.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cette exp\u00e9rience a \u00e9t\u00e9 un moment d\u00e9cisif dans notre vie de jeunes adultes. Jusque-l\u00e0, Dieu n\u2019\u00e9tait pour nous que th\u00e9orique. Nous savions dor\u00e9navant qu\u2019il veillait sur nous. Il s\u2019\u00e9tait imm\u00e9diatement occup\u00e9 du seul grand besoin que nous n\u2019avions jamais eu. Lorsque nous sommes rentr\u00e9s \u00e0 la maison, nous avons rapidement commenc\u00e9 \u00e0 nous impliquer au sein d\u2019un groupe d\u2019\u00e9tudes bibliques \u00e0 domicile. D\u00e8s le premier soir, nous avons d\u00e9couvert que la raison pour laquelle nous avions eu tant de difficult\u00e9 dans notre marche avec le Seigneur, c\u2019est que nous n\u2019avions jamais r\u00e9ellement soumis notre vie \u00e0 Dieu et \u00e0 sa direction. Cette nuit-l\u00e0 m\u00eame, chez moi, \u00e0 genoux, c\u2019est ce que j\u2019ai fait.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Quelques mois plus tard, j\u2019ai appris du pasteur Niemann qu\u2019il comptait d\u00e9marrer une \u00e9cole pensionnaire d\u2019agriculture o\u00f9 les enfants pauvres pourraient aller apprendre et payer leurs droits de scolarit\u00e9 en travaillant. La terre qu\u2019il voulait acheter \u00e9tait essentiellement recouverte de jungle. Elle devrait donc \u00eatre enti\u00e8rement d\u00e9frich\u00e9e pour faire place \u00e0 l\u2019agriculture. Il m\u2019a demand\u00e9 si j\u2019aimerais participer \u00e0 un tel projet, \u00e9tant donn\u00e9 que j\u2019avais une formation en op\u00e9ration de machinerie et en exploitation foresti\u00e8re. Si oui, il s\u2019occuperait de nos visas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">J\u2019\u00e9tais emball\u00e9! Les occasions de travail missionnaire pour les travailleurs forestiers sont plut\u00f4t rares. En r\u00e9fl\u00e9chissant au projet, je me suis rendu compte que nous aurions besoin d\u2019un bon bulldozer pour bien d\u00e9fricher. L\u2019entreprise foresti\u00e8re de notre famille en avait trois. J\u2019ai donc pos\u00e9 une question enthousiaste \u00e0 mes partenaires\u00a0: Consid\u00e9reriez-vous faire le don d\u2019un bulldozer \u00e0 la F\u00e9d\u00e9ration de la Colombie? J\u2019ai propos\u00e9 non pas notre machine la plus r\u00e9cente, mais la suivante. J\u2019ai \u00e9t\u00e9 tr\u00e8s \u00e9tonn\u00e9 lorsqu\u2019ils ont insist\u00e9 pour dire que, si nous donnions \u00e0 Dieu cette machine, alors il fallait que ce soit notre meilleure. Tout le monde \u00e9tait d\u2019accord. J\u2019ai imm\u00e9diatement \u00e9crit une lettre au pasteur Niemann pour lui apprendre la nouvelle.\u00a0<\/span><\/p>\n<p><b>Le plan de Dieu<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Quelques semaines plus tard, le conseil d\u2019administration [de la F\u00e9d\u00e9ration de la Colombie] s\u2019est r\u00e9uni. Parmi les points \u00e0 l\u2019ordre du jour, il y avait la d\u00e9cision d\u2019aller ou non de l\u2019avant avec le projet d\u2019\u00e9cole d\u2019agriculture. Ce ne sont pas tous les membres du conseil qui \u00e9taient d\u2019accord avec l\u2019id\u00e9e, et la discussion s\u2019est poursuivie durant le repas du midi. \u00ab\u00a0Messieurs, a dit le pasteur Niemann, reprenons la discussion apr\u00e8s la pause du midi. Rentrez chez vous, priez \u00e0 ce sujet et votons \u00e0 notre retour.\u00a0\u00bb<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Quand le pasteur Niemann a travers\u00e9 l\u2019entr\u00e9e du bureau de la f\u00e9d\u00e9ration \u00e0 son retour, la r\u00e9ceptionniste l\u2019a interpell\u00e9 pour lui annoncer qu\u2019il avait re\u00e7u une lettre des \u00c9tats-Unis. En entrant dans son bureau, il a ouvert ma lettre et l\u2019a lue. Quand les membres du conseil d\u2019administration sont revenus, il avait quelque chose \u00e0 leur dire. \u00ab\u00a0Mes fr\u00e8res et s\u0153urs, a-t-il dit, j\u2019ai une lettre \u00e0 vous lire. Ensuite, nous passerons au vote.\u00a0\u00bb Puis il leur a lu ma lettre. Pendant quelques minutes, on aurait pu entendre une mouche voler. Puis il a appel\u00e9 les membres \u00e0 voter. Le r\u00e9sultat fut unanime\u00a0: oui.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ils n\u2019ont jamais r\u00e9ussi \u00e0 obtenir des visas pour ma femme et moi, mais l\u2019\u00e9cole a \u00e9t\u00e9 construite sans nous. Et quant au bulldozer, ils n\u2019ont jamais trouv\u00e9 le moyen de le faire venir jusqu\u2019\u00e0 eux. Mais Dieu n\u2019avait besoin ni de notre bulldozer ni de nous. Tout ce dont il avait besoin, c\u2019est que j\u2019\u00e9crive une lettre leur offrant un bulldozer. C\u2019est ce que Dieu a choisi d\u2019utiliser pour convaincre le comit\u00e9 d\u2019aller de l\u2019avant avec le projet. Un projet, dois-je ajouter, qui \u00e9tait le sien.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">J\u2019ai souvent r\u00e9fl\u00e9chi \u00e0 la complexit\u00e9 de la logistique que Dieu a d\u00fb mettre en place afin d\u2019acheminer cette lettre au bon endroit et pr\u00e9cis\u00e9ment au bon moment.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Il avait envoy\u00e9 un couple de Floride \u00e0 Arcata, en Californie, pour rencontrer une famille qui savait que mon p\u00e8re avait une petite scierie \u00e0 deux heures de route dans les montagnes; c\u2019est l\u00e0 qu\u2019ils nous ont rencontr\u00e9s, ma femme et moi, et qu\u2019ils nous ont convaincus d\u2019aller en Colombie avec eux. Dieu a ensuite permis que notre ch\u00e8que soit endommag\u00e9, nous laissant sans moyens sur les marches du bureau de la f\u00e9d\u00e9ration \u00e0 Bogota au moment m\u00eame o\u00f9 est pass\u00e9 le pasteur Niemann. Nous sommes ensuite rentr\u00e9s aux \u00c9tats-Unis et avons appris \u00e0 soumettre notre vie enti\u00e8re \u00e0 Dieu, puis il nous a inspir\u00e9s \u00e0 faire un don de bulldozer et \u00e0 \u00e9crire une lettre au pasteur Niemann. Il s\u2019est ensuite assur\u00e9 que la lettre arrive pendant la pause du midi le jour m\u00eame de la r\u00e9union du conseil o\u00f9 la proposition de construction de l\u2019\u00e9cole serait accept\u00e9e ou rejet\u00e9e. Dieu fait toujours les choses au moment parfait!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Chers amis, nous servons un Dieu merveilleux! Pour ceux qui se soumettent sinc\u00e8rement \u00e0 lui, ce type d\u2019exp\u00e9rience devient monnaie courante, sans jamais pour autant perdre son facteur d\u2019\u00e9merveillement!\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Howard Williams, un missionnaire et pasteur \u00e0 la retraite ayant servi en Bolivie, aux Philippines, en Alaska et en Idaho, vit actuellement dans le centre de l\u2019Oregon.<\/span><\/p>\n<p>Traduction : Marie-Mich\u00e8le Robitaille<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lorsque nous nous soumettons \u00e0 Dieu, il s\u2019occupe du reste. Le 30 octobre 2024 | Silver Spring, Maryland, \u00c9tats-Unis | Howard Williams pour Adventist Review C\u2019\u00e9tait un soir d\u2019automne 1974&#8230;.<\/p>\n","protected":false},"author":3,"featured_media":121421,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[18,19],"tags":[],"class_list":["post-121602","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles-de-leglise-mondiale","category-rss-francais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Toujours le moment parfait - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/interamerica.org\/fr\/2024\/10\/toujours-le-moment-parfait\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Toujours le moment parfait - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division\" \/>\n<meta property=\"og:description\" content=\"Lorsque nous nous soumettons \u00e0 Dieu, il s\u2019occupe du reste. Le 30 octobre 2024 | Silver Spring, Maryland, \u00c9tats-Unis | Howard Williams pour Adventist Review C\u2019\u00e9tait un soir d\u2019automne 1974....\" \/>\n<meta property=\"og:url\" content=\"https:\/\/interamerica.org\/fr\/2024\/10\/toujours-le-moment-parfait\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-30T16:26:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-01T14:31:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/interamerica.org\/wp-content\/uploads\/2024\/10\/michael-baron-yqsxw2yvqyu-unsplash-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"libna\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"libna\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2024\\\/10\\\/toujours-le-moment-parfait\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2024\\\/10\\\/toujours-le-moment-parfait\\\/\"},\"author\":{\"name\":\"libna\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/#\\\/schema\\\/person\\\/29998f2bc2d8bd0d38662909289b54f1\"},\"headline\":\"Toujours le moment parfait\",\"datePublished\":\"2024-10-30T16:26:31+00:00\",\"dateModified\":\"2024-11-01T14:31:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2024\\\/10\\\/toujours-le-moment-parfait\\\/\"},\"wordCount\":1435,\"image\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2024\\\/10\\\/toujours-le-moment-parfait\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/michael-baron-yqsxw2yvqyu-unsplash-scaled.jpg\",\"articleSection\":[\"Nouvelles de l'\u00c9glise mondiale\",\"RSS Fran\u00e7ais\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2024\\\/10\\\/toujours-le-moment-parfait\\\/\",\"url\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2024\\\/10\\\/toujours-le-moment-parfait\\\/\",\"name\":\"Toujours le moment parfait - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2024\\\/10\\\/toujours-le-moment-parfait\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2024\\\/10\\\/toujours-le-moment-parfait\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/michael-baron-yqsxw2yvqyu-unsplash-scaled.jpg\",\"datePublished\":\"2024-10-30T16:26:31+00:00\",\"dateModified\":\"2024-11-01T14:31:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/#\\\/schema\\\/person\\\/29998f2bc2d8bd0d38662909289b54f1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2024\\\/10\\\/toujours-le-moment-parfait\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/interamerica.org\\\/fr\\\/2024\\\/10\\\/toujours-le-moment-parfait\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2024\\\/10\\\/toujours-le-moment-parfait\\\/#primaryimage\",\"url\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/michael-baron-yqsxw2yvqyu-unsplash-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/michael-baron-yqsxw2yvqyu-unsplash-scaled.jpg\",\"width\":2560,\"height\":1920,\"caption\":\"[Photo: Michel Baron\\\/Unsplash]\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2024\\\/10\\\/toujours-le-moment-parfait\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Toujours le moment parfait\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/\",\"name\":\"\u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/#\\\/schema\\\/person\\\/29998f2bc2d8bd0d38662909289b54f1\",\"name\":\"libna\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7c5bd30ae4b47a9ba3c856590957fd1d96dc588bf3ac05719d247e126840331f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7c5bd30ae4b47a9ba3c856590957fd1d96dc588bf3ac05719d247e126840331f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7c5bd30ae4b47a9ba3c856590957fd1d96dc588bf3ac05719d247e126840331f?s=96&d=mm&r=g\",\"caption\":\"libna\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Toujours le moment parfait - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/interamerica.org\/fr\/2024\/10\/toujours-le-moment-parfait\/","og_locale":"fr_FR","og_type":"article","og_title":"Toujours le moment parfait - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division","og_description":"Lorsque nous nous soumettons \u00e0 Dieu, il s\u2019occupe du reste. Le 30 octobre 2024 | Silver Spring, Maryland, \u00c9tats-Unis | Howard Williams pour Adventist Review C\u2019\u00e9tait un soir d\u2019automne 1974....","og_url":"https:\/\/interamerica.org\/fr\/2024\/10\/toujours-le-moment-parfait\/","og_site_name":"\u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division","article_published_time":"2024-10-30T16:26:31+00:00","article_modified_time":"2024-11-01T14:31:22+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/interamerica.org\/wp-content\/uploads\/2024\/10\/michael-baron-yqsxw2yvqyu-unsplash-scaled.jpg","type":"image\/jpeg"}],"author":"libna","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"libna","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/interamerica.org\/fr\/2024\/10\/toujours-le-moment-parfait\/#article","isPartOf":{"@id":"https:\/\/interamerica.org\/fr\/2024\/10\/toujours-le-moment-parfait\/"},"author":{"name":"libna","@id":"https:\/\/interamerica.org\/fr\/#\/schema\/person\/29998f2bc2d8bd0d38662909289b54f1"},"headline":"Toujours le moment parfait","datePublished":"2024-10-30T16:26:31+00:00","dateModified":"2024-11-01T14:31:22+00:00","mainEntityOfPage":{"@id":"https:\/\/interamerica.org\/fr\/2024\/10\/toujours-le-moment-parfait\/"},"wordCount":1435,"image":{"@id":"https:\/\/interamerica.org\/fr\/2024\/10\/toujours-le-moment-parfait\/#primaryimage"},"thumbnailUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2024\/10\/michael-baron-yqsxw2yvqyu-unsplash-scaled.jpg","articleSection":["Nouvelles de l'\u00c9glise mondiale","RSS Fran\u00e7ais"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/interamerica.org\/fr\/2024\/10\/toujours-le-moment-parfait\/","url":"https:\/\/interamerica.org\/fr\/2024\/10\/toujours-le-moment-parfait\/","name":"Toujours le moment parfait - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division","isPartOf":{"@id":"https:\/\/interamerica.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/interamerica.org\/fr\/2024\/10\/toujours-le-moment-parfait\/#primaryimage"},"image":{"@id":"https:\/\/interamerica.org\/fr\/2024\/10\/toujours-le-moment-parfait\/#primaryimage"},"thumbnailUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2024\/10\/michael-baron-yqsxw2yvqyu-unsplash-scaled.jpg","datePublished":"2024-10-30T16:26:31+00:00","dateModified":"2024-11-01T14:31:22+00:00","author":{"@id":"https:\/\/interamerica.org\/fr\/#\/schema\/person\/29998f2bc2d8bd0d38662909289b54f1"},"breadcrumb":{"@id":"https:\/\/interamerica.org\/fr\/2024\/10\/toujours-le-moment-parfait\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/interamerica.org\/fr\/2024\/10\/toujours-le-moment-parfait\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/interamerica.org\/fr\/2024\/10\/toujours-le-moment-parfait\/#primaryimage","url":"https:\/\/interamerica.org\/wp-content\/uploads\/2024\/10\/michael-baron-yqsxw2yvqyu-unsplash-scaled.jpg","contentUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2024\/10\/michael-baron-yqsxw2yvqyu-unsplash-scaled.jpg","width":2560,"height":1920,"caption":"[Photo: Michel Baron\/Unsplash]"},{"@type":"BreadcrumbList","@id":"https:\/\/interamerica.org\/fr\/2024\/10\/toujours-le-moment-parfait\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/interamerica.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Toujours le moment parfait"}]},{"@type":"WebSite","@id":"https:\/\/interamerica.org\/fr\/#website","url":"https:\/\/interamerica.org\/fr\/","name":"\u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/interamerica.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/interamerica.org\/fr\/#\/schema\/person\/29998f2bc2d8bd0d38662909289b54f1","name":"libna","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7c5bd30ae4b47a9ba3c856590957fd1d96dc588bf3ac05719d247e126840331f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7c5bd30ae4b47a9ba3c856590957fd1d96dc588bf3ac05719d247e126840331f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7c5bd30ae4b47a9ba3c856590957fd1d96dc588bf3ac05719d247e126840331f?s=96&d=mm&r=g","caption":"libna"}}]}},"_links":{"self":[{"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/posts\/121602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/comments?post=121602"}],"version-history":[{"count":0,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/posts\/121602\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/media\/121421"}],"wp:attachment":[{"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/media?parent=121602"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/categories?post=121602"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/tags?post=121602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}