{"id":32750,"date":"2017-01-12T00:00:00","date_gmt":"2017-01-12T04:00:00","guid":{"rendered":"http:\/\/192.81.217.108\/interamerica\/2017\/01\/linter-amerique-simplique-dans-la-consolidation-des-familles-pastorales\/"},"modified":"2018-03-20T13:05:48","modified_gmt":"2018-03-20T17:05:48","slug":"linter-amerique-simplique-dans-la-consolidation-des-familles-pastorales","status":"publish","type":"post","link":"https:\/\/interamerica.org\/fr\/2017\/01\/linter-amerique-simplique-dans-la-consolidation-des-familles-pastorales\/","title":{"rendered":"L\u2019Inter Am\u00e9rique s\u2019implique dans la consolidation des familles pastorales"},"content":{"rendered":"<div id=\"attachment_25681\" style=\"width: 449px\" class=\"wp-caption alignright\"><a href=\"\/interamerica\/wp-content\/uploads\/2017\/06\/InHisHands-squarebanner.png\" rel=\"fancybox\" title=\"L\u2019Inter Am\u00e9rique s\u2019implique dans la consolidation des familles pastorales\"><img fetchpriority=\"high\" decoding=\"async\" aria-describedby=\"caption-attachment-25681\" class=\" wp-image-25681\" src=\"\/interamerica\/wp-content\/uploads\/2017\/06\/InHisHands-squarebanner-1024x925.png\" alt=\"\" width=\"439\" height=\"396\" \/><\/a><p id=\"caption-attachment-25681\" class=\"wp-caption-text\">Image de la Division Inter Am\u00e9ricaine<\/p><\/div>\n<p>12 Janvier 2017 \u2013 Miami, Floride, Etats Unis \u2013 Libna Stevens\/DIA<\/p>\n<p>Avoir des familles pastorales spirituellement solides signifie avoir des congr\u00e9gations spirituellement fortes. C\u2019est le message important que l\u2019Eglise Adventiste du Septi\u00e8me Jour en Inter Am\u00e9rique a fait passer \u00e0 ses 3700 pasteurs dans le territoire.<\/p>\n<p>Les pasteurs et leurs familles auront l\u2019opportunit\u00e9 d\u2019adorer et de prier ensemble chaque jour avec des milliers d\u2019autres familles pastorales \u00e0 l\u2019occasion d\u2019une semaine de pri\u00e8re sp\u00e9ciale en ligne qui aura lieu du 22 au 27 janvier 2017.<\/p>\n<p>La semaine de pri\u00e8re dont le th\u00e8me est \u00ab Dans Ses Mains, \u00bb vise \u00e0 inspirer les couples pastoraux et leurs enfants \u00e0 prier et \u00e0 \u00e9tudier la parole de Dieu et \u00e0 mettre l\u2019accent sur le fait de remettre leurs vies entre les mains de Dieu dans le but de croitre ensemble spirituellement, et de servir l\u2019\u00e9glise et la communaut\u00e9 en proclamant la bonne nouvelle du salut.<\/p>\n<p>\u00ab Nous voulons d\u00e9buter l\u2019ann\u00e9e en rappelant \u00e0 nos familles pastorales qu\u2019elles ne sont pas seules, que le Seigneur nous guide et nous donne les outils et la protection n\u00e9cessaires pour que nous demeurions pr\u00eats et que nous tenions fermes pour Sa prochaine venue, \u00bb a d\u00e9clar\u00e9 pasteur H\u00e9ctor Sanchez, secr\u00e9taire de l\u2019association pastorale pour l\u2019Eglise Adventiste en Inter Am\u00e9rique.<\/p>\n<p>Pasteur Sanchez a indiqu\u00e9 que la semaine de pri\u00e8re en ligne est une initiative conjointe des Minist\u00e8res de la Famille et de l\u2019Association Pastorale, une initiative qui pendant trois ans d\u2019affil\u00e9e s\u2019est av\u00e9r\u00e9e \u00eatre une b\u00e9n\u00e9diction pour les familles pastorales qui exercent un minist\u00e8re aupr\u00e8s des plus de 20000 \u00e9glises et groupes \u00e0 travers la Division Inter Am\u00e9ricaine (DIA).<\/p>\n<p>\u00ab Nos pasteurs sont si affair\u00e9s \u00e0 s\u2019occuper de tant de congr\u00e9gations que nous voulons nous assurer qu\u2019ils fassent une pause pour se joindre \u00e0 nous de dimanche \u00e0 vendredi pour que nous nous r\u00e9jouissions ensemble dans la parole de Dieu, \u00bb a dit H\u00e9ctor Sanchez.<\/p>\n<p>Avec un effectif de plus de 3,7 millions de membres, un pasteur en Inter Am\u00e9rique a en moyenne cinq ou six \u00e9glises. Dans une r\u00e9gion de la Colombie, un pasteur peut avoir la charge de 15 \u00e9glises, \u00e0 d\u2019autres endroits cela peut m\u00eame \u00eatre plus a expliqu\u00e9 pasteur Sanchez.<\/p>\n<p>\u00ab Les familles pastorales sont le fer de lance dans notre \u00e9glise, elles motivent et guident l\u2019\u00e9glise dans l\u2019accomplissement de la mission, et il est donc de la plus grande importance que les membres de ces familles prennent le temps de prier les uns pour les autres et pour les autres familles pastorales dans tout le territoire pendant cette semaine, \u00bb a-t-il dit.<\/p>\n<p>Les pasteurs et leurs familles peuvent choisir le moment qui convient le mieux \u00e0 leur emploi du temps pour voir le programme de culte quotidien en ligne qui comprend 25 minutes de musique, de pri\u00e8re, de message spirituel et de t\u00e9moignages venus de tout le territoire. Le programme sera disponible en anglais, en espagnol et en fran\u00e7ais.<\/p>\n<p>Pour voir la Semaine de Pri\u00e8re des Familles Pastorales de la DIA du 22 au 27 janvier 2017, cliquez sur la banderole sp\u00e9ciale sur le site<br \/>\n<a href=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/\">interamerica.org<\/a><\/p>\n<p>Traduction: Patrick Luciathe<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avoir des familles pastorales spirituellement solides signifie avoir des congr\u00e9gations spirituellement fortes. C\u2019est le message important que l\u2019Eglise Adventiste du Septi\u00e8me Jour en Inter Am\u00e9rique a fait passer \u00e0 ses 3700 pasteurs dans le territoire.  Les pasteurs et leurs familles auront l\u2019opportunit\u00e9 d\u2019adorer et de prier ensemble chaque jour avec des milliers d\u2019autres familles pastorales \u00e0 l\u2019occasion d\u2019une semaine de pri\u00e8re sp\u00e9ciale en ligne qui aura lieu du 22 au 27 janvier 2017.<\/p>\n","protected":false},"author":1,"featured_media":29140,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[20,19],"tags":[],"class_list":["post-32750","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles-du-siege-de-la-division","category-rss-francais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u2019Inter Am\u00e9rique s\u2019implique dans la consolidation des familles pastorales - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/interamerica.org\/fr\/2017\/01\/linter-amerique-simplique-dans-la-consolidation-des-familles-pastorales\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019Inter Am\u00e9rique s\u2019implique dans la consolidation des familles pastorales - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division\" \/>\n<meta property=\"og:description\" content=\"Avoir des familles pastorales spirituellement solides signifie avoir des congr\u00e9gations spirituellement fortes. C\u2019est le message important que l\u2019Eglise Adventiste du Septi\u00e8me Jour en Inter Am\u00e9rique a fait passer \u00e0 ses 3700 pasteurs dans le territoire. Les pasteurs et leurs familles auront l\u2019opportunit\u00e9 d\u2019adorer et de prier ensemble chaque jour avec des milliers d\u2019autres familles pastorales \u00e0 l\u2019occasion d\u2019une semaine de pri\u00e8re sp\u00e9ciale en ligne qui aura lieu du 22 au 27 janvier 2017.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/interamerica.org\/fr\/2017\/01\/linter-amerique-simplique-dans-la-consolidation-des-familles-pastorales\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division\" \/>\n<meta property=\"article:published_time\" content=\"2017-01-12T04:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-03-20T17:05:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/interamerica.org\/wp-content\/uploads\/2017\/06\/InHisHands-squarebanner.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1528\" \/>\n\t<meta property=\"og:image:height\" content=\"1380\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Lorenzo Verduzco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lorenzo Verduzco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2017\\\/01\\\/linter-amerique-simplique-dans-la-consolidation-des-familles-pastorales\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2017\\\/01\\\/linter-amerique-simplique-dans-la-consolidation-des-familles-pastorales\\\/\"},\"author\":{\"name\":\"Lorenzo Verduzco\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/#\\\/schema\\\/person\\\/68ede8bdc292885bb76c1e3810e73c39\"},\"headline\":\"L\u2019Inter Am\u00e9rique s\u2019implique dans la consolidation des familles pastorales\",\"datePublished\":\"2017-01-12T04:00:00+00:00\",\"dateModified\":\"2018-03-20T17:05:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2017\\\/01\\\/linter-amerique-simplique-dans-la-consolidation-des-familles-pastorales\\\/\"},\"wordCount\":566,\"image\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2017\\\/01\\\/linter-amerique-simplique-dans-la-consolidation-des-familles-pastorales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/InHisHands-squarebanner.png\",\"articleSection\":[\"Nouvelles du si\u00e8ge de la division\",\"RSS Fran\u00e7ais\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2017\\\/01\\\/linter-amerique-simplique-dans-la-consolidation-des-familles-pastorales\\\/\",\"url\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2017\\\/01\\\/linter-amerique-simplique-dans-la-consolidation-des-familles-pastorales\\\/\",\"name\":\"L\u2019Inter Am\u00e9rique s\u2019implique dans la consolidation des familles pastorales - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2017\\\/01\\\/linter-amerique-simplique-dans-la-consolidation-des-familles-pastorales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2017\\\/01\\\/linter-amerique-simplique-dans-la-consolidation-des-familles-pastorales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/InHisHands-squarebanner.png\",\"datePublished\":\"2017-01-12T04:00:00+00:00\",\"dateModified\":\"2018-03-20T17:05:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/#\\\/schema\\\/person\\\/68ede8bdc292885bb76c1e3810e73c39\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2017\\\/01\\\/linter-amerique-simplique-dans-la-consolidation-des-familles-pastorales\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/interamerica.org\\\/fr\\\/2017\\\/01\\\/linter-amerique-simplique-dans-la-consolidation-des-familles-pastorales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2017\\\/01\\\/linter-amerique-simplique-dans-la-consolidation-des-familles-pastorales\\\/#primaryimage\",\"url\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/InHisHands-squarebanner.png\",\"contentUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/InHisHands-squarebanner.png\",\"width\":1528,\"height\":1380},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2017\\\/01\\\/linter-amerique-simplique-dans-la-consolidation-des-familles-pastorales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019Inter Am\u00e9rique s\u2019implique dans la consolidation des familles pastorales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/\",\"name\":\"\u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/#\\\/schema\\\/person\\\/68ede8bdc292885bb76c1e3810e73c39\",\"name\":\"Lorenzo Verduzco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g\",\"caption\":\"Lorenzo Verduzco\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019Inter Am\u00e9rique s\u2019implique dans la consolidation des familles pastorales - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/interamerica.org\/fr\/2017\/01\/linter-amerique-simplique-dans-la-consolidation-des-familles-pastorales\/","og_locale":"fr_FR","og_type":"article","og_title":"L\u2019Inter Am\u00e9rique s\u2019implique dans la consolidation des familles pastorales - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division","og_description":"Avoir des familles pastorales spirituellement solides signifie avoir des congr\u00e9gations spirituellement fortes. C\u2019est le message important que l\u2019Eglise Adventiste du Septi\u00e8me Jour en Inter Am\u00e9rique a fait passer \u00e0 ses 3700 pasteurs dans le territoire. Les pasteurs et leurs familles auront l\u2019opportunit\u00e9 d\u2019adorer et de prier ensemble chaque jour avec des milliers d\u2019autres familles pastorales \u00e0 l\u2019occasion d\u2019une semaine de pri\u00e8re sp\u00e9ciale en ligne qui aura lieu du 22 au 27 janvier 2017.","og_url":"https:\/\/interamerica.org\/fr\/2017\/01\/linter-amerique-simplique-dans-la-consolidation-des-familles-pastorales\/","og_site_name":"\u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division","article_published_time":"2017-01-12T04:00:00+00:00","article_modified_time":"2018-03-20T17:05:48+00:00","og_image":[{"width":1528,"height":1380,"url":"https:\/\/interamerica.org\/wp-content\/uploads\/2017\/06\/InHisHands-squarebanner.png","type":"image\/png"}],"author":"Lorenzo Verduzco","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Lorenzo Verduzco","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/interamerica.org\/fr\/2017\/01\/linter-amerique-simplique-dans-la-consolidation-des-familles-pastorales\/#article","isPartOf":{"@id":"https:\/\/interamerica.org\/fr\/2017\/01\/linter-amerique-simplique-dans-la-consolidation-des-familles-pastorales\/"},"author":{"name":"Lorenzo Verduzco","@id":"https:\/\/interamerica.org\/fr\/#\/schema\/person\/68ede8bdc292885bb76c1e3810e73c39"},"headline":"L\u2019Inter Am\u00e9rique s\u2019implique dans la consolidation des familles pastorales","datePublished":"2017-01-12T04:00:00+00:00","dateModified":"2018-03-20T17:05:48+00:00","mainEntityOfPage":{"@id":"https:\/\/interamerica.org\/fr\/2017\/01\/linter-amerique-simplique-dans-la-consolidation-des-familles-pastorales\/"},"wordCount":566,"image":{"@id":"https:\/\/interamerica.org\/fr\/2017\/01\/linter-amerique-simplique-dans-la-consolidation-des-familles-pastorales\/#primaryimage"},"thumbnailUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2017\/06\/InHisHands-squarebanner.png","articleSection":["Nouvelles du si\u00e8ge de la division","RSS Fran\u00e7ais"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/interamerica.org\/fr\/2017\/01\/linter-amerique-simplique-dans-la-consolidation-des-familles-pastorales\/","url":"https:\/\/interamerica.org\/fr\/2017\/01\/linter-amerique-simplique-dans-la-consolidation-des-familles-pastorales\/","name":"L\u2019Inter Am\u00e9rique s\u2019implique dans la consolidation des familles pastorales - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division","isPartOf":{"@id":"https:\/\/interamerica.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/interamerica.org\/fr\/2017\/01\/linter-amerique-simplique-dans-la-consolidation-des-familles-pastorales\/#primaryimage"},"image":{"@id":"https:\/\/interamerica.org\/fr\/2017\/01\/linter-amerique-simplique-dans-la-consolidation-des-familles-pastorales\/#primaryimage"},"thumbnailUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2017\/06\/InHisHands-squarebanner.png","datePublished":"2017-01-12T04:00:00+00:00","dateModified":"2018-03-20T17:05:48+00:00","author":{"@id":"https:\/\/interamerica.org\/fr\/#\/schema\/person\/68ede8bdc292885bb76c1e3810e73c39"},"breadcrumb":{"@id":"https:\/\/interamerica.org\/fr\/2017\/01\/linter-amerique-simplique-dans-la-consolidation-des-familles-pastorales\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/interamerica.org\/fr\/2017\/01\/linter-amerique-simplique-dans-la-consolidation-des-familles-pastorales\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/interamerica.org\/fr\/2017\/01\/linter-amerique-simplique-dans-la-consolidation-des-familles-pastorales\/#primaryimage","url":"https:\/\/interamerica.org\/wp-content\/uploads\/2017\/06\/InHisHands-squarebanner.png","contentUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2017\/06\/InHisHands-squarebanner.png","width":1528,"height":1380},{"@type":"BreadcrumbList","@id":"https:\/\/interamerica.org\/fr\/2017\/01\/linter-amerique-simplique-dans-la-consolidation-des-familles-pastorales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/interamerica.org\/fr\/"},{"@type":"ListItem","position":2,"name":"L\u2019Inter Am\u00e9rique s\u2019implique dans la consolidation des familles pastorales"}]},{"@type":"WebSite","@id":"https:\/\/interamerica.org\/fr\/#website","url":"https:\/\/interamerica.org\/fr\/","name":"\u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/interamerica.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/interamerica.org\/fr\/#\/schema\/person\/68ede8bdc292885bb76c1e3810e73c39","name":"Lorenzo Verduzco","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g","caption":"Lorenzo Verduzco"}}]}},"_links":{"self":[{"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/posts\/32750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/comments?post=32750"}],"version-history":[{"count":0,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/posts\/32750\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/media\/29140"}],"wp:attachment":[{"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/media?parent=32750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/categories?post=32750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/tags?post=32750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}