{"id":39545,"date":"2018-02-15T00:00:00","date_gmt":"2018-02-15T04:00:00","guid":{"rendered":"http:\/\/192.81.217.108\/2018\/02\/a-porto-rico-leglise-adventiste-continue-de-consolider-les-communautes-au-lendemain-de-la-devastation-causee-par-les-ouragans\/"},"modified":"2018-04-10T10:07:35","modified_gmt":"2018-04-10T14:07:35","slug":"a-porto-rico-leglise-adventiste-continue-de-consolider-les-communautes-au-lendemain-de-la-devastation-causee-par-les-ouragans","status":"publish","type":"post","link":"https:\/\/interamerica.org\/fr\/2018\/02\/a-porto-rico-leglise-adventiste-continue-de-consolider-les-communautes-au-lendemain-de-la-devastation-causee-par-les-ouragans\/","title":{"rendered":"A Porto Rico, l\u2019Eglise Adventiste continue de consolider les communaut\u00e9s au lendemain de la d\u00e9vastation caus\u00e9e par les ouragans"},"content":{"rendered":"<div id=\"attachment_33356\" style=\"width: 752px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/02\/PURU-homerebuilt-SanSebastian.gif\" rel=\"fancybox\" title=\"A Porto Rico, l\u2019Eglise Adventiste continue de consolider les communaut\u00e9s au lendemain de la d\u00e9vastation caus\u00e9e par les ouragans\"><img fetchpriority=\"high\" decoding=\"async\" aria-describedby=\"caption-attachment-33356\" class=\" wp-image-33356\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/02\/PURU-homerebuilt-SanSebastian.gif\" alt=\"\" width=\"742\" height=\"464\" \/><\/a><p id=\"caption-attachment-33356\" class=\"wp-caption-text\">ADRA et World Renew se sont associ\u00e9s pour reconstruire deux maisons d\u00e9truites par l\u2019Ouragan Maria dans la ville de San Sebastian, dans l\u2019ouest de Porto Rico. L\u2019\u00e9glise a un plan pour reconstruire les toitures d\u00e9truites par la temp\u00eate. Image de Libna Stevens \/ DIA<\/p><\/div>\n<p>8 F\u00e9vrier 2018 | Mayaguez, Porto Rico | Libna Stevens \/ DIA<\/p>\n<p>Porto Rico aura pour toujours deux histoires: l\u2019une avant l\u2019Ouragan Maria et l\u2019autre apr\u00e8s.<\/p>\n<p>L\u2019histoire d\u2019avant semble tr\u00e8s lointaine, et l\u2019histoire d\u2019apr\u00e8s est encore en cours, dit pasteur Jose Alberto Rodr\u00edguez, pr\u00e9sident de l\u2019Eglise Adventiste du Septi\u00e8me jour \u00e0 Porto Rico.<\/p>\n<div id=\"attachment_33341\" style=\"width: 375px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/02\/JoseARodriguez-PURU.gif\" rel=\"fancybox\" title=\"A Porto Rico, l\u2019Eglise Adventiste continue de consolider les communaut\u00e9s au lendemain de la d\u00e9vastation caus\u00e9e par les ouragans\"><img decoding=\"async\" aria-describedby=\"caption-attachment-33341\" class=\" wp-image-33341\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/02\/JoseARodriguez-PURU.gif\" alt=\"\" width=\"365\" height=\"228\" \/><\/a><p id=\"caption-attachment-33341\" class=\"wp-caption-text\">Pasteur Jose A. Rodr\u00edguez, pr\u00e9sident de l\u2019Eglise Adventiste \u00e0 Porto Rico, montre un ravin dans lequel est tomb\u00e9e une maison \u00e0 cause de l\u2019ouragan. ADRA est en train de reconstruire la maison. Image de Libna Stevens \/ DIA<\/p><\/div>\n<p>Pasteur Rodr\u00edguez n\u2019aurait jamais pens\u00e9 voir sa ch\u00e8re ile d\u00e9truite et mise compl\u00e8tement \u00e0 l\u2019arr\u00eat par la col\u00e8re d\u2019un puissant ouragan. L\u2019Ouragan Maria a frapp\u00e9 Porto Rico le 20 septembre 2017 et les effets de ce puissant cyclone de cat\u00e9gorie 5 se font toujours sentir.<\/p>\n<p>Aujourd\u2019hui, quatre mois apr\u00e8s le cyclone, 35% de l\u2019\u00eele est toujours sans \u00e9lectricit\u00e9, de nombreuses maisons attendent toujours d\u2019\u00eatre r\u00e9par\u00e9es, des entreprises ont ferm\u00e9 leurs portes, le ch\u00f4mage a augment\u00e9 et beaucoup ont besoin d\u2019aide.<\/p>\n<p><strong>L\u2019Eglise Continue de Fonctionner<\/strong><\/p>\n<p>Au milieu de d\u00e9fis extraordinaires, l\u2019\u00e9glise continue de fonctionner aujourd\u2019hui sans interruption. L\u2019\u00e9glise g\u00e8re un h\u00f4pital, une universit\u00e9, une clinique, deux stations de radio, 20 \u00e9coles primaires et secondaires et des centaines d\u2019\u00e9glises locales.<\/p>\n<p>\u00ab Dieu a \u00e9t\u00e9 bon envers nous &#8230; Dieu est si bon pour nous, \u00bb dit pasteur Rodr\u00edguez.<\/p>\n<p>La temp\u00eate n\u2019a pas stopp\u00e9 l\u2019esprit d\u2019entraide des membres d\u2019\u00e9glise et des amis dans la communaut\u00e9. Pasteur Rodr\u00edguez se rappelle de membres d\u2019\u00e9glise et de sympathisants de l\u2019\u00e9glise, dont beaucoup de chefs d\u2019entreprise, qui ont apport\u00e9 de l\u2019argent pour aider \u00e0 faire fonctionner l\u2019h\u00f4pital Adventiste et l\u2019universit\u00e9 au moment o\u00f9 les banques \u00e9taient ferm\u00e9es et o\u00f9 les liquidit\u00e9s n\u2019\u00e9taient pas disponibles.<\/p>\n<div id=\"attachment_33359\" style=\"width: 375px\" class=\"wp-caption alignright\"><a href=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/02\/PURU-power-trucks.gif\" rel=\"fancybox\" title=\"A Porto Rico, l\u2019Eglise Adventiste continue de consolider les communaut\u00e9s au lendemain de la d\u00e9vastation caus\u00e9e par les ouragans\"><img decoding=\"async\" aria-describedby=\"caption-attachment-33359\" class=\" wp-image-33359\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/02\/PURU-power-trucks.gif\" alt=\"\" width=\"365\" height=\"228\" \/><\/a><p id=\"caption-attachment-33359\" class=\"wp-caption-text\">Des camions r\u00e9parant des lignes \u00e9lectriques dans la banlieue de Mayaguez, \u00e0 Porto Rico. Image d\u2019Abel M\u00e1rquez \/ DIA<\/p><\/div>\n<p>Des centaines de membres ont afflu\u00e9 dans leurs \u00e9glises locales pour nettoyer, cuisiner et accueillir les gens de leurs communaut\u00e9s en leur offrant des repas chauds tous les jours pendant des semaines apr\u00e8s le passage de l\u2019ouragan.<\/p>\n<p>\u00ab Chaque \u00e9glise sur cette \u00eele a un coordinateur ADRA, donc quand l\u2019\u00e9lectricit\u00e9 a \u00e9t\u00e9 coup\u00e9e et les \u00e9glises n\u2019\u00e9taient plus en mesure de communiquer avec les dirigeants, ils se sont imm\u00e9diatement mobilis\u00e9s comme ils ont form\u00e9s \u00e0 le faire dans leurs communaut\u00e9s environnantes, \u00bb a dit pasteur Rodr\u00edguez. Si ce n\u2019\u00e9tait pour cette structure, les choses auraient pu prendre beaucoup plus de temps, a-t-il expliqu\u00e9.<\/p>\n<p>Il existe d\u2019innombrables r\u00e9cits relatant la mani\u00e8re dont les membres d\u2019\u00e9glise continuent \u00e0 servir dans leurs communaut\u00e9s, m\u00eame encore aujourd\u2019hui. Leur engagement \u00e0 aider ceux qui les entourent \u00e9meut encore pasteur Rodr\u00edguez. \u00ab Vous trouvez des membres d\u2019\u00e9glise qui ont un c\u0153ur d\u2019or partout o\u00f9 vous allez. \u00bb<\/p>\n<p>\u00ab Apr\u00e8s \u2018Maria\u2019 nous avons vraiment d\u00e9couvert qu\u2019il y a beaucoup de personnes qui vivent dans la pauvret\u00e9 autour de nous, \u00bb a d\u00e9clar\u00e9 pasteur Rodr\u00edguez. \u00ab Nous avons des gens tr\u00e8s pauvres, des gens humbles que nous ne connaissions pas. \u00bb<\/p>\n<p>Les plans et les programmes d\u2019\u00e9vang\u00e9lisation mis en place avant le cyclone font maintenant l\u2019objet d\u2019une approche diff\u00e9rente apr\u00e8s l\u2019ouragan, explique pasteur Rodr\u00edguez. \u00ab Notre \u00e9vang\u00e9lisation publique maintenant consiste \u00e0 servir dans la communaut\u00e9, \u00e0 aider ceux qui sont dans le besoin. C\u2019est un testament beaucoup plus grand \u00e0 un moment o\u00f9 il y a un tel besoin d\u2019amour, de compassion et d\u2019esp\u00e9rance. \u00bb<\/p>\n<div id=\"attachment_33353\" style=\"width: 375px\" class=\"wp-caption alignright\"><a href=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/02\/PURU-foodsupplies.gif\" rel=\"fancybox\" title=\"A Porto Rico, l\u2019Eglise Adventiste continue de consolider les communaut\u00e9s au lendemain de la d\u00e9vastation caus\u00e9e par les ouragans\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-33353\" class=\" wp-image-33353\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/02\/PURU-foodsupplies.gif\" alt=\"\" width=\"365\" height=\"228\" \/><\/a><p id=\"caption-attachment-33353\" class=\"wp-caption-text\">Aliments non p\u00e9rissables et provisions au si\u00e8ge de l\u2019\u00e9glise en attente d\u2019\u00eatre bient\u00f4t distribu\u00e9s aux familles sans emploi dans les communaut\u00e9s de Mayaguez, \u00e0 Puerto Rico. Image de Libna Stevens \/ DIA<\/p><\/div>\n<p><strong>L\u2019Aide d\u2019ADRA Continue<\/strong><\/p>\n<p>En outre, l\u2019\u00c9glise Adventiste a accru sa visibilit\u00e9 en tant qu\u2019\u00e9glise se souciant des autres, une \u00e9glise qui agit rapidement pour venir en aide \u00e0 ceux qui luttent encore pour reconstruire leurs vies. Gr\u00e2ce \u00e0 l\u2019Agence Adventiste de D\u00e9veloppement et de Secours (ADRA) International et ADRA Inter Am\u00e9rique et ADRA Porto Rico, l\u2019\u00e9glise supervise la construction de 125 nouvelles toitures sur des maisons qui ne sont pas \u00e9ligibles pour recevoir l\u2019aide de la FEMA (Agence F\u00e9d\u00e9rale de Gestion d\u2019Urgence), a expliqu\u00e9 pasteur Rodr\u00edguez.<\/p>\n<p>\u00ab Chaque jour apr\u00e8s l\u2019ouragan est un rappel que Dieu nous a appel\u00e9s \u00e0 servir ceux qui sont dans le besoin, \u00bb a expliqu\u00e9 Jose Rodr\u00edguez. \u00ab Nos \u00e9glises doivent \u00eatre des lampes qui brillent encore plus fort dans leurs communaut\u00e9s. \u00bb<\/p>\n<p>Il y a une centaine d\u2019\u00e9glises Adventistes qui n\u2019ont toujours pas d\u2019\u00e9lectricit\u00e9, rapporte pasteur Rodr\u00edguez. Cela repr\u00e9sente un tiers des 320 \u00e9glises et groupes dans toute l\u2019\u00eele. \u00ab Certaines fonctionnent avec des groupes \u00e9lectrog\u00e8nes alors que d\u2019autres n\u2019ont pas de courant et ont d\u00e9plac\u00e9 l\u2019horaire de leurs services de culte pour les avoir plus t\u00f4t dans la journ\u00e9e quand le soleil n\u2019est pas aussi chaud, a-t-il expliqu\u00e9.<\/p>\n<p><strong>D\u00e9fis Financiers<\/strong><\/p>\n<p>Quelque 345000 personnes ont quitt\u00e9 Porto Rico depuis le passage de \u00ab Maria \u00bb dont environ 2000 membres d\u2019\u00e9glise. Cela a amen\u00e9 les principaux dirigeants de l\u2019\u00e9glise \u00e0 regarder de plus pr\u00e8s leur gestion financi\u00e8re a indiqu\u00e9 Luis Rivera, tr\u00e9sorier de l\u2019Eglise Adventiste \u00e0 Porto Rico.<\/p>\n<div id=\"attachment_33347\" style=\"width: 374px\" class=\"wp-caption alignright\"><a href=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/02\/LuisRivera-PURU.gif\" rel=\"fancybox\" title=\"A Porto Rico, l\u2019Eglise Adventiste continue de consolider les communaut\u00e9s au lendemain de la d\u00e9vastation caus\u00e9e par les ouragans\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-33347\" class=\" wp-image-33347\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/02\/LuisRivera-PURU.gif\" alt=\"\" width=\"364\" height=\"228\" \/><\/a><p id=\"caption-attachment-33347\" class=\"wp-caption-text\">Luis Rivera, tr\u00e9sorier de l\u2019Eglise Adventiste \u00e0 Porto Rico, dit que le budget de fonctionnement de l\u2019\u00e9glise a d\u00fb \u00eatre r\u00e9ajust\u00e9 apr\u00e8s &lsquo;Maria&rsquo;. Image de Libna Stevens \/ DIA<\/p><\/div>\n<p>\u00ab Avec une \u00e9conomie en d\u00e9clin, celle qui existait avant l\u2019ouragan, \u00bb a expliqu\u00e9 Luis Rivera, \u00ab l\u2019\u00e9glise a vu une diminution de 52% des d\u00eemes au cours des deux premiers mois apr\u00e8s le cyclone. \u00bb<\/p>\n<p>Luis Rivera rapporte que 35 \u00e9tudiants ne sont pas retourn\u00e9s \u00e0 l\u2019Universit\u00e9 Adventiste des Antilles \u00e0 Mayaguez ce semestre, ce qui repr\u00e9sente une perte de 200000 $ US. De m\u00eame, 108 \u00e9l\u00e8ves ont cess\u00e9 de fr\u00e9quenter les 20 \u00e9coles primaires et secondaires de l\u2019\u00eele, ce qui \u00e9quivaut \u00e0 une perte de 300000 $ US.<\/p>\n<p>Les principaux dirigeants de l\u2019\u00e9glise ont jug\u00e9 n\u00e9cessaire de r\u00e9ajuster leur budget de fonctionnement \u00e0 environ 15% de moins. \u00ab Nos employ\u00e9s \u00e0 l\u2019union gagnent 10 pourcent de moins sur leur salaire mensuel jusqu\u2019\u00e0 nouvel ordre, \u00bb a ajout\u00e9 Luis Rivera.<\/p>\n<p>A travers tout cela, Luis Rivera r\u00e9alise que les mains de Dieu maintiennent encore l\u2019\u00e9glise forte et fonctionnelle m\u00eame au milieu de tels d\u00e9fis.<\/p>\n<p>\u00ab J\u2019ai vu un pays travailler avec plus d\u2019unit\u00e9, notre \u00e9glise plus concentr\u00e9e sur le travail missionnaire par le service, \u00bb a expliqu\u00e9 Luis Rivera. \u00ab Nos membres ont clairement r\u00e9alis\u00e9 la t\u00e2che qui consiste \u00e0 servir et \u00e0 p\u00e9n\u00e9trer dans des communaut\u00e9s non encore atteintes. \u00bb<\/p>\n<div id=\"attachment_33344\" style=\"width: 375px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/02\/JoseARodriguez-PURU2.gif\" rel=\"fancybox\" title=\"A Porto Rico, l\u2019Eglise Adventiste continue de consolider les communaut\u00e9s au lendemain de la d\u00e9vastation caus\u00e9e par les ouragans\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-33344\" class=\" wp-image-33344\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/02\/JoseARodriguez-PURU2.gif\" alt=\"\" width=\"365\" height=\"228\" \/><\/a><p id=\"caption-attachment-33344\" class=\"wp-caption-text\">Pasteur Jose A. Rodr\u00edguez, a dit les membres d\u2019\u00e9glise sont loyaux et fid\u00e8les et continueront \u00e0 servir dans leurs communaut\u00e9s en partageant l\u2019esp\u00e9rance. Image de Libna Stevens \/ DIA<\/p><\/div>\n<p>Ce qui s\u2019est av\u00e9r\u00e9 aride et sombre avec l\u2019ouragan s\u2019est transform\u00e9 en une nouvelle opportunit\u00e9 d\u2019atteindre plus de non croyants, a dit Pasteur Rodr\u00edguez. \u00ab Cette exp\u00e9rience ne nous fera pas abandonner Porto Rico. Nos membres sont loyaux et fid\u00e8les et resteront ancr\u00e9s dans les v\u00e9rit\u00e9s bibliques et continueront \u00e0 servir en partageant l\u2019esp\u00e9rance partout o\u00f9 ils iront. \u00bb<\/p>\n<p>Le r\u00e9cit de l\u2019exp\u00e9rience de l\u2019\u00e9glise \u00e0 Porto Rico apr\u00e8s &lsquo;Maria&rsquo; continuera \u00e0 \u00e9voluer, a dit pasteur Rodr\u00edguez. \u00ab Les le\u00e7ons que nous avons apprises apr\u00e8s l\u2019ouragan nous aideront \u00e0 \u00eatre mieux pr\u00e9par\u00e9s pour la prochaine saison cyclonique. \u00bb<\/p>\n<p>Il y a plus de 31000 Adventistes du Septi\u00e8me Jour qui se r\u00e9unissent pour adorer dans 320 \u00e9glises et groupes \u00e0 Porto Rico.<\/p>\n<p>Pour en savoir plus sur l\u2019Eglise Adventiste \u00e0 Porto Rico, visitez le site<br \/>\n<a href=\"mailto:http:\/\/www.upasd.org\/\">upasd.org<\/a><\/p>\n<p>Traduction: Patrick Luciathe<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Porto Rico aura pour toujours deux histoires: l\u2019une avant l\u2019Ouragan Maria et l\u2019autre apr\u00e8s.<\/p>\n<p>L\u2019histoire d\u2019avant semble tr\u00e8s lointaine, et l\u2019histoire d\u2019apr\u00e8s est encore en cours, dit pasteur Jose Alberto Rodr\u00edguez, pr\u00e9sident de l\u2019Eglise Adventiste du Septi\u00e8me jour \u00e0 Porto Rico.<\/p>\n","protected":false},"author":1,"featured_media":39460,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[21,19],"tags":[],"class_list":["post-39545","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles-du-territoire","category-rss-francais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A Porto Rico, l\u2019Eglise Adventiste continue de consolider les communaut\u00e9s au lendemain de la d\u00e9vastation caus\u00e9e par les ouragans - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/interamerica.org\/fr\/2018\/02\/a-porto-rico-leglise-adventiste-continue-de-consolider-les-communautes-au-lendemain-de-la-devastation-causee-par-les-ouragans\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Porto Rico, l\u2019Eglise Adventiste continue de consolider les communaut\u00e9s au lendemain de la d\u00e9vastation caus\u00e9e par les ouragans - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division\" \/>\n<meta property=\"og:description\" content=\"Porto Rico aura pour toujours deux histoires: l\u2019une avant l\u2019Ouragan Maria et l\u2019autre apr\u00e8s.  L\u2019histoire d\u2019avant semble tr\u00e8s lointaine, et l\u2019histoire d\u2019apr\u00e8s est encore en cours, dit pasteur Jose Alberto Rodr\u00edguez, pr\u00e9sident de l\u2019Eglise Adventiste du Septi\u00e8me jour \u00e0 Porto Rico.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/interamerica.org\/fr\/2018\/02\/a-porto-rico-leglise-adventiste-continue-de-consolider-les-communautes-au-lendemain-de-la-devastation-causee-par-les-ouragans\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-15T04:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-04-10T14:07:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/04\/puru-homerebuilt-sansebastian.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"author\" content=\"Lorenzo Verduzco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lorenzo Verduzco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/02\\\/a-porto-rico-leglise-adventiste-continue-de-consolider-les-communautes-au-lendemain-de-la-devastation-causee-par-les-ouragans\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/02\\\/a-porto-rico-leglise-adventiste-continue-de-consolider-les-communautes-au-lendemain-de-la-devastation-causee-par-les-ouragans\\\/\"},\"author\":{\"name\":\"Lorenzo Verduzco\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/#\\\/schema\\\/person\\\/68ede8bdc292885bb76c1e3810e73c39\"},\"headline\":\"A Porto Rico, l\u2019Eglise Adventiste continue de consolider les communaut\u00e9s au lendemain de la d\u00e9vastation caus\u00e9e par les ouragans\",\"datePublished\":\"2018-02-15T04:00:00+00:00\",\"dateModified\":\"2018-04-10T14:07:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/02\\\/a-porto-rico-leglise-adventiste-continue-de-consolider-les-communautes-au-lendemain-de-la-devastation-causee-par-les-ouragans\\\/\"},\"wordCount\":1478,\"image\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/02\\\/a-porto-rico-leglise-adventiste-continue-de-consolider-les-communautes-au-lendemain-de-la-devastation-causee-par-les-ouragans\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/puru-homerebuilt-sansebastian.gif\",\"articleSection\":[\"Nouvelles du territoire\",\"RSS Fran\u00e7ais\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/02\\\/a-porto-rico-leglise-adventiste-continue-de-consolider-les-communautes-au-lendemain-de-la-devastation-causee-par-les-ouragans\\\/\",\"url\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/02\\\/a-porto-rico-leglise-adventiste-continue-de-consolider-les-communautes-au-lendemain-de-la-devastation-causee-par-les-ouragans\\\/\",\"name\":\"A Porto Rico, l\u2019Eglise Adventiste continue de consolider les communaut\u00e9s au lendemain de la d\u00e9vastation caus\u00e9e par les ouragans - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/02\\\/a-porto-rico-leglise-adventiste-continue-de-consolider-les-communautes-au-lendemain-de-la-devastation-causee-par-les-ouragans\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/02\\\/a-porto-rico-leglise-adventiste-continue-de-consolider-les-communautes-au-lendemain-de-la-devastation-causee-par-les-ouragans\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/puru-homerebuilt-sansebastian.gif\",\"datePublished\":\"2018-02-15T04:00:00+00:00\",\"dateModified\":\"2018-04-10T14:07:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/#\\\/schema\\\/person\\\/68ede8bdc292885bb76c1e3810e73c39\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/02\\\/a-porto-rico-leglise-adventiste-continue-de-consolider-les-communautes-au-lendemain-de-la-devastation-causee-par-les-ouragans\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/02\\\/a-porto-rico-leglise-adventiste-continue-de-consolider-les-communautes-au-lendemain-de-la-devastation-causee-par-les-ouragans\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/02\\\/a-porto-rico-leglise-adventiste-continue-de-consolider-les-communautes-au-lendemain-de-la-devastation-causee-par-les-ouragans\\\/#primaryimage\",\"url\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/puru-homerebuilt-sansebastian.gif\",\"contentUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/puru-homerebuilt-sansebastian.gif\",\"width\":1280,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/02\\\/a-porto-rico-leglise-adventiste-continue-de-consolider-les-communautes-au-lendemain-de-la-devastation-causee-par-les-ouragans\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A Porto Rico, l\u2019Eglise Adventiste continue de consolider les communaut\u00e9s au lendemain de la d\u00e9vastation caus\u00e9e par les ouragans\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/\",\"name\":\"\u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/#\\\/schema\\\/person\\\/68ede8bdc292885bb76c1e3810e73c39\",\"name\":\"Lorenzo Verduzco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g\",\"caption\":\"Lorenzo Verduzco\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A Porto Rico, l\u2019Eglise Adventiste continue de consolider les communaut\u00e9s au lendemain de la d\u00e9vastation caus\u00e9e par les ouragans - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/interamerica.org\/fr\/2018\/02\/a-porto-rico-leglise-adventiste-continue-de-consolider-les-communautes-au-lendemain-de-la-devastation-causee-par-les-ouragans\/","og_locale":"fr_FR","og_type":"article","og_title":"A Porto Rico, l\u2019Eglise Adventiste continue de consolider les communaut\u00e9s au lendemain de la d\u00e9vastation caus\u00e9e par les ouragans - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division","og_description":"Porto Rico aura pour toujours deux histoires: l\u2019une avant l\u2019Ouragan Maria et l\u2019autre apr\u00e8s.  L\u2019histoire d\u2019avant semble tr\u00e8s lointaine, et l\u2019histoire d\u2019apr\u00e8s est encore en cours, dit pasteur Jose Alberto Rodr\u00edguez, pr\u00e9sident de l\u2019Eglise Adventiste du Septi\u00e8me jour \u00e0 Porto Rico.","og_url":"https:\/\/interamerica.org\/fr\/2018\/02\/a-porto-rico-leglise-adventiste-continue-de-consolider-les-communautes-au-lendemain-de-la-devastation-causee-par-les-ouragans\/","og_site_name":"\u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division","article_published_time":"2018-02-15T04:00:00+00:00","article_modified_time":"2018-04-10T14:07:35+00:00","og_image":[{"width":1280,"height":800,"url":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/04\/puru-homerebuilt-sansebastian.gif","type":"image\/gif"}],"author":"Lorenzo Verduzco","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Lorenzo Verduzco","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/interamerica.org\/fr\/2018\/02\/a-porto-rico-leglise-adventiste-continue-de-consolider-les-communautes-au-lendemain-de-la-devastation-causee-par-les-ouragans\/#article","isPartOf":{"@id":"https:\/\/interamerica.org\/fr\/2018\/02\/a-porto-rico-leglise-adventiste-continue-de-consolider-les-communautes-au-lendemain-de-la-devastation-causee-par-les-ouragans\/"},"author":{"name":"Lorenzo Verduzco","@id":"https:\/\/interamerica.org\/fr\/#\/schema\/person\/68ede8bdc292885bb76c1e3810e73c39"},"headline":"A Porto Rico, l\u2019Eglise Adventiste continue de consolider les communaut\u00e9s au lendemain de la d\u00e9vastation caus\u00e9e par les ouragans","datePublished":"2018-02-15T04:00:00+00:00","dateModified":"2018-04-10T14:07:35+00:00","mainEntityOfPage":{"@id":"https:\/\/interamerica.org\/fr\/2018\/02\/a-porto-rico-leglise-adventiste-continue-de-consolider-les-communautes-au-lendemain-de-la-devastation-causee-par-les-ouragans\/"},"wordCount":1478,"image":{"@id":"https:\/\/interamerica.org\/fr\/2018\/02\/a-porto-rico-leglise-adventiste-continue-de-consolider-les-communautes-au-lendemain-de-la-devastation-causee-par-les-ouragans\/#primaryimage"},"thumbnailUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/04\/puru-homerebuilt-sansebastian.gif","articleSection":["Nouvelles du territoire","RSS Fran\u00e7ais"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/interamerica.org\/fr\/2018\/02\/a-porto-rico-leglise-adventiste-continue-de-consolider-les-communautes-au-lendemain-de-la-devastation-causee-par-les-ouragans\/","url":"https:\/\/interamerica.org\/fr\/2018\/02\/a-porto-rico-leglise-adventiste-continue-de-consolider-les-communautes-au-lendemain-de-la-devastation-causee-par-les-ouragans\/","name":"A Porto Rico, l\u2019Eglise Adventiste continue de consolider les communaut\u00e9s au lendemain de la d\u00e9vastation caus\u00e9e par les ouragans - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division","isPartOf":{"@id":"https:\/\/interamerica.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/interamerica.org\/fr\/2018\/02\/a-porto-rico-leglise-adventiste-continue-de-consolider-les-communautes-au-lendemain-de-la-devastation-causee-par-les-ouragans\/#primaryimage"},"image":{"@id":"https:\/\/interamerica.org\/fr\/2018\/02\/a-porto-rico-leglise-adventiste-continue-de-consolider-les-communautes-au-lendemain-de-la-devastation-causee-par-les-ouragans\/#primaryimage"},"thumbnailUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/04\/puru-homerebuilt-sansebastian.gif","datePublished":"2018-02-15T04:00:00+00:00","dateModified":"2018-04-10T14:07:35+00:00","author":{"@id":"https:\/\/interamerica.org\/fr\/#\/schema\/person\/68ede8bdc292885bb76c1e3810e73c39"},"breadcrumb":{"@id":"https:\/\/interamerica.org\/fr\/2018\/02\/a-porto-rico-leglise-adventiste-continue-de-consolider-les-communautes-au-lendemain-de-la-devastation-causee-par-les-ouragans\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/interamerica.org\/fr\/2018\/02\/a-porto-rico-leglise-adventiste-continue-de-consolider-les-communautes-au-lendemain-de-la-devastation-causee-par-les-ouragans\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/interamerica.org\/fr\/2018\/02\/a-porto-rico-leglise-adventiste-continue-de-consolider-les-communautes-au-lendemain-de-la-devastation-causee-par-les-ouragans\/#primaryimage","url":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/04\/puru-homerebuilt-sansebastian.gif","contentUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/04\/puru-homerebuilt-sansebastian.gif","width":1280,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/interamerica.org\/fr\/2018\/02\/a-porto-rico-leglise-adventiste-continue-de-consolider-les-communautes-au-lendemain-de-la-devastation-causee-par-les-ouragans\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/interamerica.org\/fr\/"},{"@type":"ListItem","position":2,"name":"A Porto Rico, l\u2019Eglise Adventiste continue de consolider les communaut\u00e9s au lendemain de la d\u00e9vastation caus\u00e9e par les ouragans"}]},{"@type":"WebSite","@id":"https:\/\/interamerica.org\/fr\/#website","url":"https:\/\/interamerica.org\/fr\/","name":"\u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/interamerica.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/interamerica.org\/fr\/#\/schema\/person\/68ede8bdc292885bb76c1e3810e73c39","name":"Lorenzo Verduzco","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g","caption":"Lorenzo Verduzco"}}]}},"_links":{"self":[{"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/posts\/39545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/comments?post=39545"}],"version-history":[{"count":0,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/posts\/39545\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/media\/39460"}],"wp:attachment":[{"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/media?parent=39545"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/categories?post=39545"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/tags?post=39545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}