{"id":39550,"date":"2018-02-16T00:00:00","date_gmt":"2018-02-16T04:00:00","guid":{"rendered":"http:\/\/192.81.217.108\/2018\/02\/a-porto-rico-leglise-adventiste-trouve-un-moyen-daider-les-centaines-de-personnes-touchees-par-louragan-maria\/"},"modified":"2018-04-10T09:54:41","modified_gmt":"2018-04-10T13:54:41","slug":"a-porto-rico-leglise-adventiste-trouve-un-moyen-daider-les-centaines-de-personnes-touchees-par-louragan-maria","status":"publish","type":"post","link":"https:\/\/interamerica.org\/fr\/2018\/02\/a-porto-rico-leglise-adventiste-trouve-un-moyen-daider-les-centaines-de-personnes-touchees-par-louragan-maria\/","title":{"rendered":"A Porto Rico, l\u2019Eglise Adventiste trouve un moyen d\u2019aider les centaines de personnes touch\u00e9es par l\u2019Ouragan Maria"},"content":{"rendered":"<div id=\"attachment_33436\" style=\"width: 778px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/02\/Loiza-shoppers.gif\" rel=\"fancybox\" title=\"A Porto Rico, l\u2019Eglise Adventiste trouve un moyen d\u2019aider les centaines de personnes touch\u00e9es par l\u2019Ouragan Maria\"><img fetchpriority=\"high\" decoding=\"async\" aria-describedby=\"caption-attachment-33436\" class=\" wp-image-33436\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/02\/Loiza-shoppers.gif\" alt=\"\" width=\"768\" height=\"480\" \/><\/a><p id=\"caption-attachment-33436\" class=\"wp-caption-text\">Les r\u00e9sidents de Loiza, une petite ville de la c\u00f4te nord-est de Porto Rico, rassemblent des v\u00eatements et des chaussures pour les membres de leurs familles dans le centre \u00ab Otra Oportunidad \u00bb (une Autre Opportunit\u00e9) de l\u2019Eglise Adventiste, le 7 f\u00e9vrier 2018. Image d\u2019Abel M\u00e1rquez \/ DIA<\/p><\/div>\n<p>15 F\u00e9vrier 2018 | Loiza, Porto Rico | Libna Stevens \/ DIA<\/p>\n<p>Comment aider une petite ville pauvre d\u00e9vast\u00e9e par un puissant cyclone ? Comment apporter du secours \u00e0 des familles qui ont presque tout perdu pendant l\u2019ouragan ? L\u2019Eglise Adventiste du Septi\u00e8me Jour \u00e0 Loiza, \u00e0 Porto Rico, a \u00e9labor\u00e9 un plan pour aider des centaines de personnes peu apr\u00e8s le passage de l\u2019Ouragan Maria en septembre dernier. Les vents de cat\u00e9gorie 5 qui ont accompagn\u00e9 le cyclone ont frapp\u00e9 toute l\u2019\u00eele provoquant une coupure de l\u2019\u00e9lectricit\u00e9 et interrompant le fonctionnement des antennes de t\u00e9l\u00e9communication pendant les jours et les semaines qui ont suivi.<\/p>\n<p>Apr\u00e8s avoir fourni des repas chauds tous les jours \u00e0 des centaines de r\u00e9sidents pendant des semaines apr\u00e8s l\u2019ouragan, les membres d\u2019\u00e9glise ont commenc\u00e9 \u00e0 visiter les communaut\u00e9s pour recenser les besoins urgents. Ils ont qualifi\u00e9 ces visites de \u00ab jours d\u2019espoir \u00bb dans les communaut\u00e9s o\u00f9 ils ont \u00e9valu\u00e9 les besoins, distribu\u00e9 de l\u2019eau et parl\u00e9 \u00e0 de nombreuses personnes dont beaucoup de personnes \u00e2g\u00e9es, des m\u00e8res c\u00e9libataires, des ch\u00f4meurs et des individus qui se demandaient comment ils pourraient survivre et reconstruire leur vie.<\/p>\n<p>C\u2019\u00e9tait l\u2019occasion parfaite pour que le projet qu\u2019avaient envisag\u00e9 pasteur Eduardo Mack et les membres d\u2019\u00e9glise des trois communaut\u00e9s Adventistes dont il a la charge \u00e0 Loiza, d\u00e9bute en 2018. Loiza est une ville pauvre d\u2019environ 28000 habitants qui se trouve \u00e0 environ 30 minutes au nord-est de San Juan, la ville capitale.<\/p>\n<p>\u00ab Gr\u00e2ce \u00e0 nos visites dans la communaut\u00e9, nous avons r\u00e9alis\u00e9 \u00e0 quel point il y avait des besoins, nous avons donc imm\u00e9diatement commenc\u00e9 \u00e0 recueillir des v\u00eatements de notre bureau d\u2019ADRA \u00e0 la f\u00e9d\u00e9ration et nous avons pris contact avec le bureau municipal, \u00bb a expliqu\u00e9 Pasteur Mack.<\/p>\n<div id=\"attachment_33442\" style=\"width: 412px\" class=\"wp-caption alignright\"><a href=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/02\/EduardoMack.gif\" rel=\"fancybox\" title=\"A Porto Rico, l\u2019Eglise Adventiste trouve un moyen d\u2019aider les centaines de personnes touch\u00e9es par l\u2019Ouragan Maria\"><img decoding=\"async\" aria-describedby=\"caption-attachment-33442\" class=\" wp-image-33442\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/02\/EduardoMack.gif\" alt=\"\" width=\"402\" height=\"251\" \/><\/a><p id=\"caption-attachment-33442\" class=\"wp-caption-text\">Pasteur Eduardo Mack, qui dirige trois petites \u00e9glises \u00e0 Loiza, dit que le centre est une mani\u00e8re d\u2019\u00eatre en b\u00e9n\u00e9diction \u00e0 la communaut\u00e9. Image de Libna Stevens \/ DIA<\/p><\/div>\n<p>Ouvrir un centre qui pourrait avoir une influence positive dans la communaut\u00e9 \u00e9tait ce dont ils r\u00eavaient, mais pour l\u2019instant, il \u00e9tait urgent de trouver un endroit pour proposer des provisions aux familles touch\u00e9es.<\/p>\n<p>\u00ab Nous avons rencontr\u00e9 le maire de la ville et nous avons d\u00e9couvert qu\u2019il y avait 1000 familles qui avaient tout perdu, et nous avons travaill\u00e9 sur un syst\u00e8me de coupons que ces familles n\u00e9cessiteuses pouvaient apporter au centre pour \u2018acheter\u2019 des articles, \u00bb a d\u00e9clar\u00e9 pasteur Mack. Chaque personne re\u00e7oit un bon de 25 $ et choisit l\u2019\u00e9quivalent de cette somme en provisions dont elle a besoin.<\/p>\n<p><strong>Une Autre Opportunit\u00e9<\/strong><\/p>\n<p>Le centre de distribution de v\u00eatements s\u2019appelle \u00ab Otra Oportunidad \u00bb ou \u00ab Une autre Opportuni\u00e9 \u00bb et est rest\u00e9 op\u00e9rationnel depuis son ouverture le 5 d\u00e9cembre. Avant l\u2019ouverture du centre, les membres d\u2019\u00e9glise se sont port\u00e9s volontaires pour nettoyer les maisons pendant des semaines apr\u00e8s le passage du cyclone.<\/p>\n<p>Le centre a vu d\u00e9filer 500 personnes venues chercher des v\u00eatements, des articles de toilette et de la nourriture lors de la premi\u00e8re semaine d\u2019ouverture. \u00ab Nous avons vu environ 100 personnes par jour, et aujourd\u2019hui nous avons environ 45 personnes qui nous visitent chaque jour ce mois-ci, \u00bb a d\u00e9clar\u00e9 pasteur Mack.<\/p>\n<p>Le centre est dirig\u00e9 par des membres d\u2019\u00e9glise b\u00e9n\u00e9voles qui donnent de leur temps pour trier les v\u00eatements et les autres articles et aider les gens qui viennent au centre.<\/p>\n<p>\u00ab L\u2019ouragan a pr\u00e9cipit\u00e9 les choses et Dieu a ouvert les portes pour que &lsquo;Une autre opportunit\u00e9&rsquo; soit possible aussi rapidement et cela a \u00e9t\u00e9 une v\u00e9ritable b\u00e9n\u00e9diction dans la communaut\u00e9, \u00bb a d\u00e9clar\u00e9 pasteur Mack.<\/p>\n<p>Le maire a \u00e9t\u00e9 vraiment reconnaissant pour le travail que l\u2019\u00c9glise Adventiste accomplit dans la ville parce qu&rsquo;il n\u2019y avait rien en place pour aider autant de familles.<\/p>\n<p><strong>Etre en B\u00e9n\u00e9diction \u00e0 la Communaut\u00e9<\/strong><\/p>\n<p>\u00ab Nous sommes ici pour \u00eatre une b\u00e9n\u00e9diction pour les autres, pour b\u00e9nir la communaut\u00e9, et c\u2019est cela la raison d\u2019\u00eatre du centre, \u00bb a expliqu\u00e9 EduardoMack.<\/p>\n<div id=\"attachment_33439\" style=\"width: 412px\" class=\"wp-caption alignright\"><a href=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/02\/loiza-volunteers.gif\" rel=\"fancybox\" title=\"A Porto Rico, l\u2019Eglise Adventiste trouve un moyen d\u2019aider les centaines de personnes touch\u00e9es par l\u2019Ouragan Maria\"><img decoding=\"async\" aria-describedby=\"caption-attachment-33439\" class=\" wp-image-33439\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/02\/loiza-volunteers.gif\" alt=\"\" width=\"402\" height=\"251\" \/><\/a><p id=\"caption-attachment-33439\" class=\"wp-caption-text\">Maria Cirino (deuxi\u00e8me \u00e0 gauche) et sa fille Jacqueline se tiennent \u00e0 c\u00f4t\u00e9 du pasteur Eduardo Mack et d\u2019autres b\u00e9n\u00e9voles qui aident \u00e0 g\u00e9rer le centre chaque semaine. Image de Libna Stevens \/ DIA<\/p><\/div>\n<p>De l\u2019utilisation de plusieurs unit\u00e9s du centre commercial vide de la ville jusqu\u2019aux dons provenant d\u2019ADRA, de la F\u00e9d\u00e9ration du Greater New York et de l\u2019\u00c9glise Adventiste de Coral Springs en Floride, Eduardo Mack voit combien l\u2019influence du centre grandit dans la communaut\u00e9.<\/p>\n<p>\u00ab Ce projet a \u00e9t\u00e9 b\u00e9n\u00e9fique non seulement pour la communaut\u00e9, mais aussi pour les 85 membres des trois petites \u00e9glises Adventistes de la ville, \u00bb a d\u00e9clar\u00e9 pasteur Mack.<\/p>\n<p>Maria Cirino fait du b\u00e9n\u00e9volat depuis l\u2019ouverture du centre. Elle a grandi \u00e0 Loiza et est Adventiste du Septi\u00e8me Jour depuis son enfance et est membre de l\u2019\u00e9glise Adventiste de Pueblo. Dans son \u00e9glise qui compte 14 membres, elle exerce les responsabilit\u00e9s de secr\u00e9taire d\u2019\u00e9glise, secr\u00e9taire de l\u2019Ecole du Sabbat et de directrice des diaconesses.<\/p>\n<p>Etre b\u00e9n\u00e9vole pour \u00ab Une Autre Opportunit\u00e9 \u00bb lui a apport\u00e9 de la joie et lui a appris \u00e0 penser davantage aux autres personnes vivant dans sa communaut\u00e9. \u00ab J\u2019aime aider et j\u2019ai appris tous les jours que j\u2019ai pass\u00e9s ici qu\u2019il y a vraiment beaucoup de personnes dans le besoin, \u00bb a dit Maria Cirino.<\/p>\n<p>La fille de Maria Cirino, Jaqueline Perez, est revenue de Miami, en Floride avec sa famille pour vivre avec m\u00e8re, apr\u00e8s le passage de l\u2019ouragan. Jaqueline Perez est responsable de la gestion des rayons au centre et travaillait auparavant dans un magasin de v\u00eatements discount \u00e0 Miami o\u00f9 elle triait les v\u00eatements et g\u00e9rait les rayons.<\/p>\n<p>\u00ab J\u2019ai d\u00e9cid\u00e9 de rester et de chercher un emploi mais en attendant j\u2019ai d\u00e9cid\u00e9 d\u2019apporter mon aide au centre, \u00bb a dit Jaqueline Perez. J\u2019ai \u00e9t\u00e9 une fid\u00e8le Adventiste du Septi\u00e8me Jour, mais j\u2019ai quitt\u00e9 l\u2019\u00e9glise et maintenant je suis de retour chez moi et je d\u00e9couvre ce merveilleux projet pour la communaut\u00e9. \u00bb<\/p>\n<p>Depuis F\u00e9vrier, le centre ouvre seulement du mercredi au vendredi, a indiqu\u00e9 pasteur Mack. \u00ab Beaucoup ont pu se d\u00e9brouiller avec ce qu\u2019ils ont obtenu du centre et nous voulons faire de ce projet un centre d\u2019influence constant ici \u00e0 Loiza, \u00bb a-t-il ajout\u00e9.<\/p>\n<p><strong>Etablir le Contact \u00e0 Travers l\u2019Aide<br \/>\n<\/strong><\/p>\n<div id=\"attachment_33448\" style=\"width: 412px\" class=\"wp-caption alignright\"><a href=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/02\/Loiza-elderly-couple.gif\" rel=\"fancybox\" title=\"A Porto Rico, l\u2019Eglise Adventiste trouve un moyen d\u2019aider les centaines de personnes touch\u00e9es par l\u2019Ouragan Maria\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-33448\" class=\" wp-image-33448\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/02\/Loiza-elderly-couple.gif\" alt=\"\" width=\"402\" height=\"251\" \/><\/a><p id=\"caption-attachment-33448\" class=\"wp-caption-text\">Pasteur Eduardo Mack parle \u00e0 Genaro et Isabel Fuentes dont le toit a \u00e9t\u00e9 endommag\u00e9 apr\u00e8s le passage de l\u2019Ouragan Maria. Ils font parmi des trois foyers dont les maisons seront r\u00e9par\u00e9es dans le quartier par ADRA Porto Rico. Image de Libna Stevens \/ DIA<\/p><\/div>\n<p>Une Autre Opportunit\u00e9 a permis \u00e0 la communaut\u00e9 de savoir qui est l\u2019\u00c9glise Adventiste du Septi\u00e8me Jour et comment nous nous soucions des autres, a dit Eduardo Mack.<\/p>\n<p>\u00ab Tout l\u2019impact que nous avons eu a \u00e9t\u00e9 possible gr\u00e2ce aux contacts \u00e9tablis et \u00e0 l\u2019aide apport\u00e9e aux autres dans la communaut\u00e9, afin de leur faire voir que nous suivons J\u00e9sus et la m\u00e9thode qu\u2019Il utilisait pour manifester son attention \u00e0 l\u2019endroit de ceux qui \u00e9taient dans le besoin, \u00bb a-t-il dit.<\/p>\n<p>Le plan consiste \u00e0 offrir des cours de fabrication de bougies afin que les m\u00e8res c\u00e9libataires puissent cr\u00e9er une petite entreprise de vente de bougies de fabrication artisanale pour subvenir aux besoins de leurs familles. Parmi les autres services communautaires planifi\u00e9s, il y a la relation d\u2019aide, l\u2019\u00e9ducation sanitaire, et bien plus, selon pasteur Mack.<\/p>\n<p>Dans les prochains jours, l\u2019\u00e9glise, avec l\u2019aide d\u2019ADRA \u00e0 Porto Rico, aidera \u00e9galement \u00e0 r\u00e9parer plusieurs maisons de r\u00e9sidents \u00e2g\u00e9s.<\/p>\n<p>\u00ab C\u2019est l\u2019amour de Dieu \u00e0 l\u2019\u0153uvre \u00e0 travers nous, \u00bb a dit pasteur Mack.<\/p>\n<p>L\u2019objectif est de trouver un endroit permanent disposant de l\u2019\u00e9lectricit\u00e9 afin qu\u2019ils puissent \u00eatre une b\u00e9n\u00e9diction et aider \u00e0 reconstruire la vie de nombreuses personnes dans la communaut\u00e9.<\/p>\n<p>Regardez une courte vid\u00e9o sur ce projet<br \/>\n<a href=\"https:\/\/vimeo.com\/256085257\">ICI<\/a><\/p>\n<p>Traduction: Patrick Luciathe<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comment aider une petite ville pauvre d\u00e9vast\u00e9e par un puissant cyclone ? Comment apporter du secours \u00e0 des familles qui ont presque tout perdu pendant l\u2019ouragan ? L\u2019Eglise Adventiste du Septi\u00e8me Jour \u00e0 Loiza, \u00e0 Porto Rico, a \u00e9labor\u00e9 un plan pour aider des centaines de personnes peu apr\u00e8s le passage de l\u2019Ouragan Maria en septembre dernier. Les vents de cat\u00e9gorie 5 qui ont accompagn\u00e9 le cyclone ont frapp\u00e9 toute l\u2019\u00eele provoquant une coupure de l\u2019\u00e9lectricit\u00e9 et interrompant le fonctionnement des antennes de t\u00e9l\u00e9communication pendant les jours et les semaines qui ont suivi.<\/p>\n","protected":false},"author":1,"featured_media":39478,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[21,19],"tags":[],"class_list":["post-39550","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles-du-territoire","category-rss-francais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A Porto Rico, l\u2019Eglise Adventiste trouve un moyen d\u2019aider les centaines de personnes touch\u00e9es par l\u2019Ouragan Maria - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/interamerica.org\/fr\/2018\/02\/a-porto-rico-leglise-adventiste-trouve-un-moyen-daider-les-centaines-de-personnes-touchees-par-louragan-maria\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Porto Rico, l\u2019Eglise Adventiste trouve un moyen d\u2019aider les centaines de personnes touch\u00e9es par l\u2019Ouragan Maria - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division\" \/>\n<meta property=\"og:description\" content=\"Comment aider une petite ville pauvre d\u00e9vast\u00e9e par un puissant cyclone ? Comment apporter du secours \u00e0 des familles qui ont presque tout perdu pendant l\u2019ouragan ? L\u2019Eglise Adventiste du Septi\u00e8me Jour \u00e0 Loiza, \u00e0 Porto Rico, a \u00e9labor\u00e9 un plan pour aider des centaines de personnes peu apr\u00e8s le passage de l\u2019Ouragan Maria en septembre dernier. Les vents de cat\u00e9gorie 5 qui ont accompagn\u00e9 le cyclone ont frapp\u00e9 toute l\u2019\u00eele provoquant une coupure de l\u2019\u00e9lectricit\u00e9 et interrompant le fonctionnement des antennes de t\u00e9l\u00e9communication pendant les jours et les semaines qui ont suivi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/interamerica.org\/fr\/2018\/02\/a-porto-rico-leglise-adventiste-trouve-un-moyen-daider-les-centaines-de-personnes-touchees-par-louragan-maria\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-16T04:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-04-10T13:54:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/04\/loiza-shoppers.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"author\" content=\"Lorenzo Verduzco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lorenzo Verduzco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/02\\\/a-porto-rico-leglise-adventiste-trouve-un-moyen-daider-les-centaines-de-personnes-touchees-par-louragan-maria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/02\\\/a-porto-rico-leglise-adventiste-trouve-un-moyen-daider-les-centaines-de-personnes-touchees-par-louragan-maria\\\/\"},\"author\":{\"name\":\"Lorenzo Verduzco\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/#\\\/schema\\\/person\\\/68ede8bdc292885bb76c1e3810e73c39\"},\"headline\":\"A Porto Rico, l\u2019Eglise Adventiste trouve un moyen d\u2019aider les centaines de personnes touch\u00e9es par l\u2019Ouragan Maria\",\"datePublished\":\"2018-02-16T04:00:00+00:00\",\"dateModified\":\"2018-04-10T13:54:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/02\\\/a-porto-rico-leglise-adventiste-trouve-un-moyen-daider-les-centaines-de-personnes-touchees-par-louragan-maria\\\/\"},\"wordCount\":1481,\"image\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/02\\\/a-porto-rico-leglise-adventiste-trouve-un-moyen-daider-les-centaines-de-personnes-touchees-par-louragan-maria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/loiza-shoppers.gif\",\"articleSection\":[\"Nouvelles du territoire\",\"RSS Fran\u00e7ais\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/02\\\/a-porto-rico-leglise-adventiste-trouve-un-moyen-daider-les-centaines-de-personnes-touchees-par-louragan-maria\\\/\",\"url\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/02\\\/a-porto-rico-leglise-adventiste-trouve-un-moyen-daider-les-centaines-de-personnes-touchees-par-louragan-maria\\\/\",\"name\":\"A Porto Rico, l\u2019Eglise Adventiste trouve un moyen d\u2019aider les centaines de personnes touch\u00e9es par l\u2019Ouragan Maria - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/02\\\/a-porto-rico-leglise-adventiste-trouve-un-moyen-daider-les-centaines-de-personnes-touchees-par-louragan-maria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/02\\\/a-porto-rico-leglise-adventiste-trouve-un-moyen-daider-les-centaines-de-personnes-touchees-par-louragan-maria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/loiza-shoppers.gif\",\"datePublished\":\"2018-02-16T04:00:00+00:00\",\"dateModified\":\"2018-04-10T13:54:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/#\\\/schema\\\/person\\\/68ede8bdc292885bb76c1e3810e73c39\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/02\\\/a-porto-rico-leglise-adventiste-trouve-un-moyen-daider-les-centaines-de-personnes-touchees-par-louragan-maria\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/02\\\/a-porto-rico-leglise-adventiste-trouve-un-moyen-daider-les-centaines-de-personnes-touchees-par-louragan-maria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/02\\\/a-porto-rico-leglise-adventiste-trouve-un-moyen-daider-les-centaines-de-personnes-touchees-par-louragan-maria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/loiza-shoppers.gif\",\"contentUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/loiza-shoppers.gif\",\"width\":1280,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/02\\\/a-porto-rico-leglise-adventiste-trouve-un-moyen-daider-les-centaines-de-personnes-touchees-par-louragan-maria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A Porto Rico, l\u2019Eglise Adventiste trouve un moyen d\u2019aider les centaines de personnes touch\u00e9es par l\u2019Ouragan Maria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/\",\"name\":\"\u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/#\\\/schema\\\/person\\\/68ede8bdc292885bb76c1e3810e73c39\",\"name\":\"Lorenzo Verduzco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g\",\"caption\":\"Lorenzo Verduzco\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A Porto Rico, l\u2019Eglise Adventiste trouve un moyen d\u2019aider les centaines de personnes touch\u00e9es par l\u2019Ouragan Maria - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/interamerica.org\/fr\/2018\/02\/a-porto-rico-leglise-adventiste-trouve-un-moyen-daider-les-centaines-de-personnes-touchees-par-louragan-maria\/","og_locale":"fr_FR","og_type":"article","og_title":"A Porto Rico, l\u2019Eglise Adventiste trouve un moyen d\u2019aider les centaines de personnes touch\u00e9es par l\u2019Ouragan Maria - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division","og_description":"Comment aider une petite ville pauvre d\u00e9vast\u00e9e par un puissant cyclone ? Comment apporter du secours \u00e0 des familles qui ont presque tout perdu pendant l\u2019ouragan ? L\u2019Eglise Adventiste du Septi\u00e8me Jour \u00e0 Loiza, \u00e0 Porto Rico, a \u00e9labor\u00e9 un plan pour aider des centaines de personnes peu apr\u00e8s le passage de l\u2019Ouragan Maria en septembre dernier. Les vents de cat\u00e9gorie 5 qui ont accompagn\u00e9 le cyclone ont frapp\u00e9 toute l\u2019\u00eele provoquant une coupure de l\u2019\u00e9lectricit\u00e9 et interrompant le fonctionnement des antennes de t\u00e9l\u00e9communication pendant les jours et les semaines qui ont suivi.","og_url":"https:\/\/interamerica.org\/fr\/2018\/02\/a-porto-rico-leglise-adventiste-trouve-un-moyen-daider-les-centaines-de-personnes-touchees-par-louragan-maria\/","og_site_name":"\u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division","article_published_time":"2018-02-16T04:00:00+00:00","article_modified_time":"2018-04-10T13:54:41+00:00","og_image":[{"width":1280,"height":800,"url":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/04\/loiza-shoppers.gif","type":"image\/gif"}],"author":"Lorenzo Verduzco","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Lorenzo Verduzco","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/interamerica.org\/fr\/2018\/02\/a-porto-rico-leglise-adventiste-trouve-un-moyen-daider-les-centaines-de-personnes-touchees-par-louragan-maria\/#article","isPartOf":{"@id":"https:\/\/interamerica.org\/fr\/2018\/02\/a-porto-rico-leglise-adventiste-trouve-un-moyen-daider-les-centaines-de-personnes-touchees-par-louragan-maria\/"},"author":{"name":"Lorenzo Verduzco","@id":"https:\/\/interamerica.org\/fr\/#\/schema\/person\/68ede8bdc292885bb76c1e3810e73c39"},"headline":"A Porto Rico, l\u2019Eglise Adventiste trouve un moyen d\u2019aider les centaines de personnes touch\u00e9es par l\u2019Ouragan Maria","datePublished":"2018-02-16T04:00:00+00:00","dateModified":"2018-04-10T13:54:41+00:00","mainEntityOfPage":{"@id":"https:\/\/interamerica.org\/fr\/2018\/02\/a-porto-rico-leglise-adventiste-trouve-un-moyen-daider-les-centaines-de-personnes-touchees-par-louragan-maria\/"},"wordCount":1481,"image":{"@id":"https:\/\/interamerica.org\/fr\/2018\/02\/a-porto-rico-leglise-adventiste-trouve-un-moyen-daider-les-centaines-de-personnes-touchees-par-louragan-maria\/#primaryimage"},"thumbnailUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/04\/loiza-shoppers.gif","articleSection":["Nouvelles du territoire","RSS Fran\u00e7ais"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/interamerica.org\/fr\/2018\/02\/a-porto-rico-leglise-adventiste-trouve-un-moyen-daider-les-centaines-de-personnes-touchees-par-louragan-maria\/","url":"https:\/\/interamerica.org\/fr\/2018\/02\/a-porto-rico-leglise-adventiste-trouve-un-moyen-daider-les-centaines-de-personnes-touchees-par-louragan-maria\/","name":"A Porto Rico, l\u2019Eglise Adventiste trouve un moyen d\u2019aider les centaines de personnes touch\u00e9es par l\u2019Ouragan Maria - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division","isPartOf":{"@id":"https:\/\/interamerica.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/interamerica.org\/fr\/2018\/02\/a-porto-rico-leglise-adventiste-trouve-un-moyen-daider-les-centaines-de-personnes-touchees-par-louragan-maria\/#primaryimage"},"image":{"@id":"https:\/\/interamerica.org\/fr\/2018\/02\/a-porto-rico-leglise-adventiste-trouve-un-moyen-daider-les-centaines-de-personnes-touchees-par-louragan-maria\/#primaryimage"},"thumbnailUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/04\/loiza-shoppers.gif","datePublished":"2018-02-16T04:00:00+00:00","dateModified":"2018-04-10T13:54:41+00:00","author":{"@id":"https:\/\/interamerica.org\/fr\/#\/schema\/person\/68ede8bdc292885bb76c1e3810e73c39"},"breadcrumb":{"@id":"https:\/\/interamerica.org\/fr\/2018\/02\/a-porto-rico-leglise-adventiste-trouve-un-moyen-daider-les-centaines-de-personnes-touchees-par-louragan-maria\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/interamerica.org\/fr\/2018\/02\/a-porto-rico-leglise-adventiste-trouve-un-moyen-daider-les-centaines-de-personnes-touchees-par-louragan-maria\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/interamerica.org\/fr\/2018\/02\/a-porto-rico-leglise-adventiste-trouve-un-moyen-daider-les-centaines-de-personnes-touchees-par-louragan-maria\/#primaryimage","url":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/04\/loiza-shoppers.gif","contentUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/04\/loiza-shoppers.gif","width":1280,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/interamerica.org\/fr\/2018\/02\/a-porto-rico-leglise-adventiste-trouve-un-moyen-daider-les-centaines-de-personnes-touchees-par-louragan-maria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/interamerica.org\/fr\/"},{"@type":"ListItem","position":2,"name":"A Porto Rico, l\u2019Eglise Adventiste trouve un moyen d\u2019aider les centaines de personnes touch\u00e9es par l\u2019Ouragan Maria"}]},{"@type":"WebSite","@id":"https:\/\/interamerica.org\/fr\/#website","url":"https:\/\/interamerica.org\/fr\/","name":"\u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/interamerica.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/interamerica.org\/fr\/#\/schema\/person\/68ede8bdc292885bb76c1e3810e73c39","name":"Lorenzo Verduzco","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g","caption":"Lorenzo Verduzco"}}]}},"_links":{"self":[{"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/posts\/39550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/comments?post=39550"}],"version-history":[{"count":0,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/posts\/39550\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/media\/39478"}],"wp:attachment":[{"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/media?parent=39550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/categories?post=39550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/tags?post=39550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}