{"id":39754,"date":"2018-03-16T00:00:00","date_gmt":"2018-03-16T04:00:00","guid":{"rendered":"http:\/\/192.81.217.108\/2018\/03\/les-adventistes-du-bangladesh-offrent-une-education-sanitaire-aux-musulmans-et-hindous-en-charge-denfants\/"},"modified":"2018-03-16T00:00:00","modified_gmt":"2018-03-16T04:00:00","slug":"les-adventistes-du-bangladesh-offrent-une-education-sanitaire-aux-musulmans-et-hindous-en-charge-denfants","status":"publish","type":"post","link":"https:\/\/interamerica.org\/fr\/2018\/03\/les-adventistes-du-bangladesh-offrent-une-education-sanitaire-aux-musulmans-et-hindous-en-charge-denfants\/","title":{"rendered":"Les Adventistes du Bangladesh offrent une \u00e9ducation sanitaire aux Musulmans et Hindous en charge d\u2019enfants"},"content":{"rendered":"<div id=\"attachment_33986\" style=\"width: 756px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/03\/bangladesh-adventists-offer-health-education-for-muslim-and-hindu-caregivers.jpg\" rel=\"fancybox\" title=\"Les Adventistes du Bangladesh offrent une \u00e9ducation sanitaire aux Musulmans et Hindous en charge d\u2019enfants\"><img fetchpriority=\"high\" decoding=\"async\" aria-describedby=\"caption-attachment-33986\" class=\" wp-image-33986\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/03\/bangladesh-adventists-offer-health-education-for-muslim-and-hindu-caregivers.jpg\" alt=\"\" width=\"746\" height=\"373\" \/><\/a><p id=\"caption-attachment-33986\" class=\"wp-caption-text\">Image d&rsquo;ADRA<\/p><\/div>\n<p>15 Mars 2018 | <span class=\"byline-news\">Adventist Review &amp;\u00a0Litton S. Halder<\/span><\/p>\n<p><span class=\"cap\">C<\/span>onnue au Bangladesh pour l\u2019accent qu\u2019elle place sur l\u2019\u00e9ducation <a href=\"\/\/BDE00C7D-4457-475C-AE99-50DE39C62184#_ftn1\" target=\"_blank\" rel=\"noopener\">[1]<\/a>, l\u2019Eglise Adventiste du Septi\u00e8me Jour \u00e0 Dhaka est r\u00e9cemment sortie des salles de classe pour une initiative d\u2019\u00e9ducation propos\u00e9e \u00e0 une population souvent n\u00e9glig\u00e9e. Les responsables de trois d\u00e9partements de l\u2019Union Mission Adventiste du Bangladesh (BAUM) ont propos\u00e9 un programme de sant\u00e9 appel\u00e9 Atelier &amp; S\u00e9minaire pour une Vie Meilleure pour les gardiens (tuteurs) et les parents de la plus grande \u00e9cole Adventiste de Dhaka.<\/p>\n<p>La plupart des plus de 1500 \u00e9tudiants de l\u2019Ecole Pr\u00e9-S\u00e9minariste Adventiste de Dhaka (DAPS) sont musulmans, un pourcentage beaucoup plus faible repr\u00e9sentent les Hindous et les autres religions. Les tuteurs ou gardiens, qui sont majoritairement musulmans en g\u00e9n\u00e9ral, accompagnent les \u00e9l\u00e8ves \u00e0 l\u2019\u00e9cole et certains les attendent jusqu\u2019\u00e0 la fin des cours pour la journ\u00e9e. Les dirigeants de DAPS ont cherch\u00e9 des moyens d\u2019apporter quelque chose de plus \u00e0 ces femmes et aux parents des \u00e9tudiants.<\/p>\n<p>En collaboration avec le D\u00e9partement Sant\u00e9 de BAUM, le D\u00e9partement des Minist\u00e8res des Enfants de BAUM et le D\u00e9partement des Minist\u00e8res des Femmes de BAUM, DAPS a organis\u00e9 deux sessions pour les tuteurs et les parents, une le matin et une l\u2019apr\u00e8s-midi le 1er f\u00e9vrier. Plus de 250 personnes au total y ont assist\u00e9.<\/p>\n<p>Pendant les sessions, Dr. Litton S. Halder, directeur de la communication de BAUM, a soulign\u00e9 l\u2019importance de la sant\u00e9 pour tous.<\/p>\n<div id=\"attachment_33989\" style=\"width: 414px\" class=\"wp-caption alignright\"><a href=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/03\/bangladesh-2.jpg\" rel=\"fancybox\" title=\"Les Adventistes du Bangladesh offrent une \u00e9ducation sanitaire aux Musulmans et Hindous en charge d\u2019enfants\"><img decoding=\"async\" aria-describedby=\"caption-attachment-33989\" class=\" wp-image-33989\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/03\/bangladesh-2.jpg\" alt=\"\" width=\"404\" height=\"252\" \/><\/a><p id=\"caption-attachment-33989\" class=\"wp-caption-text\">Image d&rsquo;ADRA<\/p><\/div>\n<p>Mme Mahuya Roy, directrice des Minist\u00e8res des Femmes, a parl\u00e9 des opportunit\u00e9s et des responsabilit\u00e9s des femmes. Les participants ont gagn\u00e9 des prix pour leurs r\u00e9ponses correctes aux questions pos\u00e9es par Mahuya Roy, ce qui a rendu le public tr\u00e8s attentif.<\/p>\n<p>Mme Young Moon Lee, directrice des Minist\u00e8res des Femmes de BAUM, a expliqu\u00e9 les avantages d\u2019un r\u00e9gime v\u00e9g\u00e9tarien et a fait une d\u00e9monstration de la pr\u00e9paration du <em>kimchi<\/em>. Sa session \u00e9tait tr\u00e8s appr\u00e9ci\u00e9e des tuteurs puisque cette salade \/ condiment cor\u00e9enne peut \u00eatre facilement pr\u00e9par\u00e9e avec des ingr\u00e9dients locaux peu co\u00fbteux. Ils ont \u00e9galement pu savourer des \u00e9chantillons et en ont ramen\u00e9 chez eux pour les partager avec leurs employeurs, les membres de leur famille et leurs proches.<\/p>\n<p>Concernant les plans de suivi, MahuyaRoy proposera ce type de format de s\u00e9minaire dans diff\u00e9rentes \u00e9coles, missions et institutions. Chose int\u00e9ressante, les tuteurs gardiens ont voulu prendre des photos avec Mme Lee et \u00ab lui ont demand\u00e9 de faire ce type de programmes aussi souvent que possible, \u00bb d\u2019apr\u00e8s ce qu\u2019a indiqu\u00e9 Dr Halder.<\/p>\n<p>\u00ab Tous les parents et les tuteurs ont vraiment appr\u00e9ci\u00e9 nos programmes. Certains d\u2019entre eux nous ont invit\u00e9s \u00e0 mener ce type de programmes dans leurs propres \u00e9coles et institutions \u00bb, a dit Litton Halder. \u00ab Nous avons pass\u00e9 un tr\u00e8s bon moment \u00e0 partager nos messages sur la sant\u00e9, la famille et le minist\u00e8re des enfants avec nos amis Musulmans, Hindous et Chr\u00e9tiens, ainsi qu\u2019avec des personnes d\u2019autres religions, \u00bb a-t-il ajout\u00e9.<\/p>\n<p>Il y a plus de 30000 Adventistes au Bangladesh ; ils se r\u00e9unissent dans plus de 120 \u00e9glises et on d\u00e9nombre plus de 170 \u00e9coles rurales, 10 \u00e9coles urbaines et neuf internats dans ce pays \u00e0 pr\u00e9dominance Musulmane. La population compte un peu plus de 90% de Musulmans et moins de 9% d\u2019Hindous ; le bouddhisme, le christianisme et d\u2019autres religions constituant moins de 1% de la population<a href=\"\/\/BDE00C7D-4457-475C-AE99-50DE39C62184#_ftn2\" target=\"_blank\" rel=\"noopener\">[2]<\/a>. Le Bangladesh est l\u2019un des 14 pays du territoire de la Division de l\u2019Asie et du Pacifique Sud.<\/p>\n<p><em>Litton S. Halder a contribu\u00e9 \u00e0 cet article<\/em><\/p>\n<div>\n<p><a href=\"\/\/BDE00C7D-4457-475C-AE99-50DE39C62184#_ftnref1\">[1]<\/a> McChesney, Andrew. \u201c<a href=\"https:\/\/news.adventist.org\/en\/all-news\/news\/go\/2016-11-13\/schools-power-the-adventist-church-in-bangladesh-110-years-on\/\">Schools power the Adventist church in Bangladesh<\/a>.\u201d(\u00ab Les Ecoles, la Force de l\u2019Eglise Adventiste au Bangladesh. \u00bb) <em>Adventist Review<\/em>. 13 Nov. 2016. Web.<\/p>\n<\/div>\n<p><a href=\"\/\/BDE00C7D-4457-475C-AE99-50DE39C62184#_ftnref2\" target=\"_blank\" rel=\"noopener\">[2]<\/a> Rapport du Recensement 2011. <a href=\"http:\/\/bbs.dhaka.gov.bd\/sites\/default\/files\/files\/bbs.dhaka.gov.bd\/law_policy\/6ed6b42c_2015_11e7_8f57_286ed488c766\/Socio-Economic%20and%20demographic%20Report%202012.pdf\">Bureau des Statistiques du Bangladesh<\/a>.<\/p>\n<p>Traduction: Patrick Luciathe<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Connue au Bangladesh pour l\u2019accent qu\u2019elle place sur l\u2019\u00e9ducation [1], l\u2019Eglise Adventiste du Septi\u00e8me Jour \u00e0 Dhaka est r\u00e9cemment sortie des salles de classe pour une initiative d\u2019\u00e9ducation propos\u00e9e \u00e0 une population souvent n\u00e9glig\u00e9e. Les responsables de trois d\u00e9partements de l\u2019Union Mission Adventiste du Bangladesh (BAUM) ont propos\u00e9 un programme de sant\u00e9 appel\u00e9 Atelier &amp; S\u00e9minaire pour une Vie Meilleure pour les tuteurs et les parents de la plus grande \u00e9cole Adventiste de Dhaka.<\/p>\n","protected":false},"author":1,"featured_media":39624,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[18,19],"tags":[],"class_list":["post-39754","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles-de-leglise-mondiale","category-rss-francais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les Adventistes du Bangladesh offrent une \u00e9ducation sanitaire aux Musulmans et Hindous en charge d\u2019enfants - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/interamerica.org\/fr\/2018\/03\/les-adventistes-du-bangladesh-offrent-une-education-sanitaire-aux-musulmans-et-hindous-en-charge-denfants\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les Adventistes du Bangladesh offrent une \u00e9ducation sanitaire aux Musulmans et Hindous en charge d\u2019enfants - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division\" \/>\n<meta property=\"og:description\" content=\"Connue au Bangladesh pour l\u2019accent qu\u2019elle place sur l\u2019\u00e9ducation [1], l\u2019Eglise Adventiste du Septi\u00e8me Jour \u00e0 Dhaka est r\u00e9cemment sortie des salles de classe pour une initiative d\u2019\u00e9ducation propos\u00e9e \u00e0 une population souvent n\u00e9glig\u00e9e. Les responsables de trois d\u00e9partements de l\u2019Union Mission Adventiste du Bangladesh (BAUM) ont propos\u00e9 un programme de sant\u00e9 appel\u00e9 Atelier &amp; S\u00e9minaire pour une Vie Meilleure pour les tuteurs et les parents de la plus grande \u00e9cole Adventiste de Dhaka.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/interamerica.org\/fr\/2018\/03\/les-adventistes-du-bangladesh-offrent-une-education-sanitaire-aux-musulmans-et-hindous-en-charge-denfants\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-16T04:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/04\/bangladesh-adventists-offer-health-education-for-muslim-and-hindu-caregivers.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lorenzo Verduzco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lorenzo Verduzco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/03\\\/les-adventistes-du-bangladesh-offrent-une-education-sanitaire-aux-musulmans-et-hindous-en-charge-denfants\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/03\\\/les-adventistes-du-bangladesh-offrent-une-education-sanitaire-aux-musulmans-et-hindous-en-charge-denfants\\\/\"},\"author\":{\"name\":\"Lorenzo Verduzco\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/#\\\/schema\\\/person\\\/68ede8bdc292885bb76c1e3810e73c39\"},\"headline\":\"Les Adventistes du Bangladesh offrent une \u00e9ducation sanitaire aux Musulmans et Hindous en charge d\u2019enfants\",\"datePublished\":\"2018-03-16T04:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/03\\\/les-adventistes-du-bangladesh-offrent-une-education-sanitaire-aux-musulmans-et-hindous-en-charge-denfants\\\/\"},\"wordCount\":689,\"image\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/03\\\/les-adventistes-du-bangladesh-offrent-une-education-sanitaire-aux-musulmans-et-hindous-en-charge-denfants\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/bangladesh-adventists-offer-health-education-for-muslim-and-hindu-caregivers.jpg\",\"articleSection\":[\"Nouvelles de l'\u00c9glise mondiale\",\"RSS Fran\u00e7ais\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/03\\\/les-adventistes-du-bangladesh-offrent-une-education-sanitaire-aux-musulmans-et-hindous-en-charge-denfants\\\/\",\"url\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/03\\\/les-adventistes-du-bangladesh-offrent-une-education-sanitaire-aux-musulmans-et-hindous-en-charge-denfants\\\/\",\"name\":\"Les Adventistes du Bangladesh offrent une \u00e9ducation sanitaire aux Musulmans et Hindous en charge d\u2019enfants - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/03\\\/les-adventistes-du-bangladesh-offrent-une-education-sanitaire-aux-musulmans-et-hindous-en-charge-denfants\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/03\\\/les-adventistes-du-bangladesh-offrent-une-education-sanitaire-aux-musulmans-et-hindous-en-charge-denfants\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/bangladesh-adventists-offer-health-education-for-muslim-and-hindu-caregivers.jpg\",\"datePublished\":\"2018-03-16T04:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/#\\\/schema\\\/person\\\/68ede8bdc292885bb76c1e3810e73c39\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/03\\\/les-adventistes-du-bangladesh-offrent-une-education-sanitaire-aux-musulmans-et-hindous-en-charge-denfants\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/03\\\/les-adventistes-du-bangladesh-offrent-une-education-sanitaire-aux-musulmans-et-hindous-en-charge-denfants\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/03\\\/les-adventistes-du-bangladesh-offrent-une-education-sanitaire-aux-musulmans-et-hindous-en-charge-denfants\\\/#primaryimage\",\"url\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/bangladesh-adventists-offer-health-education-for-muslim-and-hindu-caregivers.jpg\",\"contentUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/bangladesh-adventists-offer-health-education-for-muslim-and-hindu-caregivers.jpg\",\"width\":1000,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/03\\\/les-adventistes-du-bangladesh-offrent-une-education-sanitaire-aux-musulmans-et-hindous-en-charge-denfants\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les Adventistes du Bangladesh offrent une \u00e9ducation sanitaire aux Musulmans et Hindous en charge d\u2019enfants\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/\",\"name\":\"\u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/#\\\/schema\\\/person\\\/68ede8bdc292885bb76c1e3810e73c39\",\"name\":\"Lorenzo Verduzco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g\",\"caption\":\"Lorenzo Verduzco\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les Adventistes du Bangladesh offrent une \u00e9ducation sanitaire aux Musulmans et Hindous en charge d\u2019enfants - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/interamerica.org\/fr\/2018\/03\/les-adventistes-du-bangladesh-offrent-une-education-sanitaire-aux-musulmans-et-hindous-en-charge-denfants\/","og_locale":"fr_FR","og_type":"article","og_title":"Les Adventistes du Bangladesh offrent une \u00e9ducation sanitaire aux Musulmans et Hindous en charge d\u2019enfants - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division","og_description":"Connue au Bangladesh pour l\u2019accent qu\u2019elle place sur l\u2019\u00e9ducation [1], l\u2019Eglise Adventiste du Septi\u00e8me Jour \u00e0 Dhaka est r\u00e9cemment sortie des salles de classe pour une initiative d\u2019\u00e9ducation propos\u00e9e \u00e0 une population souvent n\u00e9glig\u00e9e. Les responsables de trois d\u00e9partements de l\u2019Union Mission Adventiste du Bangladesh (BAUM) ont propos\u00e9 un programme de sant\u00e9 appel\u00e9 Atelier &amp; S\u00e9minaire pour une Vie Meilleure pour les tuteurs et les parents de la plus grande \u00e9cole Adventiste de Dhaka.","og_url":"https:\/\/interamerica.org\/fr\/2018\/03\/les-adventistes-du-bangladesh-offrent-une-education-sanitaire-aux-musulmans-et-hindous-en-charge-denfants\/","og_site_name":"\u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division","article_published_time":"2018-03-16T04:00:00+00:00","og_image":[{"width":1000,"height":500,"url":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/04\/bangladesh-adventists-offer-health-education-for-muslim-and-hindu-caregivers.jpg","type":"image\/jpeg"}],"author":"Lorenzo Verduzco","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Lorenzo Verduzco","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/interamerica.org\/fr\/2018\/03\/les-adventistes-du-bangladesh-offrent-une-education-sanitaire-aux-musulmans-et-hindous-en-charge-denfants\/#article","isPartOf":{"@id":"https:\/\/interamerica.org\/fr\/2018\/03\/les-adventistes-du-bangladesh-offrent-une-education-sanitaire-aux-musulmans-et-hindous-en-charge-denfants\/"},"author":{"name":"Lorenzo Verduzco","@id":"https:\/\/interamerica.org\/fr\/#\/schema\/person\/68ede8bdc292885bb76c1e3810e73c39"},"headline":"Les Adventistes du Bangladesh offrent une \u00e9ducation sanitaire aux Musulmans et Hindous en charge d\u2019enfants","datePublished":"2018-03-16T04:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/interamerica.org\/fr\/2018\/03\/les-adventistes-du-bangladesh-offrent-une-education-sanitaire-aux-musulmans-et-hindous-en-charge-denfants\/"},"wordCount":689,"image":{"@id":"https:\/\/interamerica.org\/fr\/2018\/03\/les-adventistes-du-bangladesh-offrent-une-education-sanitaire-aux-musulmans-et-hindous-en-charge-denfants\/#primaryimage"},"thumbnailUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/04\/bangladesh-adventists-offer-health-education-for-muslim-and-hindu-caregivers.jpg","articleSection":["Nouvelles de l'\u00c9glise mondiale","RSS Fran\u00e7ais"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/interamerica.org\/fr\/2018\/03\/les-adventistes-du-bangladesh-offrent-une-education-sanitaire-aux-musulmans-et-hindous-en-charge-denfants\/","url":"https:\/\/interamerica.org\/fr\/2018\/03\/les-adventistes-du-bangladesh-offrent-une-education-sanitaire-aux-musulmans-et-hindous-en-charge-denfants\/","name":"Les Adventistes du Bangladesh offrent une \u00e9ducation sanitaire aux Musulmans et Hindous en charge d\u2019enfants - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division","isPartOf":{"@id":"https:\/\/interamerica.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/interamerica.org\/fr\/2018\/03\/les-adventistes-du-bangladesh-offrent-une-education-sanitaire-aux-musulmans-et-hindous-en-charge-denfants\/#primaryimage"},"image":{"@id":"https:\/\/interamerica.org\/fr\/2018\/03\/les-adventistes-du-bangladesh-offrent-une-education-sanitaire-aux-musulmans-et-hindous-en-charge-denfants\/#primaryimage"},"thumbnailUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/04\/bangladesh-adventists-offer-health-education-for-muslim-and-hindu-caregivers.jpg","datePublished":"2018-03-16T04:00:00+00:00","author":{"@id":"https:\/\/interamerica.org\/fr\/#\/schema\/person\/68ede8bdc292885bb76c1e3810e73c39"},"breadcrumb":{"@id":"https:\/\/interamerica.org\/fr\/2018\/03\/les-adventistes-du-bangladesh-offrent-une-education-sanitaire-aux-musulmans-et-hindous-en-charge-denfants\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/interamerica.org\/fr\/2018\/03\/les-adventistes-du-bangladesh-offrent-une-education-sanitaire-aux-musulmans-et-hindous-en-charge-denfants\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/interamerica.org\/fr\/2018\/03\/les-adventistes-du-bangladesh-offrent-une-education-sanitaire-aux-musulmans-et-hindous-en-charge-denfants\/#primaryimage","url":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/04\/bangladesh-adventists-offer-health-education-for-muslim-and-hindu-caregivers.jpg","contentUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/04\/bangladesh-adventists-offer-health-education-for-muslim-and-hindu-caregivers.jpg","width":1000,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/interamerica.org\/fr\/2018\/03\/les-adventistes-du-bangladesh-offrent-une-education-sanitaire-aux-musulmans-et-hindous-en-charge-denfants\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/interamerica.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Les Adventistes du Bangladesh offrent une \u00e9ducation sanitaire aux Musulmans et Hindous en charge d\u2019enfants"}]},{"@type":"WebSite","@id":"https:\/\/interamerica.org\/fr\/#website","url":"https:\/\/interamerica.org\/fr\/","name":"\u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/interamerica.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/interamerica.org\/fr\/#\/schema\/person\/68ede8bdc292885bb76c1e3810e73c39","name":"Lorenzo Verduzco","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g","caption":"Lorenzo Verduzco"}}]}},"_links":{"self":[{"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/posts\/39754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/comments?post=39754"}],"version-history":[{"count":0,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/posts\/39754\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/media\/39624"}],"wp:attachment":[{"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/media?parent=39754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/categories?post=39754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/tags?post=39754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}