{"id":39761,"date":"2018-03-26T00:00:00","date_gmt":"2018-03-26T04:00:00","guid":{"rendered":"http:\/\/192.81.217.108\/2018\/03\/le-president-de-la-dia-annonce-son-depart-a-la-retraite-lors-des-rencontres-administratives-de-leglise\/"},"modified":"2018-04-06T11:58:23","modified_gmt":"2018-04-06T15:58:23","slug":"le-president-de-la-dia-annonce-son-depart-a-la-retraite-lors-des-rencontres-administratives-de-leglise","status":"publish","type":"post","link":"https:\/\/interamerica.org\/fr\/2018\/03\/le-president-de-la-dia-annonce-son-depart-a-la-retraite-lors-des-rencontres-administratives-de-leglise\/","title":{"rendered":"Le pr\u00e9sident de la DIA annonce son d\u00e9part \u00e0 la retraite lors des rencontres administratives de l\u2019Eglise"},"content":{"rendered":"<div id=\"attachment_34135\" style=\"width: 762px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/03\/IL-2.jpg\" rel=\"fancybox\" title=\"Le pr\u00e9sident de la DIA annonce son d\u00e9part \u00e0 la retraite lors des rencontres administratives de l\u2019Eglise\"><img fetchpriority=\"high\" decoding=\"async\" aria-describedby=\"caption-attachment-34135\" class=\" wp-image-34135\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/03\/IL-2.jpg\" alt=\"\" width=\"752\" height=\"470\" \/><\/a><p id=\"caption-attachment-34135\" class=\"wp-caption-text\">Le pr\u00e9sident de la DIA, pasteur Isra\u00ebl Leito (au centre), accueille les plus de cent administrateurs et dirigeants de l\u2019\u00e9glise venus du territoire lors de l\u2019ouverture aujourd\u2019hui des rencontres administratives biannuelles de l\u2019\u00e9glise \u00e0 Miami, en Floride. A c\u00f4t\u00e9 du pasteur Leito se trouvent Filiberto Verduzco (\u00e0 gauche), tr\u00e9sorier de la DIA et Dr Elie Henry (\u00e0 droite), secr\u00e9taire ex\u00e9cutif de la DIA. Image de Keila Trejo \/ DIA<\/p><\/div>\n<p>26 mars 2018 | Miami, Floride, \u00c9tats-Unis | Libna Stevens \/ DIA<\/p>\n<p>Le pr\u00e9sident de la Division Inter Am\u00e9ricaine, Pasteur Isra\u00ebl Leito, a annonc\u00e9 aujourd\u2019hui son d\u00e9part \u00e0 la retraite alors que d\u00e9butent \u00e0 Miami en Floride les rencontres administratives r\u00e9gionales de la d\u00e9nomination.<\/p>\n<p>\u00c0 c\u00f4t\u00e9 de ses coll\u00e8gues administrateurs, pasteur Leito s\u2019est adress\u00e9 au comit\u00e9 ex\u00e9cutif repr\u00e9sentant les 24 r\u00e9gions, ou unions, de l\u2019Inter Am\u00e9rique, indiquant que la d\u00e9cision de partir est intervenue apr\u00e8s beaucoup de r\u00e9flexion et de pri\u00e8re.<\/p>\n<div id=\"attachment_34144\" style=\"width: 417px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/03\/IL-solo.jpg\" rel=\"fancybox\" title=\"Le pr\u00e9sident de la DIA annonce son d\u00e9part \u00e0 la retraite lors des rencontres administratives de l\u2019Eglise\"><img decoding=\"async\" aria-describedby=\"caption-attachment-34144\" class=\" wp-image-34144\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/03\/IL-solo.jpg\" alt=\"\" width=\"407\" height=\"254\" \/><\/a><p id=\"caption-attachment-34144\" class=\"wp-caption-text\">Le 26 mars 2018, pasteur Isra\u00ebl Leito parle au comit\u00e9 ex\u00e9cutif de son d\u00e9part \u00e0 la retraite dans les mois \u00e0 venir. Image de Keila Trejo \/ DIA<\/p><\/div>\n<p>\u00ab Par la gr\u00e2ce de Dieu, j\u2019ai servi l\u2019\u00e9glise dans la DIA pendant de nombreuses ann\u00e9es et j\u2019ai d\u00e9cid\u00e9 de prendre ma retraite \u00e0 partir du 1er ao\u00fbt, \u00bb a d\u00e9clar\u00e9 pasteur Leito alors qu\u2019un silence s\u2019emparait de l\u2019auditorium. Pasteur Leito a parl\u00e9 dans des termes \u00e9logieux du niveau de d\u00e9vouement et d\u2019engagement dont il a \u00e9t\u00e9 t\u00e9moin \u00e0 la fois aux c\u00f4t\u00e9s de Dr Elie Henry, secr\u00e9taire ex\u00e9cutif et de Filiberto Verduzco, tr\u00e9sorier, alors qu\u2019ensemble ils ont dirig\u00e9 la Division en tant que principaux administrateurs.<\/p>\n<p>Le Pasteur Leito a partag\u00e9 une des raisons pour lesquelles pasteur Ted N.C. Wilson \u00e9tait pr\u00e9sent \u00e0 ces rencontres administratives biannuelles de l\u2019Inter Am\u00e9rique et pourquoi celles-ci ont \u00e9t\u00e9 programm\u00e9es avant les rencontres de printemps de l\u2019\u00e9glise mondiale le mois prochain.<\/p>\n<p>Avant que la commission de nominations ne se retire pour consid\u00e9rer des noms, pasteur Wilson a pris quelques instants pour reconna\u00eetre le leadership exceptionnel du pasteur Leito.<\/p>\n<p>\u00ab Au nom de l\u2019\u00e9glise mondiale et de la Conf\u00e9rence G\u00e9n\u00e9rale, je voudrais exprimer notre grande appr\u00e9ciation \u00e0 pasteur et Mme Leito pour leur extraordinaire extension de leur vie au service de leur \u00e9glise, \u00bb a d\u00e9clar\u00e9 pasteur Wilson. \u00ab Comment traitez-vous quelqu\u2019un qui a \u00e9t\u00e9 pr\u00e9sident d\u2019une division pendant pr\u00e8s d\u2019un quart de si\u00e8cle? Le pasteur Leito est vraiment concentr\u00e9 sur l\u2019\u00e9vang\u00e9lisation et tr\u00e8s enthousiaste \u00e0 propos des jeunes. \u00bb<\/p>\n<p>Pasteur Leito, qui a \u00e9t\u00e9 pr\u00e9sident de la Division Inter Am\u00e9ricaine depuis 1993, a dirig\u00e9 l\u2019\u00e9glise, faisant passer son effectif de 1 million \u00e0 3,7 millions de membres. Il d\u00e9tient le record du pr\u00e9sident de division ayant servi le plus longtemps pendant plus de deux mandats cons\u00e9cutifs selon le Bureau des Archives, des Statistiques et de la Recherche de l\u2019\u00e9glise.<\/p>\n<p>Ses 48 ann\u00e9es de service dans la d\u00e9nomination comprennent plus de 41 ann\u00e9es pass\u00e9es en Inter Am\u00e9rique, aux Pays-Bas, en Am\u00e9rique Centrale et au si\u00e8ge de la DIA.<\/p>\n<p>\u00ab Je veux exprimer ma profonde gratitude, exprimer mon extraordinaire appr\u00e9ciation pour la fa\u00e7on dont Dieu vous a conduit, et je pense que beaucoup de personnes ont le m\u00eame sentiment, \u00bb a ajout\u00e9 Pasteur Wilson alors que les membres du comit\u00e9 se levaient pour applaudir.<\/p>\n<div id=\"attachment_34138\" style=\"width: 412px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/03\/IL-3.jpg\" rel=\"fancybox\" title=\"Le pr\u00e9sident de la DIA annonce son d\u00e9part \u00e0 la retraite lors des rencontres administratives de l\u2019Eglise\"><img decoding=\"async\" aria-describedby=\"caption-attachment-34138\" class=\" wp-image-34138\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/03\/IL-3.jpg\" alt=\"\" width=\"402\" height=\"251\" \/><\/a><p id=\"caption-attachment-34138\" class=\"wp-caption-text\">Pasteur Ted N. C. Wilson, pr\u00e9sident de l\u2019Eglise Adventiste mondiale prie pour Pasteur Leito et sa famille quelques minutes apr\u00e8s l\u2019annonce de ses plans de d\u00e9part \u00e0 la retraite. Image de Keila Trejo \/ DIA<\/p><\/div>\n<p>\u00ab Avec la b\u00e9n\u00e9diction de Dieu, l\u2019Inter-Am\u00e9rique fera encore davantage de choses, donc il n\u2019y a rien \u00e0 craindre, \u00bb a dit pasteur Ted Wilson en citant 2 Timoth\u00e9e 1: 7: <sup>\u00a0\u00ab<\/sup> Car ce n\u2019est pas un esprit de timidit\u00e9 que Dieu nous a donn\u00e9, mais un esprit de force, d\u2019amour et de sagesse. \u00bb<\/p>\n<p>Les dirigeants ont pri\u00e9 pour pasteur Leito et sa famille avant que la commission de nominations ne se retire pour \u00e9tudier de nouveaux noms pour le poste de pr\u00e9sident de la DIA.<\/p>\n<p>Comme ce fut le cas pour tout le monde dans l\u2019auditorium, l\u2019annonce a choqu\u00e9 pasteur Josney Rodr\u00edguez, secr\u00e9taire de l\u2019association pastorale pour l\u2019Eglise Adventiste en Inter Am\u00e9rique et ancien pr\u00e9sident d\u2019union au Venezuela.<\/p>\n<p>Josney Rodr\u00edguez qui a d\u00e9couvert le pasteur Leito en lisant ses articles dans le magazine de la jeunesse imprim\u00e9 il y a des d\u00e9cennies, a \u00e9t\u00e9 stup\u00e9fait \u00e0 l\u2019ou\u00efe de cette annonce. \u00ab Je suis fier de l\u2019avoir eu comme mentor, et j\u2019ai vu l\u2019incroyable vision dont il a fait preuve en s\u2019assurant que l\u2019\u00e9glise soit mieux prise en charge par l\u2019organisation de plus d\u2019unions et de f\u00e9d\u00e9rations \u00e0 travers le territoire. \u00bb<\/p>\n<p>Pasteur Leito a contribu\u00e9 \u00e0 la r\u00e9organisation du territoire de l\u2019\u00e9glise en Inter Am\u00e9rique qui est pass\u00e9e de 11 \u00e0 24 unions, et de 60 champs locaux \u00e0 150, depuis son \u00e9lection en 1993.<\/p>\n<p>Son leadership a \u00e9galement amen\u00e9 la cr\u00e9ation du S\u00e9minaire Th\u00e9ologique Inter Am\u00e9ricain (SETAI) qui, pendant des d\u00e9cennies, a offert des dipl\u00f4mes d\u2019\u00e9tudes sup\u00e9rieures, \u00e9quipant des centaines de pasteurs pour le minist\u00e8re dans les \u00e9glises locales et les institutions dans le territoire.<\/p>\n<div id=\"attachment_34148\" style=\"width: 414px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/03\/IL-retirement.jpg\" rel=\"fancybox\" title=\"Le pr\u00e9sident de la DIA annonce son d\u00e9part \u00e0 la retraite lors des rencontres administratives de l\u2019Eglise\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-34148\" class=\" wp-image-34148\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2018\/03\/IL-retirement.jpg\" alt=\"\" width=\"404\" height=\"269\" \/><\/a><p id=\"caption-attachment-34148\" class=\"wp-caption-text\">Pasteur Leito, salu\u00e9 par les membres du comit\u00e9 un peu plus t\u00f4t aujourd\u2019hui. Image de Keila Trejo \/ DIA<\/p><\/div>\n<p>\u00ab\u00a0La vision de pasteur Leito a \u00e9t\u00e9 pour moi une boussole,\u00a0\u00bb a d\u00e9clar\u00e9 Dr Efra\u00edn Vel\u00e1zquez, pr\u00e9sident du SETAI en apprenant la nouvelle du d\u00e9part de son mentor. \u00ab\u00a0Je me souviens \u00e0 l\u2019\u00e2ge de 15 ans avoir rencontr\u00e9 pasteur Leito, en 1989, alors que je participais \u00e0 un Festival des La\u00efcs qui se tenait au Guatemala.\u00a0\u00bb<\/p>\n<p>Le mentorat du pasteur Leito a \u00e9t\u00e9 visible partout dans la DIA, o\u00f9 depuis plus de deux d\u00e9cennies, la formation, la responsabilisation des dirigeants et des membres d\u2019\u00e9glise font maintenant partie de la culture.<\/p>\n<p>Originaire de Cura\u00e7ao, pasteur Leito a commenc\u00e9 sa carri\u00e8re \u00e0 l\u2019\u00e9glise en 1969 en tant que pasteur de district \u00e0 la Mission des Antilles N\u00e9erlandaises. Il a ensuite servi en tant que directeur des minist\u00e8res de la jeunesse au si\u00e8ge de la Division Inter Am\u00e9ricaine \u00e0 Miami. De 1986 \u00e0 1993, pasteur Leito a \u00e9t\u00e9 directeur des Minist\u00e8res de l\u2019Eglise \u00e0 la Conf\u00e9rence G\u00e9n\u00e9rale.<\/p>\n<p>Pasteur Leito a dit qu\u2019il attend son d\u00e9part \u00e0 la retraite pour profiter du temps avec sa femme Ludmila, leur fils et leur fille et leurs trois petits-enfants, et qu\u2019il est pr\u00eat \u00e0 aider l\u2019\u00e9glise si le besoin s\u2019en fait sentir.<\/p>\n<p>Apr\u00e8s plus de deux heures pass\u00e9es en session, la commission de nominations a recommand\u00e9 le nom du Dr Elie Henry comme prochain pr\u00e9sident de la DIA. Son nom devra \u00eatre vot\u00e9 par le comit\u00e9 ex\u00e9cutif de l\u2019\u00e9glise mondiale qui se tiendra dans le Maryland la semaine prochaine, ont indiqu\u00e9 les dirigeants.<\/p>\n<p>La commission de nominations a fait une autre pause pour consid\u00e9rer des noms pour occuper le poste de secr\u00e9taire ex\u00e9cutif.<\/p>\n<p>Pour en savoir plus sur les Rencontres de Milieu d\u2019Ann\u00e9e du Comit\u00e9 Ex\u00e9cutif de l\u2019Inter-Am\u00e9rique cette semaine, visitez-nous sur le site <a href=\"mailto:https:\/\/recursing-golick.147-182-135-0.plesk.page\">interamerica.org<\/a><\/p>\n<p>Pour voir notre galerie de photos de la journ\u00e9e, cliquez <a href=\"https:\/\/www.flickr.com\/photos\/interamerica\/albums\/72157689198224960\">ICI<\/a><\/p>\n<p>Traduction: Patrick Luciathe<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le pr\u00e9sident de la Division Inter Am\u00e9ricaine, Pasteur Isra\u00ebl Leito, a annonc\u00e9 aujourd\u2019hui son d\u00e9part \u00e0 la retraite alors que d\u00e9butent \u00e0 Miami en Floride les rencontres administratives r\u00e9gionales de la d\u00e9nomination.<\/p>\n<p>\u00c0 c\u00f4t\u00e9 de ses coll\u00e8gues administrateurs, pasteur Leito s\u2019est adress\u00e9 au comit\u00e9 ex\u00e9cutif repr\u00e9sentant les 24 r\u00e9gions, ou unions, de  l\u2019Inter Am\u00e9rique, indiquant que la d\u00e9cision de partir est intervenue apr\u00e8s beaucoup de r\u00e9flexion et de pri\u00e8re.<\/p>\n","protected":false},"author":1,"featured_media":39655,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[20,19],"tags":[],"class_list":["post-39761","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles-du-siege-de-la-division","category-rss-francais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le pr\u00e9sident de la DIA annonce son d\u00e9part \u00e0 la retraite lors des rencontres administratives de l\u2019Eglise - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/interamerica.org\/fr\/2018\/03\/le-president-de-la-dia-annonce-son-depart-a-la-retraite-lors-des-rencontres-administratives-de-leglise\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le pr\u00e9sident de la DIA annonce son d\u00e9part \u00e0 la retraite lors des rencontres administratives de l\u2019Eglise - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division\" \/>\n<meta property=\"og:description\" content=\"Le pr\u00e9sident de la Division Inter Am\u00e9ricaine, Pasteur Isra\u00ebl Leito, a annonc\u00e9 aujourd\u2019hui son d\u00e9part \u00e0 la retraite alors que d\u00e9butent \u00e0 Miami en Floride les rencontres administratives r\u00e9gionales de la d\u00e9nomination.  \u00c0 c\u00f4t\u00e9 de ses coll\u00e8gues administrateurs, pasteur Leito s\u2019est adress\u00e9 au comit\u00e9 ex\u00e9cutif repr\u00e9sentant les 24 r\u00e9gions, ou unions, de l\u2019Inter Am\u00e9rique, indiquant que la d\u00e9cision de partir est intervenue apr\u00e8s beaucoup de r\u00e9flexion et de pri\u00e8re.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/interamerica.org\/fr\/2018\/03\/le-president-de-la-dia-annonce-son-depart-a-la-retraite-lors-des-rencontres-administratives-de-leglise\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-26T04:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-04-06T15:58:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/04\/il-solo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lorenzo Verduzco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lorenzo Verduzco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/03\\\/le-president-de-la-dia-annonce-son-depart-a-la-retraite-lors-des-rencontres-administratives-de-leglise\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/03\\\/le-president-de-la-dia-annonce-son-depart-a-la-retraite-lors-des-rencontres-administratives-de-leglise\\\/\"},\"author\":{\"name\":\"Lorenzo Verduzco\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/#\\\/schema\\\/person\\\/68ede8bdc292885bb76c1e3810e73c39\"},\"headline\":\"Le pr\u00e9sident de la DIA annonce son d\u00e9part \u00e0 la retraite lors des rencontres administratives de l\u2019Eglise\",\"datePublished\":\"2018-03-26T04:00:00+00:00\",\"dateModified\":\"2018-04-06T15:58:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/03\\\/le-president-de-la-dia-annonce-son-depart-a-la-retraite-lors-des-rencontres-administratives-de-leglise\\\/\"},\"wordCount\":1321,\"image\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/03\\\/le-president-de-la-dia-annonce-son-depart-a-la-retraite-lors-des-rencontres-administratives-de-leglise\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/il-solo.jpg\",\"articleSection\":[\"Nouvelles du si\u00e8ge de la division\",\"RSS Fran\u00e7ais\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/03\\\/le-president-de-la-dia-annonce-son-depart-a-la-retraite-lors-des-rencontres-administratives-de-leglise\\\/\",\"url\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/03\\\/le-president-de-la-dia-annonce-son-depart-a-la-retraite-lors-des-rencontres-administratives-de-leglise\\\/\",\"name\":\"Le pr\u00e9sident de la DIA annonce son d\u00e9part \u00e0 la retraite lors des rencontres administratives de l\u2019Eglise - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/03\\\/le-president-de-la-dia-annonce-son-depart-a-la-retraite-lors-des-rencontres-administratives-de-leglise\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/03\\\/le-president-de-la-dia-annonce-son-depart-a-la-retraite-lors-des-rencontres-administratives-de-leglise\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/il-solo.jpg\",\"datePublished\":\"2018-03-26T04:00:00+00:00\",\"dateModified\":\"2018-04-06T15:58:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/#\\\/schema\\\/person\\\/68ede8bdc292885bb76c1e3810e73c39\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/03\\\/le-president-de-la-dia-annonce-son-depart-a-la-retraite-lors-des-rencontres-administratives-de-leglise\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/03\\\/le-president-de-la-dia-annonce-son-depart-a-la-retraite-lors-des-rencontres-administratives-de-leglise\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/03\\\/le-president-de-la-dia-annonce-son-depart-a-la-retraite-lors-des-rencontres-administratives-de-leglise\\\/#primaryimage\",\"url\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/il-solo.jpg\",\"contentUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/il-solo.jpg\",\"width\":1280,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/03\\\/le-president-de-la-dia-annonce-son-depart-a-la-retraite-lors-des-rencontres-administratives-de-leglise\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le pr\u00e9sident de la DIA annonce son d\u00e9part \u00e0 la retraite lors des rencontres administratives de l\u2019Eglise\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/\",\"name\":\"\u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/#\\\/schema\\\/person\\\/68ede8bdc292885bb76c1e3810e73c39\",\"name\":\"Lorenzo Verduzco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g\",\"caption\":\"Lorenzo Verduzco\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le pr\u00e9sident de la DIA annonce son d\u00e9part \u00e0 la retraite lors des rencontres administratives de l\u2019Eglise - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/interamerica.org\/fr\/2018\/03\/le-president-de-la-dia-annonce-son-depart-a-la-retraite-lors-des-rencontres-administratives-de-leglise\/","og_locale":"fr_FR","og_type":"article","og_title":"Le pr\u00e9sident de la DIA annonce son d\u00e9part \u00e0 la retraite lors des rencontres administratives de l\u2019Eglise - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division","og_description":"Le pr\u00e9sident de la Division Inter Am\u00e9ricaine, Pasteur Isra\u00ebl Leito, a annonc\u00e9 aujourd\u2019hui son d\u00e9part \u00e0 la retraite alors que d\u00e9butent \u00e0 Miami en Floride les rencontres administratives r\u00e9gionales de la d\u00e9nomination.  \u00c0 c\u00f4t\u00e9 de ses coll\u00e8gues administrateurs, pasteur Leito s\u2019est adress\u00e9 au comit\u00e9 ex\u00e9cutif repr\u00e9sentant les 24 r\u00e9gions, ou unions, de l\u2019Inter Am\u00e9rique, indiquant que la d\u00e9cision de partir est intervenue apr\u00e8s beaucoup de r\u00e9flexion et de pri\u00e8re.","og_url":"https:\/\/interamerica.org\/fr\/2018\/03\/le-president-de-la-dia-annonce-son-depart-a-la-retraite-lors-des-rencontres-administratives-de-leglise\/","og_site_name":"\u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division","article_published_time":"2018-03-26T04:00:00+00:00","article_modified_time":"2018-04-06T15:58:23+00:00","og_image":[{"width":1280,"height":800,"url":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/04\/il-solo.jpg","type":"image\/jpeg"}],"author":"Lorenzo Verduzco","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Lorenzo Verduzco","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/interamerica.org\/fr\/2018\/03\/le-president-de-la-dia-annonce-son-depart-a-la-retraite-lors-des-rencontres-administratives-de-leglise\/#article","isPartOf":{"@id":"https:\/\/interamerica.org\/fr\/2018\/03\/le-president-de-la-dia-annonce-son-depart-a-la-retraite-lors-des-rencontres-administratives-de-leglise\/"},"author":{"name":"Lorenzo Verduzco","@id":"https:\/\/interamerica.org\/fr\/#\/schema\/person\/68ede8bdc292885bb76c1e3810e73c39"},"headline":"Le pr\u00e9sident de la DIA annonce son d\u00e9part \u00e0 la retraite lors des rencontres administratives de l\u2019Eglise","datePublished":"2018-03-26T04:00:00+00:00","dateModified":"2018-04-06T15:58:23+00:00","mainEntityOfPage":{"@id":"https:\/\/interamerica.org\/fr\/2018\/03\/le-president-de-la-dia-annonce-son-depart-a-la-retraite-lors-des-rencontres-administratives-de-leglise\/"},"wordCount":1321,"image":{"@id":"https:\/\/interamerica.org\/fr\/2018\/03\/le-president-de-la-dia-annonce-son-depart-a-la-retraite-lors-des-rencontres-administratives-de-leglise\/#primaryimage"},"thumbnailUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/04\/il-solo.jpg","articleSection":["Nouvelles du si\u00e8ge de la division","RSS Fran\u00e7ais"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/interamerica.org\/fr\/2018\/03\/le-president-de-la-dia-annonce-son-depart-a-la-retraite-lors-des-rencontres-administratives-de-leglise\/","url":"https:\/\/interamerica.org\/fr\/2018\/03\/le-president-de-la-dia-annonce-son-depart-a-la-retraite-lors-des-rencontres-administratives-de-leglise\/","name":"Le pr\u00e9sident de la DIA annonce son d\u00e9part \u00e0 la retraite lors des rencontres administratives de l\u2019Eglise - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division","isPartOf":{"@id":"https:\/\/interamerica.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/interamerica.org\/fr\/2018\/03\/le-president-de-la-dia-annonce-son-depart-a-la-retraite-lors-des-rencontres-administratives-de-leglise\/#primaryimage"},"image":{"@id":"https:\/\/interamerica.org\/fr\/2018\/03\/le-president-de-la-dia-annonce-son-depart-a-la-retraite-lors-des-rencontres-administratives-de-leglise\/#primaryimage"},"thumbnailUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/04\/il-solo.jpg","datePublished":"2018-03-26T04:00:00+00:00","dateModified":"2018-04-06T15:58:23+00:00","author":{"@id":"https:\/\/interamerica.org\/fr\/#\/schema\/person\/68ede8bdc292885bb76c1e3810e73c39"},"breadcrumb":{"@id":"https:\/\/interamerica.org\/fr\/2018\/03\/le-president-de-la-dia-annonce-son-depart-a-la-retraite-lors-des-rencontres-administratives-de-leglise\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/interamerica.org\/fr\/2018\/03\/le-president-de-la-dia-annonce-son-depart-a-la-retraite-lors-des-rencontres-administratives-de-leglise\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/interamerica.org\/fr\/2018\/03\/le-president-de-la-dia-annonce-son-depart-a-la-retraite-lors-des-rencontres-administratives-de-leglise\/#primaryimage","url":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/04\/il-solo.jpg","contentUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2018\/04\/il-solo.jpg","width":1280,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/interamerica.org\/fr\/2018\/03\/le-president-de-la-dia-annonce-son-depart-a-la-retraite-lors-des-rencontres-administratives-de-leglise\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/interamerica.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Le pr\u00e9sident de la DIA annonce son d\u00e9part \u00e0 la retraite lors des rencontres administratives de l\u2019Eglise"}]},{"@type":"WebSite","@id":"https:\/\/interamerica.org\/fr\/#website","url":"https:\/\/interamerica.org\/fr\/","name":"\u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/interamerica.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/interamerica.org\/fr\/#\/schema\/person\/68ede8bdc292885bb76c1e3810e73c39","name":"Lorenzo Verduzco","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fb81a55b6218459490a9c1dc841a34909185b81904c5337b4b27f7a6fd60c49e?s=96&d=mm&r=g","caption":"Lorenzo Verduzco"}}]}},"_links":{"self":[{"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/posts\/39761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/comments?post=39761"}],"version-history":[{"count":0,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/posts\/39761\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/media\/39655"}],"wp:attachment":[{"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/media?parent=39761"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/categories?post=39761"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/tags?post=39761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}