{"id":44703,"date":"2018-10-23T12:54:15","date_gmt":"2018-10-23T16:54:15","guid":{"rendered":"https:\/\/recursing-golick.147-182-135-0.plesk.page\/?p=44703"},"modified":"2018-10-30T09:22:47","modified_gmt":"2018-10-30T13:22:47","slug":"mythes-trompeurs","status":"publish","type":"post","link":"https:\/\/interamerica.org\/fr\/2018\/10\/mythes-trompeurs\/","title":{"rendered":"Mythes Trompeurs"},"content":{"rendered":"<header class=\"article__header article__flow spacing--quarter\">\n<div class=\"article__meta\"><span class=\"pub_date font--secondary--s gray can-be--white\">23 Octobre 2018<\/span><span class=\"divider\"> \u00a0|\u00a0 <\/span><span class=\"pub_region font--secondary--s gray can-be--white\">Silver Spring, Maryland, Etats Unis<\/span><span class=\"divider\"> \u00a0|\u00a0 <\/span><span class=\"byline font--secondary--s gray can-be--white\">Pasteur Mark Finley<\/span><\/div>\n<\/header>\n<div>\n<p class=\"CxSpFirst\">Si un mythe est r\u00e9p\u00e9t\u00e9 assez souvent et suffisamment fort, beaucoup de gens l\u2019accepteront comme une r\u00e9alit\u00e9. Pendant des si\u00e8cles, les gens ont cru que la terre \u00e9tait plate et que le soleil tournait autour de la terre. M\u00eame des scientifiques et des \u00e9rudits r\u00e9put\u00e9s de l\u2019\u00e9poque ont enseign\u00e9 et r\u00e9p\u00e9t\u00e9 le mythe. Un mythe est un mythe, peu importe la force avec laquelle il est clam\u00e9 et peu importe qui le crie.<\/p>\n<p class=\"CxSpMiddle\">Les mythes circulent de mani\u00e8re envahissante sur les r\u00e9seaux sociaux \u00e0 propos du document intitul\u00e9 :\u00a0<a href=\"https:\/\/news.adventist.org\/fileadmin\/news.adventist.org\/files\/news\/documents\/113G_Regard_for_and_Practice_of_General_Conference_Session_and_General_Conference_Executive_Committee_Actions.pdf\" target=\"_blank\" rel=\"noopener\">\u00ab Respect et Pratique des D\u00e9cisions de la Session de la Conf\u00e9rence G\u00e9n\u00e9rale et du Comit\u00e9 Ex\u00e9cutif de la Conf\u00e9rence G\u00e9n\u00e9rale, \u00bb <\/a>r\u00e9cemment vot\u00e9 lors du Concile Annuel de 2018.<\/p>\n<p class=\"CxSpMiddle\">Certains pr\u00e9tendent que la Conf\u00e9rence G\u00e9n\u00e9rale souhaite contr\u00f4ler ce qui se passe m\u00eame au niveau de l\u2019\u00e9glise locale et que personne n\u2019est \u00e0 l&rsquo;abri de ses tentacules de contr\u00f4le. Le document a \u00e9t\u00e9 qualifi\u00e9 de \u00ab papal, \u00bb \u00ab d\u2019anti-protestant, \u00bb et de \u00ab non biblique. \u00bb<\/p>\n<p class=\"CxSpMiddle\">Examinons sept mythes courants et les faits pr\u00e9sent\u00e9s dans le document.<\/p>\n<p><strong><em>Mythe n\u00b0 1 : le document est une d\u00e9marche de la Conf\u00e9rence G\u00e9n\u00e9rale visant \u00e0 centraliser le pouvoir.<\/em><\/strong><\/p>\n<p class=\"CxSpMiddle\"><strong><em>Fait n \u00b0 1 : le document dit en fait que \u00ab la planification et la d\u00e9marche visant \u00e0 s\u2019assurer du respect des d\u00e9cisions seront d\u2019abord confi\u00e9es \u00e0 l\u2019entit\u00e9 la plus proche de la situation \u00bb <\/em><\/strong><em>(p. 1, ligne 25).<\/em><\/p>\n<p class=\"CxSpMiddle\">L\u2019objectif du document est de permettre \u00e0 \u00a0<em>l\u2019entit\u00e9 la plus proche du cas de non-respect des d\u00e9cisions <\/em>\u00e0 g\u00e9rer la situation. Plut\u00f4t que de centraliser le pouvoir, il encourage le contraire. Il encourage instamment le fait que toutes les questions de non-respect des r\u00e8glements soient r\u00e9solues\u00a0<em>au niveau local<\/em>. Si cela n\u2019est pas possible, le niveau hi\u00e9rarchique sup\u00e9rieur suivant peut \u00eatre impliqu\u00e9. Par exemple, si une f\u00e9d\u00e9ration locale est confront\u00e9e \u00e0 un probl\u00e8me de non-respect des d\u00e9cisions qu\u2019elle ne peut ou ne veut pas r\u00e9soudre, l\u2019union de f\u00e9d\u00e9rations ou l\u2019union mission peut \u00eatre impliqu\u00e9e dans la recherche d\u2019une solution. Cela est vrai pour chaque niveau d\u2019organisation de l\u2019\u00e9glise.<\/p>\n<p class=\"CxSpMiddle\">En cas de non-respect d\u2019une d\u00e9cision vot\u00e9e par une Session de la Conf\u00e9rence G\u00e9n\u00e9rale ou par le Comit\u00e9 Ex\u00e9cutif, le Comit\u00e9 Ex\u00e9cutif de la Conf\u00e9rence G\u00e9n\u00e9rale peut \u00eatre impliqu\u00e9.<\/p>\n<p class=\"CxSpMiddle\"><strong><em>Mythe n \u00b0 2 : Le document utilise une m\u00e9thode de contrainte non biblique.<\/em><\/strong><\/p>\n<p class=\"CxSpMiddle\"><strong><em>Fait n \u00b0 2 : Le document fait exactement le contraire. Voici ce que dit le document : \u00ab Les administrateurs qui g\u00e8rent toute question de non-respect des d\u00e9cisions doivent appliquer le principe chr\u00e9tien, qui inclura beaucoup de pri\u00e8re et de dialogue, \u00bb \u00a0<\/em><\/strong><em>(p. 2, ligne 35).<\/em><\/p>\n<p class=\"CxSpMiddle\">Le document est con\u00e7u pour \u00eatre r\u00e9dempteur, pas punitif. Il pr\u00e9voit un processus de dialogue, de pri\u00e8re et de conseil pour d\u00e9terminer la meilleure fa\u00e7on de r\u00e9soudre le probl\u00e8me de non-respect des d\u00e9cisions. Il suit le mod\u00e8le biblique de r\u00e9conciliation et de r\u00e9solution d\u00e9crit dans Matthieu 18.<\/p>\n<p class=\"CxSpMiddle\"><strong><em>Mythe n \u00b0 3 : le document constitue une approche autoritaire brutale pour la r\u00e9solution de probl\u00e8mes.<\/em><\/strong><\/p>\n<p class=\"CxSpMiddle\"><strong><em>Fait n \u00b0 3 : le document pr\u00e9voit la tol\u00e9rance. Il laisse un d\u00e9lai de 60 jours aux administrateurs de l\u2019entit\u00e9 per\u00e7ue comme \u00e9tant dans une situation de non-respect des d\u00e9cisions afin de poursuivre le dialogue et de proposer des solutions \u00e0 la situation difficile\u00a0<\/em><\/strong><em>(p. 2, ligne 14).<\/em><\/p>\n<p class=\"CxSpMiddle\">Le processus ad\u00e9quat envisag\u00e9 dans le document encourage la discussion et la r\u00e9flexion dans la pri\u00e8re sur la fa\u00e7on de r\u00e9soudre les probl\u00e8mes de non-respect des d\u00e9cisions. Plut\u00f4t qu\u2019un ordre dictatorial autoritaire, le document assure un processus de collaboration et cherche \u00e0 trouver des solutions aux probl\u00e8mes de non-respect des r\u00e8glements.<\/p>\n<p class=\"CxSpMiddle\">Les \u00ab avertissements \u00bb et \u00ab r\u00e9primandes \u00bb propos\u00e9s sont con\u00e7us pour permettre aux entit\u00e9s de r\u00e9fl\u00e9chir \u00e0 la gravit\u00e9 du non-respect des d\u00e9cisions vot\u00e9es par l\u2019\u00c9glise mondiale et pour les encourager \u00e0 \u00eatre \u00e0 nouveau en harmonie avec l\u2019\u00c9glise mondiale. Tout avertissement, toute r\u00e9primande ou toute autre cons\u00e9quence doit \u00eatre vot\u00e9 par le Comit\u00e9 Ex\u00e9cutif de la Conf\u00e9rence G\u00e9n\u00e9rale avec une repr\u00e9sentation mondiale.<\/p>\n<p class=\"CxSpMiddle\"><strong><em>Mythe n\u00b0 4 : Le vote d\u2019autorit\u00e9 final concernant les cons\u00e9quences rel\u00e8ve du Comit\u00e9 Administratif de la Conf\u00e9rence G\u00e9n\u00e9rale \u00e0 Silver Spring, dans le Maryland.<\/em><\/strong><\/p>\n<p class=\"CxSpMiddle\"><strong><em>Fait n \u00b0 4 : le document indique clairement : \u00ab Si, apr\u00e8s que l\u2019organisation la plus proche de la situation n\u2019ait pas \u00e9t\u00e9 en mesure de r\u00e9soudre un probl\u00e8me de non-respect des d\u00e9cisions et que le Comit\u00e9 d\u2019Examen du Respect des D\u00e9cisions, ait recommand\u00e9 des sanctions,<\/em><\/strong><em>,\u00a0<strong>seul le Comit\u00e9 Ex\u00e9cutif de la Conf\u00e9rence G\u00e9n\u00e9rale et \/ ou la Conf\u00e9rence G\u00e9n\u00e9rale en Session a autorit\u00e9 pour mettre en \u0153uvre la recommandation \u00bb\u00a0<\/strong>(p. 3, lignes 27-30).<\/em><\/p>\n<p class=\"CxSpMiddle\"><strong><em>Mythe n \u00b0 5 : Ce document change la culture de l\u2019\u00c9glise Adventiste du Septi\u00e8me Jour et emp\u00eache la libert\u00e9 de conscience.<\/em><\/strong><\/p>\n<p class=\"CxSpMiddle\"><strong><em>Fait n \u00b0 5 : Ce qui changera la culture de l\u2019\u00c9glise Adventiste du Septi\u00e8me Jour, c\u2019est le fait que les votes de la Conf\u00e9rence G\u00e9n\u00e9rale en Session et de son Comit\u00e9 Ex\u00e9cutif ne soient pas respect\u00e9s. Si chaque entit\u00e9, de l\u2019\u00e9glise locale aux f\u00e9d\u00e9rations locales, en passant par les unions et les divisions ne respecte pas les d\u00e9cisions de l\u2019\u00c9glise mondiale, l\u2019\u00e9glise ira vers le chaos organisationnel, la fragmentation, la d\u00e9sunion et le congr\u00e9gationalisme.<\/em><\/strong><\/p>\n<p class=\"CxSpMiddle\">La question qui se pose \u00e0 l\u2019\u00e9glise est de savoir si elle souhaite demeurer un corps mondial uni, accordant de la valeur aux d\u00e9cisions collectives de la Conf\u00e9rence G\u00e9n\u00e9rale en Session et de son Comit\u00e9 Ex\u00e9cutif, ou si elle deviendra un corps rassemblant dans un lien tr\u00e8s l\u00e9ger diverses entit\u00e9s organisationnelles.<\/p>\n<p class=\"CxSpMiddle\"><strong><em>Mythe n \u00b0 6 : La Conf\u00e9rence G\u00e9n\u00e9rale ne dispose d\u2019aucune entit\u00e9 pour superviser ses activit\u00e9s et ses actions.\u00a0<\/em><\/strong><\/p>\n<p class=\"CxSpMiddle\"><strong><em>Fait n \u00b0 6 : La Conf\u00e9rence G\u00e9n\u00e9rale r\u00e9pond devant le Comit\u00e9 Ex\u00e9cutif de la Conf\u00e9rence G\u00e9n\u00e9rale. C\u2019est pourquoi des rapports sont r\u00e9guli\u00e8rement pr\u00e9sent\u00e9s lors de la Rencontre de Printemps et du Concile Annuel. En outre, pour s\u2019assurer de la conformit\u00e9 de ses finances, la Conf\u00e9rence G\u00e9n\u00e9rale fait l\u2019objet de v\u00e9rifications r\u00e9guli\u00e8res par un cabinet d\u2019audit ind\u00e9pendant et tr\u00e8s respect\u00e9, Maner &amp; Costerisan,<\/em><\/strong><\/p>\n<p class=\"CxSpMiddle\">Lors de la Rencontre de Printemps de 2018, les repr\u00e9sentants de Maner &amp; Costerisan ont indiqu\u00e9 que la Conf\u00e9rence G\u00e9n\u00e9rale \u00e9tait en conformit\u00e9 avec les R\u00e8glements de la Conf\u00e9rence G\u00e9n\u00e9rale concernant les questions financi\u00e8res.<\/p>\n<p class=\"CxSpMiddle\">Durant cette m\u00eame Rencontre de Printemps de 2018, dans le cadre des rapports financiers, le d\u00e9partement des finances de la Conf\u00e9rence G\u00e9n\u00e9rale a pr\u00e9sent\u00e9 le rapport intitul\u00e9 \u00ab Responsabilit\u00e9 dans l\u2019Utilisation de la D\u00eeme. \u00bb<\/p>\n<p class=\"CxSpMiddle\">Ceci, de m\u00eame que le rapport de Maner &amp; Costerisan, peut \u00eatre lu dans l&rsquo;\u00e9dition de Mai 2018 de la\u00a0<em><a href=\"https:\/\/executivecommittee.adventist.org\/wp-content\/uploads\/2018\/06\/ECN-May-2018.pdf\" target=\"_blank\" rel=\"noopener\">Newsletter du Comit\u00e9 Ex\u00e9cutif <\/a><\/em><em> de la Conf\u00e9rence G\u00e9n\u00e9rale.<\/em><\/p>\n<p class=\"CxSpMiddle\"><strong><em>Mythe n \u00b0 7 : le document n\u2019est pas biblique. Il place les r\u00e8glements au-dessus des \u00c9critures et est donc contraire \u00e0 la R\u00e9forme Protestante en ce qu\u2019elle viole la libert\u00e9 de conscience.<\/em><\/strong><\/p>\n<p class=\"CxSpMiddle\"><strong><em>Fait n \u00b0 7 : L\u2019organisation de l\u2019\u00c9glise est un principe fondamental de l\u2019enseignement du Nouveau Testament. L\u2019\u00c9glise est unie par le Saint-Esprit \u00e0 travers un engagement commun envers le Christ, une croyance partag\u00e9e dans les enseignements bibliques, une passion pour la mission et une organisation eccl\u00e9siale mondiale. Si l\u2019un quelconque de ces \u00e9l\u00e9ments \u00e9tait subtilement remis en cause, toute l\u2019\u00c9glise serait en danger.<\/em><\/strong><\/p>\n<p class=\"CxSpMiddle\">Les r\u00e8glements de l\u2019\u00c9glise ne dictent jamais et ne remplacent jamais la conscience de l\u2019individu. Chaque croyant est libre de suivre les consignes de sa conscience. Il y aura des moments o\u00f9 les honn\u00eates gens verront les choses diff\u00e9remment. Les r\u00e8glements sont des accords sur la mani\u00e8re dont l\u2019\u00c9glise fonctionnera. Ils d\u00e9terminent le fonctionnement d\u2019une famille internationale et mondiale.<\/p>\n<p class=\"CxSpMiddle\">Le point est le suivant. Les r\u00e8glements ne dictent pas ce que nous croyons mais elles devraient r\u00e9gir les actions des dirigeants d\u2019\u00e9glise. Les dirigeants d\u2019\u00e9glise ont la responsabilit\u00e9 \u00e9thique de respecter les d\u00e9cisions prises conjointement par les repr\u00e9sentants de l\u2019\u00c9glise mondiale lors d\u2019une Session de la Conf\u00e9rence G\u00e9n\u00e9rale.<\/p>\n<p class=\"CxSpMiddle\">Les r\u00e8glements ne sont pas des enseignements bibliques immuables et ne doivent jamais \u00eatre \u00e9lev\u00e9s au-dessus de la v\u00e9rit\u00e9 biblique. Ce sont des principes de fonctionnement que les d\u00e9l\u00e9gu\u00e9s \u00e0 une Session de la Conf\u00e9rence G\u00e9n\u00e9rale ou \u00e0 un Comit\u00e9 Ex\u00e9cutif peuvent changer et ont parfois chang\u00e9. Si des modifications sont apport\u00e9es aux r\u00e8glements adopt\u00e9s par la Conf\u00e9rence G\u00e9n\u00e9rale en Session ou aux d\u00e9cisions vot\u00e9es par le Comit\u00e9 Ex\u00e9cutif, elles doivent \u00eatre effectu\u00e9es par le m\u00eame corps que celui qui a vot\u00e9 ces r\u00e8glements.<\/p>\n<p class=\"CxSpMiddle\"><strong>L\u00e0 o\u00f9 la Bataille n\u2019Est Pas<\/strong><\/p>\n<p class=\"CxSpMiddle\">Les mythes ne nous servent jamais bien. Ils nous conduisent \u00e0 agir par peur dans un monde d\u2019illusion. Pire encore, ils nous \u00e9loignent de la mission de l\u2019\u00c9glise qui est de vivre et de pr\u00eacher l\u2019\u00c9vangile afin d\u2019accomplir la mission du Christ.<\/p>\n<p class=\"CxSpMiddle\">Croire aux mythes nous am\u00e8ne \u00e0 nous battre l\u00e0 o\u00f9 la bataille n\u2019est pas au lieu de concentrer nos \u00e9nergies spirituelles et notre attention sur l\u2019action aupr\u00e8s des personnes perdues afin de pr\u00e9parer des hommes et des femmes \u00e0 la venue de notre Seigneur.<\/p>\n<p class=\"CxSpMiddle\"><em>Pasteur Mark Finley est un \u00e9vang\u00e9liste bien connu, un auteur et vice-pr\u00e9sident \u00e0 la retraite de la Conf\u00e9rence G\u00e9n\u00e9rale de l\u2019\u00c9glise Adventiste du Septi\u00e8me Jour.<\/em><\/p>\n<\/div>\n<div class=\"text article__body spacing\">\n<figure class=\"figure \">\n<div class=\"img-wrap \"><picture class=\"picture \"><source srcset=\"fileadmin\/_processed_\/2\/f\/csm_Fact_vs._Myth_GettyImages-849249352_37aff6721c.jpg\" media=\"(min-width: 1100px)\" \/><source srcset=\"fileadmin\/_processed_\/2\/f\/csm_Fact_vs._Myth_GettyImages-849249352_5003128a61.jpg\" media=\"(min-width: 901px)\" \/><source srcset=\"fileadmin\/_processed_\/2\/f\/csm_Fact_vs._Myth_GettyImages-849249352_b09a4508ed.jpg\" media=\"(min-width: 701px)\" \/><source srcset=\"fileadmin\/_processed_\/2\/f\/csm_Fact_vs._Myth_GettyImages-849249352_d4589a319b.jpg\" media=\"(min-width: 401px)\" \/><\/picture><\/div>\n<div><\/div>\n<\/figure>\n<\/div>\n<p>Traduction: Patrick Luciathe<\/p>\n","protected":false},"excerpt":{"rendered":"<p>23 Octobre 2018 \u00a0|\u00a0 Silver Spring, Maryland, Etats Unis \u00a0|\u00a0 Pasteur Mark Finley Si un mythe est r\u00e9p\u00e9t\u00e9 assez souvent et suffisamment fort, beaucoup de gens l\u2019accepteront comme une r\u00e9alit\u00e9&#8230;.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[18,19],"tags":[],"class_list":["post-44703","post","type-post","status-publish","format-standard","hentry","category-nouvelles-de-leglise-mondiale","category-rss-francais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mythes Trompeurs - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/interamerica.org\/fr\/2018\/10\/mythes-trompeurs\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mythes Trompeurs - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division\" \/>\n<meta property=\"og:description\" content=\"23 Octobre 2018 \u00a0|\u00a0 Silver Spring, Maryland, Etats Unis \u00a0|\u00a0 Pasteur Mark Finley Si un mythe est r\u00e9p\u00e9t\u00e9 assez souvent et suffisamment fort, beaucoup de gens l\u2019accepteront comme une r\u00e9alit\u00e9....\" \/>\n<meta property=\"og:url\" content=\"https:\/\/interamerica.org\/fr\/2018\/10\/mythes-trompeurs\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-23T16:54:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-30T13:22:47+00:00\" \/>\n<meta name=\"author\" content=\"libna\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"libna\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/10\\\/mythes-trompeurs\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/10\\\/mythes-trompeurs\\\/\"},\"author\":{\"name\":\"libna\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/#\\\/schema\\\/person\\\/29998f2bc2d8bd0d38662909289b54f1\"},\"headline\":\"Mythes Trompeurs\",\"datePublished\":\"2018-10-23T16:54:15+00:00\",\"dateModified\":\"2018-10-30T13:22:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/10\\\/mythes-trompeurs\\\/\"},\"wordCount\":1719,\"commentCount\":0,\"articleSection\":[\"Nouvelles de l'\u00c9glise mondiale\",\"RSS Fran\u00e7ais\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/10\\\/mythes-trompeurs\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/10\\\/mythes-trompeurs\\\/\",\"url\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/10\\\/mythes-trompeurs\\\/\",\"name\":\"Mythes Trompeurs - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/#website\"},\"datePublished\":\"2018-10-23T16:54:15+00:00\",\"dateModified\":\"2018-10-30T13:22:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/#\\\/schema\\\/person\\\/29998f2bc2d8bd0d38662909289b54f1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/10\\\/mythes-trompeurs\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/10\\\/mythes-trompeurs\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2018\\\/10\\\/mythes-trompeurs\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mythes Trompeurs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/\",\"name\":\"\u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/#\\\/schema\\\/person\\\/29998f2bc2d8bd0d38662909289b54f1\",\"name\":\"libna\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7c5bd30ae4b47a9ba3c856590957fd1d96dc588bf3ac05719d247e126840331f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7c5bd30ae4b47a9ba3c856590957fd1d96dc588bf3ac05719d247e126840331f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7c5bd30ae4b47a9ba3c856590957fd1d96dc588bf3ac05719d247e126840331f?s=96&d=mm&r=g\",\"caption\":\"libna\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mythes Trompeurs - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/interamerica.org\/fr\/2018\/10\/mythes-trompeurs\/","og_locale":"fr_FR","og_type":"article","og_title":"Mythes Trompeurs - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division","og_description":"23 Octobre 2018 \u00a0|\u00a0 Silver Spring, Maryland, Etats Unis \u00a0|\u00a0 Pasteur Mark Finley Si un mythe est r\u00e9p\u00e9t\u00e9 assez souvent et suffisamment fort, beaucoup de gens l\u2019accepteront comme une r\u00e9alit\u00e9....","og_url":"https:\/\/interamerica.org\/fr\/2018\/10\/mythes-trompeurs\/","og_site_name":"\u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division","article_published_time":"2018-10-23T16:54:15+00:00","article_modified_time":"2018-10-30T13:22:47+00:00","author":"libna","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"libna","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/interamerica.org\/fr\/2018\/10\/mythes-trompeurs\/#article","isPartOf":{"@id":"https:\/\/interamerica.org\/fr\/2018\/10\/mythes-trompeurs\/"},"author":{"name":"libna","@id":"https:\/\/interamerica.org\/fr\/#\/schema\/person\/29998f2bc2d8bd0d38662909289b54f1"},"headline":"Mythes Trompeurs","datePublished":"2018-10-23T16:54:15+00:00","dateModified":"2018-10-30T13:22:47+00:00","mainEntityOfPage":{"@id":"https:\/\/interamerica.org\/fr\/2018\/10\/mythes-trompeurs\/"},"wordCount":1719,"commentCount":0,"articleSection":["Nouvelles de l'\u00c9glise mondiale","RSS Fran\u00e7ais"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/interamerica.org\/fr\/2018\/10\/mythes-trompeurs\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/interamerica.org\/fr\/2018\/10\/mythes-trompeurs\/","url":"https:\/\/interamerica.org\/fr\/2018\/10\/mythes-trompeurs\/","name":"Mythes Trompeurs - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division","isPartOf":{"@id":"https:\/\/interamerica.org\/fr\/#website"},"datePublished":"2018-10-23T16:54:15+00:00","dateModified":"2018-10-30T13:22:47+00:00","author":{"@id":"https:\/\/interamerica.org\/fr\/#\/schema\/person\/29998f2bc2d8bd0d38662909289b54f1"},"breadcrumb":{"@id":"https:\/\/interamerica.org\/fr\/2018\/10\/mythes-trompeurs\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/interamerica.org\/fr\/2018\/10\/mythes-trompeurs\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/interamerica.org\/fr\/2018\/10\/mythes-trompeurs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/interamerica.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Mythes Trompeurs"}]},{"@type":"WebSite","@id":"https:\/\/interamerica.org\/fr\/#website","url":"https:\/\/interamerica.org\/fr\/","name":"\u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/interamerica.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/interamerica.org\/fr\/#\/schema\/person\/29998f2bc2d8bd0d38662909289b54f1","name":"libna","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7c5bd30ae4b47a9ba3c856590957fd1d96dc588bf3ac05719d247e126840331f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7c5bd30ae4b47a9ba3c856590957fd1d96dc588bf3ac05719d247e126840331f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7c5bd30ae4b47a9ba3c856590957fd1d96dc588bf3ac05719d247e126840331f?s=96&d=mm&r=g","caption":"libna"}}]}},"_links":{"self":[{"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/posts\/44703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/comments?post=44703"}],"version-history":[{"count":0,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/posts\/44703\/revisions"}],"wp:attachment":[{"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/media?parent=44703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/categories?post=44703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/tags?post=44703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}