{"id":51295,"date":"2019-08-27T20:31:32","date_gmt":"2019-08-28T00:31:32","guid":{"rendered":"https:\/\/recursing-golick.147-182-135-0.plesk.page\/?p=51295"},"modified":"2019-08-28T12:54:20","modified_gmt":"2019-08-28T16:54:20","slug":"au-mexique-leglise-forme-des-interpretes-en-langue-des-signes-pour-mieux-toucher-les-malentendants","status":"publish","type":"post","link":"https:\/\/interamerica.org\/fr\/2019\/08\/au-mexique-leglise-forme-des-interpretes-en-langue-des-signes-pour-mieux-toucher-les-malentendants\/","title":{"rendered":"Au Mexique, l\u2019\u00e9glise forme des interpr\u00e8tes en langue des signes pour mieux toucher les malentendants"},"content":{"rendered":"<div id=\"attachment_51263\" style=\"width: 812px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" aria-describedby=\"caption-attachment-51263\" class=\"wp-image-51262\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2019\/08\/nomu-interpreters-1280-1024x640.jpg\" alt=\"\" width=\"802\" height=\"501\" srcset=\"https:\/\/interamerica.org\/wp-content\/uploads\/2019\/08\/nomu-interpreters-1280-1024x640.jpg 1024w, https:\/\/interamerica.org\/wp-content\/uploads\/2019\/08\/nomu-interpreters-1280-300x188.jpg 300w, https:\/\/interamerica.org\/wp-content\/uploads\/2019\/08\/nomu-interpreters-1280-768x480.jpg 768w, https:\/\/interamerica.org\/wp-content\/uploads\/2019\/08\/nomu-interpreters-1280.jpg 1280w\" sizes=\"(max-width: 802px) 100vw, 802px\" \/><p id=\"caption-attachment-51263\" class=\"wp-caption-text\">Un groupe d\u2019interpr\u00e8tes adventistes pose pour une photo tout en signant au cours de l\u2019atelier de formation de six jours visant \u00e0 les aider \u00e0 parfaire leurs comp\u00e9tences pour atteindre les malentendants dans leurs \u00e9glises et leurs communaut\u00e9s. Quelque 47 interpr\u00e8tes se sont r\u00e9unis \u00e0 Villahermosa, dans l\u2019\u00e9tat de Tabasco, au Mexique, du 22 au 27 juillet 2019. Photo : Union Nord-Mexicaine<\/p><\/div>\n<p>27 Ao\u00fbt 2019 | Villahermosa, Tabasco, Mexique | \u00c9quipe Informations DIA<\/p>\n<p>Dans le cadre des efforts actuellement d\u00e9ploy\u00e9s par l\u2019\u00c9glise adventiste du septi\u00e8me jour dans le Nord du Mexique pour mieux atteindre les personnes malentendantes dans leurs \u00e9glises et leurs communaut\u00e9s, un groupe d\u2019interpr\u00e8tes adventistes s\u2019est r\u00e9cemment r\u00e9uni pour prendre part \u00e0 un atelier de formation sp\u00e9cial \u00e0 Villahermosa, dans l\u2019\u00e9tat de Tabasco, au Mexique. Les 47 \u00e9tudiants interpr\u00e8tes des trois principales unions du Mexique se sont r\u00e9unis pour enrichir leurs connaissances, comprendre leur mission et \u00e9laborer des strat\u00e9gies pour faire progresser le minist\u00e8re de proclamation de l\u2019\u00e9vangile en langue des signes pour les malentendants.<\/p>\n<p>\u00ab Nous remercions Dieu parce qu\u2019il fortifie son peuple juste \u00e0 ce moment de la fin des temps, de telle sorte que la grande mission qui est de pr\u00eacher l\u2019\u00e9vangile \u00e0 toutes langues puisse \u00eatre accomplie, \u00bb a d\u00e9clar\u00e9 pasteur David Maldonado, directeur du minist\u00e8re des besoins sp\u00e9ciaux pour l\u2019\u00c9glise adventiste dans le Nord du Mexique. \u00ab L\u2019\u00e9glise dans le monde entier construit des ponts pour toucher la communaut\u00e9 des sourds et il est important pour nous de nous assurer que les interpr\u00e8tes soient form\u00e9s \u00e0 la Langue des Signes Mexicaine, \u00bb a expliqu\u00e9 pasteur Maldonado.<\/p>\n<p>L&rsquo;atelier de formation est la deuxi\u00e8me initiative de ce type men\u00e9e dans le cadre de l\u2019effort global du minist\u00e8re des besoins sp\u00e9ciaux lanc\u00e9 par l\u2019Union du Nord du Mexique il y a sept ans, ont d\u00e9clar\u00e9 les organisateurs.<\/p>\n<p>Cette ann\u00e9e, l\u2019\u00e9glise dans l\u2019Union du Sud-Est et dans l\u2019Union Inter-Oc\u00e9anique a r\u00e9uni son propre groupe pour participer au Deuxi\u00e8me Atelier Annuel des Interpr\u00e8tes en Langue des Signes Mexicaine, qui a permis d\u2019avoir 50 heures de formation, du 22 au 27 juillet 2019, \u00e0 l\u2019\u00e9glise adventiste 27 de Febrero \u00e0 Villahermosa.<\/p>\n<p>Les interpr\u00e8tes adventistes qui ont r\u00e9pondu \u00e0 l\u2019appel sont tous des b\u00e9n\u00e9voles, a d\u00e9clar\u00e9 David Maldonado. \u00ab Ils utilisent leurs propres ressources et leur temps pour se pr\u00e9parer et servir les sourds dans leurs propres \u00e9glises et communaut\u00e9s, \u00bb a dit pasteur Maldonado.<\/p>\n<div id=\"attachment_51255\" style=\"width: 809px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" aria-describedby=\"caption-attachment-51255\" class=\" wp-image-51254\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2019\/08\/david-maldonado-interpreters2019.jpg\" alt=\"\" width=\"799\" height=\"595\" srcset=\"https:\/\/interamerica.org\/wp-content\/uploads\/2019\/08\/david-maldonado-interpreters2019.jpg 900w, https:\/\/interamerica.org\/wp-content\/uploads\/2019\/08\/david-maldonado-interpreters2019-300x223.jpg 300w, https:\/\/interamerica.org\/wp-content\/uploads\/2019\/08\/david-maldonado-interpreters2019-768x572.jpg 768w\" sizes=\"(max-width: 799px) 100vw, 799px\" \/><p id=\"caption-attachment-51255\" class=\"wp-caption-text\">Le pasteur David Maldonado, directeur du minist\u00e8re des besoins sp\u00e9ciaux pour l\u2019\u00c9glise adventiste dans le Nord du Mexique et principal organisateur de l\u2019atelier, parle aux d\u00e9l\u00e9gu\u00e9s de leur r\u00f4le important dans la proclamation de l\u2019\u00e9vangile aux sourds l\u00e0 o\u00f9 ils se trouvent. Photo : Union Nord Mexicaine<\/p><\/div>\n<p>Selon les statistiques nationales (recensement de 2010), il y a plus de 680000 malentendants et 9000 sourds au Mexique, soit environ 12,1% de la population.<\/p>\n<p><strong>\u00c9quipe d\u2019interpr\u00e8tes<\/strong><\/p>\n<p>\u00ab Ce plan est vraiment important car nous avons besoin d\u2019une \u00e9quipe d\u2019interpr\u00e8tes qui soient en mesure de nous aider aupr\u00e8s de cette grande population de sourds que nous n\u2019avons pas encore pu toucher, \u00bb a d\u00e9clar\u00e9 pasteur Maldonado. L\u2019\u00c9glise adventiste dans le Nord du Mexique compte 169 membres d\u2019\u00e9glise qui ont \u00e9t\u00e9 identifi\u00e9s comme sourds et le plan est de continuer \u00e0 proposer des formations et des outils pour enseigner et former l\u2019\u00e9glise en g\u00e9n\u00e9ral, par exemple les diacres et les diaconesses, et les clubs d\u2019\u00e9glise comme les \u00e9claireurs, de telle sorte que l\u2019\u00e9glise puisse \u00eatre pr\u00e9par\u00e9e \u00e0 recevoir et \u00e0 inclure les nouveaux membres qui sont sourds, dans la vie de l\u2019\u00e9glise, a expliqu\u00e9 pasteur Maldonado.<\/p>\n<p>L\u2019atelier a regroup\u00e9 les interpr\u00e8tes dans trois niveaux, du niveau basique au niveau avanc\u00e9. Des strat\u00e9gies ont \u00e9t\u00e9 d\u00e9finies pour fournir un plan de formation pour chaque niveau comprenant deux ateliers par an pour le niveau avanc\u00e9, y compris une formation en ligne une fois par semaine, le dimanche. Le groupe interm\u00e9diaire assistera \u00e0 des ateliers r\u00e9gionaux pour progresser vers le groupe du niveau avanc\u00e9 et aider ceux qui se trouvent au niveau basique, a expliqu\u00e9 David Maldonado.<\/p>\n<p>Le programme de formation, qui a dur\u00e9 six jours, a permis d\u2019examiner l\u2019utilisation des signes et l\u2019utilisation de la langue des signes, les phrases et les mots ambigus, les expressions et les idiomes appropri\u00e9s, les proverbes et les paraboles bibliques. Les interpr\u00e8tes ont pris part \u00e0 des sessions d\u2019exercice de groupe et ont pris le temps d\u2019\u00e9changer leurs exp\u00e9riences.<\/p>\n<p>Daniel Vergara \u00e9tait vraiment reconnaissant et extatique d\u2019avoir appris autant de mots en langue des signes. Daniel Vergara aide un groupe de malentendants \u00e0 Guasave, dans l\u2019\u00e9tat du Sinaloa, dans le Nord du Mexique. Il faisait partie du groupe de niveau basique lors du programme. \u00ab J\u2019ai vraiment beaucoup appris avec cette formation. Il me fallait venir pour voir comment je pouvais mieux aider nos fr\u00e8res et s\u0153urs sourds dans mon pays, \u00bb a dit Daniel Vergara.<\/p>\n<div id=\"attachment_51284\" style=\"width: 811px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" aria-describedby=\"caption-attachment-51284\" class=\" wp-image-51283\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2019\/08\/interpreters-sign-prayer.jpg\" alt=\"\" width=\"801\" height=\"534\" srcset=\"https:\/\/interamerica.org\/wp-content\/uploads\/2019\/08\/interpreters-sign-prayer.jpg 1000w, https:\/\/interamerica.org\/wp-content\/uploads\/2019\/08\/interpreters-sign-prayer-300x200.jpg 300w, https:\/\/interamerica.org\/wp-content\/uploads\/2019\/08\/interpreters-sign-prayer-768x512.jpg 768w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><p id=\"caption-attachment-51284\" class=\"wp-caption-text\">Les d\u00e9l\u00e9gu\u00e9s participent \u00e0 la pri\u00e8re pendant le culte du sabbat 27 juillet \u00e0 l\u2019\u00e9glise adventiste 27 de Febrero \u00e0 Villahermosa. Photo : Union Nord-Mexicaine<\/p><\/div>\n<p>\u00c0 seulement 15 ans, Estrella Ram\u00edrez a int\u00e9gr\u00e9 le groupe interm\u00e9diaire d\u2019interpr\u00e8tes. Elle \u00e9tudie \u00e0 l\u2019\u00e9cole pr\u00e9paratoire de l\u2019Universit\u00e9 de Montemorelos et interpr\u00e8te en langue des signes lors du service religieux de l\u2019universit\u00e9 le sabbat. \u00ab Je veux \u00eatre une interpr\u00e8te pour les sourds pour le reste de ma vie, \u00bb a-t-elle d\u00e9clar\u00e9. Estrella Ram\u00edrez a remerci\u00e9 les instructeurs et ceux du groupe des interpr\u00e8tes de niveau avanc\u00e9, d\u2019avoir corrig\u00e9 certaines de ses expressions en langue des signes et de lui avoir appris \u00e0 se perfectionner.<\/p>\n<p><strong>Faciliter plus de formation<\/strong><\/p>\n<p>L\u2019objectif est de consolider et de faciliter davantage de formation pour les interpr\u00e8tes d\u00e9vou\u00e9s tels que Daniel Vergara et Estrella Ram\u00edrez, a d\u00e9clar\u00e9 pasteur Maldonado.<\/p>\n<p>Jusqu\u2019\u00e0 pr\u00e9sent, l\u2019\u00e9glise dans le Nord du Mexique a organis\u00e9 et soutenu un congr\u00e8s national adventiste annuel pour les sourds au cours des trois derni\u00e8res ann\u00e9es. De plus, les interpr\u00e8tes ont \u00e9t\u00e9 invit\u00e9s \u00e0 prendre part aux rencontres ex\u00e9cutives de l\u2019union afin de contribuer \u00e0 la prise de d\u00e9cisions et \u00e0 des initiatives visant \u00e0 toucher les sourds et les personnes ayant des besoins sp\u00e9ciaux sur le territoire de l\u2019\u00e9glise.<\/p>\n<p>Dans son message sp\u00e9cial adress\u00e9 aux interpr\u00e8tes en formation, pasteur Arturo King, pr\u00e9sident de l\u2019\u00c9glise adventiste dans le Nord du Mexique, les a f\u00e9licit\u00e9s et les a remerci\u00e9s pour leur engagement \u00e0 atteindre les malentendants et les personnes ayant des besoins sp\u00e9ciaux.<\/p>\n<p>\u00ab Quelle joie de savoir qu\u2019il y a des membres qui souhaitent tendre leurs bras de compassion et d\u2019amour vers les personnes qui n\u2019ont pas le privil\u00e8ge de pouvoir entendre, mais qui ont le privil\u00e8ge de d\u00e9couvrir l\u2019amour du Christ \u00e0 travers ses sujets, a dit Arturo king. \u00ab Nous sommes vraiment reconnaissants parce qu\u2019il a mis dans votre c\u0153ur de partager la bonne nouvelle du salut avec ce segment de la population qui a besoin de notre soutien et de notre attention. \u00bb<\/p>\n<div id=\"attachment_51287\" style=\"width: 811px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-51287\" class=\" wp-image-51286\" src=\"https:\/\/recursing-golick.147-182-135-0.plesk.page\/wp-content\/uploads\/2019\/08\/interpreters-certificate-nomu-2019.jpg\" alt=\"\" width=\"801\" height=\"534\" srcset=\"https:\/\/interamerica.org\/wp-content\/uploads\/2019\/08\/interpreters-certificate-nomu-2019.jpg 1000w, https:\/\/interamerica.org\/wp-content\/uploads\/2019\/08\/interpreters-certificate-nomu-2019-300x200.jpg 300w, https:\/\/interamerica.org\/wp-content\/uploads\/2019\/08\/interpreters-certificate-nomu-2019-768x512.jpg 768w\" sizes=\"(max-width: 801px) 100vw, 801px\" \/><p id=\"caption-attachment-51287\" class=\"wp-caption-text\">Les d\u00e9l\u00e9gu\u00e9s au programme re\u00e7oivent leur certificat apr\u00e8s avoir suivi l\u2019atelier de formation \u00e0 Villahermosa, dans l\u2019\u00e9tat de Tabasco. Photo : Union Nord Mexicaine<\/p><\/div>\n<p><strong>Se d\u00e9velopper pour atteindre plus<\/strong><\/p>\n<p>Pasteur King a encourag\u00e9 le groupe \u00e0 continuer de motiver les autres membres d\u2019\u00e9glise dans leurs \u00e9glises, mais aussi \u00e0 tendre leurs bras et \u00e0 amener d\u2019autres personnes aux pieds de J\u00e9sus.<\/p>\n<p>Dans moins de deux mois, en octobre, plus de 300 personnes malentendantes, interpr\u00e8tes et dirigeants d\u2019\u00e9glise devraient participer au quatri\u00e8me congr\u00e8s national annuel pour les sourds.<\/p>\n<p>\u00ab Dieu nous donne le privil\u00e8ge de travailler ensemble, sans fronti\u00e8res, comme une seule \u00e9glise, parce que nous partageons la m\u00eame Langue des Signes Mexicaine, \u00bb a dit pasteur Maldonado en s\u2019adressant aux d\u00e9l\u00e9gu\u00e9s. \u00ab Cette unit\u00e9, associ\u00e9e \u00e0 l\u2019engagement renouvel\u00e9 d\u2019\u00e9vang\u00e9liser la communaut\u00e9 des sourds, nous pr\u00e9pare \u00e0 recevoir \u2018la pluie de l\u2019arri\u00e8re-saison du Saint-Esprit\u2019 qui nous aidera \u00e0 accomplir cette mission. \u00bb<\/p>\n<p>Les dirigeants de l\u2019\u00e9glise se sont engag\u00e9s \u00e0 fournir davantage de ressources, telles que des le\u00e7ons de l\u2019\u00e9cole du sabbat, des hymnes et des \u00e9tudes bibliques, aux interpr\u00e8tes. En outre, des ressources seront mises \u00e0 disposition pour sensibiliser davantage les gens aux malentendants et \u00e0 leurs besoins dans les \u00e9glises, entre autres.<\/p>\n<p>Des plans sont en cours pour la tenue d\u2019un troisi\u00e8me atelier national d\u2019interpr\u00e8tes adventistes \u00e0 Puebla, au Mexique, l\u2019ann\u00e9e prochaine.<\/p>\n<p>Pour en savoir plus sur les initiatives et activit\u00e9s du minist\u00e8re des sourds et des besoins sp\u00e9ciaux dans le Nord du Mexique, visitez le site<br \/>\n<a href=\"https:\/\/adventistasumn.org\/\">adventistasumn.org<\/a><\/p>\n<p><em>Helena Corona a contribu\u00e9 \u00e0 ce reportage.<\/em><\/p>\n<p>Traduction: Patrick Luciathe<\/p>\n","protected":false},"excerpt":{"rendered":"<p>27 Ao\u00fbt 2019 | Villahermosa, Tabasco, Mexique | \u00c9quipe Informations DIA Dans le cadre des efforts actuellement d\u00e9ploy\u00e9s par l\u2019\u00c9glise adventiste du septi\u00e8me jour dans le Nord du Mexique pour&#8230;<\/p>\n","protected":false},"author":3,"featured_media":51263,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[21,19],"tags":[],"class_list":["post-51295","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles-du-territoire","category-rss-francais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Au Mexique, l\u2019\u00e9glise forme des interpr\u00e8tes en langue des signes pour mieux toucher les malentendants - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/interamerica.org\/fr\/2019\/08\/au-mexique-leglise-forme-des-interpretes-en-langue-des-signes-pour-mieux-toucher-les-malentendants\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Au Mexique, l\u2019\u00e9glise forme des interpr\u00e8tes en langue des signes pour mieux toucher les malentendants - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division\" \/>\n<meta property=\"og:description\" content=\"27 Ao\u00fbt 2019 | Villahermosa, Tabasco, Mexique | \u00c9quipe Informations DIA Dans le cadre des efforts actuellement d\u00e9ploy\u00e9s par l\u2019\u00c9glise adventiste du septi\u00e8me jour dans le Nord du Mexique pour...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/interamerica.org\/fr\/2019\/08\/au-mexique-leglise-forme-des-interpretes-en-langue-des-signes-pour-mieux-toucher-les-malentendants\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-28T00:31:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-08-28T16:54:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/interamerica.org\/wp-content\/uploads\/2019\/08\/nomu-interpreters-1280.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"libna\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"libna\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2019\\\/08\\\/au-mexique-leglise-forme-des-interpretes-en-langue-des-signes-pour-mieux-toucher-les-malentendants\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2019\\\/08\\\/au-mexique-leglise-forme-des-interpretes-en-langue-des-signes-pour-mieux-toucher-les-malentendants\\\/\"},\"author\":{\"name\":\"libna\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/#\\\/schema\\\/person\\\/29998f2bc2d8bd0d38662909289b54f1\"},\"headline\":\"Au Mexique, l\u2019\u00e9glise forme des interpr\u00e8tes en langue des signes pour mieux toucher les malentendants\",\"datePublished\":\"2019-08-28T00:31:32+00:00\",\"dateModified\":\"2019-08-28T16:54:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2019\\\/08\\\/au-mexique-leglise-forme-des-interpretes-en-langue-des-signes-pour-mieux-toucher-les-malentendants\\\/\"},\"wordCount\":1562,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2019\\\/08\\\/au-mexique-leglise-forme-des-interpretes-en-langue-des-signes-pour-mieux-toucher-les-malentendants\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/nomu-interpreters-1280.jpg\",\"articleSection\":[\"Nouvelles du territoire\",\"RSS Fran\u00e7ais\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/interamerica.org\\\/fr\\\/2019\\\/08\\\/au-mexique-leglise-forme-des-interpretes-en-langue-des-signes-pour-mieux-toucher-les-malentendants\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2019\\\/08\\\/au-mexique-leglise-forme-des-interpretes-en-langue-des-signes-pour-mieux-toucher-les-malentendants\\\/\",\"url\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2019\\\/08\\\/au-mexique-leglise-forme-des-interpretes-en-langue-des-signes-pour-mieux-toucher-les-malentendants\\\/\",\"name\":\"Au Mexique, l\u2019\u00e9glise forme des interpr\u00e8tes en langue des signes pour mieux toucher les malentendants - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2019\\\/08\\\/au-mexique-leglise-forme-des-interpretes-en-langue-des-signes-pour-mieux-toucher-les-malentendants\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2019\\\/08\\\/au-mexique-leglise-forme-des-interpretes-en-langue-des-signes-pour-mieux-toucher-les-malentendants\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/nomu-interpreters-1280.jpg\",\"datePublished\":\"2019-08-28T00:31:32+00:00\",\"dateModified\":\"2019-08-28T16:54:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/#\\\/schema\\\/person\\\/29998f2bc2d8bd0d38662909289b54f1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2019\\\/08\\\/au-mexique-leglise-forme-des-interpretes-en-langue-des-signes-pour-mieux-toucher-les-malentendants\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/interamerica.org\\\/fr\\\/2019\\\/08\\\/au-mexique-leglise-forme-des-interpretes-en-langue-des-signes-pour-mieux-toucher-les-malentendants\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2019\\\/08\\\/au-mexique-leglise-forme-des-interpretes-en-langue-des-signes-pour-mieux-toucher-les-malentendants\\\/#primaryimage\",\"url\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/nomu-interpreters-1280.jpg\",\"contentUrl\":\"https:\\\/\\\/interamerica.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/nomu-interpreters-1280.jpg\",\"width\":1280,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/2019\\\/08\\\/au-mexique-leglise-forme-des-interpretes-en-langue-des-signes-pour-mieux-toucher-les-malentendants\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Au Mexique, l\u2019\u00e9glise forme des interpr\u00e8tes en langue des signes pour mieux toucher les malentendants\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/\",\"name\":\"\u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/interamerica.org\\\/fr\\\/#\\\/schema\\\/person\\\/29998f2bc2d8bd0d38662909289b54f1\",\"name\":\"libna\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7c5bd30ae4b47a9ba3c856590957fd1d96dc588bf3ac05719d247e126840331f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7c5bd30ae4b47a9ba3c856590957fd1d96dc588bf3ac05719d247e126840331f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7c5bd30ae4b47a9ba3c856590957fd1d96dc588bf3ac05719d247e126840331f?s=96&d=mm&r=g\",\"caption\":\"libna\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Au Mexique, l\u2019\u00e9glise forme des interpr\u00e8tes en langue des signes pour mieux toucher les malentendants - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/interamerica.org\/fr\/2019\/08\/au-mexique-leglise-forme-des-interpretes-en-langue-des-signes-pour-mieux-toucher-les-malentendants\/","og_locale":"fr_FR","og_type":"article","og_title":"Au Mexique, l\u2019\u00e9glise forme des interpr\u00e8tes en langue des signes pour mieux toucher les malentendants - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division","og_description":"27 Ao\u00fbt 2019 | Villahermosa, Tabasco, Mexique | \u00c9quipe Informations DIA Dans le cadre des efforts actuellement d\u00e9ploy\u00e9s par l\u2019\u00c9glise adventiste du septi\u00e8me jour dans le Nord du Mexique pour...","og_url":"https:\/\/interamerica.org\/fr\/2019\/08\/au-mexique-leglise-forme-des-interpretes-en-langue-des-signes-pour-mieux-toucher-les-malentendants\/","og_site_name":"\u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division","article_published_time":"2019-08-28T00:31:32+00:00","article_modified_time":"2019-08-28T16:54:20+00:00","og_image":[{"width":1280,"height":800,"url":"https:\/\/interamerica.org\/wp-content\/uploads\/2019\/08\/nomu-interpreters-1280.jpg","type":"image\/jpeg"}],"author":"libna","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"libna","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/interamerica.org\/fr\/2019\/08\/au-mexique-leglise-forme-des-interpretes-en-langue-des-signes-pour-mieux-toucher-les-malentendants\/#article","isPartOf":{"@id":"https:\/\/interamerica.org\/fr\/2019\/08\/au-mexique-leglise-forme-des-interpretes-en-langue-des-signes-pour-mieux-toucher-les-malentendants\/"},"author":{"name":"libna","@id":"https:\/\/interamerica.org\/fr\/#\/schema\/person\/29998f2bc2d8bd0d38662909289b54f1"},"headline":"Au Mexique, l\u2019\u00e9glise forme des interpr\u00e8tes en langue des signes pour mieux toucher les malentendants","datePublished":"2019-08-28T00:31:32+00:00","dateModified":"2019-08-28T16:54:20+00:00","mainEntityOfPage":{"@id":"https:\/\/interamerica.org\/fr\/2019\/08\/au-mexique-leglise-forme-des-interpretes-en-langue-des-signes-pour-mieux-toucher-les-malentendants\/"},"wordCount":1562,"commentCount":0,"image":{"@id":"https:\/\/interamerica.org\/fr\/2019\/08\/au-mexique-leglise-forme-des-interpretes-en-langue-des-signes-pour-mieux-toucher-les-malentendants\/#primaryimage"},"thumbnailUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2019\/08\/nomu-interpreters-1280.jpg","articleSection":["Nouvelles du territoire","RSS Fran\u00e7ais"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/interamerica.org\/fr\/2019\/08\/au-mexique-leglise-forme-des-interpretes-en-langue-des-signes-pour-mieux-toucher-les-malentendants\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/interamerica.org\/fr\/2019\/08\/au-mexique-leglise-forme-des-interpretes-en-langue-des-signes-pour-mieux-toucher-les-malentendants\/","url":"https:\/\/interamerica.org\/fr\/2019\/08\/au-mexique-leglise-forme-des-interpretes-en-langue-des-signes-pour-mieux-toucher-les-malentendants\/","name":"Au Mexique, l\u2019\u00e9glise forme des interpr\u00e8tes en langue des signes pour mieux toucher les malentendants - \u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division","isPartOf":{"@id":"https:\/\/interamerica.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/interamerica.org\/fr\/2019\/08\/au-mexique-leglise-forme-des-interpretes-en-langue-des-signes-pour-mieux-toucher-les-malentendants\/#primaryimage"},"image":{"@id":"https:\/\/interamerica.org\/fr\/2019\/08\/au-mexique-leglise-forme-des-interpretes-en-langue-des-signes-pour-mieux-toucher-les-malentendants\/#primaryimage"},"thumbnailUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2019\/08\/nomu-interpreters-1280.jpg","datePublished":"2019-08-28T00:31:32+00:00","dateModified":"2019-08-28T16:54:20+00:00","author":{"@id":"https:\/\/interamerica.org\/fr\/#\/schema\/person\/29998f2bc2d8bd0d38662909289b54f1"},"breadcrumb":{"@id":"https:\/\/interamerica.org\/fr\/2019\/08\/au-mexique-leglise-forme-des-interpretes-en-langue-des-signes-pour-mieux-toucher-les-malentendants\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/interamerica.org\/fr\/2019\/08\/au-mexique-leglise-forme-des-interpretes-en-langue-des-signes-pour-mieux-toucher-les-malentendants\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/interamerica.org\/fr\/2019\/08\/au-mexique-leglise-forme-des-interpretes-en-langue-des-signes-pour-mieux-toucher-les-malentendants\/#primaryimage","url":"https:\/\/interamerica.org\/wp-content\/uploads\/2019\/08\/nomu-interpreters-1280.jpg","contentUrl":"https:\/\/interamerica.org\/wp-content\/uploads\/2019\/08\/nomu-interpreters-1280.jpg","width":1280,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/interamerica.org\/fr\/2019\/08\/au-mexique-leglise-forme-des-interpretes-en-langue-des-signes-pour-mieux-toucher-les-malentendants\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/interamerica.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Au Mexique, l\u2019\u00e9glise forme des interpr\u00e8tes en langue des signes pour mieux toucher les malentendants"}]},{"@type":"WebSite","@id":"https:\/\/interamerica.org\/fr\/#website","url":"https:\/\/interamerica.org\/fr\/","name":"\u00c9glise Adventiste Du Septieme Jour - Inter Am\u00e9rique Division","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/interamerica.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/interamerica.org\/fr\/#\/schema\/person\/29998f2bc2d8bd0d38662909289b54f1","name":"libna","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7c5bd30ae4b47a9ba3c856590957fd1d96dc588bf3ac05719d247e126840331f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7c5bd30ae4b47a9ba3c856590957fd1d96dc588bf3ac05719d247e126840331f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7c5bd30ae4b47a9ba3c856590957fd1d96dc588bf3ac05719d247e126840331f?s=96&d=mm&r=g","caption":"libna"}}]}},"_links":{"self":[{"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/posts\/51295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/comments?post=51295"}],"version-history":[{"count":0,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/posts\/51295\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/media\/51263"}],"wp:attachment":[{"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/media?parent=51295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/categories?post=51295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/interamerica.org\/fr\/wp-json\/wp\/v2\/tags?post=51295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}